{"id":99771,"date":"2018-04-02T17:03:53","date_gmt":"2018-04-02T15:03:53","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=99771"},"modified":"2018-04-02T17:03:53","modified_gmt":"2018-04-02T15:03:53","slug":"lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/","title":{"rendered":"LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-99773\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-01-1024x580.jpg\" alt=\"\" width=\"1024\" height=\"580\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-01-1024x580.jpg 1024w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-01-1024x580-306x173.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-01-1024x580-500x283.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-01-1024x580-810x459.jpg 810w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Im Vorfeld des diesj\u00e4hrigen Mobile World Congress in Barcelona hatte LG bekanntgegeben, dass man das hauseigene Smartphone-Flaggschiff nicht auf dem Event pr\u00e4sentieren wird sondern erst sp\u00e4ter 2018. Nun scheint demn\u00e4chst aber die Zeit der Pr\u00e4sentation gekommen zu sein und LG wird uns das LG G7 (oder auch mit anderem Namen) vorstellen.<\/p>\n<p>Erste Daten waren bereits im Netz zu lesen. Nun hat OnLeaks einmal mittels CADs ein entsprechendes 360\u00b0Render-Video erstellt, welches das Ger\u00e4t von allen Seiten zeigt. Erkennbar ist das von LG bekannte Design mit dem Fingerabdrucksensor an der R\u00fcckseite. Ebenfalls dort zu finden ist die vertikal angeordnete Dual-Kamera. Schaut man sich das Video genau an, erkennt man ebenfalls 4 Tasten an beiden Seiten. Hierbei d\u00fcrfte es sich um die Lautst\u00e4rketasten sowie einen Power-Button handeln. Wozu die vierte Taste ist, kann nur spekuliert werden.<\/p>\n<p>Ansonsten setzt auch LG auf eine Notch &#8211; ob es gef\u00e4llt oder nicht, muss der User selbst entscheiden. Vielleicht gibt&#8217;s ja wie bei Huawei direkt in den Einstellungen die M\u00f6glichkeit die Notch zu &#8222;verbergen&#8220;.<\/p>\n<div class=\"video-container\"><div style=\"position:relative;width:100%;max-width:810px;height:456px;background-color:black;color:white;padding:0px;\" data-video-id=\"JDsQXjMq4P4\">\n\t\t\t\t\t\t<div style=\"text-align: center;\">\n\t\t\t\t\t\t\t<span class=\"hint-text\">Erst durch Klick auf den Button werden Daten an Youtube \u00fcbermittelt und dir das Video angezeigt.<br\/>Mehr dazu in unserer <a href=\"https:\/\/www.deskmodder.de\/blog\/datenschutz-auf-deskmodder-de\/\" target=\"_blank\">Datenschutzrichtlinie<\/a><\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div style=\"text-align: center; margin-top: 10px;\">\n\t\t\t\t\t\t\t<button onclick=\"showVideo(this)\">Verstanden!<\/button>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"video-container\" style=\"display:none;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/JDsQXjMq4P4\/hqdefault.jpg\" alt=\"Vorschaubild\" style=\"width:100%; max-width:810px;\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script>\n\t\t\t\t\t\tfunction showVideo(button) {\n\t\t\t\t\t\t\tconst videoID = button.parentElement.parentElement.getAttribute(\"data-video-id\");\n\t\t\t\t\t\t\tconsole.log(\"Video ID:\", videoID); \/\/ Debugging\n\t\t\t\t\t\t\tconst iframeHTML = \"<iframe width='810' height='456' src='https:\/\/www.youtube-nocookie.com\/embed\/\" + videoID + \"?feature=oembed' frameborder='0' allow='accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture' allowfullscreen><\/iframe>\";\n\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").innerHTML = iframeHTML;\n\n\t\t\t\t\t\t\t\/\/ Video-Container sichtbar machen\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").style.display = \"block\";\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".hint-text\").style.display = \"none\";\n\t\t\t\t\t\t\tbutton.remove();\n\t\t\t\t\t\t}\n\t\t\t\t\t<\/script><\/div>\n<p>In Sachen Ausstattung wird das G7 wohl mit dem Snapdragon 845 kommen und 4 GB sowie 6 GB RAM haben. Die Dual-Kamera der R\u00fcckseite soll 2 x 16 MP Sensoren bieten. Ebenso gibt&#8217;s einen USB Typ C Anschluss und einen 3,5mm Klinkenanschluss. Das Display soll 6 Zoll gro\u00df sein und mit einem Seitenverh\u00e4ltnis von 19:9 kommen. Der interne Speicher betr\u00e4gt je nach Modell 64 GB oder 128 GB. Ob dieser erweitert werden kann, ist nicht bekannt.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/themrphone.com\/article\/lg-g7-renders-mr-phone-exclusive\" target=\"_blank\" rel=\"noopener\">@OnLeaks at TheMrPhone<\/a> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im Vorfeld des diesj\u00e4hrigen Mobile World Congress in Barcelona hatte LG bekanntgegeben, dass man das hauseigene Smartphone-Flaggschiff nicht auf dem Event pr\u00e4sentieren wird sondern erst sp\u00e4ter 2018. Nun scheint demn\u00e4chst aber die Zeit der Pr\u00e4sentation gekommen zu sein und LG&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":99772,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[34193],"class_list":["post-99771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-lg-g7-render-video"],"wp_featured_image":{"id":99772,"alt_text":"","description":"","media_type":"image","media_details":{"width":1024,"height":580,"file":"2018\/04\/lgg7-09-1024x580.jpg","sizes":{"thumbnail":{"file":"lgg7-09-1024x580-306x173.jpg","width":306,"height":173,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580-306x173.jpg"},"medium":{"file":"lgg7-09-1024x580-500x283.jpg","width":500,"height":283,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580-500x283.jpg"},"large":{"file":"lgg7-09-1024x580-810x459.jpg","width":810,"height":459,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580-810x459.jpg"},"wp_review_large":{"file":"lgg7-09-1024x580-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580-320x200.jpg"},"wp_review_small":{"file":"lgg7-09-1024x580-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580-65x65.jpg"},"blog-large":{"file":"lgg7-09-1024x580-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580-642x300.jpg"},"blog-medium":{"file":"lgg7-09-1024x580-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580-306x205.jpg"},"recent-thumb":{"file":"lgg7-09-1024x580-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580-350x316.jpg"},"service-featured":{"file":"lgg7-09-1024x580-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580-600x330.jpg"},"wp_rp_thumbnail":{"file":"lgg7-09-1024x580-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":99771,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht\" \/>\n<meta property=\"og:description\" content=\"Im Vorfeld des diesj\u00e4hrigen Mobile World Congress in Barcelona hatte LG bekanntgegeben, dass man das hauseigene Smartphone-Flaggschiff nicht auf dem Event pr\u00e4sentieren wird sondern erst sp\u00e4ter 2018. Nun scheint demn\u00e4chst aber die Zeit der Pr\u00e4sentation gekommen zu sein und LG&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-02T15:03:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht\",\"datePublished\":\"2018-04-02T15:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/\"},\"wordCount\":270,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/lgg7-09-1024x580.jpg\",\"keywords\":[\"LG G7 Render-Video\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/\",\"name\":\"LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/lgg7-09-1024x580.jpg\",\"datePublished\":\"2018-04-02T15:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/lgg7-09-1024x580.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/lgg7-09-1024x580.jpg\",\"width\":1024,\"height\":580},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/04\\\/02\\\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/","og_locale":"de_DE","og_type":"article","og_title":"LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht","og_description":"Im Vorfeld des diesj\u00e4hrigen Mobile World Congress in Barcelona hatte LG bekanntgegeben, dass man das hauseigene Smartphone-Flaggschiff nicht auf dem Event pr\u00e4sentieren wird sondern erst sp\u00e4ter 2018. Nun scheint demn\u00e4chst aber die Zeit der Pr\u00e4sentation gekommen zu sein und LG&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-04-02T15:03:53+00:00","og_image":[{"width":1024,"height":580,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht","datePublished":"2018-04-02T15:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/"},"wordCount":270,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580.jpg","keywords":["LG G7 Render-Video"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/","name":"LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580.jpg","datePublished":"2018-04-02T15:03:53+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580.jpg","width":1024,"height":580},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/04\/02\/lg-g7-render-video-zeigt-das-geraet-in-seiner-ganzen-pracht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"LG G7: Render-Video zeigt das Ger\u00e4t in seiner ganzen Pracht"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/04\/lgg7-09-1024x580.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/99771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=99771"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/99771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/99772"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=99771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=99771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=99771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}