{"id":99475,"date":"2018-03-27T08:19:03","date_gmt":"2018-03-27T06:19:03","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=99475"},"modified":"2018-03-27T08:50:21","modified_gmt":"2018-03-27T06:50:21","slug":"honor-9-lite-bekommt-face-unlock-spendiert","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/","title":{"rendered":"Honor 9 Lite bekommt Face Unlock spendiert"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-95545\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002.jpg\" alt=\"\" width=\"768\" height=\"768\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002.jpg 768w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-205x205.jpg 205w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-360x360.jpg 360w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-583x583.jpg 583w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-65x65.jpg 65w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-150x150.jpg 150w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Neben einem PIN einem Password oder dem Fingerabdruck l\u00e4sst sich heutzutage das Smartphone auch mittels der Gesichtserkennung entsperren. Viele Ger\u00e4te nutzen das Feature bereits. Und zu diesen darf sich nun auch das <a href=\"https:\/\/www.deskmodder.de\/blog\/2017\/12\/23\/honor-9-lite-vorgestellt\/\" target=\"_blank\" rel=\"noopener\">Honor 9 Lite<\/a> z\u00e4hlen<\/p>\n<p>Denn per Software-Update wird Face Unlock auf das Honor 9 Lite gebracht, so dass entsprechende User dann auch ihre Frontkamera zum Entsperren nutzen k\u00f6nnen. Wie immer wird das Update stufenweise ausgerollt. Es kann also auch noch ein paar Tage dauern, bis alle User versorgt wurden.<\/p>\n<p>Aktuell kostet das Honor 9 Lite um die 230,- Euro und liefert aktuelle, bekannte Hardware der Mittelklasse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neben einem PIN einem Password oder dem Fingerabdruck l\u00e4sst sich heutzutage das Smartphone auch mittels der Gesichtserkennung entsperren. Viele Ger\u00e4te nutzen das Feature bereits. Und zu diesen darf sich nun auch das Honor 9 Lite z\u00e4hlen Denn per Software-Update wird&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":95545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286,152],"tags":[28777,33752],"class_list":["post-99475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","category-software","tag-face-unlock","tag-honor-9-lite-update"],"wp_featured_image":{"id":95545,"alt_text":"","description":"","media_type":"image","media_details":{"width":768,"height":768,"file":"2017\/12\/gsmarena-002.jpg","sizes":{"thumbnail":{"file":"gsmarena-002-205x205.jpg","width":205,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-205x205.jpg"},"medium":{"file":"gsmarena-002-360x360.jpg","width":360,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-360x360.jpg"},"large":{"file":"gsmarena-002-583x583.jpg","width":583,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-583x583.jpg"},"wp_review_large":{"file":"gsmarena-002-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-320x200.jpg"},"wp_review_small":{"file":"gsmarena-002-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-65x65.jpg"},"blog-large":{"file":"gsmarena-002-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-642x300.jpg"},"blog-medium":{"file":"gsmarena-002-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-306x205.jpg"},"recent-thumb":{"file":"gsmarena-002-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-350x316.jpg"},"service-featured":{"file":"gsmarena-002-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-600x330.jpg"},"wp_rp_thumbnail":{"file":"gsmarena-002-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":95540,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002.jpg"},"commentcount":1,"wp_comments":[{"id":68566,"parent":0,"author":0,"author_name":"Peter","author_email":"ph1983@msn.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b643ad877d7524056bea2e55fa1662372ee18323c210db1683f498edaa865b25?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b643ad877d7524056bea2e55fa1662372ee18323c210db1683f498edaa865b25?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b643ad877d7524056bea2e55fa1662372ee18323c210db1683f498edaa865b25?s=96&d=mm&r=g"},"date":"2018-03-27T08:47:38","cld_nonce":"82f011626f","content":{"rendered":"<p><img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/> Facebook Unkock<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Honor 9 Lite bekommt Face Unlock spendiert - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Honor 9 Lite bekommt Face Unlock spendiert\" \/>\n<meta property=\"og:description\" content=\"Neben einem PIN einem Password oder dem Fingerabdruck l\u00e4sst sich heutzutage das Smartphone auch mittels der Gesichtserkennung entsperren. Viele Ger\u00e4te nutzen das Feature bereits. Und zu diesen darf sich nun auch das Honor 9 Lite z\u00e4hlen Denn per Software-Update wird&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-27T06:19:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-27T06:50:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Honor 9 Lite bekommt Face Unlock spendiert\",\"datePublished\":\"2018-03-27T06:19:03+00:00\",\"dateModified\":\"2018-03-27T06:50:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/\"},\"wordCount\":105,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/gsmarena-002.jpg\",\"keywords\":[\"Face Unlock\",\"Honor 9 Lite Update\"],\"articleSection\":{\"1\":\"Hardware\",\"2\":\"Software &amp; Updates\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/\",\"name\":\"Honor 9 Lite bekommt Face Unlock spendiert - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/gsmarena-002.jpg\",\"datePublished\":\"2018-03-27T06:19:03+00:00\",\"dateModified\":\"2018-03-27T06:50:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/gsmarena-002.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/gsmarena-002.jpg\",\"width\":768,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/27\\\/honor-9-lite-bekommt-face-unlock-spendiert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Honor 9 Lite bekommt Face Unlock spendiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Honor 9 Lite bekommt Face Unlock spendiert - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/","og_locale":"de_DE","og_type":"article","og_title":"Honor 9 Lite bekommt Face Unlock spendiert","og_description":"Neben einem PIN einem Password oder dem Fingerabdruck l\u00e4sst sich heutzutage das Smartphone auch mittels der Gesichtserkennung entsperren. Viele Ger\u00e4te nutzen das Feature bereits. Und zu diesen darf sich nun auch das Honor 9 Lite z\u00e4hlen Denn per Software-Update wird&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-03-27T06:19:03+00:00","article_modified_time":"2018-03-27T06:50:21+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Honor 9 Lite bekommt Face Unlock spendiert","datePublished":"2018-03-27T06:19:03+00:00","dateModified":"2018-03-27T06:50:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/"},"wordCount":105,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002.jpg","keywords":["Face Unlock","Honor 9 Lite Update"],"articleSection":{"1":"Hardware","2":"Software &amp; Updates"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/","name":"Honor 9 Lite bekommt Face Unlock spendiert - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002.jpg","datePublished":"2018-03-27T06:19:03+00:00","dateModified":"2018-03-27T06:50:21+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002.jpg","width":768,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/27\/honor-9-lite-bekommt-face-unlock-spendiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Honor 9 Lite bekommt Face Unlock spendiert"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/12\/gsmarena-002.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/99475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=99475"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/99475\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/95545"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=99475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=99475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=99475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}