{"id":98977,"date":"2018-03-13T10:39:36","date_gmt":"2018-03-13T09:39:36","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=98977"},"modified":"2018-03-13T14:54:12","modified_gmt":"2018-03-13T13:54:12","slug":"kein-broadcom-qualcomm-deal-intel-wird-sich-freuen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/","title":{"rendered":"Kein Broadcom Qualcomm Deal &#8211; Intel wird sich freuen"},"content":{"rendered":"<p>Die ganze Aufregung um den Kauf von Qualcomm durch Broadcom hat nun ein Ende gefunden. Donald Trump hat dem Ganzen nun ein Riegel vorgeschoben. Broadcom war schon einige Zeit dabei die Halbleiter-Firma Qualcomm zu \u00fcbernehmen. Man bot bis zu 130 Milliarden Dollar, um die Firma zu \u00fcbernehmen. Das war Qualcomm aber zu wenig.<\/p>\n<p>Auch die Zustimmung der US-Beh\u00f6rde hatte sich verz\u00f6gert. Jetzt hat Trump aus &#8222;Sicherheitsgr\u00fcnden&#8220; dem Ganzen Deal eine Abfuhr erteilt. <em>&#8222;Es gibt glaubw\u00fcrdige Beweise, die zu der Annahme f\u00fchren, dass Broadcom Limited, eine nach den Gesetzen in Singapurs (Broadcom) organisierte Aktiengesellschaft, durch die Kontrolle von Qualcomm Incorporated (Qualcomm), einem Unternehmen aus Delaware, Ma\u00dfnahmen ergreifen k\u00f6nnte, , die die nationale Sicherheit der Vereinigten Staaten zu beeintr\u00e4chtigen droht.&#8220;<\/em><\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo.jpg\" rel=\"lightbox[98977]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-466x360.jpg\" alt=\"\" width=\"466\" height=\"360\" class=\"aligncenter size-medium wp-image-96899\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-466x360.jpg 466w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-265x205.jpg 265w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-754x583.jpg 754w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo.jpg 792w\" sizes=\"auto, (max-width: 466px) 100vw, 466px\" \/><\/a><\/p>\n<p>Qualcomm wird es freuen und Intel auch. Denn Intel ist laut einem Bericht selber an Broadcom interessiert. Wir hatten <a href=\"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/intel-an-broadcom-und-damit-qualcomm-interessiert\/\" rel=\"noopener\" target=\"_blank\">dar\u00fcber berichtet<\/a>. Die US-Firma k\u00f6nnte so die Firma aus Singapur \u00fcbernehmen und br\u00e4uchte sich dann keine Gedanken machen sich die US Firma Qualcomm hinterher einzuverleiben. Solange die US-Beh\u00f6rden es wegen einem Markt-Monopol nicht verbieten.<\/p>\n<p>Man fragt sich nur, warum die US-Regierung erst jetzt auff\u00e4llt, dass Firmen aus anderen L\u00e4ndern die &#8222;Nationale Sicherheit&#8220; gef\u00e4hrden k\u00f6nnten&#8230;.. Der ganze Text der Ablehnung auf <a href=\"https:\/\/www.cnbc.com\/2018\/03\/12\/trump-issues-order-prohibiting-broadcoms-bid-to-take-over-qualcomm.html\" rel=\"noopener\" target=\"_blank\">cnbc.com<\/a>.<\/p>\n<p>via: <a href=\"https:\/\/www.neowin.net\/news\/broadcom-takeover-of-qualcomm-blocked-by-donald-trump\" rel=\"noopener\" target=\"_blank\">neowin<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die ganze Aufregung um den Kauf von Qualcomm durch Broadcom hat nun ein Ende gefunden. Donald Trump hat dem Ganzen nun ein Riegel vorgeschoben. Broadcom war schon einige Zeit dabei die Halbleiter-Firma Qualcomm zu \u00fcbernehmen. Man bot bis zu 130&hellip; <\/p>\n","protected":false},"author":134,"featured_media":96899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286],"tags":[24858,574,2758,32827],"class_list":["post-98977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","tag-broadcom","tag-intel","tag-qualcomm","tag-qualcomm-deal"],"wp_featured_image":{"id":96899,"alt_text":"","description":"","media_type":"image","media_details":{"width":792,"height":612,"file":"2018\/01\/qualcomm-logo.jpg","sizes":{"thumbnail":{"file":"qualcomm-logo-265x205.jpg","width":265,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-265x205.jpg"},"medium":{"file":"qualcomm-logo-466x360.jpg","width":466,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-466x360.jpg"},"large":{"file":"qualcomm-logo-754x583.jpg","width":754,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-754x583.jpg"},"wp_review_large":{"file":"qualcomm-logo-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-320x200.jpg"},"wp_review_small":{"file":"qualcomm-logo-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-65x65.jpg"},"blog-large":{"file":"qualcomm-logo-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-642x300.jpg"},"blog-medium":{"file":"qualcomm-logo-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-306x205.jpg"},"recent-thumb":{"file":"qualcomm-logo-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-350x316.jpg"},"service-featured":{"file":"qualcomm-logo-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-600x330.jpg"},"wp_rp_thumbnail":{"file":"qualcomm-logo-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":96898,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo.jpg"},"commentcount":3,"wp_comments":[{"id":67766,"parent":0,"author":0,"author_name":"SirMarcvonGoskon","author_email":"marcsenn@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=96&d=mm&r=g"},"date":"2018-03-13T12:41:01","cld_nonce":"82f011626f","content":{"rendered":"<p>Besser so, geht sowiso meistens nur um patente und 130 mill ist wirklich wennig wenn man bedenk das man den sofort plusminus 90% wenn nicht noch mehr, der handy hersteller mit cpu\/gpu beliefert<\/p>\n"},"status":"1"},{"id":67770,"parent":0,"author":0,"author_name":"RedVision81","author_email":"Redvision81@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/199e88eefc9fcd93bf9af3b35cbb886ab494a91cf20ffc93bc15a8f0c5e05166?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/199e88eefc9fcd93bf9af3b35cbb886ab494a91cf20ffc93bc15a8f0c5e05166?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/199e88eefc9fcd93bf9af3b35cbb886ab494a91cf20ffc93bc15a8f0c5e05166?s=96&d=mm&r=g"},"date":"2018-03-13T14:41:10","cld_nonce":"82f011626f","content":{"rendered":"<p>Sorry wenn ich hier rumn\u00f6len muss, aber die Rechtschreibung sollte schon gepr\u00fcft werden vorm einstellen:<\/p>\n<p>&#8222;Qualcomm wird es freuen udn Intel auch&#8230;&#8220;<\/p>\n<p>F\u00e4llt in letzter Zeit h\u00e4ufiger in diversen Portalen auf <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":67771,"parent":67770,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2018-03-13T14:56:19","cld_nonce":"82f011626f","content":{"rendered":"<p>Ein Tippfehler kann immer mal passieren. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><br \/>\nIst behoben.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kein Broadcom Qualcomm Deal - Intel wird sich freuen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kein Broadcom Qualcomm Deal - Intel wird sich freuen\" \/>\n<meta property=\"og:description\" content=\"Die ganze Aufregung um den Kauf von Qualcomm durch Broadcom hat nun ein Ende gefunden. Donald Trump hat dem Ganzen nun ein Riegel vorgeschoben. Broadcom war schon einige Zeit dabei die Halbleiter-Firma Qualcomm zu \u00fcbernehmen. Man bot bis zu 130&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-13T09:39:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-13T13:54:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"792\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Kein Broadcom Qualcomm Deal &#8211; Intel wird sich freuen\",\"datePublished\":\"2018-03-13T09:39:36+00:00\",\"dateModified\":\"2018-03-13T13:54:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/\"},\"wordCount\":224,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/qualcomm-logo.jpg\",\"keywords\":[\"Broadcom\",\"Intel\",\"Qualcomm\",\"Qualcomm Deal\"],\"articleSection\":[\"Hardware\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/\",\"name\":\"Kein Broadcom Qualcomm Deal - Intel wird sich freuen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/qualcomm-logo.jpg\",\"datePublished\":\"2018-03-13T09:39:36+00:00\",\"dateModified\":\"2018-03-13T13:54:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/qualcomm-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/qualcomm-logo.jpg\",\"width\":792,\"height\":612},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/13\\\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kein Broadcom Qualcomm Deal &#8211; Intel wird sich freuen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kein Broadcom Qualcomm Deal - Intel wird sich freuen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/","og_locale":"de_DE","og_type":"article","og_title":"Kein Broadcom Qualcomm Deal - Intel wird sich freuen","og_description":"Die ganze Aufregung um den Kauf von Qualcomm durch Broadcom hat nun ein Ende gefunden. Donald Trump hat dem Ganzen nun ein Riegel vorgeschoben. Broadcom war schon einige Zeit dabei die Halbleiter-Firma Qualcomm zu \u00fcbernehmen. Man bot bis zu 130&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-03-13T09:39:36+00:00","article_modified_time":"2018-03-13T13:54:12+00:00","og_image":[{"width":792,"height":612,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Kein Broadcom Qualcomm Deal &#8211; Intel wird sich freuen","datePublished":"2018-03-13T09:39:36+00:00","dateModified":"2018-03-13T13:54:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/"},"wordCount":224,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo.jpg","keywords":["Broadcom","Intel","Qualcomm","Qualcomm Deal"],"articleSection":["Hardware"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/","name":"Kein Broadcom Qualcomm Deal - Intel wird sich freuen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo.jpg","datePublished":"2018-03-13T09:39:36+00:00","dateModified":"2018-03-13T13:54:12+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo.jpg","width":792,"height":612},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/13\/kein-broadcom-qualcomm-deal-intel-wird-sich-freuen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Kein Broadcom Qualcomm Deal &#8211; Intel wird sich freuen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/qualcomm-logo.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/98977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=98977"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/98977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/96899"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=98977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=98977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=98977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}