{"id":98881,"date":"2018-03-10T05:19:29","date_gmt":"2018-03-10T04:19:29","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=98881"},"modified":"2018-03-10T05:19:29","modified_gmt":"2018-03-10T04:19:29","slug":"xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/","title":{"rendered":"Xiaomi Mi Mix 2S: Neuer Teaser &#038; erstes Video vom kommenden Smartphone"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-94684\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125.jpg\" alt=\"\" width=\"2100\" height=\"1010\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125.jpg 2100w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-306x147.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-500x240.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-810x390.jpg 810w\" sizes=\"auto, (max-width: 2100px) 100vw, 2100px\" \/><\/p>\n<p>Am 27.M\u00e4rz wird in China das neue Xiaomi Mi Mix 2S offiziell vorgestellt werden. Nachdem bereits einige Daten bekannt sind sowie erste Bilder im Netz gelandet waren, zeigt sich das Ger\u00e4t nun auch in einem Video.<\/p>\n<p>Das Video zeigt gut die in der oberen rechten Ecke befindliche Frontkamera des Xiaomi Mi Mix 2S.<\/p>\n<div class=\"video-container\"><div style=\"position:relative;width:100%;max-width:810px;height:456px;background-color:black;color:white;padding:0px;\" data-video-id=\"zESngYuOwPU\">\n\t\t\t\t\t\t<div style=\"text-align: center;\">\n\t\t\t\t\t\t\t<span class=\"hint-text\">Erst durch Klick auf den Button werden Daten an Youtube \u00fcbermittelt und dir das Video angezeigt.<br\/>Mehr dazu in unserer <a href=\"https:\/\/www.deskmodder.de\/blog\/datenschutz-auf-deskmodder-de\/\" target=\"_blank\">Datenschutzrichtlinie<\/a><\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div style=\"text-align: center; margin-top: 10px;\">\n\t\t\t\t\t\t\t<button onclick=\"showVideo(this)\">Verstanden!<\/button>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"video-container\" style=\"display:none;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/zESngYuOwPU\/hqdefault.jpg\" alt=\"Vorschaubild\" style=\"width:100%; max-width:810px;\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script>\n\t\t\t\t\t\tfunction showVideo(button) {\n\t\t\t\t\t\t\tconst videoID = button.parentElement.parentElement.getAttribute(\"data-video-id\");\n\t\t\t\t\t\t\tconsole.log(\"Video ID:\", videoID); \/\/ Debugging\n\t\t\t\t\t\t\tconst iframeHTML = \"<iframe width='810' height='456' src='https:\/\/www.youtube-nocookie.com\/embed\/\" + videoID + \"?feature=oembed' frameborder='0' allow='accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture' allowfullscreen><\/iframe>\";\n\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").innerHTML = iframeHTML;\n\n\t\t\t\t\t\t\t\/\/ Video-Container sichtbar machen\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").style.display = \"block\";\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".hint-text\").style.display = \"none\";\n\t\t\t\t\t\t\tbutton.remove();\n\t\t\t\t\t\t}\n\t\t\t\t\t<\/script><\/div>\n<p>Ausgestattet wird es mit dem neuen Snapdragon 845 sein, welchem nach letzten Informationen satte 8 GB RAM zur Seite gestellt werden. Der interne Speicher soll 256 GB betragen und an der R\u00fcckseite soll eine Dual-Kamera mit 2 x 12 MP verbaut sein. Nachdem Anfang M\u00e4rz ein Teaser nochmals den aktuellen Highend-Prozessor von Qualcomm best\u00e4tigt hatte, gibt&#8217;s jetzt auch ein weiteres Teaser-Bild, welches auf kabelloses Laden hinweisen k\u00f6nnte. Bislang hat Xiaomi noch kein Ger\u00e4t im Portfolio, welches Wireless Charging unterst\u00fctzt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-98883\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/03\/gsmarena-001.jpg\" alt=\"\" width=\"450\" height=\"800\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/03\/gsmarena-001.jpg 450w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/03\/gsmarena-001-115x205.jpg 115w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/03\/gsmarena-001-203x360.jpg 203w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/03\/gsmarena-001-328x583.jpg 328w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>Einige Tage m\u00fcssen wir uns noch gedulden, dann gibt&#8217;s alle Details.<\/p>\n<div class=\"viaquelle\">via: <a href=\"https:\/\/www.neowin.net\/news\/xiaomis-unannounced-mi-mix-2s-with-right-top-corner-notch-seen-in-video\" target=\"_blank\" rel=\"noopener\">Neowin<\/a>, <a href=\"https:\/\/m.gsmarena.com\/xiaomi_mi_mix_2s_will_have_wireless_charging-news-30012.php\" target=\"_blank\" rel=\"noopener\">GSMArena<\/a> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Am 27.M\u00e4rz wird in China das neue Xiaomi Mi Mix 2S offiziell vorgestellt werden. Nachdem bereits einige Daten bekannt sind sowie erste Bilder im Netz gelandet waren, zeigt sich das Ger\u00e4t nun auch in einem Video. Das Video zeigt gut&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":94684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[30112],"class_list":["post-98881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-xiaomi-mi-mix-2s"],"wp_featured_image":{"id":94684,"alt_text":"","description":"","media_type":"image","media_details":{"width":2100,"height":1010,"file":"2017\/11\/img-20171129-081125.jpg","sizes":{"thumbnail":{"file":"img-20171129-081125-306x147.jpg","width":306,"height":147,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-306x147.jpg"},"medium":{"file":"img-20171129-081125-500x240.jpg","width":500,"height":240,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-500x240.jpg"},"large":{"file":"img-20171129-081125-810x390.jpg","width":810,"height":390,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-810x390.jpg"},"wp_review_large":{"file":"img-20171129-081125-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-320x200.jpg"},"wp_review_small":{"file":"img-20171129-081125-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-65x65.jpg"},"blog-large":{"file":"img-20171129-081125-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-642x300.jpg"},"blog-medium":{"file":"img-20171129-081125-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-306x205.jpg"},"recent-thumb":{"file":"img-20171129-081125-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-350x316.jpg"},"service-featured":{"file":"img-20171129-081125-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-600x330.jpg"},"wp_rp_thumbnail":{"file":"img-20171129-081125-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":94682,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Xiaomi Mi Mix 2S: Neuer Teaser &amp; erstes Video vom kommenden Smartphone - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xiaomi Mi Mix 2S: Neuer Teaser &amp; erstes Video vom kommenden Smartphone\" \/>\n<meta property=\"og:description\" content=\"Am 27.M\u00e4rz wird in China das neue Xiaomi Mi Mix 2S offiziell vorgestellt werden. Nachdem bereits einige Daten bekannt sind sowie erste Bilder im Netz gelandet waren, zeigt sich das Ger\u00e4t nun auch in einem Video. Das Video zeigt gut&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-10T04:19:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2100\" \/>\n\t<meta property=\"og:image:height\" content=\"1010\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Xiaomi Mi Mix 2S: Neuer Teaser &#038; erstes Video vom kommenden Smartphone\",\"datePublished\":\"2018-03-10T04:19:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/\"},\"wordCount\":169,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/img-20171129-081125.jpg\",\"keywords\":[\"Xiaomi Mi Mix 2S\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/\",\"name\":\"Xiaomi Mi Mix 2S: Neuer Teaser & erstes Video vom kommenden Smartphone - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/img-20171129-081125.jpg\",\"datePublished\":\"2018-03-10T04:19:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/img-20171129-081125.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/img-20171129-081125.jpg\",\"width\":2100,\"height\":1010},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/03\\\/10\\\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xiaomi Mi Mix 2S: Neuer Teaser &#038; erstes Video vom kommenden Smartphone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Xiaomi Mi Mix 2S: Neuer Teaser & erstes Video vom kommenden Smartphone - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/","og_locale":"de_DE","og_type":"article","og_title":"Xiaomi Mi Mix 2S: Neuer Teaser & erstes Video vom kommenden Smartphone","og_description":"Am 27.M\u00e4rz wird in China das neue Xiaomi Mi Mix 2S offiziell vorgestellt werden. Nachdem bereits einige Daten bekannt sind sowie erste Bilder im Netz gelandet waren, zeigt sich das Ger\u00e4t nun auch in einem Video. Das Video zeigt gut&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-03-10T04:19:29+00:00","og_image":[{"width":2100,"height":1010,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Xiaomi Mi Mix 2S: Neuer Teaser &#038; erstes Video vom kommenden Smartphone","datePublished":"2018-03-10T04:19:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/"},"wordCount":169,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125.jpg","keywords":["Xiaomi Mi Mix 2S"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/","name":"Xiaomi Mi Mix 2S: Neuer Teaser & erstes Video vom kommenden Smartphone - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125.jpg","datePublished":"2018-03-10T04:19:29+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125.jpg","width":2100,"height":1010},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/03\/10\/xiaomi-mi-mix-2s-neuer-teaser-erstes-video-vom-kommenden-smartphone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Xiaomi Mi Mix 2S: Neuer Teaser &#038; erstes Video vom kommenden Smartphone"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/img-20171129-081125.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/98881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=98881"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/98881\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/94684"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=98881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=98881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=98881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}