{"id":97187,"date":"2018-01-30T15:05:55","date_gmt":"2018-01-30T14:05:55","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=97187"},"modified":"2018-01-30T15:10:06","modified_gmt":"2018-01-30T14:10:06","slug":"nokia-10-konzept-video-auf-grundlage-der-leaks","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/","title":{"rendered":"Nokia 10 Konzept Video auf Grundlage der Leaks"},"content":{"rendered":"<p>Das Nokia 10 von HMD ist das von vielen sicherlich mit Spannung erwartete neue Flaggschiff. Jetzt hat Concept Creator ein Konzept-Video vom Nokia 10 erstellt, dass auf den bisherigen Leaks basiert. Also besser kann es eine Werbeagentur auch nicht pr\u00e4sentieren. Das wohl auf\u00e4lligste Merkmal ist die Kamera mit der rotierenden Penta-Linse, die an das Nokia 1020 erinnert.<\/p>\n<p>Das 18:9 Display kommt mit Doppelglas vorne und hinten, vergleichbar mit dem Nokia 9. Sowie einem Fingerabdrucksensor hinten. Im Konzept enthalten ist der 3,5 mm Kopfh\u00f6reranschluss. Die CPU ist eine Snapdragon 845. Also genug Power f\u00fcr Android. Man kann gespannt sein, ob dieses Konzept dem echten Nokia 10 dann sehr nahe kommt.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1.jpg\" rel=\"lightbox[97187]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-500x274.jpg\" alt=\"\" width=\"500\" height=\"274\" class=\"aligncenter size-medium wp-image-97191\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-500x274.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-306x168.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-810x445.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-600x330.jpg 600w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1.jpg 1745w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Auf jeden Fall sieht es sehr schick aus. Schon alleine weil es kein randloses Display wie bei Samsung oder Apple ist. Aber schaut euch das Video einmal in Ruhe an.<\/p>\n<div class=\"video-container\"><div style=\"position:relative;width:100%;max-width:810px;height:456px;background-color:black;color:white;padding:0px;\" data-video-id=\"2X9wVVD60e4\">\n\t\t\t\t\t\t<div style=\"text-align: center;\">\n\t\t\t\t\t\t\t<span class=\"hint-text\">Erst durch Klick auf den Button werden Daten an Youtube \u00fcbermittelt und dir das Video angezeigt.<br\/>Mehr dazu in unserer <a href=\"https:\/\/www.deskmodder.de\/blog\/datenschutz-auf-deskmodder-de\/\" target=\"_blank\">Datenschutzrichtlinie<\/a><\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div style=\"text-align: center; margin-top: 10px;\">\n\t\t\t\t\t\t\t<button onclick=\"showVideo(this)\">Verstanden!<\/button>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"video-container\" style=\"display:none;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/2X9wVVD60e4\/hqdefault.jpg\" alt=\"Vorschaubild\" style=\"width:100%; max-width:810px;\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script>\n\t\t\t\t\t\tfunction showVideo(button) {\n\t\t\t\t\t\t\tconst videoID = button.parentElement.parentElement.getAttribute(\"data-video-id\");\n\t\t\t\t\t\t\tconsole.log(\"Video ID:\", videoID); \/\/ Debugging\n\t\t\t\t\t\t\tconst iframeHTML = \"<iframe width='810' height='456' src='https:\/\/www.youtube-nocookie.com\/embed\/\" + videoID + \"?feature=oembed' frameborder='0' allow='accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture' allowfullscreen><\/iframe>\";\n\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").innerHTML = iframeHTML;\n\n\t\t\t\t\t\t\t\/\/ Video-Container sichtbar machen\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").style.display = \"block\";\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".hint-text\").style.display = \"none\";\n\t\t\t\t\t\t\tbutton.remove();\n\t\t\t\t\t\t}\n\t\t\t\t\t<\/script><\/div>\n<p>via: <a href=\"https:\/\/nokiapoweruser.com\/nokia-10-concept-introduction-video-renders-based-leaks\/\" rel=\"noopener\" target=\"_blank\">npu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Nokia 10 von HMD ist das von vielen sicherlich mit Spannung erwartete neue Flaggschiff. Jetzt hat Concept Creator ein Konzept-Video vom Nokia 10 erstellt, dass auf den bisherigen Leaks basiert. Also besser kann es eine Werbeagentur auch nicht pr\u00e4sentieren.&hellip; <\/p>\n","protected":false},"author":134,"featured_media":97191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[894,1286],"tags":[30069,30068,30072,30070,30071],"class_list":["post-97187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-android","category-hardware","tag-mhd","tag-nokia-10","tag-nokia-10-leak","tag-nokia-10-video","tag-renderbilder"],"wp_featured_image":{"id":97191,"alt_text":"","description":"","media_type":"image","media_details":{"width":1745,"height":958,"file":"2018\/01\/nokia-10-1.jpg","sizes":{"thumbnail":{"file":"nokia-10-1-306x168.jpg","width":306,"height":168,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-306x168.jpg"},"medium":{"file":"nokia-10-1-500x274.jpg","width":500,"height":274,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-500x274.jpg"},"large":{"file":"nokia-10-1-810x445.jpg","width":810,"height":445,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-810x445.jpg"},"wp_review_large":{"file":"nokia-10-1-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-320x200.jpg"},"wp_review_small":{"file":"nokia-10-1-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-65x65.jpg"},"blog-large":{"file":"nokia-10-1-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-642x300.jpg"},"blog-medium":{"file":"nokia-10-1-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-306x205.jpg"},"recent-thumb":{"file":"nokia-10-1-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-350x316.jpg"},"service-featured":{"file":"nokia-10-1-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-600x330.jpg"},"wp_rp_thumbnail":{"file":"nokia-10-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":97187,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1.jpg"},"commentcount":3,"wp_comments":[{"id":65411,"parent":0,"author":0,"author_name":"Cluster Head","author_email":"just-an-illusion@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/18f29e1a66421136879904f8f7820ba53e205c1cc56d473f99b1fba26091bc0d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/18f29e1a66421136879904f8f7820ba53e205c1cc56d473f99b1fba26091bc0d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/18f29e1a66421136879904f8f7820ba53e205c1cc56d473f99b1fba26091bc0d?s=96&d=mm&r=g"},"date":"2018-01-30T15:18:19","cld_nonce":"82f011626f","content":{"rendered":"<p>Edel, edel&#8230;..! Vor allem das in Blau! Mal sehen, wie dass Endprodukt dann in der Realit\u00e4t aussieht!? Mein Nokia 8 gef\u00e4llt mir schon extrem gut. Und dass nicht nur in Punkto aussehen, sondern auch in Leistung und der Update Politik von HMD.<\/p>\n"},"status":"1"},{"id":65413,"parent":0,"author":0,"author_name":"Arndt","author_email":"arndtkeller@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b1fb18fbdf0c213c6484d559fe1bc3269cd72d32b2b5596d208a218820c78efb?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b1fb18fbdf0c213c6484d559fe1bc3269cd72d32b2b5596d208a218820c78efb?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b1fb18fbdf0c213c6484d559fe1bc3269cd72d32b2b5596d208a218820c78efb?s=96&d=mm&r=g"},"date":"2018-01-30T15:38:28","cld_nonce":"82f011626f","content":{"rendered":"<p>Ohh mein Lumia 950 XL Ersatz, er kommt! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":66251,"parent":0,"author":0,"author_name":"Lenny","author_email":"ruedigerochel@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/55f9c5644bffd65429da859d9b0c99b432825e0481ccb3cb1ab0f33523e67eda?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/55f9c5644bffd65429da859d9b0c99b432825e0481ccb3cb1ab0f33523e67eda?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/55f9c5644bffd65429da859d9b0c99b432825e0481ccb3cb1ab0f33523e67eda?s=96&d=mm&r=g"},"date":"2018-02-14T04:24:49","cld_nonce":"82f011626f","content":{"rendered":"<p>Oh Mann das gef\u00e4llt mir. Es erinnert mich an mein mittlerweile gestohlenes 950 XL <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_mad.gif\" alt=\":-x\" class=\"wp-smiley\" \/><br \/>\nWenn das so kommt, steht ganz gro\u00df Haben drauf <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":grin:\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nokia 10 Konzept Video auf Grundlage der Leaks - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nokia 10 Konzept Video auf Grundlage der Leaks\" \/>\n<meta property=\"og:description\" content=\"Das Nokia 10 von HMD ist das von vielen sicherlich mit Spannung erwartete neue Flaggschiff. Jetzt hat Concept Creator ein Konzept-Video vom Nokia 10 erstellt, dass auf den bisherigen Leaks basiert. Also besser kann es eine Werbeagentur auch nicht pr\u00e4sentieren.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-30T14:05:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-30T14:10:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1745\" \/>\n\t<meta property=\"og:image:height\" content=\"958\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Nokia 10 Konzept Video auf Grundlage der Leaks\",\"datePublished\":\"2018-01-30T14:05:55+00:00\",\"dateModified\":\"2018-01-30T14:10:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/\"},\"wordCount\":150,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/nokia-10-1.jpg\",\"keywords\":[\"MHD\",\"Nokia 10\",\"Nokia 10 Leak\",\"Nokia 10 Video\",\"Renderbilder\"],\"articleSection\":[\"Android\",\"Hardware\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/\",\"name\":\"Nokia 10 Konzept Video auf Grundlage der Leaks - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/nokia-10-1.jpg\",\"datePublished\":\"2018-01-30T14:05:55+00:00\",\"dateModified\":\"2018-01-30T14:10:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/nokia-10-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/nokia-10-1.jpg\",\"width\":1745,\"height\":958},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/30\\\/nokia-10-konzept-video-auf-grundlage-der-leaks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nokia 10 Konzept Video auf Grundlage der Leaks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nokia 10 Konzept Video auf Grundlage der Leaks - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/","og_locale":"de_DE","og_type":"article","og_title":"Nokia 10 Konzept Video auf Grundlage der Leaks","og_description":"Das Nokia 10 von HMD ist das von vielen sicherlich mit Spannung erwartete neue Flaggschiff. Jetzt hat Concept Creator ein Konzept-Video vom Nokia 10 erstellt, dass auf den bisherigen Leaks basiert. Also besser kann es eine Werbeagentur auch nicht pr\u00e4sentieren.&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-01-30T14:05:55+00:00","article_modified_time":"2018-01-30T14:10:06+00:00","og_image":[{"width":1745,"height":958,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Nokia 10 Konzept Video auf Grundlage der Leaks","datePublished":"2018-01-30T14:05:55+00:00","dateModified":"2018-01-30T14:10:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/"},"wordCount":150,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1.jpg","keywords":["MHD","Nokia 10","Nokia 10 Leak","Nokia 10 Video","Renderbilder"],"articleSection":["Android","Hardware"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/","name":"Nokia 10 Konzept Video auf Grundlage der Leaks - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1.jpg","datePublished":"2018-01-30T14:05:55+00:00","dateModified":"2018-01-30T14:10:06+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1.jpg","width":1745,"height":958},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/30\/nokia-10-konzept-video-auf-grundlage-der-leaks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Nokia 10 Konzept Video auf Grundlage der Leaks"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/01\/nokia-10-1.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/97187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=97187"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/97187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/97191"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=97187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=97187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=97187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}