{"id":96822,"date":"2018-01-23T05:06:31","date_gmt":"2018-01-23T04:06:31","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=96822"},"modified":"2018-01-23T05:07:36","modified_gmt":"2018-01-23T04:07:36","slug":"weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/","title":{"rendered":"Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-90572\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-810x541.jpg\" alt=\"\" width=\"810\" height=\"541\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-810x541.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-306x205.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-500x334.jpg 500w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/p>\n<p>Nachdem uns Sony auf der diesj\u00e4hrigen CES in Las Vegas seine neuen Mittelklasse-Smartphones pr\u00e4sentiert hatte, warten viele Sony Fans nun aber auf die Pr\u00e4sentation des eigentlichen Smartphone-Flaggschiffs. Dieses soll als Sony Xperia XZ Pro auf dem Mobile World Congress vorgestellt werden.<\/p>\n<p>Nachdem wir bereits vor einigen Tagen \u00fcber <a href=\"https:\/\/www.deskmodder.de\/blog\/2018\/01\/17\/sony-xperia-xz-pro-neue-infos-zum-kommenden-smartphone-flaggschiff\/\" target=\"_blank\" rel=\"noopener\">erste Spezifikationen<\/a> berichtet hatten, sind nun weitere Details aufgetaucht. So soll das Ger\u00e4t mit den Abmessungen von 152,79mm x 72,42mm etwas l\u00e4nger aber schmaler als der Vorg\u00e4nger werden. Die Abmessungen deuten somit auch auf ein Display mit einem Seitenverh\u00e4ltnis von 18:9 hin. Ebenso soll das neue Flaggschiff keinen 3,5mm Klinkenanschluss mehr haben. Auch hier soll ausschlie\u00dflich noch der USB Typ C Anschluss vorhanden sein.<\/p>\n<p>Dank <a href=\"https:\/\/twitter.com\/rquandt\/status\/955349097443020800\" target=\"_blank\" rel=\"noopener\">Roland Quandt<\/a> gibt&#8217;s nun auch noch Angaben zum vermeintlichen Preis sowie den Farben. In den Farben Schwarz, Silber und Dunkelgr\u00fcn soll das Xperia XZ Pro erscheinen und f\u00fcr 699 Euro erh\u00e4ltlich sein. Weitere Farben sollen aber m\u00f6glicherweise noch kommen.<\/p>\n<p>In wenigen Wochen wissen wir mehr. Bis dahin wird es noch den ein\u00a0 oder anderen Leak vorab geben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem uns Sony auf der diesj\u00e4hrigen CES in Las Vegas seine neuen Mittelklasse-Smartphones pr\u00e4sentiert hatte, warten viele Sony Fans nun aber auf die Pr\u00e4sentation des eigentlichen Smartphone-Flaggschiffs. Dieses soll als Sony Xperia XZ Pro auf dem Mobile World Congress vorgestellt&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":90572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[29205],"class_list":["post-96822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-sony-xperia-xz-pro"],"wp_featured_image":{"id":90572,"alt_text":"","description":"","media_type":"image","media_details":{"width":2858,"height":1910,"file":"2017\/09\/sony-logo-ifa17.jpg","sizes":{"thumbnail":{"file":"sony-logo-ifa17-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-306x205.jpg"},"medium":{"file":"sony-logo-ifa17-500x334.jpg","width":500,"height":334,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-500x334.jpg"},"large":{"file":"sony-logo-ifa17-810x541.jpg","width":810,"height":541,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-810x541.jpg"},"wp_review_large":{"file":"sony-logo-ifa17-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-320x200.jpg"},"wp_review_small":{"file":"sony-logo-ifa17-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-65x65.jpg"},"blog-large":{"file":"sony-logo-ifa17-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-642x300.jpg"},"blog-medium":{"file":"sony-logo-ifa17-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-306x205.jpg"},"recent-thumb":{"file":"sony-logo-ifa17-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-350x316.jpg"},"service-featured":{"file":"sony-logo-ifa17-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-600x330.jpg"},"wp_rp_thumbnail":{"file":"sony-logo-ifa17-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17-150x150.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"Canon PowerShot A590 IS","caption":"","created_timestamp":"1504374442","copyright":"","focal_length":"5.8","iso":"80","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]}},"post":91035,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff\" \/>\n<meta property=\"og:description\" content=\"Nachdem uns Sony auf der diesj\u00e4hrigen CES in Las Vegas seine neuen Mittelklasse-Smartphones pr\u00e4sentiert hatte, warten viele Sony Fans nun aber auf die Pr\u00e4sentation des eigentlichen Smartphone-Flaggschiffs. Dieses soll als Sony Xperia XZ Pro auf dem Mobile World Congress vorgestellt&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-23T04:06:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-23T04:07:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2858\" \/>\n\t<meta property=\"og:image:height\" content=\"1910\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff\",\"datePublished\":\"2018-01-23T04:06:31+00:00\",\"dateModified\":\"2018-01-23T04:07:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/\"},\"wordCount\":188,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/sony-logo-ifa17.jpg\",\"keywords\":[\"Sony Xperia XZ Pro\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/\",\"name\":\"Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/sony-logo-ifa17.jpg\",\"datePublished\":\"2018-01-23T04:06:31+00:00\",\"dateModified\":\"2018-01-23T04:07:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/sony-logo-ifa17.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/sony-logo-ifa17.jpg\",\"width\":2858,\"height\":1910},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/01\\\/23\\\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/","og_locale":"de_DE","og_type":"article","og_title":"Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff","og_description":"Nachdem uns Sony auf der diesj\u00e4hrigen CES in Las Vegas seine neuen Mittelklasse-Smartphones pr\u00e4sentiert hatte, warten viele Sony Fans nun aber auf die Pr\u00e4sentation des eigentlichen Smartphone-Flaggschiffs. Dieses soll als Sony Xperia XZ Pro auf dem Mobile World Congress vorgestellt&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-01-23T04:06:31+00:00","article_modified_time":"2018-01-23T04:07:36+00:00","og_image":[{"width":2858,"height":1910,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff","datePublished":"2018-01-23T04:06:31+00:00","dateModified":"2018-01-23T04:07:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/"},"wordCount":188,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17.jpg","keywords":["Sony Xperia XZ Pro"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/","name":"Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17.jpg","datePublished":"2018-01-23T04:06:31+00:00","dateModified":"2018-01-23T04:07:36+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17.jpg","width":2858,"height":1910},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/01\/23\/weitere-details-zum-kommenden-sony-xperia-smartphone-flaggschiff\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Weitere Details zum kommenden Sony Xperia Smartphone-Flaggschiff"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/sony-logo-ifa17.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/96822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=96822"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/96822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/90572"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=96822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=96822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=96822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}