{"id":95815,"date":"2017-12-28T15:30:55","date_gmt":"2017-12-28T14:30:55","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=95815"},"modified":"2017-12-28T14:57:43","modified_gmt":"2017-12-28T13:57:43","slug":"oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/","title":{"rendered":"OnePlus 3 &#038; OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-86282\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-810x456.png\" alt=\"\" width=\"810\" height=\"456\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-810x456.png 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-306x172.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-500x281.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534.png 1080w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/p>\n<p>Eben hatten wir \u00fcber die neue OxygenOS-Version f\u00fcr das OnePlus 5T berichtet. Aber auch die User eines OnePlus 3 und OnePlus 3T werden nicht vergessen. Zumindest wurden hier nun neue Open Betaversionen bereitgestellt, welche auf Android N beruhen.<\/p>\n<p>F\u00fcr das OnePlus 3 steht nun f\u00fcr die Tester die Open Betaversion 29 und f\u00fcr die Tester eines OnePlus 3T die Open Betaversion 20 bereit. Im Folgenden einmal der komplette Changelog:<\/p>\n<p>Notes (New OnePlus app)<\/p>\n<ul>\n<li>Take notes quickly and simply<\/li>\n<li>Share notes as picture<\/li>\n<li>Memo widget on Shelf is editable<\/li>\n<\/ul>\n<p>Quick clipboard<\/p>\n<ul>\n<li>Enhanced copying and editing ability<\/li>\n<\/ul>\n<p>Weather<\/p>\n<ul>\n<li>New weather widget<\/li>\n<\/ul>\n<p>File Manager<\/p>\n<ul>\n<li>Added large files category<\/li>\n<li>Speed improvements while deleting massive files<\/li>\n<\/ul>\n<p>System<\/p>\n<ul>\n<li>Added OTG toggle in Quick Settings<\/li>\n<li>Added notification when 3rd party apps delete contacts<\/li>\n<li>Updated Android security patch to December<\/li>\n<li>General bug fixes and improvements<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Eben hatten wir \u00fcber die neue OxygenOS-Version f\u00fcr das OnePlus 5T berichtet. Aber auch die User eines OnePlus 3 und OnePlus 3T werden nicht vergessen. Zumindest wurden hier nun neue Open Betaversionen bereitgestellt, welche auf Android N beruhen. F\u00fcr das&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":86282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,894,1286,152],"tags":[11997,15036,21178],"class_list":["post-95815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-android","category-hardware","category-software","tag-oneplus-3","tag-oneplus-3t","tag-open-betaversion-vom-oxygenos"],"wp_featured_image":{"id":86282,"alt_text":"","description":"","media_type":"image","media_details":{"width":1080,"height":608,"file":"2017\/06\/img-20170609-184534.png","sizes":{"thumbnail":{"file":"img-20170609-184534-306x172.png","width":306,"height":172,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-306x172.png"},"medium":{"file":"img-20170609-184534-500x281.png","width":500,"height":281,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-500x281.png"},"large":{"file":"img-20170609-184534-810x456.png","width":810,"height":456,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-810x456.png"},"wp_review_large":{"file":"img-20170609-184534-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-320x200.png"},"wp_review_small":{"file":"img-20170609-184534-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-65x65.png"},"blog-large":{"file":"img-20170609-184534-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-642x300.png"},"blog-medium":{"file":"img-20170609-184534-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-306x205.png"},"recent-thumb":{"file":"img-20170609-184534-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-350x316.png"},"service-featured":{"file":"img-20170609-184534-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-600x330.png"},"wp_rp_thumbnail":{"file":"img-20170609-184534-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":86281,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534.png"},"commentcount":1,"wp_comments":[{"id":63474,"parent":0,"author":0,"author_name":"Franz","author_email":"fitzgerald@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5bf72ef7b324662a56a49005a1baae2be7baa086bc85df7228c10bace426d9ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5bf72ef7b324662a56a49005a1baae2be7baa086bc85df7228c10bace426d9ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5bf72ef7b324662a56a49005a1baae2be7baa086bc85df7228c10bace426d9ca?s=96&d=mm&r=g"},"date":"2017-12-28T16:23:55","cld_nonce":"82f011626f","content":{"rendered":"<p>Hoffentlich geht das Battery Draining endlich weg!<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>OnePlus 3 &amp; OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OnePlus 3 &amp; OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar\" \/>\n<meta property=\"og:description\" content=\"Eben hatten wir \u00fcber die neue OxygenOS-Version f\u00fcr das OnePlus 5T berichtet. Aber auch die User eines OnePlus 3 und OnePlus 3T werden nicht vergessen. Zumindest wurden hier nun neue Open Betaversionen bereitgestellt, welche auf Android N beruhen. F\u00fcr das&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-28T14:30:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"OnePlus 3 &#038; OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar\",\"datePublished\":\"2017-12-28T14:30:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/\"},\"wordCount\":145,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/img-20170609-184534.png\",\"keywords\":[\"OnePlus 3\",\"OnePlus 3T\",\"Open Betaversion vom OxygenOS\"],\"articleSection\":{\"1\":\"Android\",\"2\":\"Hardware\",\"3\":\"Software &amp; Updates\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/\",\"name\":\"OnePlus 3 & OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/img-20170609-184534.png\",\"datePublished\":\"2017-12-28T14:30:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/img-20170609-184534.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/img-20170609-184534.png\",\"width\":1080,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/12\\\/28\\\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OnePlus 3 &#038; OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"OnePlus 3 & OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/","og_locale":"de_DE","og_type":"article","og_title":"OnePlus 3 & OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar","og_description":"Eben hatten wir \u00fcber die neue OxygenOS-Version f\u00fcr das OnePlus 5T berichtet. Aber auch die User eines OnePlus 3 und OnePlus 3T werden nicht vergessen. Zumindest wurden hier nun neue Open Betaversionen bereitgestellt, welche auf Android N beruhen. F\u00fcr das&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-12-28T14:30:55+00:00","og_image":[{"width":1080,"height":608,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534.png","type":"image\/png"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"OnePlus 3 &#038; OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar","datePublished":"2017-12-28T14:30:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/"},"wordCount":145,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534.png","keywords":["OnePlus 3","OnePlus 3T","Open Betaversion vom OxygenOS"],"articleSection":{"1":"Android","2":"Hardware","3":"Software &amp; Updates"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/","name":"OnePlus 3 & OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534.png","datePublished":"2017-12-28T14:30:55+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534.png","width":1080,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/12\/28\/oneplus-3-oneplus-3t-neue-open-betaversionen-verfuegbar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"OnePlus 3 &#038; OnePlus 3T: Neue Open Betaversionen verf\u00fcgbar"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/img-20170609-184534.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/95815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=95815"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/95815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/86282"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=95815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=95815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=95815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}