{"id":94622,"date":"2017-11-27T17:30:06","date_gmt":"2017-11-27T16:30:06","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=94622"},"modified":"2023-01-14T17:12:13","modified_gmt":"2023-01-14T16:12:13","slug":"hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/","title":{"rendered":"HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert"},"content":{"rendered":"<p>Die Firmen k\u00f6nnen es einfach nicht lassen, ungefragt Dienste zu installieren, die dazu dienen Telemetriedaten zu \u00fcbermitteln. So nun auch HP mit seinem Touchpoint Analytics Client. Als Beschreibung gibt HP auf seiner Webseite an: &#8222;Die HP Touchpoint Manager Technologie wird nun als Teil der <em>HP Device as a Service (DaaS) Analytics und Proactive Management<\/em> Funktion ausgeliefert. Aus diesem Grund stellt HP die selbstverwaltete HP Touchpoint Manager-L\u00f6sung ein.&#8220;<\/p>\n<p>Dieser erscheint in den Diensten, wo man ihn auch deaktivieren kann. Dort steht er unter &#8222;HP Touchpoint Analytics Client&#8220; mit der Beschreibung: &#8222;Sammelt Telemetrie-Informationen, die von HP Touchpoints analytischen Diensten verwendet werden.&#8220; Aber diesen Dienst kann man ohne weiteres deaktivieren.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/hp-touchpoint-analytics-client.jpg\" rel=\"lightbox[94622]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/hp-touchpoint-analytics-client-319x360.jpg\" alt=\"\" width=\"319\" height=\"360\" class=\"aligncenter size-medium wp-image-94623\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/hp-touchpoint-analytics-client-319x360.jpg 319w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/hp-touchpoint-analytics-client-182x205.jpg 182w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/11\/hp-touchpoint-analytics-client.jpg 420w\" sizes=\"auto, (max-width: 319px) 100vw, 319px\" \/><\/a><\/p>\n<p>Dazu gibt man Dienste in die Suche der Taskleiste ein, oder Windows-Taste + R <strong>services.msc<\/strong> und geht dort auf die Suche. Den Dienst dann doppelt anklicken und auf deaktiviert stellen. Wer den kompletten &#8222;HP Touchpoint Manager&#8220; entfernen m\u00f6chte, der gibt \u00fcber Windows-Taste + R <strong>appwiz.cpl<\/strong> ein und deinstalliert das Tool, was wohl eh keiner ben\u00f6tigt. Hier sonst auch die <a href=\"https:\/\/support.hp.com\/us-en\/document\/c04163604\" rel=\"noopener\" target=\"_blank\">Anleitung von HP<\/a> selber.<\/p>\n<p>Viele haben sich schon dar\u00fcber aufgeregt und beschwert. So auch im <a href=\"https:\/\/h30434.www3.hp.com\/t5\/Desktop-Software-and-How-To-Questions\/I-Didn-t-Install-HP-TouchpointAnalyticsClient-and-It-s\/td-p\/6427652\" rel=\"noopener\" target=\"_blank\">HP-Forum<\/a>, oder <a href=\"https:\/\/www.reddit.com\/r\/Hewlett_Packard\/comments\/7erb8w\/hp_touchpoint_analytics_client\/\" rel=\"noopener\" target=\"_blank\">reddit<\/a>. Da ich nichts mit HP zu tun habe, die Frage an euch. Ist der Dienst bei euch auch installiert worden?<\/p>\n<p>via: <a href=\"https:\/\/www.borncity.com\/blog\/2017\/11\/27\/hp-installiert-heimlich-hp-touchpoint-analytics-client-telemetriedatenprogramm\/\" rel=\"noopener\" target=\"_blank\">borncity<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Firmen k\u00f6nnen es einfach nicht lassen, ungefragt Dienste zu installieren, die dazu dienen Telemetriedaten zu \u00fcbermitteln. So nun auch HP mit seinem Touchpoint Analytics Client. Als Beschreibung gibt HP auf seiner Webseite an: &#8222;Die HP Touchpoint Manager Technologie wird&hellip; <\/p>\n","protected":false},"author":134,"featured_media":72748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286,2689,11],"tags":[26287,26288,26291,26289,26290],"class_list":["post-94622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","category-windows-10","category-windows","tag-hp-hp-touchpoint-analytics-client","tag-hp-telemetrie-dienst-deaktivieren","tag-hp-touchpoint-analytics","tag-hp-touchpoint-deinstallieren","tag-windows-10-hp-touchpoint"],"wp_featured_image":{"id":72748,"alt_text":"","description":"","media_type":"image","media_details":{"width":461,"height":360,"file":"2016\/09\/hp-logo-redesign_640-461x360.jpg","sizes":{"thumbnail":{"file":"hp-logo-redesign_640-461x360-263x205.jpg","width":263,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360-263x205.jpg"},"medium":{"file":"hp-logo-redesign_640-461x360-461x360.jpg","width":461,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360-461x360.jpg"},"wp_review_large":{"file":"hp-logo-redesign_640-461x360-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360-320x200.jpg"},"wp_review_small":{"file":"hp-logo-redesign_640-461x360-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360-65x65.jpg"},"blog-large":{"file":"hp-logo-redesign_640-461x360-461x300.jpg","width":461,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360-461x300.jpg"},"blog-medium":{"file":"hp-logo-redesign_640-461x360-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360-306x205.jpg"},"recent-thumb":{"file":"hp-logo-redesign_640-461x360-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360-350x316.jpg"},"service-featured":{"file":"hp-logo-redesign_640-461x360-461x330.jpg","width":461,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360-461x330.jpg"},"wp_rp_thumbnail":{"file":"hp-logo-redesign_640-461x360-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":72746,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360.jpg"},"commentcount":2,"wp_comments":[{"id":60496,"parent":0,"author":0,"author_name":"Dekre","author_email":"detlef.krentz@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/cca83c68f8ba4c703ec6b800e954aec25225f3513f6b98fb74bd9fb7663c1f9f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/cca83c68f8ba4c703ec6b800e954aec25225f3513f6b98fb74bd9fb7663c1f9f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/cca83c68f8ba4c703ec6b800e954aec25225f3513f6b98fb74bd9fb7663c1f9f?s=96&d=mm&r=g"},"date":"2017-11-27T19:13:03","cld_nonce":"82f011626f","content":{"rendered":"<p>Der &#8222;HP Touchpoint Manager&#8220; hat nichts mit dem Telemetriedatenprogramm &#8222;HP Touchpoint Analytics Client&#8220; zu tun. F\u00fcr das erstere muss man bezahlen. Es ist ein Programm um u.a. bei Diebstahl die Ger\u00e4te zu verfolgen. Daf\u00fcr muss man sich auch registrieren.<\/p>\n"},"status":"1"},{"id":60596,"parent":0,"author":0,"author_name":"G\u00fcnter Born","author_email":"gborn@borncity.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c6c3d1982d1426f034067bc433aee9708e29fee40430338da1564f848e4e9bf9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c6c3d1982d1426f034067bc433aee9708e29fee40430338da1564f848e4e9bf9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c6c3d1982d1426f034067bc433aee9708e29fee40430338da1564f848e4e9bf9?s=96&d=mm&r=g"},"date":"2017-11-29T23:51:52","cld_nonce":"82f011626f","content":{"rendered":"<p>Herr Krentz, von dem der erste Hinweis stammt, hatte hatte schon in seinem Kommentar darauf hingewiesen, dass das Ganz nichts mit dem \u201eHP Touchpoint Manager\u201c zu tun hat. Ich habe inzwischen meinen Artikel um weitere Details &#8211;<br \/>\n u.a. Stellungsnahmen von HP und weitere Insides erg\u00e4nzt. <\/p>\n<p><a href=\"http:\/\/www.borncity.com\/blog\/2017\/11\/27\/hp-installiert-heimlich-hp-touchpoint-analytics-client-telemetriedatenprogramm\/\" rel=\"nofollow ugc\">http:\/\/www.borncity.com\/blog\/2017\/11\/27\/hp-installiert-heimlich-hp-touchpoint-analytics-client-telemetriedatenprogramm\/<\/a><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert\" \/>\n<meta property=\"og:description\" content=\"Die Firmen k\u00f6nnen es einfach nicht lassen, ungefragt Dienste zu installieren, die dazu dienen Telemetriedaten zu \u00fcbermitteln. So nun auch HP mit seinem Touchpoint Analytics Client. Als Beschreibung gibt HP auf seiner Webseite an: &#8222;Die HP Touchpoint Manager Technologie wird&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-27T16:30:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-14T16:12:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"461\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert\",\"datePublished\":\"2017-11-27T16:30:06+00:00\",\"dateModified\":\"2023-01-14T16:12:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/\"},\"wordCount\":220,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/hp-logo-redesign_640-461x360.jpg\",\"keywords\":[\"HP HP Touchpoint Analytics Client\",\"HP Telemetrie Dienst deaktivieren\",\"HP Touchpoint Analytics\",\"HP Touchpoint deinstallieren\",\"Windows 10 HP Touchpoint\"],\"articleSection\":[\"Hardware\",\"Windows 10\",\"Windows \u00e4lter\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/\",\"name\":\"HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/hp-logo-redesign_640-461x360.jpg\",\"datePublished\":\"2017-11-27T16:30:06+00:00\",\"dateModified\":\"2023-01-14T16:12:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/hp-logo-redesign_640-461x360.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/hp-logo-redesign_640-461x360.jpg\",\"width\":461,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/27\\\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/","og_locale":"de_DE","og_type":"article","og_title":"HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert","og_description":"Die Firmen k\u00f6nnen es einfach nicht lassen, ungefragt Dienste zu installieren, die dazu dienen Telemetriedaten zu \u00fcbermitteln. So nun auch HP mit seinem Touchpoint Analytics Client. Als Beschreibung gibt HP auf seiner Webseite an: &#8222;Die HP Touchpoint Manager Technologie wird&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-11-27T16:30:06+00:00","article_modified_time":"2023-01-14T16:12:13+00:00","og_image":[{"width":461,"height":360,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert","datePublished":"2017-11-27T16:30:06+00:00","dateModified":"2023-01-14T16:12:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/"},"wordCount":220,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360.jpg","keywords":["HP HP Touchpoint Analytics Client","HP Telemetrie Dienst deaktivieren","HP Touchpoint Analytics","HP Touchpoint deinstallieren","Windows 10 HP Touchpoint"],"articleSection":["Hardware","Windows 10","Windows \u00e4lter"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/","name":"HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360.jpg","datePublished":"2017-11-27T16:30:06+00:00","dateModified":"2023-01-14T16:12:13+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360.jpg","width":461,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/27\/hp-touchpoint-analytics-client-als-telemetrie-service-wird-heimlich-mitinstalliert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"HP Touchpoint Analytics Client als Telemetrie-Service wird heimlich mitinstalliert"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/09\/hp-logo-redesign_640-461x360.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/94622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=94622"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/94622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/72748"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=94622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=94622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=94622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}