{"id":93838,"date":"2017-11-09T05:54:19","date_gmt":"2017-11-09T04:54:19","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=93838"},"modified":"2017-11-09T07:38:59","modified_gmt":"2017-11-09T06:38:59","slug":"mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/","title":{"rendered":"MediaTek will vorerst keine Highend-Prozessor  mehr produzieren"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15722\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-500x274.jpg\" alt=\"\" width=\"500\" height=\"274\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-500x274.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-150x82.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg 620w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Schaut man mal ins Innere der Smartphones, dann gibt&#8217;s oftmals als Herzst\u00fcck einen Prozessor von Qualcomm oder MediaTek. Weiterhin gibt&#8217;s die Eigenproduktionen von Apple, Samsung und Co., welche immer mehr zum Einsatz kommen.<\/p>\n<p>Im Highend-Bereich hatte dieses Jahr MediaTek seinen Helio X30 vorgestellt und versucht, hiermit die Hersteller zu \u00fcberzeugen. Doch gegen\u00fcber der Konkurrenz von Qualcomm hatte man das Nachsehen. Der Helio X30 war einfach in Teilen nicht geeignet, um die Hersteller zu \u00fcberzeugen.<\/p>\n<p>Und nun teilt MediaTek mit, dass man sich vorerst aus dem Gesch\u00e4ft der Highend-Prozessoren zur\u00fcckziehen wird. Man wird das Hauptaugenmerk auf die eigenen Mittelklasse-Prozessoren der Helio P-Reihe setzen, welche deutlich h\u00e4ufiger zum Einsatz kommen.<\/p>\n<p>Zumindest im Highend-Bereich bei den mobilen Prozessoren gibt es einen Mitstreiter weniger. Mal schauen ob hier 2018 jemand anders MediaTeks Platz einnehmen wird.<\/p>\n<p><div class=\"quelle\">Quelle: <a href=\"https:\/\/gearburn.com\/2017\/11\/mediatek-break-flagship-chips\/\" target=\"_blank\" rel=\"noopener\">gearburn<\/a> <\/div><div class=\"viaquelle\">via: <a href=\"https:\/\/www.mobiflip.de\/mediatek-high-end\/amp\/\" target=\"_blank\" rel=\"noopener\">Mobiflip<\/a> <\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schaut man mal ins Innere der Smartphones, dann gibt&#8217;s oftmals als Herzst\u00fcck einen Prozessor von Qualcomm oder MediaTek. Weiterhin gibt&#8217;s die Eigenproduktionen von Apple, Samsung und Co., welche immer mehr zum Einsatz kommen. Im Highend-Bereich hatte dieses Jahr MediaTek seinen&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":15722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286,231],"tags":[3704,3589],"class_list":["post-93838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","category-mobile","tag-mediatek","tag-prozessoren"],"wp_featured_image":{"id":15722,"alt_text":"","description":"","media_type":"image","media_details":{"width":620,"height":340,"file":"2013\/11\/mediatek-chip.jpg","sizes":{"thumbnail":{"file":"mediatek-chip-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-150x150.jpg"},"medium":{"file":"mediatek-chip-150x82.jpg","width":150,"height":82,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-150x82.jpg"},"large":{"file":"mediatek-chip-500x274.jpg","width":500,"height":274,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-500x274.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":15721,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg"},"commentcount":3,"wp_comments":[{"id":59477,"parent":0,"author":0,"author_name":"sirmarc","author_email":"marcsenn@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=96&d=mm&r=g"},"date":"2017-11-09T12:20:28","cld_nonce":"82f011626f","content":{"rendered":"<p>Wer gibt es den noch ausser Mediatek und samsungs cpu und Qualcomm?<\/p>\n"},"status":"1"},{"id":59481,"parent":59477,"author":0,"author_name":"Stefan","author_email":"stefanandlinger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d4acefc3626d22b7e3066389a5ed8041b670bdf2a463ba270cdb7ab5045c23f3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d4acefc3626d22b7e3066389a5ed8041b670bdf2a463ba270cdb7ab5045c23f3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d4acefc3626d22b7e3066389a5ed8041b670bdf2a463ba270cdb7ab5045c23f3?s=96&d=mm&r=g"},"date":"2017-11-09T13:01:36","cld_nonce":"82f011626f","content":{"rendered":"<p>Baut TSMC nicht die Halbleiterchips f\u00fcr Apple, Qualcomm, NVIDIA, AMD, Conexant, Marvell, VIA und Broadcom?<\/p>\n"},"status":"1"},{"id":59492,"parent":59477,"author":4122,"author_name":"aydin_bln","author_email":"aydin_bln@msn.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/2173993a616c06084fa6c9a724ff84d50ea7c1df1cfeb1a08ece94874bd9274b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/2173993a616c06084fa6c9a724ff84d50ea7c1df1cfeb1a08ece94874bd9274b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/2173993a616c06084fa6c9a724ff84d50ea7c1df1cfeb1a08ece94874bd9274b?s=96&d=mm&r=g"},"date":"2017-11-09T17:12:17","cld_nonce":"82f011626f","content":{"rendered":"<p><img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_surprised.gif\" alt=\":eek:\" class=\"wp-smiley\" \/> im mobilen Bereich gibt es noch Hisilicon Kirin Prozessors von Huawei (:<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MediaTek will vorerst keine Highend-Prozessor mehr produzieren - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MediaTek will vorerst keine Highend-Prozessor mehr produzieren\" \/>\n<meta property=\"og:description\" content=\"Schaut man mal ins Innere der Smartphones, dann gibt&#8217;s oftmals als Herzst\u00fcck einen Prozessor von Qualcomm oder MediaTek. Weiterhin gibt&#8217;s die Eigenproduktionen von Apple, Samsung und Co., welche immer mehr zum Einsatz kommen. Im Highend-Bereich hatte dieses Jahr MediaTek seinen&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-09T04:54:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T06:38:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"MediaTek will vorerst keine Highend-Prozessor mehr produzieren\",\"datePublished\":\"2017-11-09T04:54:19+00:00\",\"dateModified\":\"2017-11-09T06:38:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/\"},\"wordCount\":152,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/mediatek-chip.jpg\",\"keywords\":[\"MediaTek\",\"Prozessoren\"],\"articleSection\":{\"1\":\"Hardware\",\"2\":\"Mobile\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/\",\"name\":\"MediaTek will vorerst keine Highend-Prozessor mehr produzieren - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/mediatek-chip.jpg\",\"datePublished\":\"2017-11-09T04:54:19+00:00\",\"dateModified\":\"2017-11-09T06:38:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/mediatek-chip.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/mediatek-chip.jpg\",\"width\":620,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/11\\\/09\\\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MediaTek will vorerst keine Highend-Prozessor mehr produzieren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MediaTek will vorerst keine Highend-Prozessor mehr produzieren - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/","og_locale":"de_DE","og_type":"article","og_title":"MediaTek will vorerst keine Highend-Prozessor mehr produzieren","og_description":"Schaut man mal ins Innere der Smartphones, dann gibt&#8217;s oftmals als Herzst\u00fcck einen Prozessor von Qualcomm oder MediaTek. Weiterhin gibt&#8217;s die Eigenproduktionen von Apple, Samsung und Co., welche immer mehr zum Einsatz kommen. Im Highend-Bereich hatte dieses Jahr MediaTek seinen&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-11-09T04:54:19+00:00","article_modified_time":"2017-11-09T06:38:59+00:00","og_image":[{"width":620,"height":340,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"MediaTek will vorerst keine Highend-Prozessor mehr produzieren","datePublished":"2017-11-09T04:54:19+00:00","dateModified":"2017-11-09T06:38:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/"},"wordCount":152,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","keywords":["MediaTek","Prozessoren"],"articleSection":{"1":"Hardware","2":"Mobile"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/","name":"MediaTek will vorerst keine Highend-Prozessor mehr produzieren - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","datePublished":"2017-11-09T04:54:19+00:00","dateModified":"2017-11-09T06:38:59+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","width":620,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/11\/09\/mediatek-soll-vorerst-keine-highend-prozessor-enthalten-mehr-produzieren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"MediaTek will vorerst keine Highend-Prozessor mehr produzieren"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/93838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=93838"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/93838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/15722"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=93838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=93838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=93838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}