{"id":93228,"date":"2017-10-25T13:14:04","date_gmt":"2017-10-25T11:14:04","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=93228"},"modified":"2017-10-25T16:04:00","modified_gmt":"2017-10-25T14:04:00","slug":"update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/","title":{"rendered":"Update auf die Windows 10 1709 &#8211; Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar]"},"content":{"rendered":"<p>Seit dem 17.Oktober gibt es nun die neue Windows 10 1709 16299 (Fall Creators Update). Viele sind ja schon vorher dank der <a href=\"https:\/\/www.deskmodder.de\/blog\/2017\/09\/27\/16299-iso-esd-deutsch-english\/\" target=\"_blank\" rel=\"noopener\">ISO-Dateien<\/a> umgestiegen. Ich hatte damit noch gewartet. Denn ich brauchte immer noch einen Vergleich zwischen der neuen Version, die in einer virtuellen Maschine l\u00e4uft, und der &#8222;alten&#8220; 1703 f\u00fcr das <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" target=\"_blank\" rel=\"noopener\">Windows 10 Wiki<\/a>.<\/p>\n<p>Gestern hatte ich aus Neugierde nach einem neuen kumulativen Update Ausschau gehalten und hab in den Einstellungen auf &#8222;Nach Updates suchen gedr\u00fcckt&#8220; und nat\u00fcrlich prompt die 1709 aufgedr\u00fcckt bekommen. Alles kein Problem. Dienstags l\u00e4uft eh bei mir das Backup automatisch durch, kann also nicht viel schief gehen.<\/p>\n<p>Und es ging nicht viel schief. Einzig die <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Das_Windows_10_Startmen%C3%BC_richtig_einrichten_Tipps_und_Tricks\" target=\"_blank\" rel=\"noopener\">vorgeschlagenen Apps im Startmen\u00fc<\/a> tauchten wieder auf. Kann man mit leben. Aber ansonsten wurde hier soweit alles in Ruhe gelassen. Selbst die <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=UAC_Benutzerkontensteuerung_deaktivieren_einstellen_Windows_10\" target=\"_blank\" rel=\"noopener\">Benutzerkontensteuerung<\/a> blieb so, wie ich sie eingestellt hatte.<\/p>\n<p>Dass man bei den Systemwiederherstellungspunkten nachschauen muss und diese wieder aktivieren muss, ist nicht neu. Denn durch das Update werden die angelegten \u00fcberfl\u00fcssig. Warum Microsoft diese nicht einfach nur l\u00f6scht, aber die Einstellung auf &#8222;An&#8220; l\u00e4sst, kann ich nicht nachvollziehen. Wer nachschauen will: <em>Windows-Taste + R<\/em> dr\u00fccken und <em>SystemPropertiesProtection.exe<\/em> eingeben und starten.<\/p>\n<p>In den Foren und sonst wo liest man die reinsten Horrorgeschichten. Und wie bei jedem Featureupdate kommen dann nat\u00fcrlich auch wieder die \u00fcblichen Spr\u00fcche, wie &#8222;Microsoft kann nichts&#8220;, &#8222;Es wird alles immer schlimmer&#8220; und nat\u00fcrlich &#8222;ich wechsele zu Apple&#8220;. Komisch nur, dass die das alle halbe Jahr loslassen. Klar berichten wir auch \u00fcber die Probleme. Nur eben nicht als Horrorgeschichte, sondern mit Workarounds oder L\u00f6sungen, wie man es l\u00f6sen kann.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_1709_16299_oder_1703_15063_l%C3%A4sst_sich_nicht_installieren\" target=\"_blank\" rel=\"noopener\">Dass Probleme auftreten<\/a>, ist logisch. Ich schreibe ja immer wieder, dass jeder Rechner seinen eigenen &#8222;Charakter&#8220; hat. Bedingt durch die verschiedene Ausstattung, den f\u00fcr die Hardware unterschiedlich bereitgestellten Treibern und nicht zu vergessen durch die installierte Software. Aber deshalb Microsoft immer und ewig die Schuld zuweisen, finde ich pers\u00f6nlich nicht fair. So, nun d\u00fcrft ihr auch ein Wort dazu sagen.<\/p>\n<h3>Windows 10 Tutorials und Hilfe<\/h3>\n<p>Ihr sucht weitere Tipps, Tricks und Tutorials f\u00fcr Windows 10? Dann schaut in unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" target=\"_blank\" rel=\"noopener\"><strong>Wiki<\/strong><\/a> vorbei bzw. speichert die Seite in den Favoriten. Falls ihr Fragen habt, dann stellt diese (auch als Gast) ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=326\" target=\"_blank\" rel=\"noopener\"><strong>Forum<\/strong><\/a>. Wir werden versuchen euch bei euren Problemen zu helfen.<\/p>\n<ul>\n<li>Wichtige Tutorials im Wiki:<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_reparieren_wiederherstellen_mit_DISM_Inplace_Upgrade_und_vielen_weiteren_Varianten\" target=\"_blank\" rel=\"noopener\">Windows 10 reparieren, Fehler beheben<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_Update_reparieren_Windows_10\" target=\"_blank\" rel=\"noopener\">Win 10 Updates reparieren<\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Automatische_Updates_deaktivieren_oder_auf_manuell_setzen_Windows_10\" target=\"_blank\" rel=\"noopener\">richtig einstellen<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Autostart_Windows_10_Programme_deaktivieren_hinzuf%C3%BCgen_entfernen\" target=\"_blank\" rel=\"noopener\">Windows 10 Autostart Programme entfernen<\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Datentr%C3%A4gerbereinigung_Windows_10_Alte_Daten_richtig_l%C3%B6schen\" target=\"_blank\" rel=\"noopener\">Festplatte \/ SSD aufr\u00e4umen<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_automatisch_anmelden_ohne_Passworteingabe\" target=\"_blank\" rel=\"noopener\">Ohne Passwort anmelden Windows 10<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Cortana_deaktivieren_Windows_10\" target=\"_blank\" rel=\"noopener\">Cortana entfernen, deaktivieren<\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Onedrive_deinstallieren_windows_10\" target=\"_blank\" rel=\"noopener\">OneDive entfernen<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Das_Windows_10_Startmen%C3%BC_richtig_einrichten_Tipps_und_Tricks\" target=\"_blank\" rel=\"noopener\">Windows 10 Tipps zum Startmen\u00fc <\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Startmen%C3%BC_reparieren_Windows_10\" target=\"_blank\" rel=\"noopener\">Reparatur<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Seit dem 17.Oktober gibt es nun die neue Windows 10 1709 16299 (Fall Creators Update). Viele sind ja schon vorher dank der ISO-Dateien umgestiegen. Ich hatte damit noch gewartet. Denn ich brauchte immer noch einen Vergleich zwischen der neuen Version,&hellip; <\/p>\n","protected":false},"author":134,"featured_media":84588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[24080,22281],"class_list":["post-93228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-probleme-bei-der-installation","tag-windows-10-1709-fall-creators-update"],"wp_featured_image":{"id":84588,"alt_text":"","description":"","media_type":"image","media_details":{"width":1600,"height":1000,"file":"2017\/05\/windows10-fall-creators-update.jpg","sizes":{"thumbnail":{"file":"windows10-fall-creators-update-306x191.jpg","width":306,"height":191,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update-306x191.jpg"},"medium":{"file":"windows10-fall-creators-update-500x313.jpg","width":500,"height":313,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update-500x313.jpg"},"large":{"file":"windows10-fall-creators-update-810x506.jpg","width":810,"height":506,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update-810x506.jpg"},"wp_review_large":{"file":"windows10-fall-creators-update-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update-320x200.jpg"},"wp_review_small":{"file":"windows10-fall-creators-update-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update-65x65.jpg"},"blog-large":{"file":"windows10-fall-creators-update-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update-642x300.jpg"},"blog-medium":{"file":"windows10-fall-creators-update-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update-306x205.jpg"},"recent-thumb":{"file":"windows10-fall-creators-update-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update-350x316.jpg"},"service-featured":{"file":"windows10-fall-creators-update-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update-600x330.jpg"},"wp_rp_thumbnail":{"file":"windows10-fall-creators-update-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":84581,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update.jpg"},"commentcount":24,"wp_comments":[{"id":58812,"parent":0,"author":0,"author_name":"Hoffnung","author_email":"zenpeneu@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9afab5a0d0e075a49d566c46de0490105508b72e249791213ff291e504960acf?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9afab5a0d0e075a49d566c46de0490105508b72e249791213ff291e504960acf?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9afab5a0d0e075a49d566c46de0490105508b72e249791213ff291e504960acf?s=96&d=mm&r=g"},"date":"2017-10-25T13:24:33","cld_nonce":"b6d6726996","content":{"rendered":"<p>MS ist wie das wahre Leben es l\u00e4uft nicht alles so wie man es sich denkt.<\/p>\n"},"status":"1"},{"id":58813,"parent":0,"author":0,"author_name":"Peter Sch\u00f6nthal","author_email":"peter@schoenthal.org","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4e83a9b1764fe459346d3570c6a963a3d3c565324c1317d04f2c6dcbb4b6b083?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4e83a9b1764fe459346d3570c6a963a3d3c565324c1317d04f2c6dcbb4b6b083?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4e83a9b1764fe459346d3570c6a963a3d3c565324c1317d04f2c6dcbb4b6b083?s=96&d=mm&r=g"},"date":"2017-10-25T13:27:29","cld_nonce":"b6d6726996","content":{"rendered":"<p>So was von einverstanden. Sehr guter Artikel.<\/p>\n"},"status":"1"},{"id":58814,"parent":0,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-10-25T13:36:12","cld_nonce":"b6d6726996","content":{"rendered":"<p>Oh ja, das kann man ruhig laut sagen \/ schreiben <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/> <\/p>\n<p>ich hatte die Tage diverse &#8222;kleine&#8220; Problemchen &#8211; z.B. das mit dem Nachtmodus ging nicht bzw. der schaltete sich immer ein , obwohl sich da an der Bildschirmfront gar nix tat &#8211; im Startmen\u00fc hatte ich diverse Programme \/ Apps immer als &#8222;NEU&#8220; stehen, und das war auch nach jdem Neustart wieder da (trotz anklicken mit rechter Maustaste <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/> ) <\/p>\n<p>Und das alles mit der Version 16299.19 (16299.15 + CU \u00fcber Windows Update) &#8211; Inplaceinstallation behob mir diese &#8222;Fehlerchen&#8220; nicht noch nebenbei bemerke <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n<p>Nun habe ich folgendes gemacht :<\/p>\n<p>16299 (.0) installiert (Clean) &#8211; TreiberUpdate ausgestellt &#8211; Windows Update angesto\u00dfen, es wurde dann nach anf\u00e4nlichen Hin und Hergezicke dann das Update 16299.19 DIREKT eingespielt &#8211; und siehe da , Grafik geht richtig, Nachtmodus geht richtig und neu installierte Prgramme seh ich nach anklicken mit der rechten Maustaste auch keine mehr ( nach Neustart) <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n<p>Das jeder PC \/ Rechner so seine Macken hat kann man ja nicht ausschlie\u00dfen , aber jetzt ist mein einzigstes Problem das ich (mal wieder) mein Office 2016 nicht aktiviert bekomme <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":58815,"parent":0,"author":0,"author_name":"Axel58","author_email":"axel.schmeissner@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9435a43dd49215dd8ef999063d52c6140b21abd9435bf57f79c6cfc273fe52c3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9435a43dd49215dd8ef999063d52c6140b21abd9435bf57f79c6cfc273fe52c3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9435a43dd49215dd8ef999063d52c6140b21abd9435bf57f79c6cfc273fe52c3?s=96&d=mm&r=g"},"date":"2017-10-25T13:49:22","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich habe noch nichts gefunden, was ich als wesentlich Neu ansehen kann.<br \/>\nDas Update verlief problemlos durch.<br \/>\nLediglich hat mein Computer den MS Joystick nicht sofort gefunden,<br \/>\nwas aber kein Problem war, USB gezogen und wieder angeschlossen.<br \/>\nWas aber immer noch nicht geht sind auf dem Startbildschirm, das<br \/>\nWetter, der Kalender u.a.<br \/>\nEinzig hier erscheint das Datum und die Uhrzeit, hier stehe ich aber<br \/>\nnicht alleine die MS Hilfe Seite bietet auch noch keine<br \/>\nL\u00f6sung an.<\/p>\n"},"status":"1"},{"id":58816,"parent":58814,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-10-25T13:55:55","cld_nonce":"b6d6726996","content":{"rendered":"<p>Achja Nachtrag, nach erfolgtem CleanInstall ist einer der ersten Sachen was ich automatisch von mir aus ausschalte die Systemwiederherstellungsoption, die habe ich noch nie gebraucht , wenn alles ann\u00e4hernd &#8222;perfekt&#8220; l\u00e4uft wird eh mit externem Programm ein SystemImage gemacht <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":58817,"parent":0,"author":0,"author_name":"Karl","author_email":"Karl@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7fa1ab665c9cbc7fcb7227e4a32c0d88221f568db6533ea479b28977fe5efdce?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7fa1ab665c9cbc7fcb7227e4a32c0d88221f568db6533ea479b28977fe5efdce?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7fa1ab665c9cbc7fcb7227e4a32c0d88221f568db6533ea479b28977fe5efdce?s=96&d=mm&r=g"},"date":"2017-10-25T14:04:14","cld_nonce":"b6d6726996","content":{"rendered":"<p>Microsoft immer und ewig die Schuld zuweisen finde ich auch nicht fair.<br \/>\nAber wenn seit Jahren immer wieder die selben Fehler auftauchen, die in vorherigen Versionen nicht mehr vorhanden waren, dann zeigt das doch, dass die ausgelieferten Windows-Versionen nur unzureichend getestet werden (trotz Insiderprogramm).<br \/>\nWarum kann man in der 1709 z.B. das Anmeldebild nicht mehr ver\u00e4ndern? Das ging in der Vorversion doch problemlos.<br \/>\nViel schlimmer ist aber, dass seit Windows NT 3.x der selbe Netzwerkfehler in allen weiteren Versionen vorhanden ist.<br \/>\nEs ist oft nicht m\u00f6glich, freigegebene Ordner \u00fcber die Schreibweise &#8222;\\\\Rechnername\\Ordnername&#8220; zu erreichen.<br \/>\nWenn im Netzwerk nur eine Fehlermeldung produziert wird weil z.B. ein Netzwerkdrucker nicht erreichbar ist (da ausgeschaltet), wir jeder weitere Versuch mit o.a. angef\u00fchrten Schreibweise auf Netzwerkressourcen zuzugreifen mit einer Fehlermeldung quittiert.<br \/>\nWohl dem, der dann ein Systemimage zur Wiederherstellung hat.<br \/>\nAuch die Einstellungen in der Netzwerkumgebung (z.B. die Anzeige der IP-Adresse) kann sich das dumme Teil bis heute nicht merken.<br \/>\nDie Hoffnung, dass der grosse unfehlbare Konzern das alles einmal richtet, statt dauernd neue unn\u00f6tige Tools in sein Betriebssystem zu packen, habe ich inzwischen aufgegeben.<br \/>\nWindows kann eigentlich nur sein Entwickler lieben.<\/p>\n"},"status":"1"},{"id":58818,"parent":58817,"author":0,"author_name":"Axel58","author_email":"axel.schmeissner@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9435a43dd49215dd8ef999063d52c6140b21abd9435bf57f79c6cfc273fe52c3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9435a43dd49215dd8ef999063d52c6140b21abd9435bf57f79c6cfc273fe52c3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9435a43dd49215dd8ef999063d52c6140b21abd9435bf57f79c6cfc273fe52c3?s=96&d=mm&r=g"},"date":"2017-10-25T14:08:55","cld_nonce":"b6d6726996","content":{"rendered":"<p>Anmeldebildschirm geht bei meinem Rechner von Anfang an nicht<br \/>\n(Ausnahme Datum, Uhrzeit).<\/p>\n<p>Wurde von MS auf dem Anmeldebildschirm gefragt ob ich das haben m\u00f6chte, bisher wurde aber nichts getan.<\/p>\n"},"status":"1"},{"id":58819,"parent":0,"author":0,"author_name":"SirMarc","author_email":"marcsenn@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=96&d=mm&r=g"},"date":"2017-10-25T14:14:23","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich installiere jedes upgrade per Clean install, ssd 250gb l\u00f6schen und auf weiter, 16port Business switch ausgeschaltet,<br \/>\nHab so immer am  wenigsten problem.<br \/>\nMit office 2016 pro plus aber nie probleme<br \/>\nApps werden alle gel\u00f6scht plus webshop<br \/>\nDa kommt den auch nichts nach.<br \/>\nHatte noch nie probleme, mit keinem Windows.<\/p>\n"},"status":"1"},{"id":58820,"parent":0,"author":0,"author_name":"Holgi","author_email":"holger_freese@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=96&d=mm&r=g"},"date":"2017-10-25T14:31:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>ich bekomme Windows 10 1709 nicht auf meinen Bootcamp unter Apple MACOS 10.13 (HighSierra) auf MacMini 2014.<br \/>\nEs ging weder ein Update vom alten 1607, noch eine Neuinstallation \u00fcber USB Stick. Nach dem kopieren der Dateien und mehreren Neustarts bricht das Setup immer wieder ab.<br \/>\nHabe gelesen, dass es schon im April Schwierigkeiten gab, die 1703 zu installieren und Apple und MS sich gegenseitig die Schuld zuweisen.<br \/>\nIrgendjemand eine L\u00f6sung?<br \/>\nIch k\u00f6nnte mir vorstellen, dass die Bootcamp-Driver veraltet sind (Stand 6.1) und Apple wohl auch keine gro\u00dfe Lust hat, sich dahinterzuklemmen. Ansonsten habe ich Windows 1709 noch auf jede noch so alte Hardware bekommen.<br \/>\nSelbst meinen alten Windows Tablets (HP und DELL) laufen super unter 1709. Die Dinger kamen urspr\u00fcnglich mal mit Windows 8.1 raus.<\/p>\n"},"status":"1"},{"id":58821,"parent":58816,"author":0,"author_name":"Corinne","author_email":"corinnelaub@women-at-work.org","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3a8b3219afbaf103b59e7f634a5d78678f10a055b110aaa9f8c81b2a400efc36?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3a8b3219afbaf103b59e7f634a5d78678f10a055b110aaa9f8c81b2a400efc36?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3a8b3219afbaf103b59e7f634a5d78678f10a055b110aaa9f8c81b2a400efc36?s=96&d=mm&r=g"},"date":"2017-10-25T14:32:37","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ist ja sch\u00f6n und gut, dass bei einem Clean-Install eitel Sonnenschein ist, daf\u00fcr muss man das ganze ***system wieder von null auf einrichten. Clean-Install ist f\u00fcr alle ausser den Nerd schlicht UNZUMUTBAR.<br \/>\nICH WILL, DASS DAS UPGRADE FUNTKIONIERT!!!!!!!!!!!!!!!!!!!!!!!!!!!!!! (wenn es einem schon aufgezwungen wird).<\/p>\n"},"status":"1"},{"id":58822,"parent":0,"author":0,"author_name":"Holgi","author_email":"holger_freese@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=96&d=mm&r=g"},"date":"2017-10-25T14:38:07","cld_nonce":"b6d6726996","content":{"rendered":"<p>BTW: wei\u00df jemand, wie man ein altes OSX Leopard auf einen neueren MAC-Rechner bekommt?<br \/>\nHabe mal versucht OSX Leopard und auch Snow Leopard auf einem MACMini 2014 zu installieren (per DVD).<br \/>\nDas Setup stoppt jedoch jedesmal sofort, so als ob Apple verhindern wolle, dass so alte Betriebs-Systeme weiter genutzt werden.<\/p>\n"},"status":"1"},{"id":58824,"parent":58819,"author":0,"author_name":"Name","author_email":"mailadresse@inter.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7ba45ccc029549029ffb0fe7def0b51ed38636dfed3b42efbc4f2ef129912ae7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7ba45ccc029549029ffb0fe7def0b51ed38636dfed3b42efbc4f2ef129912ae7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7ba45ccc029549029ffb0fe7def0b51ed38636dfed3b42efbc4f2ef129912ae7?s=96&d=mm&r=g"},"date":"2017-10-25T15:11:00","cld_nonce":"b6d6726996","content":{"rendered":"<p>Irrelevant und l\u00e4cherlich &#8211; wie jeder deiner Beitr\u00e4ge.<\/p>\n"},"status":"1"},{"id":58825,"parent":58817,"author":3447,"author_name":"Roland Brem","author_email":"brem_roland@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fbc4e28e6998147d96f9d842218f2d144dd023b24edb2e782537c654ef56fa72?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fbc4e28e6998147d96f9d842218f2d144dd023b24edb2e782537c654ef56fa72?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fbc4e28e6998147d96f9d842218f2d144dd023b24edb2e782537c654ef56fa72?s=96&d=mm&r=g"},"date":"2017-10-25T15:14:39","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Karl: Die Test von den Insidern sagen nicht wirklich viel aus. Klar werden viele Fehler gemeldet, wenn man die Insider betrachtet, die auch wirklich Feedback geben.<br \/>\nAllerdings haben die internen Tests, wo MS und Angeh\u00f6rige von Firmen testen Vorrang. Dies bezieht sich aber explizit an Pro und Enterprise.<br \/>\nDer Vorteil der Insider ist da, dass jeder andere Erwartungen hat bzw. sein System anders verwendet. Deshalb ist jedes Feedback wichtig.<br \/>\nNur immer Aussagen wie &#8222;MS ist schei\u00dfe&#8220;, &#8222;MS kann nichts&#8220; usw. (wie oben von moinmoin bereits angegeben) ist daher fehl am Platz.<br \/>\nWenn man schon die M\u00f6glichkeit hat, Teil einer Entwicklung zu sein, dann sollte man das auch nutzen. <\/p>\n<p>Ansonsten ist das Insiderprogramm f\u00fcr solche Leute sinnlos, nur um die aktuelle Build zu haben.<\/p>\n<p>Ich bin z. B. nebenbei Gamer. Nach einer &#8222;Clean&#8220;-Installation funktionierte mein Xbox Wireless Adapter f\u00fcr Windows mangels Treiber nicht. Feedback gegeben. Allerdings nutze ich am Lappi die RS4-Insider. Angedockt, Adapter funktioniert. Treiber extrahiert, in die 1709 installiert und alles ist super.<\/p>\n"},"status":"1"},{"id":58826,"parent":58822,"author":0,"author_name":"SirMarc","author_email":"marcsenn@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=96&d=mm&r=g"},"date":"2017-10-25T15:27:24","cld_nonce":"b6d6726996","content":{"rendered":"<p>Geht nicht, alte z\u00f6pfe werden gl\u00fccklicherweise schneller abgeschnitten, hat auch vorteile gegen\u00fcber windows, niemand auf dem mac ist mit einem 13 jahre alten macos unterwegs.;)<br \/>\nKostet ja auch nicht die welt ein macos upgrade.<\/p>\n"},"status":"1"},{"id":58829,"parent":0,"author":3858,"author_name":"spy007","author_email":"san.martino@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b40117591536a4310527812c22bb549341a390b8173ef8d2630b701704ce65a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b40117591536a4310527812c22bb549341a390b8173ef8d2630b701704ce65a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b40117591536a4310527812c22bb549341a390b8173ef8d2630b701704ce65a?s=96&d=mm&r=g"},"date":"2017-10-25T15:58:31","cld_nonce":"b6d6726996","content":{"rendered":"<p>Selbst meine zwei alten Windows Laptop (beide Acer Aspire) laufen super unter 1709. Die Dinger kamen urspr\u00fcnglich mal mit Windows 7 und Windows 8 raus. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":58832,"parent":58826,"author":0,"author_name":"Holgi","author_email":"holger_freese@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=96&d=mm&r=g"},"date":"2017-10-25T17:07:50","cld_nonce":"b6d6726996","content":{"rendered":"<p>geht nicht? hast du da eine Quelle f\u00fcr?<br \/>\nnicht jeder Rechner muss zwangsl\u00e4ufig am Netz h\u00e4ngen und ein Sicherheitsrisiko darstellen.<br \/>\n&#8222;Kostet ja auch nicht die welt ein macos upgrade.&#8220; &gt; ist schon klar, ist sogar kostenlos. hatte ja auch schon High Sierra drauf. Es geht eher um die Machbarkeit, nicht um den Sinn.<\/p>\n"},"status":"1"},{"id":58835,"parent":58832,"author":0,"author_name":"SirMarc","author_email":"marcsenn@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=96&d=mm&r=g"},"date":"2017-10-25T18:35:31","cld_nonce":"b6d6726996","content":{"rendered":"<p>Naja was bring mir ein BS ohne Netz Anschluss, bin 80% im Netz unterwegs.<\/p>\n<p>wird schon gehen aber wurde sicher Software\/Hardware m\u00e4\u00dfig gesperrt(der Mac ist ja eigentlich ein normaler PC), und nat\u00fcrlich kein Treiber f\u00fcr die neuste Hardware wo ja jedes mal \u00e4ndert.<\/p>\n"},"status":"1"},{"id":58836,"parent":58829,"author":0,"author_name":"SirMarc","author_email":"marcsenn@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=96&d=mm&r=g"},"date":"2017-10-25T18:38:45","cld_nonce":"b6d6726996","content":{"rendered":"<p>Na klar PCs ab win 7 laufen meistens unter Win 10. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":58845,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-10-25T20:36:09","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8222;Aber deshalb Microsoft immer und ewig die Schuld zuweisen, finde ich pers\u00f6nlich nicht fair.&#8220;<\/p>\n<p>Den Redmond-Boys braucht man garnix &#8222;zuzuweisen&#8220;, die schie\u00dfen sich oft genug selbst ins Knie, grins! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_mrgreen.gif\" alt=\":mrgreen:\" class=\"wp-smiley\" \/> <\/p>\n<p>Ich finde es z.B. pers\u00f6nlich nicht fair, das Win10 \u00f6fter nachfragt, ob ich WIRKlich mit Chrome browsen will, oder mir immer mal wieder OneDrive &#8222;anbietet&#8220;, obwohl das bei einem Local Account wenig sinnvoll ist.<\/p>\n<p>Oder das sie nicht schaffen, ihren eigenen Store upzudaten, und man selber fummeln mu\u00df, um die neueste Version zu bekommen.<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\nWas also macht Herr Hugo-N\u00f6rgler: schiefes Grinsen und fummeln\/zur\u00fcckfummeln &#8211; business als usual, wie bei jedem Win10 Update. Und fr\u00fchestens 2018 auf Win10 umsteigen &#8211; bis dann tun die beiden Win10 &#8222;Test-PCs&#8220; gute Dienste, auch um die oben angesprochenen &#8222;Workarounds oder L\u00f6sungen&#8220; zu testen.<\/p>\n<p>Von hier &#8211; oder von anderswo im Net. Ist ja nicht so, das ich NUR euch glaube, neien! Nur MS, denen glaube ich nix, was nicht iwi\/iwo anders etwas objektiver dargestellt wird.<\/p>\n"},"status":"1"},{"id":58858,"parent":0,"author":2844,"author_name":"Patrick Kriechmayr","author_email":"patrickkriechmayr@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/300c26ad14d39be9674ef4cc37d4901c5905dd18af1828b004beb76f760dbf36?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/300c26ad14d39be9674ef4cc37d4901c5905dd18af1828b004beb76f760dbf36?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/300c26ad14d39be9674ef4cc37d4901c5905dd18af1828b004beb76f760dbf36?s=96&d=mm&r=g"},"date":"2017-10-25T22:56:47","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hallo ich wei\u00df das ich da falsch bin k\u00f6nnt ihr mir helfen weil ich komme unter benutzer nammen nicht mehr rein wie kann man das machen das man wider rein kommt email *E-Mail-Adresse entfernt*<\/p>\n"},"status":"1"},{"id":58870,"parent":58817,"author":0,"author_name":"SvenC","author_email":"sven.carstensen@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fd04f07253e99bc9d52d012636eb2b44371833bac68e5cb4aa102e0b3a841ed2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fd04f07253e99bc9d52d012636eb2b44371833bac68e5cb4aa102e0b3a841ed2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fd04f07253e99bc9d52d012636eb2b44371833bac68e5cb4aa102e0b3a841ed2?s=96&d=mm&r=g"},"date":"2017-10-26T09:28:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>Welcher Fehler kommt denn bei Zugriffen \u00fcber \u201e\\\\Rechnername\\Ordnername\u201c in Abh\u00e4ngigkeit von ausgeschalteten Ger\u00e4ten? Mal davon ausgehend, dass das Ger\u00e4t &#8222;Rechnername&#8220; eingeschaltet ist.<\/p>\n<p>&#8222;Rechnername&#8220; ist nicht aufl\u00f6sbar oder keine Rechte auf &#8222;Ordnername&#8220; oder Firewall blockt Freigaben gilt nicht, das sind Konfigurationsfehler f\u00fcr die Windows nichts kann <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":58873,"parent":0,"author":0,"author_name":"E. Rittmann","author_email":"reaper.bln@freenet.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/be5d1460740cc8bc00f25d07c585a71a5b8b2bb636b7165c47d392bf70a0d780?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/be5d1460740cc8bc00f25d07c585a71a5b8b2bb636b7165c47d392bf70a0d780?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/be5d1460740cc8bc00f25d07c585a71a5b8b2bb636b7165c47d392bf70a0d780?s=96&d=mm&r=g"},"date":"2017-10-26T09:52:29","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich kann mich auch nicht beklagen, auf meinem 2012er 2500k System lief bisher jedes Win10 Upgrade halbwegs sauber durch. Meine Einstellungen blieben gr\u00f6\u00dftenteils erhalten. Lediglich PDF musste ich neu zuweisen. Nur die X-Fi und meine USB-Controller muss ich jedes mal neu installieren. Als Profi-Anwender ist das nat\u00fcrlich keine H\u00fcrde. Auf einem HP Laptop mit AMD-Chipsatz hatte ich dahingegen gr\u00f6\u00dfere Probleme, da der Grafiktreiber partout nicht laufen wollte. Zum Gl\u00fcck gab es gleich einen neuen BETA-Treiber von AMD, jetzt geht es. Ist also nicht immer Microsoft am Ende Schuld. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n<p>Have a nice day!<\/p>\n"},"status":"1"},{"id":58875,"parent":0,"author":0,"author_name":"Peter Busch","author_email":"pbuschjoh@colliganet.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/33006cf1b96df9cce191d9d9b3f89470c4767cd22e98f980da49eb9fa17e3c84?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/33006cf1b96df9cce191d9d9b3f89470c4767cd22e98f980da49eb9fa17e3c84?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/33006cf1b96df9cce191d9d9b3f89470c4767cd22e98f980da49eb9fa17e3c84?s=96&d=mm&r=g"},"date":"2017-10-26T10:24:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>Fast keine Probleme. Als Inplace-Update mit ISO liefe es bei allen Rechnern schnell und problemlos durch. Kleine Systemeinstellungen (Deaktivieren der Zip-Funktionalit\u00e4t, Doppelte Anzeige der Laufwerke im Explorer &#8222;removeable drives&#8220;, und meine geliebte schnelle Bildvorschau im Kontextmen\u00fc) mu\u00dften wieder eingerichtet werden.<br \/>\nEin Rechner eines Freundes hatte noch das Aniversary drauf, da ging es mit dem online Update auf Fall Creator nicht, wohl aber mit der ISO wie oben beschrieben.<\/p>\n"},"status":"1"},{"id":59006,"parent":0,"author":2483,"author_name":"MrX1980","author_email":"dfinken@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/14d16a4a4d8343b8eae9de25d7c303406db1f32cd99c34fe0147c9c71261fcfa?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/14d16a4a4d8343b8eae9de25d7c303406db1f32cd99c34fe0147c9c71261fcfa?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/14d16a4a4d8343b8eae9de25d7c303406db1f32cd99c34fe0147c9c71261fcfa?s=96&d=mm&r=g"},"date":"2017-10-29T16:21:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>Was ich derzeit nach jeden Build neu einstellen muss:<br \/>\n&#8211; Realtek Soundtreiber: Enable Bass Management, Loudness Equalization, DTS = on<br \/>\n&#8211; Zuverl\u00e4ssigkeitsverlauf: Gruppierung entfernen, Spaltenbreiten, Sortierung (neuste nach oben)<br \/>\n&#8211; Spybot Search &amp; Destroy: Immunisierung ausf\u00fchren<\/p>\n<p>In der Vergangenheit waren es deutlich mehr Punkte.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Update auf die Windows 10 1709 - Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar] - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Update auf die Windows 10 1709 - Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar]\" \/>\n<meta property=\"og:description\" content=\"Seit dem 17.Oktober gibt es nun die neue Windows 10 1709 16299 (Fall Creators Update). Viele sind ja schon vorher dank der ISO-Dateien umgestiegen. Ich hatte damit noch gewartet. Denn ich brauchte immer noch einen Vergleich zwischen der neuen Version,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-25T11:14:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-25T14:04:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Update auf die Windows 10 1709 &#8211; Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar]\",\"datePublished\":\"2017-10-25T11:14:04+00:00\",\"dateModified\":\"2017-10-25T14:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/\"},\"wordCount\":438,\"commentCount\":24,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/windows10-fall-creators-update.jpg\",\"keywords\":[\"Probleme bei der Installation\",\"Windows 10 1709 Fall Creators Update\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/\",\"name\":\"Update auf die Windows 10 1709 - Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar] - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/windows10-fall-creators-update.jpg\",\"datePublished\":\"2017-10-25T11:14:04+00:00\",\"dateModified\":\"2017-10-25T14:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/windows10-fall-creators-update.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/windows10-fall-creators-update.jpg\",\"width\":1600,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/25\\\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Update auf die Windows 10 1709 &#8211; Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Update auf die Windows 10 1709 - Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar] - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/","og_locale":"de_DE","og_type":"article","og_title":"Update auf die Windows 10 1709 - Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar]","og_description":"Seit dem 17.Oktober gibt es nun die neue Windows 10 1709 16299 (Fall Creators Update). Viele sind ja schon vorher dank der ISO-Dateien umgestiegen. Ich hatte damit noch gewartet. Denn ich brauchte immer noch einen Vergleich zwischen der neuen Version,&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-10-25T11:14:04+00:00","article_modified_time":"2017-10-25T14:04:00+00:00","og_image":[{"width":1600,"height":1000,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Update auf die Windows 10 1709 &#8211; Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar]","datePublished":"2017-10-25T11:14:04+00:00","dateModified":"2017-10-25T14:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/"},"wordCount":438,"commentCount":24,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update.jpg","keywords":["Probleme bei der Installation","Windows 10 1709 Fall Creators Update"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/","name":"Update auf die Windows 10 1709 - Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar] - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update.jpg","datePublished":"2017-10-25T11:14:04+00:00","dateModified":"2017-10-25T14:04:00+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update.jpg","width":1600,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/25\/update-auf-die-windows-10-1709-einstellungen-werden-zurueckgesetzt-nicht-bei-mir-kommentar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Update auf die Windows 10 1709 &#8211; Einstellungen werden zur\u00fcckgesetzt? Nicht bei mir [Kommentar]"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/windows10-fall-creators-update.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/93228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=93228"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/93228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/84588"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=93228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=93228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=93228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}