{"id":92888,"date":"2017-10-18T07:15:38","date_gmt":"2017-10-18T05:15:38","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=92888"},"modified":"2017-10-18T07:15:38","modified_gmt":"2017-10-18T05:15:38","slug":"microsoft-stellt-neues-surface-book-2-offiziell-vor","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/","title":{"rendered":"Microsoft stellt neues Surface Book 2 offiziell vor"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-92895\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-810x540.jpg\" alt=\"\" width=\"810\" height=\"540\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-810x540.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-306x205.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-500x333.jpg 500w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/p>\n<p>Seit gestern steht das Windows 10 Fall Creators Update zur Verf\u00fcgung aber passend zu diesem Termin hat uns Microsoft noch mit einem anderen Produkt \u00fcberraschen k\u00f6nnen. Denn das neue Surface Book 2 wurde offiziell vorgestellt.<\/p>\n<p>Das Surface Book 2 komme mit 13,5 Zoll und 15 Zoll Display daher, wobei in Deutschland ausschlie\u00dflich das kleinere Modell verf\u00fcgbar sein wird. Am 16. November 2017 wird das Ger\u00e4t auf dem deutschen Markt verf\u00fcgbar. In Deutschland wird das Surface Book 2 als Version mit 13,5-Zoll-Display in vier verschiedenen Modell-Varianten erh\u00e4ltlich sein. Je nach Modellvariante ist das Ger\u00e4t ausgestattet mit Intels Dual-Core Prozessoren der 7. Generation oder Quad-Core Prozessoren der 8. Generation, einer NVIDIA GeForce Grafikkarte, einem USB-C Port und bis zu 17 Stunden Akkulaufzeit. Es verf\u00fcgt \u00fcber die f\u00fcnffache Grafikleistung im Vergleich zum Vorg\u00e4nger und ein hochaufl\u00f6sendes PixelSense Display f\u00fcr eine Touch-Bedienung mittels Finger oder Stift. Anspruchsvolle Programme von Herstellern wie Adobe, Autodesk oder Dassault laufen ebenso fl\u00fcssig wie aktuelle Gaming-Titel und Windows Mixed Reality Anwendungen.<\/p>\n<div id='gallery-1' class='gallery galleryid-92888 gallery-columns-4 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-3.jpg' rel=\"lightbox[92888]\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-3.jpg 1080w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-3-306x172.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-3-500x281.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-3-810x456.jpg 810w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-1.jpg' rel=\"lightbox[92888]\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-1.jpg 1080w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-1-306x172.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-1-500x281.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-1-810x456.jpg 810w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-4.jpg' rel=\"lightbox[92888]\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-4.jpg 1080w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-4-306x172.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-4-500x281.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-4-810x456.jpg 810w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-2.png' rel=\"lightbox[92888]\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-2.png 1080w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-2-306x172.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-2-500x281.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-2-810x456.png 810w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Preislich startet man beim Surface Book 2 bei 1749,- Euro. Hier die Preise:<\/p>\n<ul>\n<li>Intel Core i5 \/ 8 GB RAM \/ 256 GB SSD: 1.749 \u20ac<\/li>\n<li>Intel Core i7 Quad-Core \/ 8 GB RAM \/ 256 GB SSD \/ Nvidia Geforce GTX 1050: 2.249 \u20ac<\/li>\n<li>Intel Core i7 Quad-Core \/ 16 GB RAM \/ 512 GB SSD \/ Nvidia Geforce GTX 1050: 2.849 \u20ac<\/li>\n<li>Intel Core i7 Quad-Core \/ 16 GB RAM \/ 1 TB SSD \/ Nvidia Geforce GTX 1050: 3.449 \u20ac<\/li>\n<\/ul>\n<div class=\"video-container\"><div style=\"position:relative;width:100%;max-width:810px;height:456px;background-color:black;color:white;padding:0px;\" data-video-id=\"4ck5RbTQj28\">\n\t\t\t\t\t\t<div style=\"text-align: center;\">\n\t\t\t\t\t\t\t<span class=\"hint-text\">Erst durch Klick auf den Button werden Daten an Youtube \u00fcbermittelt und dir das Video angezeigt.<br\/>Mehr dazu in unserer <a href=\"https:\/\/www.deskmodder.de\/blog\/datenschutz-auf-deskmodder-de\/\" target=\"_blank\">Datenschutzrichtlinie<\/a><\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div style=\"text-align: center; margin-top: 10px;\">\n\t\t\t\t\t\t\t<button onclick=\"showVideo(this)\">Verstanden!<\/button>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"video-container\" style=\"display:none;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/4ck5RbTQj28\/hqdefault.jpg\" alt=\"Vorschaubild\" style=\"width:100%; max-width:810px;\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script>\n\t\t\t\t\t\tfunction showVideo(button) {\n\t\t\t\t\t\t\tconst videoID = button.parentElement.parentElement.getAttribute(\"data-video-id\");\n\t\t\t\t\t\t\tconsole.log(\"Video ID:\", videoID); \/\/ Debugging\n\t\t\t\t\t\t\tconst iframeHTML = \"<iframe width='810' height='456' src='https:\/\/www.youtube-nocookie.com\/embed\/\" + videoID + \"?feature=oembed' frameborder='0' allow='accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture' allowfullscreen><\/iframe>\";\n\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").innerHTML = iframeHTML;\n\n\t\t\t\t\t\t\t\/\/ Video-Container sichtbar machen\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").style.display = \"block\";\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".hint-text\").style.display = \"none\";\n\t\t\t\t\t\t\tbutton.remove();\n\t\t\t\t\t\t}\n\t\t\t\t\t<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seit gestern steht das Windows 10 Fall Creators Update zur Verf\u00fcgung aber passend zu diesem Termin hat uns Microsoft noch mit einem anderen Produkt \u00fcberraschen k\u00f6nnen. Denn das neue Surface Book 2 wurde offiziell vorgestellt. Das Surface Book 2 komme&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":92895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[4470,148,13516],"class_list":["post-92888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-laptop","tag-microsoft","tag-surface-book-2"],"wp_featured_image":{"id":92895,"alt_text":"","description":"","media_type":"image","media_details":{"width":5498,"height":3665,"file":"2017\/10\/surface-book-2-5.jpg","sizes":{"thumbnail":{"file":"surface-book-2-5-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-306x205.jpg"},"medium":{"file":"surface-book-2-5-500x333.jpg","width":500,"height":333,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-500x333.jpg"},"large":{"file":"surface-book-2-5-810x540.jpg","width":810,"height":540,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-810x540.jpg"},"wp_review_large":{"file":"surface-book-2-5-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-320x200.jpg"},"wp_review_small":{"file":"surface-book-2-5-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-65x65.jpg"},"blog-large":{"file":"surface-book-2-5-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-642x300.jpg"},"blog-medium":{"file":"surface-book-2-5-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-306x205.jpg"},"recent-thumb":{"file":"surface-book-2-5-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-350x316.jpg"},"service-featured":{"file":"surface-book-2-5-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-600x330.jpg"},"wp_rp_thumbnail":{"file":"surface-book-2-5-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5-150x150.jpg"}},"image_meta":{"aperture":"10","credit":"","camera":"Canon EOS 5DS","caption":"","created_timestamp":"1492452443","copyright":"","focal_length":"55","iso":"100","shutter_speed":"0.005","title":"","orientation":"1","keywords":[]}},"post":92888,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5.jpg"},"commentcount":1,"wp_comments":[{"id":58406,"parent":0,"author":0,"author_name":"KnorxThieus","author_email":"knorxthieus@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=96&d=mm&r=g"},"date":"2017-10-19T10:05:08","cld_nonce":"82f011626f","content":{"rendered":"<p>Haha, mein Bruder hat vor wenigen Tagen das Surface Book 1 erstanden! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft stellt neues Surface Book 2 offiziell vor - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft stellt neues Surface Book 2 offiziell vor\" \/>\n<meta property=\"og:description\" content=\"Seit gestern steht das Windows 10 Fall Creators Update zur Verf\u00fcgung aber passend zu diesem Termin hat uns Microsoft noch mit einem anderen Produkt \u00fcberraschen k\u00f6nnen. Denn das neue Surface Book 2 wurde offiziell vorgestellt. Das Surface Book 2 komme&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-18T05:15:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5498\" \/>\n\t<meta property=\"og:image:height\" content=\"3665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Microsoft stellt neues Surface Book 2 offiziell vor\",\"datePublished\":\"2017-10-18T05:15:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/\"},\"wordCount\":236,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/surface-book-2-5.jpg\",\"keywords\":[\"Laptop\",\"Microsoft\",\"Surface Book 2\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/\",\"name\":\"Microsoft stellt neues Surface Book 2 offiziell vor - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/surface-book-2-5.jpg\",\"datePublished\":\"2017-10-18T05:15:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/surface-book-2-5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/surface-book-2-5.jpg\",\"width\":5498,\"height\":3665},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/18\\\/microsoft-stellt-neues-surface-book-2-offiziell-vor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft stellt neues Surface Book 2 offiziell vor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft stellt neues Surface Book 2 offiziell vor - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft stellt neues Surface Book 2 offiziell vor","og_description":"Seit gestern steht das Windows 10 Fall Creators Update zur Verf\u00fcgung aber passend zu diesem Termin hat uns Microsoft noch mit einem anderen Produkt \u00fcberraschen k\u00f6nnen. Denn das neue Surface Book 2 wurde offiziell vorgestellt. Das Surface Book 2 komme&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-10-18T05:15:38+00:00","og_image":[{"width":5498,"height":3665,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Microsoft stellt neues Surface Book 2 offiziell vor","datePublished":"2017-10-18T05:15:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/"},"wordCount":236,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5.jpg","keywords":["Laptop","Microsoft","Surface Book 2"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/","name":"Microsoft stellt neues Surface Book 2 offiziell vor - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5.jpg","datePublished":"2017-10-18T05:15:38+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5.jpg","width":5498,"height":3665},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/18\/microsoft-stellt-neues-surface-book-2-offiziell-vor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft stellt neues Surface Book 2 offiziell vor"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/surface-book-2-5.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/92888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=92888"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/92888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/92895"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=92888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=92888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=92888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}