{"id":92280,"date":"2017-10-05T08:22:22","date_gmt":"2017-10-05T06:22:22","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=92280"},"modified":"2017-10-05T08:22:22","modified_gmt":"2017-10-05T06:22:22","slug":"google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/","title":{"rendered":"Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-92283\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-810x457.png\" alt=\"\" width=\"810\" height=\"457\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-810x457.png 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-306x173.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-500x282.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927.png 1080w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/p>\n<p>Als letztes Produkt aus dem neuen Hardware-Sortiment von Google m\u00f6chte ich hier im Blog noch kurz die Google Pixel Buds erw\u00e4hnen. Hierbei handelt es sich um Googles erste Bluetooth-Kopfh\u00f6rer, welche mit \u00dcbersetzungs-Funktion ausgestattet sind.<\/p>\n<p>\u00c4hnlich der Apple AirPods werden diese in einem Case geliefert, welches auch zum Laden der Kopfh\u00f6rer dient. 5 Stunden sollen die Pixel Buds durchhalten k\u00f6nnen. Das Case liefert dann nochmal 25 Stunden Akkulaufzeit.<\/p>\n<p>Zum Preis von 179,- Euro solle die Ohrh\u00f6rer sehr guten Sound liefern. Wie geschrieben kommen die Pixel Buds mit integriertem Google \u00dcbersetzer. Ben\u00f6tigt wird aber ein eigenes Smartphone, welches mit dem Pixel Buds gekoppelt ist. Hei\u00dft also das Smartphone \u00fcbersetzt und \u00fcber die Pixel Buds wird dann die \u00dcbersetzung ausgegeben.<\/p>\n<div id='gallery-1' class='gallery galleryid-92280 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/blog-apollo-3grp-t-v08-simpwidth-1000.jpg' rel=\"lightbox[92280]\"><img loading=\"lazy\" decoding=\"async\" width=\"938\" height=\"835\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/blog-apollo-3grp-t-v08-simpwidth-1000.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/blog-apollo-3grp-t-v08-simpwidth-1000.jpg 938w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/blog-apollo-3grp-t-v08-simpwidth-1000-230x205.jpg 230w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/blog-apollo-3grp-t-v08-simpwidth-1000-404x360.jpg 404w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/blog-apollo-3grp-t-v08-simpwidth-1000-655x583.jpg 655w\" sizes=\"auto, (max-width: 938px) 100vw, 938px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081913.png' rel=\"lightbox[92280]\"><img loading=\"lazy\" decoding=\"async\" width=\"911\" height=\"894\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081913.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081913.png 911w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081913-209x205.png 209w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081913-367x360.png 367w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081913-594x583.png 594w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081913-65x65.png 65w\" sizes=\"auto, (max-width: 911px) 100vw, 911px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Auch der Google Assistant ist mit an Bord so dass eine Kopplung mit anderen Google Cast f\u00e4higen Ger\u00e4ten m\u00f6glich ist.<\/p>\n<p>Vorbestellungen in Deutschland sind aktuell noch nicht m\u00f6glich. <a href=\"https:\/\/store.google.com\/product\/google_pixel_buds\" target=\"_blank\" rel=\"noopener\">HIER<\/a> k\u00f6nnt ihr euch bei Interesse aber auf eine Warteliste setzen lassen. Weitere Details gibt&#8217;s im <a href=\"https:\/\/www.blog.google\/products\/pixel\/pixel-buds\/\" target=\"_blank\" rel=\"noopener\">Google Blog<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als letztes Produkt aus dem neuen Hardware-Sortiment von Google m\u00f6chte ich hier im Blog noch kurz die Google Pixel Buds erw\u00e4hnen. Hierbei handelt es sich um Googles erste Bluetooth-Kopfh\u00f6rer, welche mit \u00dcbersetzungs-Funktion ausgestattet sind. \u00c4hnlich der Apple AirPods werden diese&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":92283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[22385,5912],"class_list":["post-92280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-google-pixel-buds","tag-kopfhoerer"],"wp_featured_image":{"id":92283,"alt_text":"","description":"","media_type":"image","media_details":{"width":1080,"height":609,"file":"2017\/10\/img-20171005-081927.png","sizes":{"thumbnail":{"file":"img-20171005-081927-306x173.png","width":306,"height":173,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-306x173.png"},"medium":{"file":"img-20171005-081927-500x282.png","width":500,"height":282,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-500x282.png"},"large":{"file":"img-20171005-081927-810x457.png","width":810,"height":457,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-810x457.png"},"wp_review_large":{"file":"img-20171005-081927-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-320x200.png"},"wp_review_small":{"file":"img-20171005-081927-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-65x65.png"},"blog-large":{"file":"img-20171005-081927-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-642x300.png"},"blog-medium":{"file":"img-20171005-081927-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-306x205.png"},"recent-thumb":{"file":"img-20171005-081927-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-350x316.png"},"service-featured":{"file":"img-20171005-081927-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-600x330.png"},"wp_rp_thumbnail":{"file":"img-20171005-081927-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":92280,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927.png"},"commentcount":2,"wp_comments":[{"id":57113,"parent":0,"author":3634,"author_name":"m0skito","author_email":"info@tinogottschalk.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3c90a63b17a4d5ba8774b079239cbe27f063554238465ac09f42f233222df61f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3c90a63b17a4d5ba8774b079239cbe27f063554238465ac09f42f233222df61f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3c90a63b17a4d5ba8774b079239cbe27f063554238465ac09f42f233222df61f?s=96&d=mm&r=g"},"date":"2017-10-05T12:19:06","cld_nonce":"82f011626f","content":{"rendered":"<p>bis zu 5h Spieldauer, find ich zu wenig f\u00fcr 180\u20ac, man rennt langsam von Ladebuchse zu Ladebuchse jeden Tag (Fittracker,e-Zigarette,Handy,Smartwatch,Bluetoothkopfh\u00f6rer etc.)<\/p>\n"},"status":"1"},{"id":57114,"parent":57113,"author":0,"author_name":"SirMarc","author_email":"marcsenn@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/59c6e3fb6f2806821335f75dc76a3d3ec1f806de540bc83ddae2860efe268672?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/59c6e3fb6f2806821335f75dc76a3d3ec1f806de540bc83ddae2860efe268672?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/59c6e3fb6f2806821335f75dc76a3d3ec1f806de540bc83ddae2860efe268672?s=96&d=mm&r=g"},"date":"2017-10-05T12:24:45","cld_nonce":"82f011626f","content":{"rendered":"<p>Eziggis weglassen, gibt nur Krebs.<br \/>\nUnd wegen preis google ist nicht apple also 2-3 monate warte und schon f\u00e4llt der preis, tief<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion\" \/>\n<meta property=\"og:description\" content=\"Als letztes Produkt aus dem neuen Hardware-Sortiment von Google m\u00f6chte ich hier im Blog noch kurz die Google Pixel Buds erw\u00e4hnen. Hierbei handelt es sich um Googles erste Bluetooth-Kopfh\u00f6rer, welche mit \u00dcbersetzungs-Funktion ausgestattet sind. \u00c4hnlich der Apple AirPods werden diese&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-05T06:22:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"609\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion\",\"datePublished\":\"2017-10-05T06:22:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/\"},\"wordCount\":192,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/img-20171005-081927.png\",\"keywords\":[\"Google Pixel Buds\",\"Kopfh\u00f6rer\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/\",\"name\":\"Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/img-20171005-081927.png\",\"datePublished\":\"2017-10-05T06:22:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/img-20171005-081927.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/img-20171005-081927.png\",\"width\":1080,\"height\":609},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/10\\\/05\\\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/","og_locale":"de_DE","og_type":"article","og_title":"Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion","og_description":"Als letztes Produkt aus dem neuen Hardware-Sortiment von Google m\u00f6chte ich hier im Blog noch kurz die Google Pixel Buds erw\u00e4hnen. Hierbei handelt es sich um Googles erste Bluetooth-Kopfh\u00f6rer, welche mit \u00dcbersetzungs-Funktion ausgestattet sind. \u00c4hnlich der Apple AirPods werden diese&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-10-05T06:22:22+00:00","og_image":[{"width":1080,"height":609,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927.png","type":"image\/png"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion","datePublished":"2017-10-05T06:22:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/"},"wordCount":192,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927.png","keywords":["Google Pixel Buds","Kopfh\u00f6rer"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/","name":"Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927.png","datePublished":"2017-10-05T06:22:22+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927.png","width":1080,"height":609},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/10\/05\/google-pixel-buds-vorgestellt-googles-erste-bluetooth-kopfhoerer-samt-uebersetzungs-funktion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Google Pixel Buds vorgestellt: Googles erste Bluetooth-Kopfh\u00f6rer samt \u00dcbersetzungs-Funktion"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/img-20171005-081927.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/92280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=92280"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/92280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/92283"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=92280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=92280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=92280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}