{"id":91783,"date":"2017-09-28T04:58:22","date_gmt":"2017-09-28T02:58:22","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=91783"},"modified":"2017-09-28T17:18:44","modified_gmt":"2017-09-28T15:18:44","slug":"amazon-stellt-neuen-fire-tv-offiziell-vor","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/","title":{"rendered":"Amazon stellt neuen Fire TV offiziell vor"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-91785\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-583x583.jpg\" alt=\"\" width=\"583\" height=\"583\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-583x583.jpg 583w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-205x205.jpg 205w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-360x360.jpg 360w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-65x65.jpg 65w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-150x150.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg 1772w\" sizes=\"auto, (max-width: 583px) 100vw, 583px\" \/><\/p>\n<p>Bereits vor einigen Tagen hatten wir \u00fcber einen neuen Fire TV und Fire TV Stick von Amazon berichtet, welche noch in diesem Jahr gezeigt werden sollten.\u00a0 Gestern Abend nun hat Amazon in Rahmen eines Presse-Events ein wahres Produktfeuerwerk losgelassen und zumindest auch den neuen Amazon Fire TV offiziell vorgestellt.<\/p>\n<p>Der neue Fire TV unterst\u00fctzt 4k-Videomaterial und HDR. Ebenso wird auch Dolby Atmos unterst\u00fctzt. Angetrieben wird er von einem 1,5 GHz starken Quadcore-Prozessor und 2 GB RAM. Der interne Speicher betr\u00e4gt 8 GB. Zudem gibt&#8217;s auch Dual WLAN ac. Einen direkten Ethernet-Anschluss gibt&#8217;s offenbar nicht. Hier soll es aber einen optionalen Ethernet-Adapter geben, wenn man den Fire TV per Netzwerkkabel anschlie\u00dfen m\u00f6chte. Einen optischen oder koaxialen Audio-Anschluss gibt es leider nicht.<\/p>\n<p>Beim Design hat sich Amazon wohl etwas an Google orientiert. Kompakter kommt der neue Fire TV daher und nimmt so noch weniger Platz weg. Der Anschluss ans heimische TV-Ger\u00e4t erfolgt per am Fire TV befindlichen HDMI-Kabel.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-91784\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-plug-in-810x540.jpg\" alt=\"\" width=\"810\" height=\"540\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-plug-in-810x540.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-plug-in-306x205.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-plug-in-500x333.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-plug-in.jpg 1772w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/p>\n<p>Ebenso kommt der Fire TV mit der Alexa Sprachfernbedienung. Hier\u00fcber kann man dann innerhalb des Fire TV nach Inhalten suchen und Medien starten lassen. Mit der Alexa Sprachfernbedienung kann der Fire TV zudem Smart-Home-Ger\u00e4te wie beispielsweise Philips Hue, TP-Link und tado steuern. Demn\u00e4chst werden auch Smart-Home-Kameras von allen Fire TVs und Fire TV Stick ab der zweiten Generation unterst\u00fctzt. Damit wird es m\u00f6glich, auf dem Fire TV Live-Video-Feeds von kompatiblen Smart-Home-Kameras \u00fcber Alexa mit dem Befehl: \u201eAlexa, zeig mir die Kinderzimmerkamera\u201c zu aktivieren.<\/p>\n<p>Das neue Fire TV kann ab sofort vorbestellt werden. Ab dem 25.Oktober ist er dann erh\u00e4ltlich und wird ausgeliefert. Auch preislich kann sich der neue Fire TV sehen lassen. Denn mit 79,99 Euro ist es der bislang g\u00fcnstigste Fire TV von Amazon.<\/p>\n<p>Wer Lust bekommen hat, findet <a href=\"https:\/\/www.amazon.de\/b\/?&#038;node=530883031&#038;tag=deskmodderde-21&#038;ref_=pe_1083541_215438161\" target=\"_blank\" rel=\"noopener\">HIER<\/a> den neuen Amazon Fire TV und alle weiteren Ger\u00e4te.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/amazon-presse.de\/Top-Navi\/Pressetexte\/Pressedetail\/amazon\/de\/Devices\/2017-09-27-Fire-TV-mit-HDR\/\" target=\"_blank\" rel=\"noopener\">Pressemitteilung Amazon<\/a> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bereits vor einigen Tagen hatten wir \u00fcber einen neuen Fire TV und Fire TV Stick von Amazon berichtet, welche noch in diesem Jahr gezeigt werden sollten.\u00a0 Gestern Abend nun hat Amazon in Rahmen eines Presse-Events ein wahres Produktfeuerwerk losgelassen und&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":91785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[6739],"class_list":["post-91783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-amazon-fire-tv"],"wp_featured_image":{"id":91785,"alt_text":"","description":"","media_type":"image","media_details":{"width":1772,"height":1772,"file":"2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg","sizes":{"thumbnail":{"file":"amazon-fire-tv-with-alexa-voice-remote-hero-image-205x205.jpg","width":205,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-205x205.jpg"},"medium":{"file":"amazon-fire-tv-with-alexa-voice-remote-hero-image-360x360.jpg","width":360,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-360x360.jpg"},"large":{"file":"amazon-fire-tv-with-alexa-voice-remote-hero-image-583x583.jpg","width":583,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-583x583.jpg"},"wp_review_large":{"file":"amazon-fire-tv-with-alexa-voice-remote-hero-image-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-320x200.jpg"},"wp_review_small":{"file":"amazon-fire-tv-with-alexa-voice-remote-hero-image-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-65x65.jpg"},"blog-large":{"file":"amazon-fire-tv-with-alexa-voice-remote-hero-image-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-642x300.jpg"},"blog-medium":{"file":"amazon-fire-tv-with-alexa-voice-remote-hero-image-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-306x205.jpg"},"recent-thumb":{"file":"amazon-fire-tv-with-alexa-voice-remote-hero-image-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-350x316.jpg"},"service-featured":{"file":"amazon-fire-tv-with-alexa-voice-remote-hero-image-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-600x330.jpg"},"wp_rp_thumbnail":{"file":"amazon-fire-tv-with-alexa-voice-remote-hero-image-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":91783,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg"},"commentcount":5,"wp_comments":[{"id":56493,"parent":0,"author":3956,"author_name":"John-Boy","author_email":"edv.fst@gmx.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/36d3d6b28ddfa30d30dc8bed484ba2a32c95cfd9c83bde308d8fb476bb1abc84?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/36d3d6b28ddfa30d30dc8bed484ba2a32c95cfd9c83bde308d8fb476bb1abc84?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/36d3d6b28ddfa30d30dc8bed484ba2a32c95cfd9c83bde308d8fb476bb1abc84?s=96&d=mm&r=g"},"date":"2017-09-28T09:23:08","cld_nonce":"82f011626f","content":{"rendered":"<p>Kein Ethernet-Anschluss&#8230; das ist f\u00fcr mich so nicht zu gebrauchen<br \/>\nund warum muss das Ding so am HDMI Kabel baumeln. Sieht echt doof aus <\/p>\n<p>Da bleibe ich lieber bei der 2.Gen Box<\/p>\n"},"status":"1"},{"id":56494,"parent":56493,"author":0,"author_name":"t-matic","author_email":"kat83@gmx.at","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5408ac9d7ac4d58e09eee8d4011a891bb656b2ce34f457c64bcb5363214d2fa9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5408ac9d7ac4d58e09eee8d4011a891bb656b2ce34f457c64bcb5363214d2fa9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5408ac9d7ac4d58e09eee8d4011a891bb656b2ce34f457c64bcb5363214d2fa9?s=96&d=mm&r=g"},"date":"2017-09-28T09:59:12","cld_nonce":"82f011626f","content":{"rendered":"<p>Genau das gleiche hab ich mir auch gerade gedacht.<\/p>\n"},"status":"1"},{"id":56499,"parent":56493,"author":0,"author_name":"Manuel","author_email":"mail@manuel-maier.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/73a7311782fc5047038ef0529671365de71072f6920c320402e0e41bb1082d67?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/73a7311782fc5047038ef0529671365de71072f6920c320402e0e41bb1082d67?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/73a7311782fc5047038ef0529671365de71072f6920c320402e0e41bb1082d67?s=96&d=mm&r=g"},"date":"2017-09-28T10:23:38","cld_nonce":"82f011626f","content":{"rendered":"<p>F\u00fcr 4K ist nur WLAN schon etwas &#8222;schlecht&#8220; &#8211; gut es ist AC, aber Gbit ist halt einfach nochmal was anderes.<\/p>\n"},"status":"1"},{"id":56539,"parent":56493,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-09-28T15:02:53","cld_nonce":"82f011626f","content":{"rendered":"<p>F\u00fcr 14,99 gibts einen Adapter f\u00fcr LAN, grins. Ich bleibe aber auch bei meinem &#8222;K\u00e4stchen&#8220; 1.Gen &#8211; bis evtl. ein &#8222;K\u00e4stchen&#8220; 3.Gen kommt.<\/p>\n<p>4K und Smart Home kommt f\u00fcr mich eher weniger in Frage, also warte ich mal ruhig zu.<\/p>\n"},"status":"1"},{"id":56542,"parent":0,"author":0,"author_name":"Maxi","author_email":"ma.janowitz@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3f01a6e00d997bad35a4ae2a531af3e4d64500eac000d24aaf908190a2b0ef46?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3f01a6e00d997bad35a4ae2a531af3e4d64500eac000d24aaf908190a2b0ef46?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3f01a6e00d997bad35a4ae2a531af3e4d64500eac000d24aaf908190a2b0ef46?s=96&d=mm&r=g"},"date":"2017-09-28T15:15:22","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo<\/p>\n<p>Naja ich hole mir kein Amazon ich hab Netflex und kann da zu Amazon keine Vorteile finden das doch alles irgendwie das selbe nur bei Netflex brauch ich keine weitere Hardware wie ein Stick usw&#8230;<\/p>\n<p>Oder sehe ich das falsch?<\/p>\n<p>LG<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Amazon stellt neuen Fire TV offiziell vor - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amazon stellt neuen Fire TV offiziell vor\" \/>\n<meta property=\"og:description\" content=\"Bereits vor einigen Tagen hatten wir \u00fcber einen neuen Fire TV und Fire TV Stick von Amazon berichtet, welche noch in diesem Jahr gezeigt werden sollten.\u00a0 Gestern Abend nun hat Amazon in Rahmen eines Presse-Events ein wahres Produktfeuerwerk losgelassen und&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-28T02:58:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-28T15:18:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"1772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Amazon stellt neuen Fire TV offiziell vor\",\"datePublished\":\"2017-09-28T02:58:22+00:00\",\"dateModified\":\"2017-09-28T15:18:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/\"},\"wordCount\":320,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg\",\"keywords\":[\"Amazon Fire TV\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/\",\"name\":\"Amazon stellt neuen Fire TV offiziell vor - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg\",\"datePublished\":\"2017-09-28T02:58:22+00:00\",\"dateModified\":\"2017-09-28T15:18:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg\",\"width\":1772,\"height\":1772},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/28\\\/amazon-stellt-neuen-fire-tv-offiziell-vor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amazon stellt neuen Fire TV offiziell vor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Amazon stellt neuen Fire TV offiziell vor - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/","og_locale":"de_DE","og_type":"article","og_title":"Amazon stellt neuen Fire TV offiziell vor","og_description":"Bereits vor einigen Tagen hatten wir \u00fcber einen neuen Fire TV und Fire TV Stick von Amazon berichtet, welche noch in diesem Jahr gezeigt werden sollten.\u00a0 Gestern Abend nun hat Amazon in Rahmen eines Presse-Events ein wahres Produktfeuerwerk losgelassen und&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-09-28T02:58:22+00:00","article_modified_time":"2017-09-28T15:18:44+00:00","og_image":[{"width":1772,"height":1772,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Amazon stellt neuen Fire TV offiziell vor","datePublished":"2017-09-28T02:58:22+00:00","dateModified":"2017-09-28T15:18:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/"},"wordCount":320,"commentCount":5,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg","keywords":["Amazon Fire TV"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/","name":"Amazon stellt neuen Fire TV offiziell vor - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg","datePublished":"2017-09-28T02:58:22+00:00","dateModified":"2017-09-28T15:18:44+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg","width":1772,"height":1772},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/28\/amazon-stellt-neuen-fire-tv-offiziell-vor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Amazon stellt neuen Fire TV offiziell vor"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/amazon-fire-tv-with-alexa-voice-remote-hero-image.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/91783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=91783"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/91783\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/91785"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=91783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=91783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=91783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}