{"id":90508,"date":"2017-09-02T18:04:49","date_gmt":"2017-09-02T16:04:49","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=90508"},"modified":"2017-09-02T18:12:44","modified_gmt":"2017-09-02T16:12:44","slug":"microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/","title":{"rendered":"Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert"},"content":{"rendered":"<p>Die &#8222;normalen&#8220; Nutzer der Windows 10 1703 (Creators Update) haben die Lizenzbestimmungen noch vom Dezember 2016. In der neuen Insider f\u00fcr die kommende 1709 (Fall Creators Update), die am <a href=\"https:\/\/www.deskmodder.de\/blog\/2017\/09\/01\/17-oktober-dann-soll-die-windows-10-1709-fall-creators-update-erscheinen\/\" target=\"_blank\">17.Oktober offiziell erscheinen wird<\/a> hat man diese nun auf Juli 2017 aktualisiert. Ich hab beide einmal verglichen und es wurde an zwei Punkten eine \u00c4nderung vorgenommen.<\/p>\n<p>Ob dies noch aktualisiert wird, muss man abwarten. Unter Punkt 4: \u00dcbertragung So hat man aus: &#8222;Die Bestimmungen dieser Ziffer gelten nicht, wenn Sie die Software in Deutschland oder in einem unter (aka.ms\/transfer) aufgef\u00fchrten Land erworben haben.&#8220; in  &#8222;Die Bestimmungen dieser Ziffer gelten nicht, wenn Sie die Software <strong>als Verbraucher<\/strong> in Deutschland oder in einem unter (aka.ms\/transfer) aufgef\u00fchrten Land erworben haben.&#8220; ge\u00e4ndert.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg\" rel=\"lightbox[90508]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-500x334.jpg\" alt=\"\" width=\"500\" height=\"334\" class=\"aligncenter size-medium wp-image-90509\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-500x334.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-306x205.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-810x541.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg 986w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Der Punkt 7 Herabstufungsrechte wurde in Downgraderechte umbenannt. Hier wurde der ganze Abschnitt umge\u00e4ndert. Selber aufrufen k\u00f6nnt ihr es \u00fcber Einstellungen -> System -> Info -> Microsoft Software Lizenzbestimmungen lesen.<\/p>\n<h3>Das Original von 2016:<\/h3>\n<blockquote class=\"quote_border_top\">\"7. Herabstufungsrechte. Wenn Sie ein Ger\u00e4t von einem Hersteller oder Installer mit einer vorinstallierten Windows Professional-Version erworben haben <i>und diese im Vollfunktionsmodus konfiguriert ist<\/i>, sind Sie berechtigt, entweder eine Windows 8.1 Pro- oder eine Windows 7 Professional-Version zu nutzen, aber nur solange, wie Microsoft Kundendienst f\u00fcr diese fr\u00fchere Version erbringt, wie in (aka.ms\/windowslifecycle) dargelegt. Dieser Vertrag gilt f\u00fcr Ihre Nutzung der fr\u00fcheren Versionen. Wenn die fr\u00fchere Version verschiedene Komponenten enth\u00e4lt, gelten Bestimmungen f\u00fcr solche Komponenten im Vertrag der fr\u00fcheren Version f\u00fcr Ihre Nutzung dieser Komponenten. Weder der Hersteller oder Installer noch Microsoft sind verpflichtet, Ihnen fr\u00fchere Versionen zu liefern. Sie m\u00fcssen die fr\u00fchere Version separat erlangen, f\u00fcr die Sie eventuell eine Geb\u00fchr entrichten m\u00fcssen. Sie k\u00f6nnen jederzeit eine fr\u00fchere Version durch die urspr\u00fcnglich erworbene Version ersetzen.\"<\/blockquote>\n<h3>Die \u00c4nderung 2017:<\/h3>\n<blockquote class=\"quote_border_top\">\"7. <strong>Downgraderechte<\/strong>. Wenn Sie ein Ger\u00e4t von einem Hersteller oder <strong>Installateur<\/strong> mit einer vorinstallierten, <strong>nicht schulischen<\/strong> Windows Professional-Version erworben haben, sind Sie berechtigt, entweder eine Windows 8.1 Pro- oder eine Windows 7 Professional-Version zu nutzen, aber nur solange, wie Microsoft Kundendienst f\u00fcr diese fr\u00fchere Version erbringt, wie in (aka.ms\/windowslifecycle) dargelegt. Dieser Vertrag gilt f\u00fcr <strong>die<\/strong> Nutzung der fr\u00fcheren Versionen <strong>durch Sie<\/strong>. Wenn die fr\u00fchere Version <strong>andere<\/strong> Komponenten enth\u00e4lt, gelten <strong>f\u00fcr die Nutzung solcher Komponenten durch Sie die entsprechenden Bestimmungen des mit der fr\u00fcheren Version mitgelieferten Vertrages.<\/strong> Weder der Hersteller bzw. <strong>das Installationsunternehmen<\/strong> noch Microsoft sind verpflichtet, Ihnen fr\u00fchere Versionen zu liefern. Sie m\u00fcssen die fr\u00fchere Version separat <strong>erwerben<\/strong>. <strong>Hierf\u00fcr wird Ihnen m\u00f6glicherweise eine Geb\u00fchr in Rechnung gestellt.<\/strong> Sie <strong>sind jederzeit berechtigt,<\/strong> eine fr\u00fchere Version durch die urspr\u00fcnglich erworbene Version zu ersetzen.\"<\/blockquote>\n<p>Alles andere ist gleich geblieben. Man hat die Berechtigung zum Downgrade also noch einmal spezifiziert.<\/p>\n<h3>Tutorials und Hilfe<\/h3>\n<p>Ihr sucht weitere Tipps, Tricks und Tutorials f\u00fcr Windows 10? Dann schaut in unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" target=\"_blank\"><strong>Wiki<\/strong><\/a> vorbei bzw. speichert die Seite in den Favoriten. Falls ihr Fragen habt, dann stellt diese (auch als Gast) ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=326\" target=\"_blank\"><strong>Forum<\/strong><\/a>. Wir werden versuchen euch bei euren Problemen zu helfen.<\/p>\n<ul>\n<li>Wichtige Tutorials im Wiki:<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_reparieren_wiederherstellen_mit_DISM_Inplace_Upgrade_und_vielen_weiteren_Varianten\" target=\"_blank\">Windows 10 reparieren, Fehler beheben<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_Update_reparieren_Windows_10\" target=\"_blank\">Win 10 Updates reparieren<\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Automatische_Updates_deaktivieren_oder_auf_manuell_setzen_Windows_10\" target=\"_blank\">richtig einstellen<\/a>  <\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Autostart_Windows_10_Programme_deaktivieren_hinzuf%C3%BCgen_entfernen\" target=\"_blank\">Windows 10 Autostart Programme entfernen<\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Datentr%C3%A4gerbereinigung_Windows_10_Alte_Daten_richtig_l%C3%B6schen\" target=\"_blank\">Festplatte \/ SSD aufr\u00e4umen<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_automatisch_anmelden_ohne_Passworteingabe\" target=\"_blank\">Ohne Passwort anmelden Windows 10<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Cortana_deaktivieren_Windows_10\" target=\"_blank\">Cortana entfernen, deaktivieren<\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Onedrive_deinstallieren_windows_10\" target=\"_blank\">OneDive entfernen<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Das_Windows_10_Startmen%C3%BC_richtig_einrichten_Tipps_und_Tricks\" target=\"_blank\">Windows 10 Tipps zum Startmen\u00fc <\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Startmen%C3%BC_reparieren_Windows_10\" target=\"_blank\">Reparatur<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Die &#8222;normalen&#8220; Nutzer der Windows 10 1703 (Creators Update) haben die Lizenzbestimmungen noch vom Dezember 2016. In der neuen Insider f\u00fcr die kommende 1709 (Fall Creators Update), die am 17.Oktober offiziell erscheinen wird hat man diese nun auf Juli 2017&hellip; <\/p>\n","protected":false},"author":134,"featured_media":90509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[18986,1579,9751],"class_list":["post-90508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-aenderungen-juli-2017","tag-lizenzbestimmungen","tag-windows-10"],"wp_featured_image":{"id":90509,"alt_text":"","description":"","media_type":"image","media_details":{"width":986,"height":658,"file":"2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg","sizes":{"thumbnail":{"file":"neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-306x205.jpg"},"medium":{"file":"neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-500x334.jpg","width":500,"height":334,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-500x334.jpg"},"large":{"file":"neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-810x541.jpg","width":810,"height":541,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-810x541.jpg"},"wp_review_large":{"file":"neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-320x200.jpg"},"wp_review_small":{"file":"neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-65x65.jpg"},"blog-large":{"file":"neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-642x300.jpg"},"blog-medium":{"file":"neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-306x205.jpg"},"recent-thumb":{"file":"neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-350x316.jpg"},"service-featured":{"file":"neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-600x330.jpg"},"wp_rp_thumbnail":{"file":"neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":90508,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert - Deskmodder.de<\/title>\n<meta name=\"description\" content=\"Mit der Windows 10 1709 (Fall Creators Update) \u00e4ndern sich zum Teil die Lizenzbedingungen. Diese hat Microsoft nun angepasst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert\" \/>\n<meta property=\"og:description\" content=\"Mit der Windows 10 1709 (Fall Creators Update) \u00e4ndern sich zum Teil die Lizenzbedingungen. Diese hat Microsoft nun angepasst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-02T16:04:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-02T16:12:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"986\" \/>\n\t<meta property=\"og:image:height\" content=\"658\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert\",\"datePublished\":\"2017-09-02T16:04:49+00:00\",\"dateModified\":\"2017-09-02T16:12:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/\"},\"wordCount\":568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg\",\"keywords\":[\"\u00c4nderungen Juli 2017\",\"Lizenzbestimmungen\",\"Windows 10\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/\",\"name\":\"Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg\",\"datePublished\":\"2017-09-02T16:04:49+00:00\",\"dateModified\":\"2017-09-02T16:12:44+00:00\",\"description\":\"Mit der Windows 10 1709 (Fall Creators Update) \u00e4ndern sich zum Teil die Lizenzbedingungen. Diese hat Microsoft nun angepasst.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg\",\"width\":986,\"height\":658},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/09\\\/02\\\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert - Deskmodder.de","description":"Mit der Windows 10 1709 (Fall Creators Update) \u00e4ndern sich zum Teil die Lizenzbedingungen. Diese hat Microsoft nun angepasst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert","og_description":"Mit der Windows 10 1709 (Fall Creators Update) \u00e4ndern sich zum Teil die Lizenzbedingungen. Diese hat Microsoft nun angepasst.","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-09-02T16:04:49+00:00","article_modified_time":"2017-09-02T16:12:44+00:00","og_image":[{"width":986,"height":658,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert","datePublished":"2017-09-02T16:04:49+00:00","dateModified":"2017-09-02T16:12:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/"},"wordCount":568,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg","keywords":["\u00c4nderungen Juli 2017","Lizenzbestimmungen","Windows 10"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/","name":"Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg","datePublished":"2017-09-02T16:04:49+00:00","dateModified":"2017-09-02T16:12:44+00:00","description":"Mit der Windows 10 1709 (Fall Creators Update) \u00e4ndern sich zum Teil die Lizenzbedingungen. Diese hat Microsoft nun angepasst.","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg","width":986,"height":658},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/09\/02\/microsoft-software-lizenzbestimmungen-wurden-auf-juli-2017-aktualisiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft Software Lizenzbestimmungen wurden auf Juli 2017 aktualisiert"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/09\/neue-lizenzbedingungen-windows-10-1709-fall-creators-update-juli-2017.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/90508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=90508"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/90508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/90509"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=90508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=90508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=90508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}