{"id":89593,"date":"2017-08-12T23:02:00","date_gmt":"2017-08-12T21:02:00","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=89593"},"modified":"2017-08-12T23:02:00","modified_gmt":"2017-08-12T21:02:00","slug":"nintendo-hat-kopiert","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/","title":{"rendered":"Nintendo hat kopiert!"},"content":{"rendered":"<p>Nintendo hat kopiert! Dies meint zumindest Gamevice und hat nun eine Patentklage gegen das japanische Unternehmen eingereicht. Mit der Switch m\u00f6chte dieses wieder einmal den Gaming-Bereich umkrempeln, wie z.B. damals mit der Wii. Das wird zwar nicht so klappen wie gew\u00fcnscht, aber auf jeden Fall wird man wieder viele neue Kunden gewinnen.<\/p>\n<p>Mit der Switch bekommt der Kunde n\u00e4mlich eine innovative Konsole, welche Zuhause und auch unterwegs nutzbar ist. Sehr vorteilhaft sind da die Joy-Cons, welche man auch einzeln als Kontroller benutzen kann, um so mit Freunden \u00fcberall Mario Kart oder \u00e4hnliches spielen zu k\u00f6nnen.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/01\/CI_NSwitch_Console_02_mediaplayer_large.jpg\" rel=\"lightbox[89593]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/01\/CI_NSwitch_Console_02_mediaplayer_large.jpg\" alt=\"\" width=\"641\" height=\"427\" class=\"aligncenter size-full wp-image-78347\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/01\/CI_NSwitch_Console_02_mediaplayer_large.jpg 641w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/01\/CI_NSwitch_Console_02_mediaplayer_large-306x205.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/01\/CI_NSwitch_Console_02_mediaplayer_large-500x333.jpg 500w\" sizes=\"auto, (max-width: 641px) 100vw, 641px\" \/><\/a><\/p>\n<h3>Joy-Cons inspiriert<\/h3>\n<p>Die Joy-Cons sollen interessanterweise aber inspiriert\/kopiert worden sein. Dies behaupte Gamevice und verweist auf sein eigenes Produkt &#8222;Wikipad 7&#8220;. Das Unternehmen f\u00fcr Gaming-Zubeh\u00f6r f\u00fcr Smartphones und Tablets pr\u00e4sentierte das Tablet mit dem Joy-Con \u00e4hnlichen ansteck U-Controller bereits 2012.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12.png\" rel=\"lightbox[89593]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-810x524.png\" alt=\"\" width=\"810\" height=\"524\" class=\"aligncenter size-large wp-image-89594\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-810x524.png 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-306x198.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-500x324.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12.png 1190w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n<p>Aufgrund der \u00c4hnlichkeit fordert Gamevice nun den Verkaufsstopp der Nintendo Switch. Ebenfalls wird Schadensersatz gefordert, wobei ich mir echt nicht vorstellen kann, dass das Unternehmen damit irgendwie durchkommt.<\/p>\n<p>Via: <a href=\"https:\/\/www.heise.de\/newsticker\/meldung\/Klage-gegen-Nintendo-Switch-Controller-sollen-Patent-verletzten-3798804.html?wt_mc=rss.ho.beitrag.atom\">heise<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nintendo hat kopiert! Dies meint zumindest Gamevice und hat nun eine Patentklage gegen das japanische Unternehmen eingereicht. Mit der Switch m\u00f6chte dieses wieder einmal den Gaming-Bereich umkrempeln, wie z.B. damals mit der Wii. Das wird zwar nicht so klappen wie&hellip; <\/p>\n","protected":false},"author":2550,"featured_media":89594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286],"tags":[18402,15782,8860,15780,18401],"class_list":["post-89593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","tag-gamevice","tag-joy-con","tag-nintendo","tag-switch","tag-wikipad"],"wp_featured_image":{"id":89594,"alt_text":"","description":"","media_type":"image","media_details":{"width":1190,"height":770,"file":"2017\/08\/wikipad-fdf2b857c0843a12.png","sizes":{"thumbnail":{"file":"wikipad-fdf2b857c0843a12-306x198.png","width":306,"height":198,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-306x198.png"},"medium":{"file":"wikipad-fdf2b857c0843a12-500x324.png","width":500,"height":324,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-500x324.png"},"large":{"file":"wikipad-fdf2b857c0843a12-810x524.png","width":810,"height":524,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-810x524.png"},"wp_review_large":{"file":"wikipad-fdf2b857c0843a12-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-320x200.png"},"wp_review_small":{"file":"wikipad-fdf2b857c0843a12-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-65x65.png"},"blog-large":{"file":"wikipad-fdf2b857c0843a12-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-642x300.png"},"blog-medium":{"file":"wikipad-fdf2b857c0843a12-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-306x205.png"},"recent-thumb":{"file":"wikipad-fdf2b857c0843a12-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-350x316.png"},"service-featured":{"file":"wikipad-fdf2b857c0843a12-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-600x330.png"},"wp_rp_thumbnail":{"file":"wikipad-fdf2b857c0843a12-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":89593,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12.png"},"commentcount":5,"wp_comments":[{"id":53086,"parent":0,"author":0,"author_name":"Formadt C:","author_email":"drogy@freenet.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8bf898dcc60f3e9b5babb7542a1e47f1d98accecddf5dddafabc24e70e81a61a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8bf898dcc60f3e9b5babb7542a1e47f1d98accecddf5dddafabc24e70e81a61a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8bf898dcc60f3e9b5babb7542a1e47f1d98accecddf5dddafabc24e70e81a61a?s=96&d=mm&r=g"},"date":"2017-08-13T03:15:58","cld_nonce":"82f011626f","content":{"rendered":"<p>Boohr !<br \/>\nKrass !!!!!<\/p>\n"},"status":"1"},{"id":53088,"parent":0,"author":0,"author_name":"Erazor84","author_email":"spam84@ymail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=96&d=mm&r=g"},"date":"2017-08-13T07:56:28","cld_nonce":"82f011626f","content":{"rendered":"<p>OH EHM GEEEE, das Teil der klagenden Partei sieht aus wie ein SEGA Game Gear von 1990, bzw. hat damit gro\u00dfe \u00c4hnlichkeit! SEGA, verklag die Schwe**** <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n<p>Furchtbar, dieses absolut unn\u00f6tige Patentsystem &#8230;.<\/p>\n"},"status":"1"},{"id":53091,"parent":0,"author":0,"author_name":"Ben","author_email":"BenderArsch@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=96&d=mm&r=g"},"date":"2017-08-13T10:34:26","cld_nonce":"82f011626f","content":{"rendered":"<p>Das Wikipad schaut aber auch ganz sch\u00f6n nach kopiert aus n\u00e4mlich nach der Wii U<\/p>\n"},"status":"1"},{"id":53097,"parent":53086,"author":2550,"author_name":"MAX","author_email":"max@mximum.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g"},"date":"2017-08-13T13:04:54","cld_nonce":"82f011626f","content":{"rendered":"<p>Voll oder?!?!? <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53318,"parent":0,"author":0,"author_name":"Stefan","author_email":"stefan.even@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dd95be1ca637fe6dfb29099deb97b5810badd2234c8f6ae658a0c68f15d89b1c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dd95be1ca637fe6dfb29099deb97b5810badd2234c8f6ae658a0c68f15d89b1c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dd95be1ca637fe6dfb29099deb97b5810badd2234c8f6ae658a0c68f15d89b1c?s=96&d=mm&r=g"},"date":"2017-08-14T13:52:47","cld_nonce":"82f011626f","content":{"rendered":"<p>Das aktuell vertriebene Produkt von Gamevice sieht der Switch mit den ansteckbaren Joy Con schon sehr \u00e4hnlich.<\/p>\n<p>Artikel:<br \/>\n<a href=\"http:\/\/newatlas.com\/wikipad-gamevice-ipad-controller\/35507\/\" rel=\"nofollow ugc\">http:\/\/newatlas.com\/wikipad-gamevice-ipad-controller\/35507\/<\/a><\/p>\n<p>Ohne Ger\u00e4t:<br \/>\n<a href=\"http:\/\/in.gamerekon.com\/wp-content\/uploads\/2015\/01\/wikipad-gamevice-7.jpg\"  rel=\"lightbox[89593] nofollow ugc\">http:\/\/in.gamerekon.com\/wp-content\/uploads\/2015\/01\/wikipad-gamevice-7.jpg<\/a><\/p>\n<p>Homepage:<br \/>\n<a href=\"https:\/\/gamevice.com\/\" rel=\"nofollow ugc\">https:\/\/gamevice.com\/<\/a><\/p>\n"},"status":"1"}],"wp_author":{"id":2550,"name":"MAX","description":"Begeisterter Technik-Enthusiast, der aktuell zwei Welten vereint. Windows auf PC sowie Xbox und iOS auf dem iPhone, als auch auf dem iPad. Gespaltene Pers\u00f6nlichkeit w\u00fcrde ich sagen. ;)","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nintendo hat kopiert! - Deskmodder.de<\/title>\n<meta name=\"description\" content=\"Nintendo hat kopiert! Dies meint zumindest Gamevice, verweist auf das eigene Produkt und hat nun eine Patentklage gegen das Unternehmen eingereicht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nintendo hat kopiert!\" \/>\n<meta property=\"og:description\" content=\"Nintendo hat kopiert! Dies meint zumindest Gamevice, verweist auf das eigene Produkt und hat nun eine Patentklage gegen das Unternehmen eingereicht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-12T21:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1190\" \/>\n\t<meta property=\"og:image:height\" content=\"770\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"MAX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@themximum\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/\"},\"author\":{\"name\":\"MAX\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/bd4b9506e83c661f1de1af925c726d7c\"},\"headline\":\"Nintendo hat kopiert!\",\"datePublished\":\"2017-08-12T21:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/\"},\"wordCount\":176,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/wikipad-fdf2b857c0843a12.png\",\"keywords\":[\"Gamevice\",\"Joy-Con\",\"Nintendo\",\"Switch\",\"Wikipad\"],\"articleSection\":[\"Hardware\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/\",\"name\":\"Nintendo hat kopiert! - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/wikipad-fdf2b857c0843a12.png\",\"datePublished\":\"2017-08-12T21:02:00+00:00\",\"description\":\"Nintendo hat kopiert! Dies meint zumindest Gamevice, verweist auf das eigene Produkt und hat nun eine Patentklage gegen das Unternehmen eingereicht.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/wikipad-fdf2b857c0843a12.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/wikipad-fdf2b857c0843a12.png\",\"width\":1190,\"height\":770},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/nintendo-hat-kopiert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nintendo hat kopiert!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/bd4b9506e83c661f1de1af925c726d7c\",\"name\":\"MAX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g\",\"caption\":\"MAX\"},\"description\":\"Begeisterter Technik-Enthusiast, der aktuell zwei Welten vereint. Windows auf PC sowie Xbox und iOS auf dem iPhone, als auch auf dem iPad. Gespaltene Pers\u00f6nlichkeit w\u00fcrde ich sagen. ;)\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/themximum\\\/\",\"https:\\\/\\\/x.com\\\/themximum\"],\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/max\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nintendo hat kopiert! - Deskmodder.de","description":"Nintendo hat kopiert! Dies meint zumindest Gamevice, verweist auf das eigene Produkt und hat nun eine Patentklage gegen das Unternehmen eingereicht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/","og_locale":"de_DE","og_type":"article","og_title":"Nintendo hat kopiert!","og_description":"Nintendo hat kopiert! Dies meint zumindest Gamevice, verweist auf das eigene Produkt und hat nun eine Patentklage gegen das Unternehmen eingereicht.","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-08-12T21:02:00+00:00","og_image":[{"width":1190,"height":770,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12.png","type":"image\/png"}],"author":"MAX","twitter_card":"summary_large_image","twitter_creator":"@themximum","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/"},"author":{"name":"MAX","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/bd4b9506e83c661f1de1af925c726d7c"},"headline":"Nintendo hat kopiert!","datePublished":"2017-08-12T21:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/"},"wordCount":176,"commentCount":5,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12.png","keywords":["Gamevice","Joy-Con","Nintendo","Switch","Wikipad"],"articleSection":["Hardware"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/","name":"Nintendo hat kopiert! - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12.png","datePublished":"2017-08-12T21:02:00+00:00","description":"Nintendo hat kopiert! Dies meint zumindest Gamevice, verweist auf das eigene Produkt und hat nun eine Patentklage gegen das Unternehmen eingereicht.","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12.png","width":1190,"height":770},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/nintendo-hat-kopiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Nintendo hat kopiert!"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/bd4b9506e83c661f1de1af925c726d7c","name":"MAX","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g","caption":"MAX"},"description":"Begeisterter Technik-Enthusiast, der aktuell zwei Welten vereint. Windows auf PC sowie Xbox und iOS auf dem iPhone, als auch auf dem iPad. Gespaltene Pers\u00f6nlichkeit w\u00fcrde ich sagen. ;)","sameAs":["https:\/\/www.instagram.com\/themximum\/","https:\/\/x.com\/themximum"],"url":"https:\/\/www.deskmodder.de\/blog\/author\/max\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/wikipad-fdf2b857c0843a12.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/89593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2550"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=89593"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/89593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/89594"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=89593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=89593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=89593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}