{"id":89587,"date":"2017-08-12T12:56:36","date_gmt":"2017-08-12T10:56:36","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=89587"},"modified":"2017-08-12T12:56:36","modified_gmt":"2017-08-12T10:56:36","slug":"sharex-als-app-im-windows-store","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/","title":{"rendered":"ShareX 11.9 als App im Windows Store"},"content":{"rendered":"<p>Das ShareX Team hat nicht nur die aktuelle Version 11.9 vor ein paar Tagen ver\u00f6ffentlicht. Es wurde nun auch die App im Windows Store zum Download bereitgestellt. Das Tool werden sicherlich viele von euch schon kennen. Es ist ein kostenloses Programm um Screenshots zu erstellen, Aufnahmen von Spielen zu machen und vieles mehr.<\/p>\n<p>M\u00f6chte man dann das Bild oder Video hochladen, so ist die Auswahl riesengross. 9 Jahre t\u00fcfteln die Jungs und M\u00e4dels nun schon an diesem Programm und es kommen immer weitere Features hinzu. Die Changelog zur neuen Version kommt weiter unten.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store.jpg\" rel=\"lightbox[89587]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-500x357.jpg\" alt=\"\" width=\"500\" height=\"357\" class=\"aligncenter size-medium wp-image-89588\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-500x357.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-287x205.jpg 287w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-810x579.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store.jpg 1048w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Die App ist mit dem Desktop App Converter erstellt worden. Ist also in der Handhabung genauso wie auch das Programm. Wer auf Apps und deren Ausf\u00fchrung als Container in einer Sandbox steht, kann sie sich hier herunterladen.  Windows 10 S Nutzer wird es sicherlich freuen, ein so umfangreiches Screenshot-Tool nutzen zu k\u00f6nnen.<\/p>\n<p><!-- WP-Appbox (Version: 4.5.13 \/\/ Store: microsoftstore \/\/ ID: 9nblggh4z1sp) -->\n<div class=\"wpappbox wpappbox-123f488fb55a398cc475f1534adcf659 microsoftstore simple\">\n\t<div class=\"qrcode\"><img decoding=\"async\" src=\"https:\/\/api.qrserver.com\/v1\/create-qr-code\/?data=https%3A%2F%2Fwww.microsoft.com%2Fde-de%2Fp%2Fapp%2F9nblggh4z1sp&size=200x200&ecc=M&margin=0\" alt=\"ShareX\" \/><\/div>\n\t<div class=\"appicon\">\n\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/p\/app\/9nblggh4z1sp\" aria-label=\"ShareX\"><img decoding=\"async\" src=\"\/\/store-images.s-microsoft.com\/image\/apps.48570.13510798887692934.c184c40e-9bd1-4456-97e3-41e7901f5c73.c21a627b-b6d2-49a1-815a-86ced6e3b9fe?w=92&#038;q=80\" alt=\"ShareX\" \/><\/a>\n\t<\/div>\n\t<div class=\"applinks\">\n\t\t<div class=\"appbuttons\">\n\t\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/p\/app\/9nblggh4z1sp\" aria-label=\"ShareX\">Download<\/a>\n\t\t\t<span onMouseOver=\"jQuery('.wpappbox-123f488fb55a398cc475f1534adcf659 .qrcode').show();\" onMouseOut=\"jQuery('.wpappbox-123f488fb55a398cc475f1534adcf659 .qrcode').hide();\">QR-Code<\/span>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"appdetails\">\n\t\t<div class=\"apptitle\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/p\/app\/9nblggh4z1sp\" title=\"ShareX\" aria-label=\"ShareX\" class=\"apptitle\">ShareX<\/a><\/div>\n\t\t<div class=\"developer\">\n\t\t\t<span class=\"label\">Entwickler: <\/span>\n\t\t\t<span class=\"value\">\u202aShareX Team\u202c<\/span>\n\t\t<\/div>\n\t\t<div class=\"price\">\n\t\t\t<span class=\"label\">Preis: <\/span>\n\t\t\t<span class=\"value\">Kostenlos<\/span> \n\t\t\t<span class=\"rating\"><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div><!-- \/WP-Appbox --><br \/>\n<a href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/sharex\/9nblggh4z1sp\" target=\"_blank\">https:\/\/www.microsoft.com\/de-de\/store\/p\/sharex\/9nblggh4z1sp<\/a><\/p>\n<h3>Changelog:<\/h3>\n<ul>\n<li>Added Italian language support (by @pjammo)<\/li>\n<li>Added cursor tool to region capture which allows moving, deleting or adding more cursors<\/li>\n<li>Added multiple center point support to line and arrow tools<\/li>\n<li>Added arrows on both ends option to arrow tool<\/li>\n<li>Added batch image thumbnailer tool<\/li>\n<li>Added random syntax to Custom uploader, which can be used to return random domain each upload, check here for more info<\/li>\n<li>Added custom domain support for Azure storage (by @Lego6245)<\/li>\n<li>Added padding and border size option to text watermark<\/li>\n<li>Added unread counter to news button<\/li>\n<\/ul>\n<p><a href=\"https:\/\/getsharex.com\/\" target=\"_blank\">getsharex.com\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das ShareX Team hat nicht nur die aktuelle Version 11.9 vor ein paar Tagen ver\u00f6ffentlicht. Es wurde nun auch die App im Windows Store zum Download bereitgestellt. Das Tool werden sicherlich viele von euch schon kennen. Es ist ein kostenloses&hellip; <\/p>\n","protected":false},"author":134,"featured_media":89588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[152,2689,3031],"tags":[924,5247,88,18400,942],"class_list":["post-89587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software","category-windows-10","category-windows-apps","tag-app","tag-changelog","tag-download","tag-sharex-11-9","tag-windows-store"],"wp_featured_image":{"id":89588,"alt_text":"","description":"","media_type":"image","media_details":{"width":1048,"height":749,"file":"2017\/08\/sharex-1190-als-app-im-windows-store.jpg","sizes":{"thumbnail":{"file":"sharex-1190-als-app-im-windows-store-287x205.jpg","width":287,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-287x205.jpg"},"medium":{"file":"sharex-1190-als-app-im-windows-store-500x357.jpg","width":500,"height":357,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-500x357.jpg"},"large":{"file":"sharex-1190-als-app-im-windows-store-810x579.jpg","width":810,"height":579,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-810x579.jpg"},"wp_review_large":{"file":"sharex-1190-als-app-im-windows-store-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-320x200.jpg"},"wp_review_small":{"file":"sharex-1190-als-app-im-windows-store-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-65x65.jpg"},"blog-large":{"file":"sharex-1190-als-app-im-windows-store-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-642x300.jpg"},"blog-medium":{"file":"sharex-1190-als-app-im-windows-store-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-306x205.jpg"},"recent-thumb":{"file":"sharex-1190-als-app-im-windows-store-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-350x316.jpg"},"service-featured":{"file":"sharex-1190-als-app-im-windows-store-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-600x330.jpg"},"wp_rp_thumbnail":{"file":"sharex-1190-als-app-im-windows-store-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":89587,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store.jpg"},"commentcount":5,"wp_comments":[{"id":53071,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-08-12T17:21:42","cld_nonce":"82f011626f","content":{"rendered":"<p>Herr &#8222;App-nicht-M\u00f6ger&#8220; Hugo probiert ab\/an doch mal so\u00b4ne App. ShareX w\u00e4re noch nicht mal so schlecht &#8211; man mu\u00df ja nicht sharen, was ich so nicht will, sondern eben nur Screenshots machen. Das geht auch fix, die Shots sind nicht \u00fcbel, aber sie werden immer bei\/in:<\/p>\n<p>C:\\Users\\HerrHugo\\Documents\\ShareX\\Screenshots<\/p>\n<p>abgespeichert &#8211; und das gef\u00e4llt mir \u00fcberhaupt nicht. Ich habe mal in den Einstellungen geguckt &#8211; aber ich sehe da nix, wie\/wo man den Speicherort \u00e4ndern k\u00f6nnte. <\/p>\n<p>Meine Frage: bin ich nur zu doof (grins) um die Einstellung zu finden oder geht das gar nicht? Wenn das jemand wei\u00df, m\u00f6ge er es bitte nicht f\u00fcr sich behalten, sondern es mal hinschreiben. Diesen &#8222;Jemand&#8220; w\u00fcrde ich zum Danke in mein Nachtgebet einschlie\u00dfen. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53072,"parent":53071,"author":2819,"author_name":"KeyserSoze","author_email":"ahmedschlickum@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ea2aef017dab1e7b1a1fb5263914c0e19c5f81495b5196683aae99b329b9e46f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ea2aef017dab1e7b1a1fb5263914c0e19c5f81495b5196683aae99b329b9e46f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ea2aef017dab1e7b1a1fb5263914c0e19c5f81495b5196683aae99b329b9e46f?s=96&d=mm&r=g"},"date":"2017-08-12T17:32:12","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8230; also einen eigenen Ordnerpfad ausw\u00e4hlen funktioniert ziemlich einfach:<br \/>\n&#8211; Einstellungen<br \/>\n&#8211; Pfade<\/p>\n"},"status":"1"},{"id":53074,"parent":0,"author":0,"author_name":"Harald","author_email":"jolly@koker.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/cf3e1e9eed7d5e185fe81d634872d5f4f920de329e1cda6501e779acb92be141?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/cf3e1e9eed7d5e185fe81d634872d5f4f920de329e1cda6501e779acb92be141?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/cf3e1e9eed7d5e185fe81d634872d5f4f920de329e1cda6501e779acb92be141?s=96&d=mm&r=g"},"date":"2017-08-12T18:03:04","cld_nonce":"82f011626f","content":{"rendered":"<p>Also wer derartig dreist bei Google das Logo klaut, sollte sich nicht wundern, wenn er Post von den<br \/>\nGoogle Anw\u00e4lten bekommt.<\/p>\n<p><a href=\"https:\/\/research.google.com\/\" rel=\"nofollow ugc\">https:\/\/research.google.com\/<\/a><\/p>\n<p>Aber v\u00f6llig unabh\u00e4ngig davon:<br \/>\nDer Sinn solcher Screen-Snapshot-Tools erschliesst sich mir aber trotzdem nicht so ganz.<br \/>\nDie allgemein bekannten Tastenkombinationen &#8222;Windows-Taste+Druck&#8220;, &#8222;Altgr+Druck&#8220;<br \/>\nbzw. das systemeigene Snipping-Tools reichen IMO doch v\u00f6llig aus um Screenshots zu handlen.<\/p>\n"},"status":"1"},{"id":53085,"parent":53072,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-08-13T01:54:38","cld_nonce":"82f011626f","content":{"rendered":"<p>Herr KeyserSoze &#8211; das mit dem Nachtgebet geht klar, du bist praktisch schon eingeschlossen, grins! Bi\u00dfchen blind war ich ja schon, aber mit deiner Hilfe hat es geklappt. Jetzt ist im gew\u00fcnschten Ordner auf Laufwerk E ein Unterorder erstellt nach folgendem Muster\/Namen:<\/p>\n<p>ShareX-2017-08<\/p>\n<p>Da kommen\/k\u00e4men also alle Screenshots von August 2017 rein &#8211; es klappt, ich habe es schon mit einigen getestet.<\/p>\n<p>Mit der App an sich mu\u00df ich mich aber noch ein wenig vertraut machen. Aber Hauptsache war f\u00fcr mich erstmal der Speicherort au\u00dferhalb &#8222;C&#8220;, weil ich da prinzipiell nix abspeichern will.<\/p>\n<p>Danke dir noch mal. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n<p>PS: ich werde aber mal nach dem &#8222;normalen&#8220; Prog ShareX gucken, das liegt mir wohl n\u00e4her&#8230;<\/p>\n"},"status":"1"},{"id":53173,"parent":53074,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-08-13T17:25:50","cld_nonce":"82f011626f","content":{"rendered":"<p>Herr Harald, der Sinn kommt zum tragen, wenn man z.B. Apple-Tastaturen an Win-Rechnern einsetzt, die haben keine &#8222;Druck&#8220;-Taste, grins. Ich w\u00fcrde die aber auch an Win-Tastaturen nicht daf\u00fcr nutzen, weil ich lieber Tools daf\u00fcr nehme.<\/p>\n<p>Bevor Fragen k\u00f6mmen: ja, ich komme prima mit &#8222;Apple an Win&#8220; zurecht. Und: es sind auch nicht nur die angeschlossenen Apples vorhanden, sondern Win-Tastaturen w\u00e4ren schnell zur Hand.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ShareX 11.9 als App im Windows Store - Deskmodder.de<\/title>\n<meta name=\"description\" content=\"ShareX 11.9 als App nun auch im Windows Store verf\u00fcgbar. Sie ist identisch mit dem kostenlosen Screenshot-Tool.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ShareX 11.9 als App im Windows Store\" \/>\n<meta property=\"og:description\" content=\"ShareX 11.9 als App nun auch im Windows Store verf\u00fcgbar. Sie ist identisch mit dem kostenlosen Screenshot-Tool.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-12T10:56:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1048\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"ShareX 11.9 als App im Windows Store\",\"datePublished\":\"2017-08-12T10:56:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/\"},\"wordCount\":262,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/sharex-1190-als-app-im-windows-store.jpg\",\"keywords\":[\"App\",\"changelog\",\"Download\",\"ShareX 11.9\",\"Windows Store\"],\"articleSection\":[\"Software &amp; Updates\",\"Windows 10\",\"Windows Apps\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/\",\"name\":\"ShareX 11.9 als App im Windows Store - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/sharex-1190-als-app-im-windows-store.jpg\",\"datePublished\":\"2017-08-12T10:56:36+00:00\",\"description\":\"ShareX 11.9 als App nun auch im Windows Store verf\u00fcgbar. Sie ist identisch mit dem kostenlosen Screenshot-Tool.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/sharex-1190-als-app-im-windows-store.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/sharex-1190-als-app-im-windows-store.jpg\",\"width\":1048,\"height\":749},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/12\\\/sharex-als-app-im-windows-store\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ShareX 11.9 als App im Windows Store\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ShareX 11.9 als App im Windows Store - Deskmodder.de","description":"ShareX 11.9 als App nun auch im Windows Store verf\u00fcgbar. Sie ist identisch mit dem kostenlosen Screenshot-Tool.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/","og_locale":"de_DE","og_type":"article","og_title":"ShareX 11.9 als App im Windows Store","og_description":"ShareX 11.9 als App nun auch im Windows Store verf\u00fcgbar. Sie ist identisch mit dem kostenlosen Screenshot-Tool.","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-08-12T10:56:36+00:00","og_image":[{"width":1048,"height":749,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"ShareX 11.9 als App im Windows Store","datePublished":"2017-08-12T10:56:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/"},"wordCount":262,"commentCount":5,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store.jpg","keywords":["App","changelog","Download","ShareX 11.9","Windows Store"],"articleSection":["Software &amp; Updates","Windows 10","Windows Apps"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/","name":"ShareX 11.9 als App im Windows Store - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store.jpg","datePublished":"2017-08-12T10:56:36+00:00","description":"ShareX 11.9 als App nun auch im Windows Store verf\u00fcgbar. Sie ist identisch mit dem kostenlosen Screenshot-Tool.","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store.jpg","width":1048,"height":749},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/12\/sharex-als-app-im-windows-store\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"ShareX 11.9 als App im Windows Store"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/sharex-1190-als-app-im-windows-store.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/89587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=89587"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/89587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/89588"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=89587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=89587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=89587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}