{"id":89138,"date":"2017-08-21T15:30:33","date_gmt":"2017-08-21T13:30:33","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=89138"},"modified":"2023-01-14T17:09:36","modified_gmt":"2023-01-14T16:09:36","slug":"copyme-6-0-erschienen-dateien-und-ordner-synchron-halten","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/","title":{"rendered":"CopyMe 6.6 erschienen &#8211; Dateien und Ordner synchron halten"},"content":{"rendered":"<p>Es gibt viele Tools f\u00fcr die Synchronisation von Daten und Ordnern unter Windows. Selbst Windows 10 hat mit dem Dateiversionsverlauf eine \u00e4hnliche Funktion an Board. CopyMe ist ein Leichtgewicht, ist portabel und in deutsch und englisch. Nun ist die Version 6.0 erschienen. [Update 21.08]: Aktuell die Version 6.6. Changelog weiter unten.<\/p>\n<p>Das Tool arbeitet mit Windows 10 bis runter zu Windows XP.Einmal entpackt kann es auch schon losgehen. In der aktuellen Insider konnte ich  das Tool \u00fcber den Warnhinweis &#8222;Trotzdem ausf\u00fchren&#8220; erst starten. Danach zieht man ganz einfach einen Ordner in das Fenster und legt den Zielordner fest.<\/p>\n<div id='gallery-1' class='gallery galleryid-89138 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg' rel=\"lightbox[89138]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"194\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-306x194.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-306x194.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-500x316.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg 591w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-002.jpg' rel=\"lightbox[89138]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"181\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-002-306x181.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-002-306x181.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-002-500x296.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-002.jpg 697w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-003.jpg' rel=\"lightbox[89138]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"187\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-003-306x187.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-003-306x187.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-003-500x305.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-003-810x495.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-003.jpg 907w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Dann kann man sich noch die Optionen anschauen und einstellen und eine *.cbpx Datei erzeugen. Danach wird der Ordner synchronisiert. Alle \u00c4nderungen werden dann inkrementell und im Hintergrund vorgenommen. Ich hab es jetzt erst einmal nur zum Test auf dem Desktop angelegt.<\/p>\n<div id='gallery-2' class='gallery galleryid-89138 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-004.jpg' rel=\"lightbox[89138]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"200\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-004-306x200.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-004-306x200.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-004-500x327.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-004.jpg 732w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-005.jpg' rel=\"lightbox[89138]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"182\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-005-306x182.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-005-306x182.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-005-500x297.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-005.jpg 730w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Hat man zum Beispiel einen USB-Stick mit Musik, den man immer synchron mit seiner Sammlung halten will, dann kopiert man die angelegte *.cbpx Datei mit auf den Stick. Dies ist laut Webseite auch f\u00fcr externe Speichermedien ratsam. Wer das Tool einmal testen m\u00f6chte, findet ihr weitere Infos und nat\u00fcrlich die Datei als Setup, portable oder Portable-Setup. <a href=\"https:\/\/www.js-tools.de\/copyme.htm\" target=\"_blank\" rel=\"noopener\">js-tools.de\/copyme<\/a><\/p>\n<h3>Version 6.6 Die \u00c4nderungen<\/h3>\n<ul>\n<li><strong>[Update 21.08.]:<\/strong> Seit der Version 6.4 und nun auch in der 6.6 gibt es immer eine Changelog, die Joachim  (Ersteller des Tool) hinzuf\u00fcgt.<\/li>\n<li>Bez\u00fcglich der Geschwindigkeit, einige weitere Optimierungen durchgef\u00fchrt.<\/li>\n<li>\u201eBericht nach Auftragsende immer anzeigen\u201c unter Optionen hinzugef\u00fcgt.<\/li>\n<li>\u201eSkins\u201c im Men\u00fc Extras hinzugef\u00fcgt.<\/li>\n<li>Sprachauswahl weiter angepasst.<\/li>\n<li><a href=\"https:\/\/www.js-tools.de\/copyme.htm\" target=\"_blank\" rel=\"noopener\">js-tools.de\/copyme<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Es gibt viele Tools f\u00fcr die Synchronisation von Daten und Ordnern unter Windows. Selbst Windows 10 hat mit dem Dateiversionsverlauf eine \u00e4hnliche Funktion an Board. CopyMe ist ein Leichtgewicht, ist portabel und in deutsch und englisch. Nun ist die Version&hellip; <\/p>\n","protected":false},"author":134,"featured_media":89139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[152,2689,11],"tags":[18294,1757,18295],"class_list":["post-89138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software","category-windows-10","category-windows","tag-copyme","tag-daten-synchronisieren","tag-inkrementell"],"wp_featured_image":{"id":89139,"alt_text":"","description":"","media_type":"image","media_details":{"width":591,"height":374,"file":"2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg","sizes":{"thumbnail":{"file":"copyme-dateien-ordner-schnell-synchronisieren-001-306x194.jpg","width":306,"height":194,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-306x194.jpg"},"medium":{"file":"copyme-dateien-ordner-schnell-synchronisieren-001-500x316.jpg","width":500,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-500x316.jpg"},"wp_review_large":{"file":"copyme-dateien-ordner-schnell-synchronisieren-001-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-320x200.jpg"},"wp_review_small":{"file":"copyme-dateien-ordner-schnell-synchronisieren-001-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-65x65.jpg"},"blog-large":{"file":"copyme-dateien-ordner-schnell-synchronisieren-001-591x300.jpg","width":591,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-591x300.jpg"},"blog-medium":{"file":"copyme-dateien-ordner-schnell-synchronisieren-001-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-306x205.jpg"},"recent-thumb":{"file":"copyme-dateien-ordner-schnell-synchronisieren-001-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-350x316.jpg"},"service-featured":{"file":"copyme-dateien-ordner-schnell-synchronisieren-001-591x330.jpg","width":591,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-591x330.jpg"},"wp_rp_thumbnail":{"file":"copyme-dateien-ordner-schnell-synchronisieren-001-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":89138,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg"},"commentcount":61,"wp_comments":[{"id":52219,"parent":0,"author":0,"author_name":"Sandro","author_email":"s.chudowski@posteo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dcaf690d51279f2b3d8351be4101b3816cf8f060ead23dc18f04f6e7550705a6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dcaf690d51279f2b3d8351be4101b3816cf8f060ead23dc18f04f6e7550705a6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dcaf690d51279f2b3d8351be4101b3816cf8f060ead23dc18f04f6e7550705a6?s=96&d=mm&r=g"},"date":"2017-08-03T22:07:38","cld_nonce":"82f011626f","content":{"rendered":"<p>Das sollte ich mir mal angucken. Danke f\u00fcr den Tipp!<\/p>\n"},"status":"1"},{"id":52328,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-08-04T11:39:31","cld_nonce":"82f011626f","content":{"rendered":"<p>Hmm, hmm, hmm &#8211; vielleicht k\u00f6nnte ich wirklich mal mit einem USB-Stick testen, wo (auch) paar GB Musik drauf sind &#8211; nat\u00fcrlich nur Kopien von auf der HDD gespeicherten Daten.<\/p>\n<p>Vorher vom Stick einen Schwung l\u00f6schen und dann probieren, wie das Tool im Hintergrund werkelt. Passieren kann prinzipiell nix, weil die Daten eh mehrfach gesichert sind.<\/p>\n"},"status":"1"},{"id":52345,"parent":0,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-04T13:08:18","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo,<\/p>\n<p>CopyMe besitzt ein g\u00fcltiges Zertifikat und kann ohne Bedenken gestartet werden.<\/p>\n<p>CopyMe unterst\u00fctzt die Sprachen Deutsch und Englisch. Zum Umstellen der Sprache nach der Installation, einfach in der Statuszeile auf die Flagge klicken.<\/p>\n<p>F\u00fcr jeden Auftrag kann eine Verkn\u00fcpfung auf dem Desktop angelegt werden. So reicht ein Klick um den jeweiligen Auftrag zu starten.<\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n<p>JS-Tools.de<\/p>\n"},"status":"1"},{"id":52349,"parent":52345,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-08-04T13:14:10","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo Joachim,<br \/>\nder Hinweis von mir ist extra geschrieben worden, da sonst Nachfragen in den Kommentaren kommen wegen &#8222;..wird von Windows geblockt&#8220; etc.<br \/>\nDie Sicherheitsma\u00dfnahmen in der RS3 sind durch die Integration von &#8222;EMET&#8220; doch um einiges h\u00f6her. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":52477,"parent":52345,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-08-05T11:06:00","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8222;&#8230;l\u00e4uft dann unbemerkt im Hintergrund.&#8220; Kannst du das ein bi\u00dfchen &#8222;griffiger&#8220; ausdr\u00fccken? Ich gebe ein konkretes Beispiel, von einem Backup, das ich mit Personal Backup mache\/nutze:<\/p>\n<p>&#8211; 236 GB in 11624 Ordnern mit 94150 Dateien<\/p>\n<p>Das ist alles zusammen in einem &#8222;Oberordner&#8220; und wird mind. 1x\/Tag von mir gesynct von interner HDD &gt; externer HDD (USB 3.0). Vorgehensweise: externe einschalten, das Backup manuell ansto\u00dfen, unter\/knapp 2 min werkeln lassen, fertig &gt; externe HDD ausschalten .<\/p>\n<p>Die Zeit gilt, wenn sich nicht \u00fcberdurchschnittlich viel ge\u00e4ndert hat (sonst eben etwas l\u00e4nger) &#8211; ist also nicht n\u00f6tig, das Personal Backup &#8222;unbemerkt im Hintergrund&#8220; l\u00e4uft, weil es so fix geht. Du als Erfinder m\u00fc\u00dftest doch auch Beispiele haben, wie lange Backups bei dir dauern, oder?<\/p>\n"},"status":"1"},{"id":52834,"parent":0,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-10T01:28:37","cld_nonce":"82f011626f","content":{"rendered":"<p>Hi,<br \/>\nwenn Interesse an dem Programm besteht, ist ein Test von meiner Seite \u00fcberfl\u00fcssig. Wenn nicht?! Gibt es viele Programme im Netz, mit der gleichen oder sogar besseren Funktion. Ich muss hier nichts beweisen! Wichtig ist mir, dass jeder Nutzer direkt das Programm einrichten und loslegen kann.<\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":52884,"parent":52834,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-08-10T15:29:59","cld_nonce":"82f011626f","content":{"rendered":"<p>Zus\u00e4tzliche Infos schaden aber auch nicht&#8230; Gru\u00df, Herr Hugo<\/p>\n"},"status":"1"},{"id":52936,"parent":52884,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-11T11:00:12","cld_nonce":"82f011626f","content":{"rendered":"<p>Ja, das stimmt.<\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":52962,"parent":52884,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-11T15:23:09","cld_nonce":"82f011626f","content":{"rendered":"<p>Gerne k\u00f6nnen wir uns unter https.\/\/www.js-tools.de\/support.htm austauschen.<\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":52963,"parent":0,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-11T15:24:42","cld_nonce":"82f011626f","content":{"rendered":"<p><a href=\"https:\/\/www.js-tools.de\/support.htm\" rel=\"nofollow ugc\">https:\/\/www.js-tools.de\/support.htm<\/a><\/p>\n"},"status":"1"},{"id":53008,"parent":52349,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-12T00:08:29","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo deine letzten Satz verstehe ich nicht. Was ich eigentlich sagen will, dass ich mir ein Zertifikat erstellen lassen habe. Dies und das ist wichtig, zeigt Dir, dass die Software wirklich von mir stammt und nach der Ver\u00f6ffentlichung nicht ge\u00e4ndert wurde. Oder gibt es eine andere M\u00f6glichkeit? Vielleicht kostenlos? \u00dcber deine Antwort w\u00fcrde ich mich sehr freuen! Mir ist nicht ganz klar warum Windows noch blockt, habe Geld f\u00fcr die Zertifizierung ausgegeben und das Zertifikat erfolgreich in alle EXE-Dateien auf meiner Homepage eingebunden. Der ganze Mist mit den Zertifikaten geht mir sowas von auf den Sender. LG<\/p>\n"},"status":"1"},{"id":53023,"parent":53008,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-08-12T08:17:20","cld_nonce":"82f011626f","content":{"rendered":"<p>Das mit den Zertifikaten ist schon korrekt. Warum Windows in der Insider nun erst noch diesen Warnhinweis vorschaltet, um es auszuf\u00fchren bin ich \u00fcberfragt. Aber das d\u00fcrfte am dort schon eingebauten Exploitschutz liegen. Siehe<br \/>\n<a href=\"https:\/\/www.deskmodder.de\/blog\/2017\/06\/30\/exploitschutz-unter-windows-10-emet-einmal-angeschaut\/\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2017\/06\/30\/exploitschutz-unter-windows-10-emet-einmal-angeschaut\/<\/a><\/p>\n"},"status":"1"},{"id":53600,"parent":0,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-08-19T17:15:58","cld_nonce":"82f011626f","content":{"rendered":"<p>Inzwischen als 6.4 erschienen. Sogar mit einer Changelog.  Super. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n<p>Die Aktualisierung der Ordnerstruktur um 90% beschleunigt.<br \/>\nBez\u00fcglich der Geschwindigkeit, einige weitere Optimierungen durchgef\u00fchrt.<br \/>\nVerlauf hinzugef\u00fcgt.<\/p>\n<p><i>Hat die Unterhaltung hier scheinbar etwas gebracht?<\/i><\/p>\n"},"status":"1"},{"id":53651,"parent":53600,"author":0,"author_name":"Joachim","author_email":"achim3868@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fa06e1adc959c0141d3688d1d85b9674a380aca65c8ea76e07be1b20af7550c5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fa06e1adc959c0141d3688d1d85b9674a380aca65c8ea76e07be1b20af7550c5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fa06e1adc959c0141d3688d1d85b9674a380aca65c8ea76e07be1b20af7550c5?s=96&d=mm&r=g"},"date":"2017-08-21T09:30:17","cld_nonce":"82f011626f","content":{"rendered":"<p>Ja, hat sie wohl <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53652,"parent":53651,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-08-21T10:45:19","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo Joachim,<br \/>\nbietet sich das Programm auch f\u00fcr Datentr\u00e4ger an , die z.B. am Router angeschlossen sind  (NAS) ? Habe zwar schon ein Programm aber man sollte ja flexibel sein und auch mal was neues testen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53667,"parent":53652,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-21T15:12:48","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo Manny,<\/p>\n<p>Danke f\u00fcr deine Anfrage.<\/p>\n<p>Befinden sich die Daten auf einem Laufwerk (Netzwerk, USB etc.) kein Problem f\u00fcr CopyMe. Auf Internet- bzw. Netzwerkadressen ( http:\/\/ &#8230; , 192.168.1.1, etc.) kann CopyMe nicht zugreifen. Es muss immer ein Laufwerk definiert worden sein, damit CopyMe arbeitet kann.<\/p>\n"},"status":"1"},{"id":53668,"parent":0,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-08-21T15:17:56","cld_nonce":"82f011626f","content":{"rendered":"<p>@Joachim<\/p>\n<p>Danke f\u00fcr die Info &#8211; denke das ich dann ja auf die Platte(n) zugreifen kann, habe beide als Netzwerkverbindung im Dateiexplorer eingebunden und werde das dann mal testen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53669,"parent":0,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-21T15:19:27","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo zusammen,<\/p>\n<p>ich habe eine neue Version 6.6 Online gestellt, da ich viele \u00c4nderungen am Quellcode durchgef\u00fchrt habe. Die letzten Tests (3 Tage) konnte ich ohne Fehler abschlie\u00dfen.<\/p>\n<p>Version 6.6 &#8211; 21.08.2017<br \/>\nBez\u00fcglich der Geschwindigkeit, einige weitere Optimierungen durchgef\u00fchrt.<\/p>\n<p>&#8222;Bericht nach Auftragsende immer anzeigen&#8220; unter Optionen hinzugef\u00fcgt.<\/p>\n<p>&#8222;Skins&#8220; im Men\u00fc Extras hinzugef\u00fcgt.<\/p>\n<p>Sprachauswahl weiter angepasst.<\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":53670,"parent":53669,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-08-21T15:32:32","cld_nonce":"82f011626f","content":{"rendered":"<p>Danke Joachim.<br \/>\nIch hab es oben einmal aktualisiert. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n<p>Gut dass du da jetzt eine Changelog hinzugef\u00fcgt hast. Ist doch besser, f\u00fcr diejenigen, die sich f\u00fcr das Programm interessieren<\/p>\n"},"status":"1"},{"id":53671,"parent":0,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-21T15:45:15","cld_nonce":"82f011626f","content":{"rendered":"<p>Wie ist eigentlich den Vorname? Meinen kennst Du ja auch.<\/p>\n<p>Vielen Dank f\u00fcr deine Infos.<\/p>\n<p>Zum Programm:<br \/>\nIch m\u00f6chte Dich darum bitten, in der ersten Programmbeschreibung (ganz oben im Thread) die M\u00f6glichkeit zu er\u00f6rtern,  dass CopyMe die Sprache DE und EN unterst\u00fctzt. <\/p>\n<p>Vielen Dank <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53672,"parent":53669,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-08-21T15:48:03","cld_nonce":"82f011626f","content":{"rendered":"<p><img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/> Funktioniert ( auch bei NAS) angeschlossenen Datentr\u00e4gern &#8211; ca. 6 Minuten ~ 7,81 GB (USB 2 Router allerdings nur )<\/p>\n"},"status":"1"},{"id":53673,"parent":53671,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-08-21T15:48:35","cld_nonce":"82f011626f","content":{"rendered":"<p>Hab ich, (J\u00fcrgen) erg\u00e4nzt. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53674,"parent":53672,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-21T15:50:20","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo Manny,<\/p>\n<p>vielen Dank f\u00fcr die Info. Das freut mich sehr <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":53675,"parent":53673,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-21T15:54:14","cld_nonce":"82f011626f","content":{"rendered":"<p>THX J\u00fcrgen<\/p>\n"},"status":"1"},{"id":53676,"parent":53674,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-08-21T16:01:39","cld_nonce":"82f011626f","content":{"rendered":"<p>Kein Thema <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><br \/>\nich habe jetzt erst die portable Version getestet, ich vermute mal das man wenn man die Skins benutzen m\u00f6chte, die Installationsvariante nehmen muss ?<\/p>\n<p>Nachtrag kein Men\u00fceintrag Skins bei Extras vorhanden<\/p>\n"},"status":"1"},{"id":53677,"parent":53676,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-21T16:13:50","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo Manny,<\/p>\n<p>die Einstellung des Skins, sollte auch bei der Portable-Version funktionieren.<\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":53678,"parent":0,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-08-21T16:15:52","cld_nonce":"82f011626f","content":{"rendered":"<p>Nachtrag zu den Skins &#8211; jetzt Men\u00fceintrag vorhanden &#8211; man sollte auch ab und zu mal die Webseite aktualisieren <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53679,"parent":53678,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-21T16:21:37","cld_nonce":"82f011626f","content":{"rendered":"<p>Da ich meine Arbeit schon seit 1994 den Nutzern kostenlos, so aktuell wie m\u00f6glich, zur Verf\u00fcgung stelle, halte ich dein jetziges Anliegen f\u00fcr nicht vakant! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":53680,"parent":53679,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-08-21T16:26:40","cld_nonce":"82f011626f","content":{"rendered":"<p>ich meinte damit ICH habe die Downloadseite von dir nicht aktualisiert gehabt, hatte statt der Version 6.6 die 6.4 noch runtergeladen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53681,"parent":53679,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-21T16:26:54","cld_nonce":"82f011626f","content":{"rendered":"<p>Werde die Screenshots aktulasieren ,,,<\/p>\n"},"status":"1"},{"id":53682,"parent":53680,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-21T16:37:32","cld_nonce":"82f011626f","content":{"rendered":"<p>Die \u00dcbernahme der \u00c4nderung an meiner Seite kann manchmal etwas dauern. Bitte immer 10 Minuten warten, danach ist die Aktualisierung komplett. Im Browser bei meiner Seite schon mal F5 dr\u00fccken.<\/p>\n<p>Vielen Dank!<\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":53683,"parent":0,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-08-21T16:49:43","cld_nonce":"82f011626f","content":{"rendered":"<p>L\u00e4uft einwandfrei, 9 Minuten ~11,5 GB zum USB 2 Port am Router noch mal nachtrage <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53687,"parent":53683,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-21T19:46:49","cld_nonce":"82f011626f","content":{"rendered":"<p>9 Minuten f\u00fcr 11,5 GB finde ich voll in Ordnung.<\/p>\n"},"status":"1"},{"id":53693,"parent":0,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-08-22T00:52:58","cld_nonce":"82f011626f","content":{"rendered":"<p>Denke ich auch, kommt ja auch auf die Art der Daten an die man kopiert, in den letztem Fall waren das Image-Files meiner Systemplatte die ich ja zus\u00e4tzlich zur Festplatte noch auf die Routerplatte sichere <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53710,"parent":53669,"author":0,"author_name":"Sandro","author_email":"s.chudowski@posteo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dcaf690d51279f2b3d8351be4101b3816cf8f060ead23dc18f04f6e7550705a6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dcaf690d51279f2b3d8351be4101b3816cf8f060ead23dc18f04f6e7550705a6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dcaf690d51279f2b3d8351be4101b3816cf8f060ead23dc18f04f6e7550705a6?s=96&d=mm&r=g"},"date":"2017-08-22T12:54:14","cld_nonce":"82f011626f","content":{"rendered":"<p>Hab die Unterhaltung am Rande mit verfolgt. Was w\u00fcrde sich denn f\u00fcr einen Datenabgleich \/ Sicherung mit OneDrive eignen? Daf\u00fcr suche ich etwas. Zur Zeit mache ich das immer noch alles manuell. Wollte das f\u00fcr meine Partnerin einrichten, dass dies automatisiert vorgenommen wird, also von ihrem Laptop auf ihr OneDrive. Vielleicht hat jemand einen Tipp?<\/p>\n"},"status":"1"},{"id":53791,"parent":53710,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-23T23:25:27","cld_nonce":"82f011626f","content":{"rendered":"<p>Da ich mit OneDrive nicht arbeite, bin ich auf deine Hilfe angewiesen. Solange Du als Quelle und Ziel einen Ordner angeben kannst m\u00fcsste alles laufen. Ich bitte um R\u00fcckinfo <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":53943,"parent":0,"author":0,"author_name":"petershaw","author_email":"14super07@turboprinzessin.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/796b2ccd5606d2904a8f3369101d077f1bdf59870ebb5d9d0d0a44fc5def4f25?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/796b2ccd5606d2904a8f3369101d077f1bdf59870ebb5d9d0d0a44fc5def4f25?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/796b2ccd5606d2904a8f3369101d077f1bdf59870ebb5d9d0d0a44fc5def4f25?s=96&d=mm&r=g"},"date":"2017-08-26T13:09:45","cld_nonce":"82f011626f","content":{"rendered":"<p>Kopieren auf einen an der Fritzbox 7490 angeschlossenen 16GB USB Stick funktioniert nicht.<br \/>\nDer USB Stick ist leer (FAT32). Die Daten sind nur Textdateien mit einer Gesamtgr\u00f6\u00dfe von nur 837MB.<\/p>\n<p><a href=\"http:\/\/imgur.com\/a\/SXKSJ\" rel=\"nofollow ugc\">http:\/\/imgur.com\/a\/SXKSJ<\/a><\/p>\n"},"status":"1"},{"id":53950,"parent":53943,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-08-26T16:52:43","cld_nonce":"82f011626f","content":{"rendered":"<p>Enth\u00e4lt der Auftrag Dateien die gr\u00f6\u00dfer sind wie 4GB, was sagt der Auftrags-bericht?<\/p>\n"},"status":"1"},{"id":54059,"parent":53791,"author":0,"author_name":"Sandro","author_email":"s.chudowski@posteo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dcaf690d51279f2b3d8351be4101b3816cf8f060ead23dc18f04f6e7550705a6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dcaf690d51279f2b3d8351be4101b3816cf8f060ead23dc18f04f6e7550705a6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dcaf690d51279f2b3d8351be4101b3816cf8f060ead23dc18f04f6e7550705a6?s=96&d=mm&r=g"},"date":"2017-08-29T15:51:36","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo Joachim,<br \/>\nwollte dir mal eine kleine R\u00fcckmeldung bez\u00fcglich &#8218;OneDrive&#8216; geben. Ich habe mal ein, zwei kleine Tests gemacht und soweit funktionierte alles, allerdings sind dabei noch keine \u00c4nderungen Quellverzeichnis zum Zielverzeichnis enthalten gewesen. Denke aber, dass sollte kein Problem sein. Ggf. \u00c4nderungen an Ordnernamen, etc. werden doch sicherlich ber\u00fccksichtigt, auch wenn ein Ordner im Quellverzeichnis z. B. gel\u00f6scht wurde? Das konnte ich leider noch nicht testen. Eine andere kleine Frage h\u00e4tte ich: W\u00e4re es m\u00f6glich, z. B. im Dokumenteverzeichnis einen Zielordner neu erstellen zu lassen, also das eine quasi 1:1 Kopie im Zielverzeichnis erstellt wird? Ich hatte das vorhin probiert und es war erforderlich, dass ich in einen vorhandenen bzw. einen zuvor neu erstellten Ordner kopiere. Das \u00dcbernehmen des Ordnernamens vom Quellordner w\u00fcrde einiges erleichtern. Vielleicht liegt auch ein Bedienfehler meinerseits vor  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":58554,"parent":0,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-10-22T00:32:40","cld_nonce":"82f011626f","content":{"rendered":"<p>Habe jetzt gerade die Version 7.4 aktualisiert.<br \/>\nhttps:\\\\www.js-tools.de\/copyme.htm<\/p>\n<p>Viel Spass damit.<\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":58555,"parent":58554,"author":0,"author_name":"Joachim","author_email":"joachim-68@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=96&d=mm&r=g"},"date":"2017-10-22T01:35:21","cld_nonce":"82f011626f","content":{"rendered":"<p>Nat\u00fcrlich: https:\\\\www.js-tools.de\\copyme.htm<\/p>\n"},"status":"1"},{"id":59318,"parent":0,"author":0,"author_name":"Joachim","author_email":"joachim-68@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=96&d=mm&r=g"},"date":"2017-11-05T01:45:15","cld_nonce":"82f011626f","content":{"rendered":"<p>Es gibt mittlerweile Version 7.6<\/p>\n<p><a href=\"https:\/\/www.js-tools.de\/copyme.htm\" rel=\"nofollow ugc\">https:\/\/www.js-tools.de\/copyme.htm<\/a><br \/>\n<a href=\"https:\/\/www.js-tools.de\/copyme\/copyme-setup.exe\" rel=\"nofollow ugc\">https:\/\/www.js-tools.de\/copyme\/copyme-setup.exe<\/a><\/p>\n<p>Es hat sich viel getan <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":59323,"parent":59318,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-11-05T08:04:24","cld_nonce":"82f011626f","content":{"rendered":"<p>Bist aber auch immer fleissig am \u00fcberarbeiten. Super <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":59331,"parent":59318,"author":0,"author_name":"fehlersucher","author_email":"forenantwort@arcor.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f4659d0cadab9dfec597cab492a17e1c18b730c858aa560e067fc27c67d81236?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f4659d0cadab9dfec597cab492a17e1c18b730c858aa560e067fc27c67d81236?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f4659d0cadab9dfec597cab492a17e1c18b730c858aa560e067fc27c67d81236?s=96&d=mm&r=g"},"date":"2017-11-05T12:02:58","cld_nonce":"82f011626f","content":{"rendered":"<p>wo ist der denkfehler?<br \/>\nein ordner programme soll von der ssd mit dem auf<br \/>\ndem usb-stick angelegten ordner programme<br \/>\nabgearbeitet werden.<br \/>\nes gibt aber nur die m\u00f6glichkeit dies in einen ordner (nicht root) zu erstellen.<br \/>\nsomit kann vorhandenes nicht gemacht werden?<br \/>\nau\u00dferdem kommt 2x die abfrage beim auftrag anlegen!<\/p>\n"},"status":"1"},{"id":59359,"parent":59331,"author":0,"author_name":"Joachim","author_email":"joachim-68@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=96&d=mm&r=g"},"date":"2017-11-06T11:31:46","cld_nonce":"82f011626f","content":{"rendered":"<p>Danke fehlersucher <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/> Ich habe eine neue Version hochgeladen, wo als &#8222;Zielordner&#8220; auch ein Laufwerk angegeben werden kann.<\/p>\n<p>Tipp:<br \/>\nAuftragsdatei im Zielordner speichern und als Ziel zuvor &#8222;Ordner der CBPX-Datei&#8220; ausw\u00e4hlen. So funktioniert auch noch alles, selbst wenn sich der Laufwerksbuchstabe des Ziels \u00e4ndert.<\/p>\n<p>au\u00dferdem kommt 2x die abfrage beim auftrag anlegen! Wie lautet der Text der Abfrage?<\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":59360,"parent":0,"author":0,"author_name":"fehlersucher","author_email":"forenantwort@arcor.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f4659d0cadab9dfec597cab492a17e1c18b730c858aa560e067fc27c67d81236?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f4659d0cadab9dfec597cab492a17e1c18b730c858aa560e067fc27c67d81236?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f4659d0cadab9dfec597cab492a17e1c18b730c858aa560e067fc27c67d81236?s=96&d=mm&r=g"},"date":"2017-11-06T12:23:17","cld_nonce":"82f011626f","content":{"rendered":"<p>es ist das &#8222;speichern unter&#8220; fenster<br \/>\nhab aber vermutlich auch hier ein zuweisungsproblem<br \/>\nwenn der auftragsname (programme) der gleiche name wie das verzeichnis ist,<br \/>\nwird das verzeichnis ausgew\u00e4hlt<br \/>\n(dann kommt nochmal das fenster) und es wird darin der auftrag gespeichert.<br \/>\nwenn der name gek\u00fcrtzt (prog) wurde bleibt das auf dem root verzeichnis und es kommt nur 1x das fenster.<\/p>\n"},"status":"1"},{"id":59361,"parent":59360,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-11-06T13:22:06","cld_nonce":"82f011626f","content":{"rendered":"<p>Danke f\u00fcr deine Hinweise <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n<p>CopyMe nutzt den \u00d6ffnen- und Speicherndialog von Windows. Windows, Office und alle Programmen, die diesen Dialog nutzen, verhalten sich genau so.<\/p>\n<p>Hier kann ich leider nichts machen.<\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":59362,"parent":59360,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-11-06T15:10:18","cld_nonce":"82f011626f","content":{"rendered":"<p>Konntest Du dein Vorhaben &#8222;Programme&#8220; jetzt umsetzen?<\/p>\n"},"status":"1"},{"id":59363,"parent":59323,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-11-06T15:24:54","cld_nonce":"82f011626f","content":{"rendered":"<p>moinmoin, ja das Programm l\u00e4sst mich nicht in Ruhe <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":59366,"parent":0,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-11-06T17:23:45","cld_nonce":"82f011626f","content":{"rendered":"<p>Sooo, ich hab das jetzt in etwa so wie ich mir das vorstelle:<\/p>\n<p>F\u00fcr JEDE Platte \/ Aktualisierung eine Datei, (hochgeladen in meine Cloud zur sp\u00e4teren Verwendung)- Verkn\u00fcpfung jeder einzelnen &#8222;T\u00e4tigkeit&#8220; auf dem Desktop \/ Startmen\u00fc ( *.cbx Dateien nat\u00fcrlich mit CopyMe verkn\u00fcpfen) &#8211; nun kann ich nach und nach alles auf den Router sichern <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":59370,"parent":59366,"author":0,"author_name":"Joachim","author_email":"joachim-68@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8ad81394d51cf2cb6ca82c9addd4035cbb09bf0254590d92d5e1dab5e262ff72?s=96&d=mm&r=g"},"date":"2017-11-06T17:52:43","cld_nonce":"82f011626f","content":{"rendered":"<p>Darf ich sagen, es klappt alles bei Dir mit CopyMe?!<\/p>\n"},"status":"1"},{"id":59372,"parent":59370,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-11-06T18:12:33","cld_nonce":"82f011626f","content":{"rendered":"<p>Ja kann man so sagen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/> hatte zwar auch mal Probs auf angeschlossenes Ger\u00e4t was zu kopieren, aber das lag an der Freigabe im Router ( wenn man nicht gerade alle am Router angeschlossenen Ger\u00e4te f\u00fcr das Konto freigibt sondern nur einzelne Verzeichnisse dann kann CopyMe auch nicht auf ein Ger\u00e4t speichern ( auch wenn das leer ist)<\/p>\n"},"status":"1"},{"id":59374,"parent":59372,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-11-06T18:50:39","cld_nonce":"82f011626f","content":{"rendered":"<p>CopyMe arbeitet mit Freigaben von Windows. Wenn in diesem Fall Fehler auftreten liegt es nicht an CopyMe.<br \/>\nLeider ist es mir nicht m\u00f6glich bei CopyMe jegliche Systemkonfiguration abzufangen. Bitte habt Verst\u00e4ndnis daf\u00fcr!<\/p>\n<p>&#8222;sondern nur einzelne Verzeichnisse dann kann CopyMe auch nicht auf ein Ger\u00e4t speichern ( auch wenn das leer ist)&#8220;<br \/>\nDas verstehe ich nicht ganz, kannst Du das genauer darlegen?<\/p>\n<p>&#8222;Kann man so sagen&#8220; reicht mir <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n<p>Gru\u00df<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":59375,"parent":0,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-11-06T18:57:41","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich freue mich \u00fcber jeden Hinweis, aber es geht halt nicht alles, Sorry!<\/p>\n"},"status":"1"},{"id":59376,"parent":0,"author":0,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2017-11-06T18:59:02","cld_nonce":"82f011626f","content":{"rendered":"<p>@Joachim<br \/>\nEs gibt die M\u00f6glichkeit im Router (bei AVM Fritzbox jeden Falls) wenn man dort mehrere Benutzer einrichtet ( z.B. wer worauf auf welche Platte \/ Verzeichniss  Zugriff haben soll anlegt &#8211; wenn man dann aber (z.B. neue Platte oder Verzeichnisse (noch) nicht in den Zugriffsregeln hat dann bekommt man z.B. so eine Fehlermeldung wie z.B.<br \/>\npetershaw  26. August 2017 um 13:09 Uhr<br \/>\nKopieren auf einen an der Fritzbox 7490 angeschlossenen 16GB USB Stick funktioniert nicht.<br \/>\nDer USB Stick ist leer (FAT32). Die Daten sind nur Textdateien mit einer Gesamtgr\u00f6\u00dfe von nur 837MB.<br \/>\nbeschrieben hat<\/p>\n"},"status":"1"},{"id":59377,"parent":59376,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-11-06T19:56:49","cld_nonce":"82f011626f","content":{"rendered":"<p>Habe zum Gl\u00fcck auch eine Fritzbox! Ich schau mal was ich machen kann.<br \/>\nDanke f\u00fcr deine Hinweise.<\/p>\n<p>Liebe Gr\u00fc\u00dfe<br \/>\nJoachim<\/p>\n"},"status":"1"},{"id":59387,"parent":59362,"author":0,"author_name":"fehlersucher","author_email":"forenantwort@arcor.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f4659d0cadab9dfec597cab492a17e1c18b730c858aa560e067fc27c67d81236?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f4659d0cadab9dfec597cab492a17e1c18b730c858aa560e067fc27c67d81236?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f4659d0cadab9dfec597cab492a17e1c18b730c858aa560e067fc27c67d81236?s=96&d=mm&r=g"},"date":"2017-11-07T13:54:53","cld_nonce":"82f011626f","content":{"rendered":"<p>noch am testen<br \/>\n\u00fcbertragungs-\/vergleichsgeschwindigkei ist auf usb3 stick<br \/>\noder hd sehr niedrig!<br \/>\n(245-300kb\/s anstatt m\u00f6glicher 65-95mb\/s)<br \/>\nauch einige dateien werden scheinbar nicht erkannt?<br \/>\n(gesperrte oder nicht vorhandene dateien!)<\/p>\n<p>ist es richtig das die vergleichsliste nicht gespeichert wird?<br \/>\njedesmal ein durchlauf mit \u00fcber 34000 dateien,<br \/>\num davon 1000-3000 zu setzen,<br \/>\ndauert dadurch ernorm lange.<\/p>\n"},"status":"1"},{"id":59389,"parent":59377,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-11-07T14:11:18","cld_nonce":"82f011626f","content":{"rendered":"<p>Bei so vielen Fragen w\u00e4re es vielleicht gar nicht mal so schlecht einen eigenen Forenbereich bei uns einzurichten.  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":59424,"parent":59389,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-11-08T14:02:54","cld_nonce":"82f011626f","content":{"rendered":"<p>Gemacht:<br \/>\n<a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewtopic.php?f=291&#038;t=19663\" rel=\"ugc\">https:\/\/www.deskmodder.de\/phpBB3\/viewtopic.php?f=291&#038;t=19663<\/a><\/p>\n"},"status":"1"},{"id":59447,"parent":59376,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-11-09T00:34:45","cld_nonce":"82f011626f","content":{"rendered":"<p><a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewtopic.php?f=291&#038;t=19663&#038;p=303699#p303699\" rel=\"ugc\">https:\/\/www.deskmodder.de\/phpBB3\/viewtopic.php?f=291&#038;t=19663&#038;p=303699#p303699<\/a><\/p>\n"},"status":"1"},{"id":59448,"parent":59387,"author":0,"author_name":"Joachim","author_email":"support@js-tools.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1d6394212e745839ab7c876442f5062ef5a9efb564b55c81a2d4bf280fc11b8?s=96&d=mm&r=g"},"date":"2017-11-09T00:35:16","cld_nonce":"82f011626f","content":{"rendered":"<p><a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewtopic.php?f=291&#038;t=19663&#038;p=303699#p303699\" rel=\"ugc\">https:\/\/www.deskmodder.de\/phpBB3\/viewtopic.php?f=291&#038;t=19663&#038;p=303699#p303699<\/a><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CopyMe 6.6 erschienen - Dateien und Ordner synchron halten - Deskmodder.de<\/title>\n<meta name=\"description\" content=\"CopyMe - Dateien und Ordner immer synchronisieren mit dem portablen Tool.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CopyMe 6.6 erschienen - Dateien und Ordner synchron halten\" \/>\n<meta property=\"og:description\" content=\"CopyMe - Dateien und Ordner immer synchronisieren mit dem portablen Tool.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-21T13:30:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-14T16:09:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"591\" \/>\n\t<meta property=\"og:image:height\" content=\"374\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"CopyMe 6.6 erschienen &#8211; Dateien und Ordner synchron halten\",\"datePublished\":\"2017-08-21T13:30:33+00:00\",\"dateModified\":\"2023-01-14T16:09:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/\"},\"wordCount\":271,\"commentCount\":61,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg\",\"keywords\":[\"CopyMe\",\"Daten synchronisieren\",\"inkrementell\"],\"articleSection\":[\"Software &amp; Updates\",\"Windows 10\",\"Windows \u00e4lter\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/\",\"name\":\"CopyMe 6.6 erschienen - Dateien und Ordner synchron halten - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg\",\"datePublished\":\"2017-08-21T13:30:33+00:00\",\"dateModified\":\"2023-01-14T16:09:36+00:00\",\"description\":\"CopyMe - Dateien und Ordner immer synchronisieren mit dem portablen Tool.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg\",\"width\":591,\"height\":374},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/08\\\/21\\\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CopyMe 6.6 erschienen &#8211; Dateien und Ordner synchron halten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CopyMe 6.6 erschienen - Dateien und Ordner synchron halten - Deskmodder.de","description":"CopyMe - Dateien und Ordner immer synchronisieren mit dem portablen Tool.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/","og_locale":"de_DE","og_type":"article","og_title":"CopyMe 6.6 erschienen - Dateien und Ordner synchron halten","og_description":"CopyMe - Dateien und Ordner immer synchronisieren mit dem portablen Tool.","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-08-21T13:30:33+00:00","article_modified_time":"2023-01-14T16:09:36+00:00","og_image":[{"width":591,"height":374,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"CopyMe 6.6 erschienen &#8211; Dateien und Ordner synchron halten","datePublished":"2017-08-21T13:30:33+00:00","dateModified":"2023-01-14T16:09:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/"},"wordCount":271,"commentCount":61,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg","keywords":["CopyMe","Daten synchronisieren","inkrementell"],"articleSection":["Software &amp; Updates","Windows 10","Windows \u00e4lter"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/","name":"CopyMe 6.6 erschienen - Dateien und Ordner synchron halten - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg","datePublished":"2017-08-21T13:30:33+00:00","dateModified":"2023-01-14T16:09:36+00:00","description":"CopyMe - Dateien und Ordner immer synchronisieren mit dem portablen Tool.","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg","width":591,"height":374},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/08\/21\/copyme-6-0-erschienen-dateien-und-ordner-synchron-halten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"CopyMe 6.6 erschienen &#8211; Dateien und Ordner synchron halten"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/08\/copyme-dateien-ordner-schnell-synchronisieren-001.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/89138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=89138"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/89138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/89139"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=89138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=89138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=89138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}