{"id":88395,"date":"2017-07-22T13:33:40","date_gmt":"2017-07-22T11:33:40","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=88395"},"modified":"2017-07-23T18:58:36","modified_gmt":"2017-07-23T16:58:36","slug":"waehrungsrechner-nun-in-der-rechner-app-windows-10","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/","title":{"rendered":"W\u00e4hrungsrechner nun in der Rechner App Windows 10"},"content":{"rendered":"<p>Die Rechner App in der Windows 10 hat schon einige Konverter integriert. Damit kann man die Temperatur, L\u00e4nge, Zeit oder Geschwindigkeit umrechnen lassen. In der aktuellen Version 10.1706.1862.0 ist nun eine neue sehr interessante Funktion hinzugekommen. Denn man kann nun auch W\u00e4hrungen zum Beispiel von Euro in Dollar umrechnen lassen.<\/p>\n<p>Damit erspart man sich nun endlich eine zus\u00e4tzliche App. Ben\u00f6tigt wird f\u00fcr diese Funktion aber eine Internetverbindung. Denn die Kurse werden automatisch aktualisiert. Dies steht dann immer unten links. Will man auf Nummer sicher gehen, kann es auch selbst aktualisieren.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg\" rel=\"lightbox[88395]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-500x294.jpg\" alt=\"\" width=\"500\" height=\"294\" class=\"aligncenter size-medium wp-image-88396\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-500x294.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-306x180.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-810x477.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg 1197w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Die Auswahlliste der einzelnen W\u00e4hrungen ist sehr lang. Von A wie Afghanistan (Afghani) bis V wie Vietnam (Dong) ist alles soweit vertreten. Also schaut in eurem Downloadverlauf nach, ob die App schon aktualisiert wurde. Die Insider hatten ja schon das Vergn\u00fcgen seit dem 13.Juli oder sogar etwas l\u00e4nger.<\/p>\n<p><!-- WP-Appbox (Version: 4.5.13 \/\/ Store: microsoftstore \/\/ ID: 9wzdncrfhvn5) -->\n<div class=\"wpappbox wpappbox-b837d77a72604a95af130bf29f849214 microsoftstore simple\">\n\t<div class=\"qrcode\"><img decoding=\"async\" src=\"https:\/\/api.qrserver.com\/v1\/create-qr-code\/?data=https%3A%2F%2Fwww.microsoft.com%2Fde-de%2Fstore%2Fp%2Fapp%2F9wzdncrfhvn5&size=200x200&ecc=M&margin=0\" alt=\"Windows-Rechner\" \/><\/div>\n\t<div class=\"appicon\">\n\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/app\/9wzdncrfhvn5\" aria-label=\"Windows-Rechner\"><img decoding=\"async\" src=\"\/\/store-images.s-microsoft.com\/image\/apps.37096.9007199266248474.3e19ef49-2bad-44f6-86d7-514e0eff139c.5a967995-5d68-4de6-92c2-0cec8f3155dd?w=180&#038;h=180&#038;q=60\" alt=\"Windows-Rechner\" \/><\/a>\n\t<\/div>\n\t<div class=\"applinks\">\n\t\t<div class=\"appbuttons\">\n\t\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/app\/9wzdncrfhvn5\" aria-label=\"Windows-Rechner\">Download<\/a>\n\t\t\t<span onMouseOver=\"jQuery('.wpappbox-b837d77a72604a95af130bf29f849214 .qrcode').show();\" onMouseOut=\"jQuery('.wpappbox-b837d77a72604a95af130bf29f849214 .qrcode').hide();\">QR-Code<\/span>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"appdetails\">\n\t\t<div class=\"apptitle\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/app\/9wzdncrfhvn5\" title=\"Windows-Rechner\" aria-label=\"Windows-Rechner\" class=\"apptitle\">Windows-Rechner<\/a><\/div>\n\t\t<div class=\"developer\">\n\t\t\t<span class=\"label\">Entwickler: <\/span>\n\t\t\t<span class=\"value\">Microsoft Corporation<\/span>\n\t\t<\/div>\n\t\t<div class=\"price\">\n\t\t\t<span class=\"label\">Preis: <\/span>\n\t\t\t<span class=\"value\">Kostenlos<\/span> \n\t\t\t<span class=\"rating\"><div title=\"4 von 5 Sternen\" class=\"rating-stars stars-monochrome stars40\"><\/div><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div><!-- \/WP-Appbox --><br \/>\n<div class=\"viaquelle\">via: <a href=\"https:\/\/thewincentral.com\/windows-10-calculator-app-currency-converter\/\" target=\"_blank\">wincentral<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Rechner App in der Windows 10 hat schon einige Konverter integriert. Damit kann man die Temperatur, L\u00e4nge, Zeit oder Geschwindigkeit umrechnen lassen. In der aktuellen Version 10.1706.1862.0 ist nun eine neue sehr interessante Funktion hinzugekommen. Denn man kann nun&hellip; <\/p>\n","protected":false},"author":134,"featured_media":88396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689,3031],"tags":[13890,10096,18103,9751],"class_list":["post-88395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","category-windows-apps","tag-konverter","tag-rechner-app","tag-waehrung-umrechnen","tag-windows-10"],"wp_featured_image":{"id":88396,"alt_text":"","description":"","media_type":"image","media_details":{"width":1197,"height":705,"file":"2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg","sizes":{"thumbnail":{"file":"waehrungsrechner-in-der-rechner-app-windows-10-306x180.jpg","width":306,"height":180,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-306x180.jpg"},"medium":{"file":"waehrungsrechner-in-der-rechner-app-windows-10-500x294.jpg","width":500,"height":294,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-500x294.jpg"},"large":{"file":"waehrungsrechner-in-der-rechner-app-windows-10-810x477.jpg","width":810,"height":477,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-810x477.jpg"},"wp_review_large":{"file":"waehrungsrechner-in-der-rechner-app-windows-10-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-320x200.jpg"},"wp_review_small":{"file":"waehrungsrechner-in-der-rechner-app-windows-10-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-65x65.jpg"},"blog-large":{"file":"waehrungsrechner-in-der-rechner-app-windows-10-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-642x300.jpg"},"blog-medium":{"file":"waehrungsrechner-in-der-rechner-app-windows-10-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-306x205.jpg"},"recent-thumb":{"file":"waehrungsrechner-in-der-rechner-app-windows-10-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-350x316.jpg"},"service-featured":{"file":"waehrungsrechner-in-der-rechner-app-windows-10-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-600x330.jpg"},"wp_rp_thumbnail":{"file":"waehrungsrechner-in-der-rechner-app-windows-10-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":88395,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg"},"commentcount":7,"wp_comments":[{"id":51384,"parent":0,"author":0,"author_name":"Christian Koch","author_email":"christiankoch001@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bf097c741719d1efc35ca273c7841e2e3add1908741ef38c0371f7ac5bf3a70e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bf097c741719d1efc35ca273c7841e2e3add1908741ef38c0371f7ac5bf3a70e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bf097c741719d1efc35ca273c7841e2e3add1908741ef38c0371f7ac5bf3a70e?s=96&d=mm&r=g"},"date":"2017-07-22T16:59:56","cld_nonce":"82f011626f","content":{"rendered":"<p>Dueses Feature habe ich 2015 im Feedback Hub vorgeschlagen. Freut mich, dass man nun umsetzt &#8211; ob es nun an meinem Feedback gelegen hat oder nicht <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":51385,"parent":0,"author":3730,"author_name":"slevin007","author_email":"sketchyskate@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1bff0051fa0778daee45c5c266ae6e091330d2ebc9c99256765c311c0f1802a4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1bff0051fa0778daee45c5c266ae6e091330d2ebc9c99256765c311c0f1802a4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1bff0051fa0778daee45c5c266ae6e091330d2ebc9c99256765c311c0f1802a4?s=96&d=mm&r=g"},"date":"2017-07-22T17:10:33","cld_nonce":"82f011626f","content":{"rendered":"<p>Habe die Funktion seit Monaten schon<\/p>\n"},"status":"1"},{"id":51391,"parent":0,"author":0,"author_name":"Morku","author_email":"morku@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b1e989f7fab964d7606f572b6fb989a15421cd1b5b0e224d196271e038634940?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b1e989f7fab964d7606f572b6fb989a15421cd1b5b0e224d196271e038634940?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b1e989f7fab964d7606f572b6fb989a15421cd1b5b0e224d196271e038634940?s=96&d=mm&r=g"},"date":"2017-07-22T22:29:50","cld_nonce":"82f011626f","content":{"rendered":"<p>Kam schon vor Wochen mit dem letzten Update rein.<br \/>\nDie Frage ist nur: Wo bleibt es f\u00fcr W10m?<\/p>\n"},"status":"1"},{"id":51403,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-07-23T11:09:07","cld_nonce":"82f011626f","content":{"rendered":"<p>Klappt &#8211; 1,- \u20ac waren 7,89 Yuan. Leider ist ein Kurs von einem beliebten Reiseland, Nordkorea, nicht aufgef\u00fchrt, grins. Man wird die nordkoreanischen Won\u00b4s schwarz tauschen m\u00fcssen. Aber sie nehmen sicher auch $ollars vom gro\u00dfen Feind, wenn ein Touri ein Poster vom gro\u00dfen F\u00fchrer Kim Yong Un kaufen m\u00f6chte.<\/p>\n"},"status":"1"},{"id":51418,"parent":0,"author":0,"author_name":"Michael Bormann","author_email":"mbo54@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a6db4717a529eea30725b9f12eb446d243bc52fe9b7cc3101efd596833007513?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a6db4717a529eea30725b9f12eb446d243bc52fe9b7cc3101efd596833007513?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a6db4717a529eea30725b9f12eb446d243bc52fe9b7cc3101efd596833007513?s=96&d=mm&r=g"},"date":"2017-07-23T18:32:32","cld_nonce":"82f011626f","content":{"rendered":"<p>Nennt sich Calc, der Rechner ist schon l\u00e4nger in Win10 drin und auch in der 1703.10563.483<br \/>\nkann man W\u00e4hrungen und anderes umrechnen, was ist jetzt so neu daran?<\/p>\n"},"status":"1"},{"id":51420,"parent":51418,"author":1525,"author_name":"W8U","author_email":"windows-8-user@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"},"date":"2017-07-23T18:54:30","cld_nonce":"82f011626f","content":{"rendered":"<p>Version 10.1706.1602.0 (und neuer) des Taschenrechners kann die W\u00e4hrung umrechnen. Ab Windows 10 Build 16226 ist diese Version (oder neuer) ins System integriert. Seitdem bekommen auch andere Windows 10 Nutzer diese Version \u00fcber den Store. Dein &#8222;schon l\u00e4nger&#8220; meint in diesem Fall genau einen einzigen Monat.<\/p>\n"},"status":"1"},{"id":51421,"parent":51418,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-07-23T18:55:12","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich hab auch nichts von der Insider Version geschrieben. Sondern f\u00fcr die 10563.483.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>W\u00e4hrungsrechner nun in der Rechner App Windows 10 - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"W\u00e4hrungsrechner nun in der Rechner App Windows 10\" \/>\n<meta property=\"og:description\" content=\"Die Rechner App in der Windows 10 hat schon einige Konverter integriert. Damit kann man die Temperatur, L\u00e4nge, Zeit oder Geschwindigkeit umrechnen lassen. In der aktuellen Version 10.1706.1862.0 ist nun eine neue sehr interessante Funktion hinzugekommen. Denn man kann nun&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-22T11:33:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-23T16:58:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1197\" \/>\n\t<meta property=\"og:image:height\" content=\"705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"W\u00e4hrungsrechner nun in der Rechner App Windows 10\",\"datePublished\":\"2017-07-22T11:33:40+00:00\",\"dateModified\":\"2017-07-23T16:58:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/\"},\"wordCount\":159,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/waehrungsrechner-in-der-rechner-app-windows-10.jpg\",\"keywords\":[\"Konverter\",\"Rechner App\",\"W\u00e4hrung umrechnen\",\"Windows 10\"],\"articleSection\":[\"Windows 10\",\"Windows Apps\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/\",\"name\":\"W\u00e4hrungsrechner nun in der Rechner App Windows 10 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/waehrungsrechner-in-der-rechner-app-windows-10.jpg\",\"datePublished\":\"2017-07-22T11:33:40+00:00\",\"dateModified\":\"2017-07-23T16:58:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/waehrungsrechner-in-der-rechner-app-windows-10.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/waehrungsrechner-in-der-rechner-app-windows-10.jpg\",\"width\":1197,\"height\":705},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/07\\\/22\\\/waehrungsrechner-nun-in-der-rechner-app-windows-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"W\u00e4hrungsrechner nun in der Rechner App Windows 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"W\u00e4hrungsrechner nun in der Rechner App Windows 10 - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/","og_locale":"de_DE","og_type":"article","og_title":"W\u00e4hrungsrechner nun in der Rechner App Windows 10","og_description":"Die Rechner App in der Windows 10 hat schon einige Konverter integriert. Damit kann man die Temperatur, L\u00e4nge, Zeit oder Geschwindigkeit umrechnen lassen. In der aktuellen Version 10.1706.1862.0 ist nun eine neue sehr interessante Funktion hinzugekommen. Denn man kann nun&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-07-22T11:33:40+00:00","article_modified_time":"2017-07-23T16:58:36+00:00","og_image":[{"width":1197,"height":705,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"W\u00e4hrungsrechner nun in der Rechner App Windows 10","datePublished":"2017-07-22T11:33:40+00:00","dateModified":"2017-07-23T16:58:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/"},"wordCount":159,"commentCount":7,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg","keywords":["Konverter","Rechner App","W\u00e4hrung umrechnen","Windows 10"],"articleSection":["Windows 10","Windows Apps"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/","name":"W\u00e4hrungsrechner nun in der Rechner App Windows 10 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg","datePublished":"2017-07-22T11:33:40+00:00","dateModified":"2017-07-23T16:58:36+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg","width":1197,"height":705},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/07\/22\/waehrungsrechner-nun-in-der-rechner-app-windows-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"W\u00e4hrungsrechner nun in der Rechner App Windows 10"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/07\/waehrungsrechner-in-der-rechner-app-windows-10.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/88395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=88395"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/88395\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/88396"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=88395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=88395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=88395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}