{"id":87213,"date":"2017-06-29T13:02:34","date_gmt":"2017-06-29T11:02:34","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=87213"},"modified":"2023-01-14T17:11:33","modified_gmt":"2023-01-14T16:11:33","slug":"minitool-shadowmaker-in-einem-kurzen-test","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/","title":{"rendered":"Minitool ShadowMaker in einem kurzen Test"},"content":{"rendered":"<p>Die Firma Minitool ist f\u00fcr ihren Partition Manager und Data Recovery bekannt. Jetzt m\u00f6chte man mit dem ShadowMaker eine Backup- \/ Sicherungssoftware anbieten. Mit dieser neuen Software erfindet man zwar das Rad nicht neu, aber ein weiterer Konkurrent auf dem Markt kann nicht schaden.<\/p>\n<p>Eine Sicherung oder ein Backup ist wichtig. Egal mit welchem Programm man es erstellt. Denn es kann immer mal wieder dazu kommen, dass Windows nicht mehr will oder die Festplatte &#8222;raucht ab&#8220;. Wer ganz auf Nummer Sicher gehen will, der erstellt die Sicherungen grunds\u00e4tzlich auf einer externen Festplatte und zieht danach den Stecker ab. Denn so hat auch ein Krypto-Trojaner keinen Zugriff.<\/p>\n<p>Noch ist die Software im Beta-Stadium und bietet nach dem Start die M\u00f6glichkeit sich mit dem Computer oder \u00fcber eine IP per Remote zu verbinden. Ich habe es auf meinem PC getestet. Die Men\u00fc\u00fcbersicht ist sehr aufger\u00e4umt und man hat alle wichtigen Punkte in einem Men\u00fc.<\/p>\n<p>\u00dcber den Men\u00fcpunkt Backup kommt man zu den Optionen. Oder besser gesagt den Feineinstellungen f\u00fcr die Backups. So kann man die Kompression ausw\u00e4hlen, oder auch die Einstellung &#8222;Nur benutzte Sektoren, oder Sektor f\u00fcr Sektor Sicherung.<\/p>\n<div id='gallery-1' class='gallery galleryid-87213 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"163\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-306x163.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-306x163.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-500x266.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-810x431.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg 1113w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-002.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-002-285x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-002-285x205.jpg 285w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-002-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-002-810x583.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-002.jpg 1096w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003-285x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003-285x205.jpg 285w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003-810x583.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003.jpg 1096w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Links kann man die Planung so einstellen, wann die Aufgabenplanung ein Backup automatisch erstellen kann. Ist alles fertig, dann kann man sein erstes Backup erstellen. Diese werden als Vollbackup, differenziell (\u00c4nderungen zum ersten Vollbackup werden gesichert). Oder inkrementelles Backup (\u00c4nderungen zum letzten Backup werden gespeichert).<\/p>\n<div id='gallery-2' class='gallery galleryid-87213 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003-1-1.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"281\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003-1-1-281x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003-1-1-281x205.jpg 281w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003-1-1-493x360.jpg 493w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003-1-1-798x583.jpg 798w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-003-1-1.jpg 1135w\" sizes=\"auto, (max-width: 281px) 100vw, 281px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-004.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-004-284x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-004-284x205.jpg 284w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-004-498x360.jpg 498w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-004-807x583.jpg 807w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-004.jpg 1096w\" sizes=\"auto, (max-width: 284px) 100vw, 284px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h3>Tools und Bootmedium erstellen<\/h3>\n<p>Wichtig ist nat\u00fcrlich ein Bootmedium zu erstellen, mit dem man bei Problemen dann booten kann. Hier hat man die M\u00f6glichkeit Windows PE ins Bootmen\u00fc zu integrieren, oder man erstellt sich einen Bootf\u00e4higen USB-Stick bzw. ISO. Dort hat man dann noch die Auswahl seine eigenen Treiber zu integrieren, oder die wichtigen vom System mit einem Klick hinzuzuf\u00fcgen.<\/p>\n<div id='gallery-3' class='gallery galleryid-87213 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005-285x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005-285x205.jpg 285w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005-810x583.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005.jpg 1098w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-006.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-006-272x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-006-272x205.jpg 272w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-006-478x360.jpg 478w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-006-774x583.jpg 774w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-006.jpg 790w\" sizes=\"auto, (max-width: 272px) 100vw, 272px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-008.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-008-285x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-008-285x205.jpg 285w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-008-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-008-810x583.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-008.jpg 1098w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-1.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"182\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-1-306x182.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-1-306x182.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-1-500x297.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-1-810x481.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-1.jpg 1258w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h3>Weitere Funktionen im ShadowMaker<\/h3>\n<p>Startet man das Programm \u00fcber das Bootmen\u00fc oder per USB-Stick, dann hat man im Prinzip die gleiche Ansicht wie im Programm auch. Nebenbei bietet der PE Loader noch eine Eingabeaufforderung oder auch die Funktion Treiber zu laden.  Unter dem Men\u00fc Tools kann man die erstellte Sicherung verifizieren lassen. Das Backup kann gemountet werden, um nur einzelne Daten herauszukopieren. Oder man kann die ganze Festplatte klonen. Ist nat\u00fcrlich praktisch, wenn man sich eine neue Festplatte zulegen will.<\/p>\n<div id='gallery-4' class='gallery galleryid-87213 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-3.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"292\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-3-292x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-3-292x205.jpg 292w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-3-500x351.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-3-810x568.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-3.jpg 1263w\" sizes=\"auto, (max-width: 292px) 100vw, 292px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-2.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"279\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-2-279x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-2-279x205.jpg 279w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-2-490x360.jpg 490w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-2-793x583.jpg 793w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-009-2.jpg 1230w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005-1.jpg' rel=\"lightbox[87213]\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005-1-285x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005-1-285x205.jpg 285w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005-1-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005-1-810x583.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-005-1.jpg 1098w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h3>Kleines Fazit<\/h3>\n<p>Wer keine grosse Ahnung von Backups und deren Einstellungen hat, findet mit dem ShadowMaker ein Programm, dass wirklich sehr \u00fcbersichtlich ist. Alle Einstellungen sind dort wo sie hingeh\u00f6ren und es st\u00f6rt nichts. Die Erstellung, Wiederherstellung ging z\u00fcgig von statten. Auch der Start \u00fcber das Bootmen\u00fc ging sehr gut. Da man hier die selbe Grafik und auch Einstellungen vorfindet, findet man sich schnell zurecht.<\/p>\n<h3>Wann erscheint der ShadowMaker und ist es Freeware?<\/h3>\n<p>Die Beta-Phase geht noch bis etwa Ende September. Solange wird diese Beta auch voll funktionsf\u00e4hig sein. Dann wird die finale Version erscheinen. Auf meine Anfrage best\u00e4tigte Jenne mir, dass es dann zwei Versionen geben wird. Eine Freeware Version, in der nicht alle Funktionen zur Verf\u00fcgung stehen und eine kostenpflichtige. Aber das kennen wir ja auch von den anderen Herstellern. Ich bin dann mal auf den Preis gespannt.<\/p>\n<p>Das Programm ist f\u00fcr Windows 7, 8 und Windows 10 geeignet. Wer mehr \u00fcber das Programm wissen m\u00f6chte: <a href=\"http:\/\/www.minitool.com\/backup\/system-backup.html\" target=\"_blank\" rel=\"noopener\">minitool.com\/backup<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Firma Minitool ist f\u00fcr ihren Partition Manager und Data Recovery bekannt. Jetzt m\u00f6chte man mit dem ShadowMaker eine Backup- \/ Sicherungssoftware anbieten. Mit dieser neuen Software erfindet man zwar das Rad nicht neu, aber ein weiterer Konkurrent auf dem&hellip; <\/p>\n","protected":false},"author":134,"featured_media":87215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689,11],"tags":[17762,2350,1744],"class_list":["post-87213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","category-windows","tag-minitool-shadowmaker","tag-review","tag-test"],"wp_featured_image":{"id":87215,"alt_text":"","description":"","media_type":"image","media_details":{"width":1113,"height":592,"file":"2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg","sizes":{"thumbnail":{"file":"minitool-shadowmaker-kurzer-test-001-306x163.jpg","width":306,"height":163,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-306x163.jpg"},"medium":{"file":"minitool-shadowmaker-kurzer-test-001-500x266.jpg","width":500,"height":266,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-500x266.jpg"},"large":{"file":"minitool-shadowmaker-kurzer-test-001-810x431.jpg","width":810,"height":431,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-810x431.jpg"},"wp_review_large":{"file":"minitool-shadowmaker-kurzer-test-001-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-320x200.jpg"},"wp_review_small":{"file":"minitool-shadowmaker-kurzer-test-001-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-65x65.jpg"},"blog-large":{"file":"minitool-shadowmaker-kurzer-test-001-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-642x300.jpg"},"blog-medium":{"file":"minitool-shadowmaker-kurzer-test-001-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-306x205.jpg"},"recent-thumb":{"file":"minitool-shadowmaker-kurzer-test-001-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-350x316.jpg"},"service-featured":{"file":"minitool-shadowmaker-kurzer-test-001-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-600x330.jpg"},"wp_rp_thumbnail":{"file":"minitool-shadowmaker-kurzer-test-001-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":87213,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg"},"commentcount":8,"wp_comments":[{"id":50411,"parent":0,"author":0,"author_name":"Garfield","author_email":"garfield9992003@freenet.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9c8d63eb857e96201dda5bf3892e4cfeee4d4243af2d1119a250679450487ff0?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9c8d63eb857e96201dda5bf3892e4cfeee4d4243af2d1119a250679450487ff0?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9c8d63eb857e96201dda5bf3892e4cfeee4d4243af2d1119a250679450487ff0?s=96&d=mm&r=g"},"date":"2017-06-29T13:07:22","cld_nonce":"82f011626f","content":{"rendered":"<p>Ist etwas dar\u00fcber bekannt, ob sich ein Image auf abweichender Hardware wiederhergestellen l\u00e4sst?<\/p>\n"},"status":"1"},{"id":50412,"parent":50411,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-06-29T13:20:15","cld_nonce":"82f011626f","content":{"rendered":"<p>W\u00e4re dann \u00fcber das Bootmedium m\u00f6glich. Dort kannst du auch Treiber hinzuf\u00fcgen.<\/p>\n"},"status":"1"},{"id":50467,"parent":0,"author":0,"author_name":"Rising Darkness","author_email":"info@mightful-noobs.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/275372d6a1bc8cf12e4ee274e8101a24473499e5cbe6473d18037a509b14d59e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/275372d6a1bc8cf12e4ee274e8101a24473499e5cbe6473d18037a509b14d59e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/275372d6a1bc8cf12e4ee274e8101a24473499e5cbe6473d18037a509b14d59e?s=96&d=mm&r=g"},"date":"2017-06-30T11:39:56","cld_nonce":"82f011626f","content":{"rendered":"<p>Hmm, ich nutze bis jetzt kein Backup. Mache mir aber schon \u00fcber 2-3 Wochen gedanken dar\u00fcber. Habe eine 3TB HDD mit USB2.0 und eine 512GB HDD mit USB3.0. Gibts irgendwelche Software oder Artikel, die ihr zu dem Thema empfehlt?<\/p>\n<p>EDIT: Freeware bzw. OpenSource w\u00e4re ganz gut<\/p>\n"},"status":"1"},{"id":50468,"parent":50467,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-06-30T11:43:59","cld_nonce":"82f011626f","content":{"rendered":"<p>Empfehlen ist immer so eine Sache. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/> Kommt immer darauf an, was man genau ben\u00f6tigt. Wenn du keinen Schnickschnack brauchst, ist Macrium Reflect gut. Finde ich jedenfalls und nutze es auch. Belastet nicht den Start durch viele Dienste (so wie Acronis) und hat nichts unn\u00f6tiges an Board.<\/p>\n"},"status":"1"},{"id":50516,"parent":50411,"author":0,"author_name":"Gunter","author_email":"gheinze@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/34a36961b9d14dfcc512aa764f32024a92dcf82f65c9cd5885bd2663bad80cdb?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/34a36961b9d14dfcc512aa764f32024a92dcf82f65c9cd5885bd2663bad80cdb?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/34a36961b9d14dfcc512aa764f32024a92dcf82f65c9cd5885bd2663bad80cdb?s=96&d=mm&r=g"},"date":"2017-07-01T14:26:40","cld_nonce":"82f011626f","content":{"rendered":"<p>Ja geht. Habe einen T400 auf T430 umgezogen.<\/p>\n"},"status":"1"},{"id":230802,"parent":0,"author":0,"author_name":"Heinz","author_email":"Biedermeyer@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/11d2e63b223e4eb6437dd93a6257f8b2acef2b85f299d03830fc832b5edd3002?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/11d2e63b223e4eb6437dd93a6257f8b2acef2b85f299d03830fc832b5edd3002?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/11d2e63b223e4eb6437dd93a6257f8b2acef2b85f299d03830fc832b5edd3002?s=96&d=mm&r=g"},"date":"2023-01-14T02:37:19","cld_nonce":"82f011626f","content":{"rendered":"<p>Hi,<br \/>\ndie Auflistung empfinde ich um einiges mehr als standard bspw Acronis, Symantec\/Veritas&#8230;<\/p>\n<p>Eingabeaufforderung (um z.B. mit TC zu arbeiten), Mounten von Backups zu LW-Buchstaben (Veritas kann das, Acronis nicht bzw. nur extrem umstaendlich ohne zu mounten)<br \/>\nDifferenzielle Backups, auch eine Seltenheit<br \/>\nHoffe, dass auch komplette laufwerke gesichert werden koennen, also mit allen Partitionen (Acroniskann das, Veritas nicht)<\/p>\n<p>Hat jemand seit dem Erscheinen dieses Artikels, also seit 5 Jahren, Erfahrungen mit diesem Programm sammeln koennen?<\/p>\n"},"status":"1"},{"id":260695,"parent":0,"author":0,"author_name":"Markus","author_email":"sch.rott@solnet.ch","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4ba71f21831c01aeb9bba4fd10940945376fcec96fc740310f7a12bc15ccab15?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4ba71f21831c01aeb9bba4fd10940945376fcec96fc740310f7a12bc15ccab15?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4ba71f21831c01aeb9bba4fd10940945376fcec96fc740310f7a12bc15ccab15?s=96&d=mm&r=g"},"date":"2023-12-02T22:10:24","cld_nonce":"82f011626f","content":{"rendered":"<p>@Heinz<br \/>\nIch nutze Macrium Reflect. Das beherrscht differenzielle und inkrementelle Images (manuell und automatisch), kann sogar auf andere Hardware deployed werden (das werde ich allerdings erst noch testen).<br \/>\nAuch mounten kann man Images (\u00fcber mitinstallierte VirtualBox).<br \/>\nPreislich: ich habe es beim Macrium-Shop f\u00fcr unter 60\u20ac bekommen (lebenslange Lizenz).<br \/>\nMinitool Shadowmaker wird gerade heute auf <a href=\"https:\/\/de.giveawayoftheday.com\/minitool-shadowmaker-4-3\/\" rel=\"nofollow ugc\">https:\/\/de.giveawayoftheday.com\/minitool-shadowmaker-4-3\/<\/a> gratis angeboten. Lizenzpreis Kaufversion $9.99 \/ Monat &#8230;<br \/>\nGruss<br \/>\nMarkus<\/p>\n"},"status":"1"},{"id":260696,"parent":0,"author":0,"author_name":"Heinz","author_email":"biedermeyer@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/11d2e63b223e4eb6437dd93a6257f8b2acef2b85f299d03830fc832b5edd3002?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/11d2e63b223e4eb6437dd93a6257f8b2acef2b85f299d03830fc832b5edd3002?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/11d2e63b223e4eb6437dd93a6257f8b2acef2b85f299d03830fc832b5edd3002?s=96&d=mm&r=g"},"date":"2023-12-02T22:20:03","cld_nonce":"82f011626f","content":{"rendered":"<p>Danke dir fuer die Info, Markus.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Minitool ShadowMaker in einem kurzen Test - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minitool ShadowMaker in einem kurzen Test\" \/>\n<meta property=\"og:description\" content=\"Die Firma Minitool ist f\u00fcr ihren Partition Manager und Data Recovery bekannt. Jetzt m\u00f6chte man mit dem ShadowMaker eine Backup- \/ Sicherungssoftware anbieten. Mit dieser neuen Software erfindet man zwar das Rad nicht neu, aber ein weiterer Konkurrent auf dem&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-29T11:02:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-14T16:11:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1113\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Minitool ShadowMaker in einem kurzen Test\",\"datePublished\":\"2017-06-29T11:02:34+00:00\",\"dateModified\":\"2023-01-14T16:11:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/\"},\"wordCount\":576,\"commentCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/minitool-shadowmaker-kurzer-test-001.jpg\",\"keywords\":[\"Minitool ShadowMaker\",\"Review\",\"Test\"],\"articleSection\":[\"Windows 10\",\"Windows \u00e4lter\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/\",\"name\":\"Minitool ShadowMaker in einem kurzen Test - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/minitool-shadowmaker-kurzer-test-001.jpg\",\"datePublished\":\"2017-06-29T11:02:34+00:00\",\"dateModified\":\"2023-01-14T16:11:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/minitool-shadowmaker-kurzer-test-001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/minitool-shadowmaker-kurzer-test-001.jpg\",\"width\":1113,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/29\\\/minitool-shadowmaker-in-einem-kurzen-test\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minitool ShadowMaker in einem kurzen Test\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Minitool ShadowMaker in einem kurzen Test - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/","og_locale":"de_DE","og_type":"article","og_title":"Minitool ShadowMaker in einem kurzen Test","og_description":"Die Firma Minitool ist f\u00fcr ihren Partition Manager und Data Recovery bekannt. Jetzt m\u00f6chte man mit dem ShadowMaker eine Backup- \/ Sicherungssoftware anbieten. Mit dieser neuen Software erfindet man zwar das Rad nicht neu, aber ein weiterer Konkurrent auf dem&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-06-29T11:02:34+00:00","article_modified_time":"2023-01-14T16:11:33+00:00","og_image":[{"width":1113,"height":592,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Minitool ShadowMaker in einem kurzen Test","datePublished":"2017-06-29T11:02:34+00:00","dateModified":"2023-01-14T16:11:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/"},"wordCount":576,"commentCount":8,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg","keywords":["Minitool ShadowMaker","Review","Test"],"articleSection":["Windows 10","Windows \u00e4lter"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/","name":"Minitool ShadowMaker in einem kurzen Test - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg","datePublished":"2017-06-29T11:02:34+00:00","dateModified":"2023-01-14T16:11:33+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg","width":1113,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/29\/minitool-shadowmaker-in-einem-kurzen-test\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Minitool ShadowMaker in einem kurzen Test"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/minitool-shadowmaker-kurzer-test-001.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/87213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=87213"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/87213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/87215"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=87213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=87213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=87213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}