{"id":86957,"date":"2017-06-23T15:53:46","date_gmt":"2017-06-23T13:53:46","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=86957"},"modified":"2017-06-23T15:53:46","modified_gmt":"2017-06-23T13:53:46","slug":"dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/","title":{"rendered":"Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden"},"content":{"rendered":"<p>Microsoft spielt wohl zur Zeit ein wenig herum, oder wir hatten mit der <a href=\"https:\/\/www.deskmodder.de\/blog\/2017\/06\/10\/dateiversionsverlauf-laesst-sich-nur-noch-wiederherstellen-in-der-windows-10-1709\/\" target=\"_blank\">Build 16215<\/a> eine Insider aus einem anderen &#8222;Versuchsumfeld&#8220; bekommen. Denn der Dateiversionsverlauf ist wieder vorhanden und man kann seine Daten und Bibliotheken sichern, so wie man es bisher von Win 10 gew\u00f6hnt war.<\/p>\n<p>Der Versuch \u00fcber die Einstellungen den Dateiversionsverlauf zu aktivieren, schlug mit einem Crash fehl. \u00dcber die alte Systemsteuerung hingegen, liess sich alles aktivieren und auch die Ordner einstellen. Danach war auch in den neuen Einstellungen alles m\u00f6glich.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg\" rel=\"lightbox[86957]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-500x360.jpg\" alt=\"\" width=\"500\" height=\"360\" class=\"aligncenter size-medium wp-image-86958\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-286x205.jpg 286w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-810x581.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg 1039w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Man kann gespannt sein, ob Microsoft nun zum Beispiel durch die Feedback-Hub Eintr\u00e4ge zur\u00fcckgerudert ist, oder ob es nur ein &#8222;versehen&#8220; war, dass man Dateien nur noch wiederherstellen konnte. Ich f\u00fcr mich brauche diese Funktion nicht. Aber sicherlich werden viele ihre Dateien so sichern.<\/p>\n<p>Bei <a href=\"https:\/\/mspoweruser.com\/windows-10s-file-history-backup-system-isnt-going-to-die-after-all\/\" target=\"_blank\">mspu<\/a> spekuliert man, dass ein Zusammenhang mit den nun eingef\u00fchrten <a href=\"https:\/\/www.deskmodder.de\/blog\/2017\/06\/13\/onedrive-platzhalter-windows-10-registry-eintraege-schon-vorhanden\/\" target=\"_blank\">OneDrive Platzhaltern<\/a> (Dateien bei Bedarf) besteht. Ob es wirklich daran lag, wissen nur die Redmonder selber.<\/p>\n<h3>Tutorials und Hilfe<\/h3>\n<p>Ihr sucht weitere Tipps, Tricks und Tutorials f\u00fcr Windows 10? Dann schaut in unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" target=\"_blank\"><strong>Wiki<\/strong><\/a> vorbei bzw. speichert die Seite in den Favoriten. Falls ihr Fragen habt, dann stellt diese (auch als Gast) ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=326\" target=\"_blank\"><strong>Forum<\/strong><\/a>. Wir werden versuchen euch bei euren Problemen zu helfen.<\/p>\n<ul>\n<li>Wichtige Tutorials im Wiki:<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_reparieren_wiederherstellen_mit_DISM_Inplace_Upgrade_und_vielen_weiteren_Varianten\" target=\"_blank\">Windows 10 reparieren, Fehler beheben<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_Update_reparieren_Windows_10\" target=\"_blank\">Win 10 Updates reparieren<\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Automatische_Updates_deaktivieren_oder_auf_manuell_setzen_Windows_10\" target=\"_blank\">richtig einstellen<\/a>  <\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Autostart_Windows_10_Programme_deaktivieren_hinzuf%C3%BCgen_entfernen\" target=\"_blank\">Windows 10 Autostart Programme entfernen<\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Datentr%C3%A4gerbereinigung_Windows_10_Alte_Daten_richtig_l%C3%B6schen\" target=\"_blank\">Festplatte \/ SSD aufr\u00e4umen<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_automatisch_anmelden_ohne_Passworteingabe\" target=\"_blank\">Ohne Passwort anmelden Windows 10<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Cortana_deaktivieren_Windows_10\" target=\"_blank\">Cortana entfernen, deaktivieren<\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Onedrive_deinstallieren_windows_10\" target=\"_blank\">OneDive entfernen<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Das_Windows_10_Startmen%C3%BC_richtig_einrichten_Tipps_und_Tricks\" target=\"_blank\">Windows 10 Tipps zum Startmen\u00fc <\/a> und <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Startmen%C3%BC_reparieren_Windows_10\" target=\"_blank\">Reparatur<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft spielt wohl zur Zeit ein wenig herum, oder wir hatten mit der Build 16215 eine Insider aus einem anderen &#8222;Versuchsumfeld&#8220; bekommen. Denn der Dateiversionsverlauf ist wieder vorhanden und man kann seine Daten und Bibliotheken sichern, so wie man es&hellip; <\/p>\n","protected":false},"author":134,"featured_media":86958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[678,7013,16950],"class_list":["post-86957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-dateiversionsverlauf","tag-insider","tag-windows-10-1709"],"wp_featured_image":{"id":86958,"alt_text":"","description":"","media_type":"image","media_details":{"width":1039,"height":745,"file":"2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg","sizes":{"thumbnail":{"file":"dateiversionsverlauf-windows-10-1709-funktioniert-wieder-286x205.jpg","width":286,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-286x205.jpg"},"medium":{"file":"dateiversionsverlauf-windows-10-1709-funktioniert-wieder-500x360.jpg","width":500,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-500x360.jpg"},"large":{"file":"dateiversionsverlauf-windows-10-1709-funktioniert-wieder-810x581.jpg","width":810,"height":581,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-810x581.jpg"},"wp_review_large":{"file":"dateiversionsverlauf-windows-10-1709-funktioniert-wieder-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-320x200.jpg"},"wp_review_small":{"file":"dateiversionsverlauf-windows-10-1709-funktioniert-wieder-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-65x65.jpg"},"blog-large":{"file":"dateiversionsverlauf-windows-10-1709-funktioniert-wieder-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-642x300.jpg"},"blog-medium":{"file":"dateiversionsverlauf-windows-10-1709-funktioniert-wieder-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-306x205.jpg"},"recent-thumb":{"file":"dateiversionsverlauf-windows-10-1709-funktioniert-wieder-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-350x316.jpg"},"service-featured":{"file":"dateiversionsverlauf-windows-10-1709-funktioniert-wieder-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-600x330.jpg"},"wp_rp_thumbnail":{"file":"dateiversionsverlauf-windows-10-1709-funktioniert-wieder-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":86957,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg"},"commentcount":3,"wp_comments":[{"id":50130,"parent":0,"author":2213,"author_name":"KnorxThieus","author_email":"knorxthieus@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=96&d=mm&r=g"},"date":"2017-06-23T17:30:01","cld_nonce":"82f011626f","content":{"rendered":"<p>PUUUH &#8230; Da bin ich aber erst mal erleichtert. Sicherlich, genauso, wie sie es zur Entwicklung einer neuen Funktion rausgenommen haben k\u00f6nnen, k\u00f6nnen sie es jetzt wieder nur testweise reingetan haben, aber da scheinen wir ja doch noch mal glimpflich davongekommen zu sein. Und ich dachte schon, ich m\u00fcsste mich jetzt mit robocopy auseinandersetzen. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":50141,"parent":0,"author":0,"author_name":"Holunder","author_email":"12345@holunder.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/2d11d10b8a6e9c997d562a8d44492b70d31f91321b036819c468e6a2e8b3a757?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/2d11d10b8a6e9c997d562a8d44492b70d31f91321b036819c468e6a2e8b3a757?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/2d11d10b8a6e9c997d562a8d44492b70d31f91321b036819c468e6a2e8b3a757?s=96&d=mm&r=g"},"date":"2017-06-23T22:18:38","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich bin auch stolzer Besitzer einer robocopy-batch. Echt geil!<\/p>\n"},"status":"1"},{"id":50151,"parent":50141,"author":2213,"author_name":"KnorxThieus","author_email":"knorxthieus@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=96&d=mm&r=g"},"date":"2017-06-24T09:33:35","cld_nonce":"82f011626f","content":{"rendered":"<p>Aber weniger benutzerfreundlich <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n<p>Ich bin da derzeit eh noch am T\u00fcfteln: <a href=\"https:\/\/www.gutefrage.net\/frage\/wie-gut-waere-mein-pc-eigentlich-gegen-ransomware-geschuetzt\" rel=\"nofollow ugc\">https:\/\/www.gutefrage.net\/frage\/wie-gut-waere-mein-pc-eigentlich-gegen-ransomware-geschuetzt<\/a>? <a href=\"https:\/\/www.gutefrage.net\/frage\/wie-kann-ich-fuer-eine-netzwerkfreigabe-unter-windows-10-ein-speicherkontingent-festlegen\" rel=\"nofollow ugc\">https:\/\/www.gutefrage.net\/frage\/wie-kann-ich-fuer-eine-netzwerkfreigabe-unter-windows-10-ein-speicherkontingent-festlegen<\/a>?<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden - Deskmodder.de<\/title>\n<meta name=\"description\" content=\"Dateiversionsverlauf wieder in der Insider integriert\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden\" \/>\n<meta property=\"og:description\" content=\"Dateiversionsverlauf wieder in der Insider integriert\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-23T13:53:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1039\" \/>\n\t<meta property=\"og:image:height\" content=\"745\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden\",\"datePublished\":\"2017-06-23T13:53:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/\"},\"wordCount\":255,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg\",\"keywords\":[\"Dateiversionsverlauf\",\"insider\",\"Windows 10 1709\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/\",\"name\":\"Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg\",\"datePublished\":\"2017-06-23T13:53:46+00:00\",\"description\":\"Dateiversionsverlauf wieder in der Insider integriert\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg\",\"width\":1039,\"height\":745},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/23\\\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden - Deskmodder.de","description":"Dateiversionsverlauf wieder in der Insider integriert","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/","og_locale":"de_DE","og_type":"article","og_title":"Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden","og_description":"Dateiversionsverlauf wieder in der Insider integriert","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-06-23T13:53:46+00:00","og_image":[{"width":1039,"height":745,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden","datePublished":"2017-06-23T13:53:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/"},"wordCount":255,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg","keywords":["Dateiversionsverlauf","insider","Windows 10 1709"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/","name":"Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg","datePublished":"2017-06-23T13:53:46+00:00","description":"Dateiversionsverlauf wieder in der Insider integriert","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg","width":1039,"height":745},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/23\/dateiversionsverlauf-in-der-windows-10-build-16226-wieder-vorhanden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Dateiversionsverlauf in der Windows 10 Build 16226 wieder vorhanden"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/dateiversionsverlauf-windows-10-1709-funktioniert-wieder.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/86957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=86957"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/86957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/86958"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=86957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=86957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=86957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}