{"id":86210,"date":"2017-06-08T15:43:20","date_gmt":"2017-06-08T13:43:20","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=86210"},"modified":"2017-06-08T16:02:03","modified_gmt":"2017-06-08T14:02:03","slug":"microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/","title":{"rendered":"Microsoft &#8211; Kauf von Hexadite nun offiziell best\u00e4tigt"},"content":{"rendered":"<p>Schon seit ca. zwei Wochen kamen die Meldungen auf, dass Microsoft den Abwehrspezialisten Hexadite f\u00fcr gesch\u00e4tzte 100 Millionen Dollar kaufen will. Jetzt wurde es von beiden Seiten offiziell best\u00e4tigt. Auch die Webseite von Hexadite zeigt nun gleich auf der Hauptseite, dass man zu Microsoft wechselt.<\/p>\n<p>Die Firma wurde 2014 gegr\u00fcndet und ist spezialisiert auf einen erweiterten Schutz gegen schwere Sicherheitsbedrohungen im Netz. Damit passt diese Firma perfekt zum Windows Defender Advanced Threat Protection von Microsoft. Die Redmonder erhoffen sich so einen noch besseren Schutz seiner Gesch\u00e4fts-Kunden.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft.jpg\" rel=\"lightbox[86210]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-500x245.jpg\" alt=\"\" width=\"500\" height=\"245\" class=\"aligncenter size-medium wp-image-86211\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-500x245.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-306x150.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-810x397.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft.jpg 920w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<blockquote class=\"quote_border_top\">\"Terry Myerson: Our vision is to deliver a new generation of security capabilities that helps our customers protect, detect and respond to the constantly evolving and ever-changing cyberthreat landscape. Hexadite\u2019s technology and talent will augment our existing capabilities and enable our ability to add new tools and services to Microsoft\u2019s robust enterprise security offerings.\"<\/blockquote>\n<p>Die Firma wird nach Abschluss des Kaufes vollst\u00e4ndig in Redmond integriert werden. Der Bisherige Sitz in Bosten und Tel-Aviv wird dann aufgegeben.<\/p>\n<p>Quelle: <a href=\"https:\/\/news.microsoft.com\/2017\/06\/08\/microsoft-signs-agreement-to-acquire-hexadite\/\" target=\"_blank\">news.microsoft<\/a>, <a href=\"https:\/\/www.hexadite.com\/blog\/hexadite-join-microsoft\/\" target=\"_blank\">hexadite<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schon seit ca. zwei Wochen kamen die Meldungen auf, dass Microsoft den Abwehrspezialisten Hexadite f\u00fcr gesch\u00e4tzte 100 Millionen Dollar kaufen will. Jetzt wurde es von beiden Seiten offiziell best\u00e4tigt. Auch die Webseite von Hexadite zeigt nun gleich auf der Hauptseite,&hellip; <\/p>\n","protected":false},"author":134,"featured_media":86211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[17477,113,9751],"class_list":["post-86210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-kauf-bestaetigt","tag-sicherheit","tag-windows-10"],"wp_featured_image":{"id":86211,"alt_text":"","description":"","media_type":"image","media_details":{"width":920,"height":451,"file":"2017\/06\/hexadite-microsoft.jpg","sizes":{"thumbnail":{"file":"hexadite-microsoft-306x150.jpg","width":306,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-306x150.jpg"},"medium":{"file":"hexadite-microsoft-500x245.jpg","width":500,"height":245,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-500x245.jpg"},"large":{"file":"hexadite-microsoft-810x397.jpg","width":810,"height":397,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-810x397.jpg"},"wp_review_large":{"file":"hexadite-microsoft-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-320x200.jpg"},"wp_review_small":{"file":"hexadite-microsoft-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-65x65.jpg"},"blog-large":{"file":"hexadite-microsoft-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-642x300.jpg"},"blog-medium":{"file":"hexadite-microsoft-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-306x205.jpg"},"recent-thumb":{"file":"hexadite-microsoft-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-350x316.jpg"},"service-featured":{"file":"hexadite-microsoft-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-600x330.jpg"},"wp_rp_thumbnail":{"file":"hexadite-microsoft-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":86210,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft - Kauf von Hexadite nun offiziell best\u00e4tigt - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft - Kauf von Hexadite nun offiziell best\u00e4tigt\" \/>\n<meta property=\"og:description\" content=\"Schon seit ca. zwei Wochen kamen die Meldungen auf, dass Microsoft den Abwehrspezialisten Hexadite f\u00fcr gesch\u00e4tzte 100 Millionen Dollar kaufen will. Jetzt wurde es von beiden Seiten offiziell best\u00e4tigt. Auch die Webseite von Hexadite zeigt nun gleich auf der Hauptseite,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-08T13:43:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-08T14:02:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Microsoft &#8211; Kauf von Hexadite nun offiziell best\u00e4tigt\",\"datePublished\":\"2017-06-08T13:43:20+00:00\",\"dateModified\":\"2017-06-08T14:02:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/\"},\"wordCount\":186,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/hexadite-microsoft.jpg\",\"keywords\":[\"Kauf best\u00e4tigt\",\"Sicherheit\",\"Windows 10\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/\",\"name\":\"Microsoft - Kauf von Hexadite nun offiziell best\u00e4tigt - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/hexadite-microsoft.jpg\",\"datePublished\":\"2017-06-08T13:43:20+00:00\",\"dateModified\":\"2017-06-08T14:02:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/hexadite-microsoft.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/hexadite-microsoft.jpg\",\"width\":920,\"height\":451},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/06\\\/08\\\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft &#8211; Kauf von Hexadite nun offiziell best\u00e4tigt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft - Kauf von Hexadite nun offiziell best\u00e4tigt - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft - Kauf von Hexadite nun offiziell best\u00e4tigt","og_description":"Schon seit ca. zwei Wochen kamen die Meldungen auf, dass Microsoft den Abwehrspezialisten Hexadite f\u00fcr gesch\u00e4tzte 100 Millionen Dollar kaufen will. Jetzt wurde es von beiden Seiten offiziell best\u00e4tigt. Auch die Webseite von Hexadite zeigt nun gleich auf der Hauptseite,&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-06-08T13:43:20+00:00","article_modified_time":"2017-06-08T14:02:03+00:00","og_image":[{"width":920,"height":451,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Microsoft &#8211; Kauf von Hexadite nun offiziell best\u00e4tigt","datePublished":"2017-06-08T13:43:20+00:00","dateModified":"2017-06-08T14:02:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/"},"wordCount":186,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft.jpg","keywords":["Kauf best\u00e4tigt","Sicherheit","Windows 10"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/","name":"Microsoft - Kauf von Hexadite nun offiziell best\u00e4tigt - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft.jpg","datePublished":"2017-06-08T13:43:20+00:00","dateModified":"2017-06-08T14:02:03+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft.jpg","width":920,"height":451},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/06\/08\/microsoft-kauf-von-hexadite-nun-offiziell-bestaetigt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft &#8211; Kauf von Hexadite nun offiziell best\u00e4tigt"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/hexadite-microsoft.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/86210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=86210"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/86210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/86211"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=86210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=86210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=86210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}