{"id":85141,"date":"2017-05-21T18:30:20","date_gmt":"2017-05-21T16:30:20","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=85141"},"modified":"2017-05-21T18:35:40","modified_gmt":"2017-05-21T16:35:40","slug":"microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/","title":{"rendered":"Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event"},"content":{"rendered":"<p>Am 23. Mai wird Microsoft in Shanghai auf einem Event mit ziemlich gro\u00dfer Wahrscheinlichkeit das bereits umfassend geleakte <strong><a href=\"https:\/\/www.deskmodder.de\/blog\/2017\/05\/19\/so-soll-das-neue-surface-pro-von-microsoft-aussehen\/\" target=\"_blank\" rel=\"noopener noreferrer\">neue Surface Pro<\/a><\/strong> vorstellen. Allerdings wird es dazu von den Redmondern\u00a0dieses Mal keine Live-\u00dcbetragung im Internet geben.<\/p>\n<p>Im Umkehrschluss k\u00f6nnte man sagen: Es wird abgesehen von dem kleinen Hardware-Refresh einfach nichts besonderes gezeigt. Selbst der <strong><a href=\"https:\/\/www.deskmodder.de\/blog\/2017\/05\/10\/home-hub-bilder-geleakt-windows-10-zentrale-mit-cortana-unterstuetzung\/\" target=\"_blank\" rel=\"noopener noreferrer\">Home Hub<\/a><\/strong> scheint daher beim Shanghai-Event (noch) keine Rolle zu spielen &#8211; denn das w\u00e4re durchaus eine recht gro\u00dfe Nummer. Aber mal abwarten: Noch zwei Mal schlafen und wir sind alle schlauer.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/tab.jpg\" rel=\"lightbox[85141]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-85023\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/tab-810x286.jpg\" alt=\"\" width=\"810\" height=\"286\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/tab-810x286.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/tab-306x108.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/tab-500x176.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/tab.jpg 1024w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/www.drwindows.de\/content\/12704-kein-livestream-surface-event-shanghai.html\" target=\"_blank\" rel=\"noopener noreferrer\">DrWindows<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Am 23. Mai wird Microsoft in Shanghai auf einem Event mit ziemlich gro\u00dfer Wahrscheinlichkeit das bereits umfassend geleakte neue Surface Pro vorstellen. Allerdings wird es dazu von den Redmondern\u00a0dieses Mal keine Live-\u00dcbetragung im Internet geben. Im Umkehrschluss k\u00f6nnte man sagen:&hellip; <\/p>\n","protected":false},"author":1525,"featured_media":85025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286,2689],"tags":[1145,1137,148,17182,1898],"class_list":["post-85141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","category-windows-10","tag-event","tag-livestream","tag-microsoft","tag-shanghai","tag-surface-pro"],"wp_featured_image":{"id":85025,"alt_text":"","description":"","media_type":"image","media_details":{"width":578,"height":268,"file":"2017\/05\/hero.jpg","sizes":{"thumbnail":{"file":"hero-306x142.jpg","width":306,"height":142,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero-306x142.jpg"},"medium":{"file":"hero-500x232.jpg","width":500,"height":232,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero-500x232.jpg"},"wp_review_large":{"file":"hero-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero-320x200.jpg"},"wp_review_small":{"file":"hero-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero-65x65.jpg"},"blog-medium":{"file":"hero-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero-306x205.jpg"},"recent-thumb":{"file":"hero-350x268.jpg","width":350,"height":268,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero-350x268.jpg"},"wp_rp_thumbnail":{"file":"hero-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":85021,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":1525,"name":"W8U","description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event\" \/>\n<meta property=\"og:description\" content=\"Am 23. Mai wird Microsoft in Shanghai auf einem Event mit ziemlich gro\u00dfer Wahrscheinlichkeit das bereits umfassend geleakte neue Surface Pro vorstellen. Allerdings wird es dazu von den Redmondern\u00a0dieses Mal keine Live-\u00dcbetragung im Internet geben. Im Umkehrschluss k\u00f6nnte man sagen:&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-21T16:30:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-21T16:35:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"578\" \/>\n\t<meta property=\"og:image:height\" content=\"268\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"W8U\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/\"},\"author\":{\"name\":\"W8U\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\"},\"headline\":\"Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event\",\"datePublished\":\"2017-05-21T16:30:20+00:00\",\"dateModified\":\"2017-05-21T16:35:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/\"},\"wordCount\":102,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/hero.jpg\",\"keywords\":[\"event\",\"LiveStream\",\"Microsoft\",\"Shanghai\",\"Surface Pro\"],\"articleSection\":[\"Hardware\",\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/\",\"name\":\"Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/hero.jpg\",\"datePublished\":\"2017-05-21T16:30:20+00:00\",\"dateModified\":\"2017-05-21T16:35:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/hero.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/hero.jpg\",\"width\":578,\"height\":268},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/21\\\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\",\"name\":\"W8U\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"caption\":\"W8U\"},\"description\":\"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/w8u\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event","og_description":"Am 23. Mai wird Microsoft in Shanghai auf einem Event mit ziemlich gro\u00dfer Wahrscheinlichkeit das bereits umfassend geleakte neue Surface Pro vorstellen. Allerdings wird es dazu von den Redmondern\u00a0dieses Mal keine Live-\u00dcbetragung im Internet geben. Im Umkehrschluss k\u00f6nnte man sagen:&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-05-21T16:30:20+00:00","article_modified_time":"2017-05-21T16:35:40+00:00","og_image":[{"width":578,"height":268,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero.jpg","type":"image\/jpeg"}],"author":"W8U","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/"},"author":{"name":"W8U","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469"},"headline":"Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event","datePublished":"2017-05-21T16:30:20+00:00","dateModified":"2017-05-21T16:35:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/"},"wordCount":102,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero.jpg","keywords":["event","LiveStream","Microsoft","Shanghai","Surface Pro"],"articleSection":["Hardware","Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/","name":"Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero.jpg","datePublished":"2017-05-21T16:30:20+00:00","dateModified":"2017-05-21T16:35:40+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero.jpg","width":578,"height":268},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/21\/microsoft-verzichtet-auf-livestream-fuer-kommendes-surface-event\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft verzichtet auf Livestream f\u00fcr kommendes Surface-Event"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469","name":"W8U","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","caption":"W8U"},"description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","url":"https:\/\/www.deskmodder.de\/blog\/author\/w8u\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/hero.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/85141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=85141"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/85141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/85025"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=85141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=85141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=85141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}