{"id":84381,"date":"2017-05-09T13:50:34","date_gmt":"2017-05-09T11:50:34","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=84381"},"modified":"2017-05-09T13:50:34","modified_gmt":"2017-05-09T11:50:34","slug":"keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/","title":{"rendered":"Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB)"},"content":{"rendered":"<p>Heute ist es nun soweit. Die erste Windows 10 10240 bekommt ab heute keine Sicherheitsupdates mehr. Eigentlich h\u00e4tte schon im M\u00e4rz Schluss sein m\u00fcssen, aber man hat das Ende in den Mai verschoben. Somit erhalten die <a href=\"https:\/\/www.deskmodder.de\/blog\/2017\/05\/05\/microsoft-aendert-die-einzelnen-bezeichnungen-ab-der-windows-10-1709\/\" target=\"_blank\">CB und CBB Versionen<\/a> kein Update mehr. Davon nat\u00fcrlich ausgeschlossen sind die LTSB Versionen der Enterprise und IoT. Diese haben eine 10-J\u00e4hrige Updatezeit.<\/p>\n<p>Aber erinnern wir uns zur\u00fcck. Am <a href=\"https:\/\/www.deskmodder.de\/blog\/2015\/07\/13\/windows-10-10240-die-finale-rtm-version\/\" target=\"_blank\">13.Juli 2015<\/a> stand endlich fest welche Version die RTM sein wird. Es gab nur eine Version die Updates erhielt und kein Chaos, wie es nun ist. Denn weiterhin werden die 1607 und 1703 mit Updates versorgt.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240.jpg\" rel=\"lightbox[84381]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-500x224.jpg\" alt=\"\" width=\"500\" height=\"224\" class=\"aligncenter size-medium wp-image-84382\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-500x224.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-306x137.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-810x364.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240.jpg 1105w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Damals hatten wir sogar noch <a href=\"https:\/\/www.deskmodder.de\/blog\/2015\/07\/10\/leak-windows-10-10176-th1-iso-steht-zum-download-bereit\/\" target=\"_blank\">Leaks<\/a> einiger Vorversionen. Heute freuen wir uns, wenn wir ein paar Stunden vorab die neue Buildnummer von Dona erfahren. In der Zeit hat sich doch viel ge\u00e4ndert. Die wohl auff\u00e4lligsten \u00c4nderungen haben wohl das Startmen\u00fc und auch die Einstellungen hinter sich. Apps mal aussen vor gelassen. Damals hatten wir eine optimierte Windows 8 Version, die mit den heutigen nicht mehr zu vergleichen ist. Alles ist &#8222;vernetzt&#8220; miteinander. \u00c4nderungen sind fast nicht mehr m\u00f6glich. Ob die \u00c4nderungen nun alle positiv oder viele auch negativ sind, kann man so schwer beantworten. <strong>K\u00f6nnt ihr es?<\/strong><\/p>\n<p>Auf jeden Fall Tsch\u00fcss Windows 10 1507, war eine sch\u00f6ne Zeit mit dir.<\/p>\n<p>Quelle: <a href=\"https:\/\/blogs.technet.microsoft.com\/windowsitpro\/2017\/01\/19\/windows-10-v1607-media-now-available\/\" target=\"_blank\">blogs.technet<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute ist es nun soweit. Die erste Windows 10 10240 bekommt ab heute keine Sicherheitsupdates mehr. Eigentlich h\u00e4tte schon im M\u00e4rz Schluss sein m\u00fcssen, aber man hat das Ende in den Mai verschoben. Somit erhalten die CB und CBB Versionen&hellip; <\/p>\n","protected":false},"author":134,"featured_media":84382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[],"class_list":["post-84381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10"],"wp_featured_image":{"id":84382,"alt_text":"","description":"","media_type":"image","media_details":{"width":1105,"height":496,"file":"2017\/05\/10240.jpg","sizes":{"thumbnail":{"file":"10240-306x137.jpg","width":306,"height":137,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-306x137.jpg"},"medium":{"file":"10240-500x224.jpg","width":500,"height":224,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-500x224.jpg"},"large":{"file":"10240-810x364.jpg","width":810,"height":364,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-810x364.jpg"},"wp_review_large":{"file":"10240-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-320x200.jpg"},"wp_review_small":{"file":"10240-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-65x65.jpg"},"blog-large":{"file":"10240-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-642x300.jpg"},"blog-medium":{"file":"10240-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-306x205.jpg"},"recent-thumb":{"file":"10240-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-350x316.jpg"},"service-featured":{"file":"10240-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-600x330.jpg"},"wp_rp_thumbnail":{"file":"10240-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":84381,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240.jpg"},"commentcount":3,"wp_comments":[{"id":48272,"parent":0,"author":2343,"author_name":"SirMarcvonGoskon","author_email":"marcsenn@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=96&d=mm&r=g"},"date":"2017-05-09T14:17:05","cld_nonce":"82f011626f","content":{"rendered":"<p>Mich h\u00e4lt nie eine rtm Windows auf \u00fcber l\u00e4ngere zeit \u00fcber den Nachfolger, bis auf Win 8-8.1 die hab ich \u00fcbersprungen.<br \/>\ndie 1607 war schon ne woche fr\u00fcher  als rtm auf pc und die 1507 gel\u00f6scht.<\/p>\n"},"status":"1"},{"id":48279,"parent":0,"author":0,"author_name":"Roy","author_email":"info@cm-wanfried.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9a010c50bcb338069f3fcfd1e6de951df1a05918acf7842b52467f24184d0e27?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9a010c50bcb338069f3fcfd1e6de951df1a05918acf7842b52467f24184d0e27?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9a010c50bcb338069f3fcfd1e6de951df1a05918acf7842b52467f24184d0e27?s=96&d=mm&r=g"},"date":"2017-05-09T15:30:27","cld_nonce":"82f011626f","content":{"rendered":"<p>Hmm, bl\u00f6d. Auf meinem HauptPC l\u00e4uft die Version aktuell noch produktiv, da jegliche Upgrades auf neue Versionen scheitern. Installation l\u00e4uft zwar problemlos durch, aber in den neuen Versionen habe ich keinerlei Netzwerkverbindungen mehr. Weder WLAN noch LAN. Habe schon alles m\u00f6gliche gesucht und gefunden, getestet und verworfen. Blieb nix anderes als zur\u00fcck zur 1507.<\/p>\n<p>Irgendwann werde ich wohl neu aufsetzen m\u00fcssen, aber momentan fehlt die Zeit dann alle Programme neu zu installieren!<br \/>\nRoy<\/p>\n"},"status":"1"},{"id":48280,"parent":0,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2017-05-09T15:45:50","cld_nonce":"82f011626f","content":{"rendered":"<p>Es wird dringend erforderlich sein, dass parallel zu 1703 auch weiterhin 1607 nicht nur die Sicherheitsupdates erf\u00e4hrt, sondern gleicherma\u00dfen solche, die f\u00fcr ein ordentlich stabiles System sorgen. Ich glaube, da \u00fcbertreibe ich nicht mit meiner Mutma\u00dfung, dass viele Nutzer auch mit 1607 (siehe Feedback-Hub) noch Probleme haben. Ein objektiver Blick in den eigenen Zuverl\u00e4ssigkeitsverlauf d\u00fcrfte auch sicherlich das Eine oder Andere an Fehlern sichtbar machen; wobei die Ursachen und die Quellen zur Behebung von Fehlern oft im Nebulosem liegen. Es ist daher angebracht, wenn Windows seine Bem\u00fchungen in Richtung Sicherheit und Zuverl\u00e4ssigkeit noch um einen Gang h\u00f6her schaltet.<br \/>\nWenn das Security Research von Google schon mehrmals in Richtung Microsoft signalisierte, dass Sicherheitsl\u00fccken in ihrem System entdeckt wurden, dann sollten bei Microsoft s\u00e4mtliche Alarmglocken schrillen. Das macht aus meiner Sicht keinen guten Eindruck auf Kunden, denen ein stabil sicheres System gegen grobe Malware oder gar Exploits versprochen wurde. Der Defender ist nicht irgendein zu vernachl\u00e4ssigendes Programm, sondern Kernst\u00fcck und auch bei Deskmodder propagierter Garant f\u00fcr ein sicheres Bewegen im Netz. Und das auch bei aller Ber\u00fccksichtigung und aktiver Vorsicht, was man sich wo herunterl\u00e4dt. Diese Eigenverantwortung sollte grunds\u00e4tzlich die geforderte Voraussetzung sein, die man erwarten darf. Und nat\u00fcrlich, eine legitime Forderung an die User, die auch Microsoft von seinen Kunden erwarten darf, wenn man Windows nutzt.  <\/p>\n<p>Das ist ok und ist selbstverst\u00e4ndlich akzeptabel. <\/p>\n<p>Richtig ist aber auch, dass die Erwartungshaltung an ein technisches System im allgemeinen (Hardware oder Software) 2 Dinge von den Kunden erwartet werden: 1. Gr\u00f6\u00dftm\u00f6gliche Sicherheit und 2. stabile Zuverl\u00e4ssigkeit in der Allgemein-Performance.<\/p>\n<p>Solange hier noch Defizite erkennbar sind, solange mu\u00df noch daran gearbeitet werden.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB) - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB)\" \/>\n<meta property=\"og:description\" content=\"Heute ist es nun soweit. Die erste Windows 10 10240 bekommt ab heute keine Sicherheitsupdates mehr. Eigentlich h\u00e4tte schon im M\u00e4rz Schluss sein m\u00fcssen, aber man hat das Ende in den Mai verschoben. Somit erhalten die CB und CBB Versionen&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-09T11:50:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1105\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB)\",\"datePublished\":\"2017-05-09T11:50:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/\"},\"wordCount\":226,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/10240.jpg\",\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/\",\"name\":\"Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB) - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/10240.jpg\",\"datePublished\":\"2017-05-09T11:50:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/10240.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/10240.jpg\",\"width\":1105,\"height\":496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/09\\\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB) - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/","og_locale":"de_DE","og_type":"article","og_title":"Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB)","og_description":"Heute ist es nun soweit. Die erste Windows 10 10240 bekommt ab heute keine Sicherheitsupdates mehr. Eigentlich h\u00e4tte schon im M\u00e4rz Schluss sein m\u00fcssen, aber man hat das Ende in den Mai verschoben. Somit erhalten die CB und CBB Versionen&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-05-09T11:50:34+00:00","og_image":[{"width":1105,"height":496,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB)","datePublished":"2017-05-09T11:50:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/"},"wordCount":226,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240.jpg","articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/","name":"Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB) - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240.jpg","datePublished":"2017-05-09T11:50:34+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240.jpg","width":1105,"height":496},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/09\/keine-updates-mehr-fuer-windows-10-1507-10240-ausser-ltsb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Keine Updates mehr f\u00fcr Windows 10 1507 10240 (ausser LTSB)"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/05\/10240.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/84381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=84381"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/84381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/84382"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=84381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=84381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=84381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}