{"id":83050,"date":"2017-05-08T20:57:39","date_gmt":"2017-05-08T18:57:39","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=83050"},"modified":"2019-08-02T15:21:23","modified_gmt":"2019-08-02T13:21:23","slug":"so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/","title":{"rendered":"So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus"},"content":{"rendered":"<p>Wer den Fu\u00dfball liebt, der schaut jedes Spiel im Fernsehen. Wer den Sport liebt, freut sich auf Olympia 2018. Und wer Abends gerne einen Blockbuster sehen m\u00f6chte, der schaut RTL, Sat.1 und Co. In der Zeit von 4K oder sogar 8K wirkt das Bild des TV-Ger\u00e4tes oft milchig und unscharf. Die eigene Mannschaft ist auf dem 60 Zoll Fernseher kaum noch zu erkennen und Olympia gibt&#8217;s nicht mal bei den HD-Sendern ARD oder ZDF. Doch mit HD+ kommt nahezu jeder Sport in gestochen scharfer Qualit\u00e4t ins Haus.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd.jpg\" rel=\"lightbox[83050]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-83051\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-500x193.jpg\" alt=\"\" width=\"557\" height=\"215\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-500x193.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-306x118.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-810x313.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd.jpg 1314w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><\/a><\/p>\n<p>4K Streaming bei Netflix und Amazon, UHD bei Sky Deutschland und Full-HD bei YouTube sind nur wenige Beispiele von der heutigen Qualit\u00e4t im Ton- und Bildbereich. Und beim Fernsehen? Da geht es nat\u00fcrlich auch. Die Zeiten von schlechten Bildern, unscharfen Texten und rauschenden T\u00f6nen sind schon seit Jahren vorbei. Fernseher werden immer gr\u00f6\u00dfer und bieten gro\u00dfe Versprechungen. &#8222;UHD&#8220; oder &#8222;4K&#8220; werden gro\u00df auf den Kartons der Ger\u00e4te angepriesen. Allerdings ist das UHD-Angebot im linearen TV noch relativ \u00fcberschaubar.<\/p>\n<p>Wer die Leistungsf\u00e4higkeit des TV-Ger\u00e4tes maximal ausnutzen m\u00f6chte, kommt um Satellit kombiniert mit einem HD+ Abo nicht herum. Auf Basis des HD-Eingangssignals k\u00f6nnen UHD-Ger\u00e4te ein imposantes Bild hochrechnen. Zus\u00e4tzlich betreibt HD+ den Demosender UHD1, der in UHD gedrehtes Filmmaterial sendet. Auch ohne UHD-Fernseher lohnt sich HD+, denn nur mit dem Abo k\u00f6nnen 23 deutsche Privatsender in HD-Qualit\u00e4t empfangen werden. Was hinter HD+ steckt, wie man es installiert und welche Vorteile es bringt, werde ich in diesem Beitrag ausf\u00fchrlich beschreiben.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/uhd.jpg\" rel=\"lightbox[83050]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-83053\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/uhd-500x246.jpg\" alt=\"\" width=\"500\" height=\"246\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/uhd-500x246.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/uhd-306x150.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/uhd.jpg 655w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><strong>Was ist HD+?<\/strong><\/p>\n<p>HD+ ist ein Unternehmen, welches aktuell 23\u00a0der gro\u00dfen privaten Sender in HD \u00fcber Satellit anbietet. Durch eine Smartcard, einen Receiver, einem Sky-Abo oder durch IPTV kann jeder RTL, Sat.1, ProSieben und weitere in guter und scharfer Qualit\u00e4t schauen. Dazu gibt es \u00fcber 30 frei empfangbare HD-Sender wie ARD, ZDF, NDR oder auch Sky Sport News HD, HSE24 HD. Satellit mit HD+ bietet damit das gr\u00f6\u00dfte lineare HD-Angebot. Die Vorteile sind unten detailliert aufgef\u00fchrt.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wie installiere ich HD+?<\/strong><\/p>\n<p>Wie gerade schon beschrieben, gibt es viele M\u00f6glichkeiten ein HD+ Abo zu erwerben. Wer Fernsehen \u00fcber Satellit schaut, kann sich einen HD+ Receiver kaufen oder ein HD+ Modul, das in die vorgesehenen CI-Spalte am Fernseher gesteckt wird. Nach einer kurzen \u00dcberpr\u00fcfung ist HD+ freigeschaltet.\u00a0Alternativ kann man sich auch einen HD-Receiver kaufen, der ebenfalls eine Smartcard integriert hat. Dadurch werden auch Kunden ins Boot geholt, die keinen CI-Plus-Schacht haben. Wer Entertain Sat oder Sky besitzt, kann HD+ zu seinem bisherigen Abo dazu buchen. Die Freischaltung sollte hier ebenfalls schnell vonstatten gehen. Kabelkunden hingegen m\u00fcssen das Angebot des Anbieters wahrnehmen, um in den Genuss von HD zu kommen. Informationen findet man oft auf den jeweiligen Webseiten oder bei der Support-Hotline.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-receiver.jpg\" rel=\"lightbox[83050]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-83414\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-receiver-500x170.jpg\" alt=\"\" width=\"500\" height=\"170\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-receiver-500x170.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-receiver-306x104.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-receiver-810x275.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-receiver.jpg 1375w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><strong>Welche Vorteile hat HD+?<\/strong><\/p>\n<p>Wer Sportfreund ist und sich gerne tagelang vor den Fernseher setzt, um Olympia zu schauen, konnte dies bis dato in der ARD oder beim ZDF tun. Seit letztem Jahr ist aber klar: Die Rechte sind neu vergeben und ARD und ZDF werden Olympia 2018 nicht \u00fcbertragen. Doch f\u00fcr HD+ Nutzer stellt dies kein Problem dar. Der Sender Eurosport 1, der die Rechte erlangt hat, kann \u00fcber die Smartcard in HD empfangen werden und somit gibt es auch hier keinen technisch-grafischen Unterschied\u00a0mehr zur vorherigen Berichterstattung.<\/p>\n<p>Neben dem gr\u00f6\u00dften Ereignis Olympia gibt es aber auch andere Sportarten, die in HD noch besser aussehen. So l\u00e4uft z.B. im Mai die Eishockey-WM auf SPORT1 HD. Handball auf SPORT1 HD und Fu\u00dfball auf RTL HD sind ebenfalls zwei gr\u00f6\u00dfere Beispiele, denn auch hier haben die \u00f6ffentlich-rechtlichen Sender keine Rechte bekommen.\u00a0 Die privaten Sender sind weiter auf dem Vormarsch und werden ihr Angebot k\u00fcnftig weiter ausbauen, da macht es doch wirklich keinen Spa\u00df mehr, Pixel zu z\u00e4hlen oder? <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" style=\"height: 1em; max-height: 1em;\" \/><br \/>\nDazu muss man aber sagen, dass HD+ nach und nach bessere Qualit\u00e4ten als 1080i mitbringt. Bei der RTL-Group und der Sat1.ProSieben GmbH ist das vorerst Standard.<\/p>\n<p style=\"text-align: center;\"><em>Ich nutze auch seit ein paar Wochen das Angebot von HD+ und m\u00f6chte davon auch nicht mehr weg. Ich bin ebenfalls fu\u00dfballbegeistert und schaue mir gerne Spiele der deutschen Nationalmannschaft auf RTL an. Neidisch wurde ich an dem Punkt, wo andere ein &#8222;Public Viewing&#8220; gestartet haben und auf ihrem 60 Zoll Fernseher RTL HD stand. Der Unterschied ist wirklich gro\u00df und ich kann es empfehlen.<\/em><\/p>\n<p style=\"text-align: left;\">HD+ Karte f\u00fcr 12 Monate mit CI+ (1.2) Modul: <a href=\"https:\/\/www.amazon.de\/HD-PLUS-Modul-inkl-Satellitenempfang\/dp\/B0035KMZN2\/ref=sr_1_2?ie=UTF8&amp;qid=1492696414&amp;sr=8-2&amp;keywords=HD%2B\/?tag=deskmodderde-21\">Amazon.de<\/a><\/p>\n<p style=\"text-align: left;\">HD+ Karte f\u00fcr 6 Monate mit CI+ (1.3) Modul: <a href=\"https:\/\/www.amazon.de\/dp\/B01E2XX3X6?ref=emc_b_5_t\/?tag=deskmodderde-21\">Amazon.de<\/a><br \/>\n> <em>Hier ist CI+ Standard 1.3 vorgesehen, dieser bringt schnellere Umschaltzeiten und optional UHD Unterst\u00fctzung<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer den Fu\u00dfball liebt, der schaut jedes Spiel im Fernsehen. Wer den Sport liebt, freut sich auf Olympia 2018. Und wer Abends gerne einen Blockbuster sehen m\u00f6chte, der schaut RTL, Sat.1 und Co. In der Zeit von 4K oder sogar&hellip; <\/p>\n","protected":false},"author":2650,"featured_media":83051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286,152],"tags":[3546,7312,2369,16982,2632,7775,16981,3751,2718,3985,16984,1833,882,16983,1929,2431,164],"class_list":["post-83050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","category-software","tag-4k","tag-8k","tag-amazon","tag-ci","tag-fernseher","tag-film","tag-full","tag-fussball","tag-hd","tag-netflix","tag-olympia","tag-ram","tag-samsung","tag-serie","tag-sony","tag-streaming","tag-tv"],"wp_featured_image":{"id":83051,"alt_text":"","description":"","media_type":"image","media_details":{"width":1314,"height":507,"file":"2017\/04\/hd.jpg","sizes":{"thumbnail":{"file":"hd-306x118.jpg","width":306,"height":118,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-306x118.jpg"},"medium":{"file":"hd-500x193.jpg","width":500,"height":193,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-500x193.jpg"},"large":{"file":"hd-810x313.jpg","width":810,"height":313,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-810x313.jpg"},"wp_review_large":{"file":"hd-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-320x200.jpg"},"wp_review_small":{"file":"hd-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-65x65.jpg"},"blog-large":{"file":"hd-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-642x300.jpg"},"blog-medium":{"file":"hd-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-306x205.jpg"},"recent-thumb":{"file":"hd-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-350x316.jpg"},"service-featured":{"file":"hd-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-600x330.jpg"},"wp_rp_thumbnail":{"file":"hd-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"Tim Westerhoff","camera":"","caption":"","created_timestamp":"1492108077","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":83050,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd.jpg"},"commentcount":58,"wp_comments":[{"id":48238,"parent":0,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-08T21:18:58","cld_nonce":"d8513d7dba","content":{"rendered":"<h1 style=\"color:red; text-align:center; font-weight: bold;\">Kleiner Hinweis:<\/h1>\n<p><center>Wir wissen, dass dies ein kontroverses Thema ist, w\u00fcrden euch aber trotzdem bitten unsere \u2192 <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewtopic.php?f=189&#038;t=2076\" >Netiquette<\/a> \u2190 einzuhalten. Bei Verst\u00f6\u00dfen werde ich die Texte entweder umschreiben oder entfernen. Sollte es zu wiederholten Verst\u00f6\u00dfen kommen, dann werde ich auch die tempor\u00e4re &#8222;Bannkeule&#8220; schwingen. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/center><\/p>\n"},"status":"1"},{"id":48210,"parent":0,"author":0,"author_name":"Siebenhof","author_email":"akoerner@netcologne.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/2f1d3e76c596e8aa0ce1a43f3457f523d0f2d208c2b9e618cfa59be3e636c2bc?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/2f1d3e76c596e8aa0ce1a43f3457f523d0f2d208c2b9e618cfa59be3e636c2bc?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/2f1d3e76c596e8aa0ce1a43f3457f523d0f2d208c2b9e618cfa59be3e636c2bc?s=96&d=mm&r=g"},"date":"2017-05-08T21:29:24","cld_nonce":"d8513d7dba","content":{"rendered":"<p>wie tief wollt ihr eigentlich noch sinken?<\/p>\n"},"status":"1"},{"id":48211,"parent":0,"author":0,"author_name":"Kommentator","author_email":"Usio1948@cuvox.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/39bffe7d8fe9914b2ebe7b53ab6f312e283161adae0f76774cfd8295c0b8029b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/39bffe7d8fe9914b2ebe7b53ab6f312e283161adae0f76774cfd8295c0b8029b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/39bffe7d8fe9914b2ebe7b53ab6f312e283161adae0f76774cfd8295c0b8029b?s=96&d=mm&r=g"},"date":"2017-05-08T21:29:28","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Da hier Kommentare gel\u00f6scht werden: Screenshot gemacht und als Tipmail an andere Medien und Blogs senden. Und via Twitter. Aber erst sp\u00e4ter wenn du schl\u00e4fst. Wird ein tolles Erwachen. Man bel\u00fcgt keine Leser und macht ungekennzeichnete Werbung. Noch hast du die Chance zum l\u00f6schen.<\/p>\n"},"status":"1"},{"id":48212,"parent":48211,"author":2650,"author_name":"TimboTillo","author_email":"dschungelapp@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g"},"date":"2017-05-08T21:33:10","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Hallo @Kommentator, <\/p>\n<p>Ich habe den vorherigen Kommentar aufgrund einer falschen Tatsachenbehauptung gel\u00f6scht. Dieser Beitrag soll keine Werbung oder desgleichen darstellen, sondern lediglich die Vorteile des Produkts zeigen. Es ist wie andere Testberichte gleichzusetzen. Inwiefern siehst du denn hier negatives? Das w\u00fcrde mich sehr interessieren. LG Tim.<\/p>\n"},"status":"1"},{"id":48213,"parent":48210,"author":2650,"author_name":"TimboTillo","author_email":"dschungelapp@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g"},"date":"2017-05-08T21:34:56","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Hallo @Siebenhof. Ich verstehe nicht genau, wieso dieser Beitrag so schlecht ankommt. Ich habe versucht, die Vorteile von HD+ zu beschreiben, die ich selbst getestet habe. Wie meine anderen Testberichte, ist auch dieser in der Art und Weise gleichzusetzen. Ich habe lediglich das Produkt beschrieben und die Vorteile kenntlich gemacht.<\/p>\n"},"status":"1"},{"id":48214,"parent":0,"author":0,"author_name":"Joh'","author_email":"acls86@me.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b09518d13503e7904ecbfdc507bede0925d46b6229a08c2e5034746b0ad3770c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b09518d13503e7904ecbfdc507bede0925d46b6229a08c2e5034746b0ad3770c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b09518d13503e7904ecbfdc507bede0925d46b6229a08c2e5034746b0ad3770c?s=96&d=mm&r=g"},"date":"2017-05-08T21:41:31","cld_nonce":"d8513d7dba","content":{"rendered":"<p>wow&#8230;. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":48217,"parent":48211,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-08T21:52:23","cld_nonce":"d8513d7dba","content":{"rendered":"<p>@Kommentator<br \/>\nEs gibt drei selbstverst\u00e4ndliche Regeln hier bei uns: 1. Bevor wir irgendwelche Unterstellungen machen, kann man den Autor auch lieb darauf hinweisen, dass einem der Artikel wie Werbung vorkommt und dieser, falls es so sein sollte, noch kennzeichnen soll. 2.  Haben wir das Recht Kommentare zu l\u00f6schen. 3. Wir Autoren d\u00fcrfen uns doch f\u00fcr etwas begeistern oder nicht? Weil ansonsten k\u00f6nnte man alle meine AMD-Beitr\u00e4ge auch als Werbung abstempeln.<\/p>\n<p>PS: Ich wei\u00df, dass HD+ ein sehr schwieriges Thema ist. Jeder hat eben eine subjektive Sicht auf die Pixelanzahl.<\/p>\n"},"status":"1"},{"id":48218,"parent":48214,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-08T21:53:26","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Du meinst: <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":48219,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-05-08T21:59:54","cld_nonce":"d8513d7dba","content":{"rendered":"<p>&#8222;Wer den Fu\u00dfball liebt, der schaut jedes Spiel im Fernsehen.&#8220; &#8211; das macht Herr Hugo nur bei bestimmten Spielen &#8211; z.B. dem WM-Endspiel 2014.<\/p>\n<p>Da hat er anderes getan und kurz nach der Halbzeit mal geguckt. Die Zeit gemerkt &#8211; kurz vor Schlu\u00df wieder geguckt. Aaah &#8211; Verl\u00e4ngerung. Zeit gemerkt und die letzten 5 Minuten geguckt &#8211; schie\u00dfen die Gauchos noch ein Tor? Neien &#8211; Klappe zu, Affe tot.<\/p>\n<p>Ein erfolgreicher Abend f\u00fcr Fu\u00dfballliebhaber Herr Hugo. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<br \/>\nKurz zum Thema: mir reichen die HD-Sender von Kabel D\/Vodafone ganz gut aus.<\/p>\n"},"status":"1"},{"id":48220,"parent":48212,"author":0,"author_name":"Co Commentator","author_email":"brainswap@koeln.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7c7257acfa32d126b48dd916840e836fa5475eada08d8fe346a2d359287661a1?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7c7257acfa32d126b48dd916840e836fa5475eada08d8fe346a2d359287661a1?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7c7257acfa32d126b48dd916840e836fa5475eada08d8fe346a2d359287661a1?s=96&d=mm&r=g"},"date":"2017-05-08T22:01:51","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Tolles Klima heute!<\/p>\n<p>Ich verstehe nur nicht, warum sich eine Plusterbacke mit Spass an Drohungen &#8222;Kommentator&#8220; nennt&#8230;<br \/>\nZum Inhalt:<\/p>\n<p>Ich wohne innerst\u00e4dtisch und hab keine Satellitensch\u00fcssel.<br \/>\nKomme aber mit Dvbt2 gut zurecht.<\/p>\n<p>Aber Vorsicht:<\/p>\n<p>Das ist total legal!<br \/>\nUnd kostet Geld.<br \/>\nEine Pizza im Monat.<\/p>\n<p>Beste Gr\u00fc\u00dfe!<\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":48221,"parent":48219,"author":2650,"author_name":"TimboTillo","author_email":"dschungelapp@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g"},"date":"2017-05-08T22:04:21","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Hallo Herr Hugo <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/> Wir sind ja trotzdem Weltmeister geworden und das ist auch gut so&#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":48223,"parent":48217,"author":0,"author_name":"winmx","author_email":"winm10@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/429ea8ec1937a07d31f6838de7edbe69468c6654398cde322fc7220b49bc446a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/429ea8ec1937a07d31f6838de7edbe69468c6654398cde322fc7220b49bc446a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/429ea8ec1937a07d31f6838de7edbe69468c6654398cde322fc7220b49bc446a?s=96&d=mm&r=g"},"date":"2017-05-08T22:39:18","cld_nonce":"d8513d7dba","content":{"rendered":"<p>wahrscheinlich geht es um den Amazon Link, der mit einem Advertising Code verbunden ist? <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_surprised.gif\" alt=\":eek:\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":48224,"parent":48210,"author":2371,"author_name":"Birkuli","author_email":"zbk8x@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=96&d=mm&r=g"},"date":"2017-05-08T22:42:48","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Hallo <b>destruktive Kritiker*<\/b>,<br \/>\nihr seid euch glaub ich nicht dar\u00fcber im Klaren, dass die hier geleistete Arbeit in der <b>Freizeit<\/b> von nicht durch irgendwelche Geb\u00fchren oder L\u00f6hne abgedeckten Menschen stattfindet, die sowohl ihr Herzblut als auch ihre Freizeit damit verbringen f\u00fcr alle <b>kostenlos<\/b> Beitr\u00e4ge zu sammeln und zu verfassen, ebenso leisten diverse freiwillige Helfer hier kostenlos f\u00fcr die User tolle Arbeit.<br \/>\nWenn einige der Meinung sind hier <b>Prinzessin oder B\u00f6sewicht*<\/b> spielen zu k\u00f6nnen so empfehle ich euch, euch hinzusetzen und Texte oder Tutorials zu verfassen, ihr m\u00fcsst nicht einmal perfekt in DTP sein, das \u00fcbernehmen auch noch die Redakteure f\u00fcr euch in ihrer Freizeit, also wenn ihr Meckerer es anders oder eurer Meinung nach besser k\u00f6nnt, immer her mit euren Beitr\u00e4gen ansonsten begebt* euch zu den \u00fcblichen Troll Foren aber lasst uns hier in Ruhe unser Ding machen.<br \/>\nWenn jemand ein Problem hat so kann er gerne \u00fcber die Tipp Box oder eine PN Kontakt aufnehmen und sachlich seine Meinung kundtun.*<br \/>\nMal f\u00fcr die Kritiker klargestellt, jedes Produkt \u00fcber das berichtet wird, stellt eine positiv oder negativ Werbung da, das liegt nun mal so in der Sache begr\u00fcndet.<br \/>\n<b>*<\/b><br \/>\nSch\u00f6ne Gr\u00fc\u00dfe Birkuli<br \/>\nNein, ich geh\u00f6re nicht zum Deskmodder Team und vertrete auch nicht deren Meinung dazu in der \u00d6ffentlichkeit.<\/p>\n<p><i>Alle Stellen mit einem * wurden der Netiquette entsprechend eingeschr\u00e4nkt und\/ oder paraphrasiert, sodass der Sinn erhalten bleibt. &#8211; Max<\/i><\/p>\n"},"status":"1"},{"id":48225,"parent":48223,"author":2650,"author_name":"TimboTillo","author_email":"dschungelapp@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g"},"date":"2017-05-08T23:00:07","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Das ist ja immer so&#8230; Bei allen Produkten, die man kaufen kann <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_surprised.gif\" alt=\":-o\" class=\"wp-smiley\" \/><\/p>\n<p>Da h\u00e4tte ich ja nichts neues gemacht <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":48226,"parent":48213,"author":0,"author_name":"Ingo","author_email":"ich@ingoboettcher.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5a0c425eb8c121489d0b36b2c85effdf0e649ea529265c4b90c7ce062790cf52?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5a0c425eb8c121489d0b36b2c85effdf0e649ea529265c4b90c7ce062790cf52?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5a0c425eb8c121489d0b36b2c85effdf0e649ea529265c4b90c7ce062790cf52?s=96&d=mm&r=g"},"date":"2017-05-08T23:01:45","cld_nonce":"d8513d7dba","content":{"rendered":"<p>In einem Test beschreibt man normalerweise relativ n\u00fcchtern die Vor- und Nachteile, die m\u00f6glichen Optionen und Alternativen. Das alles findet sich hier nicht.<br \/>\nHier wird einfach nur HD+ bejubelt, darunter finden sich Affiliate-Links zum Kauf. Das nennt sich Werbung. Insofern ist es relativ klar, warum der Beitrag schlecht ankommt.<br \/>\nIch w\u00fcsste nicht, warum man ein Kommentar-Feld unter einem Beitrag hat, wenn man dann kritische Kommentare per PN schicken soll? Ihr schreibt gen\u00fcgend tolle Artikel, aber dieser hier ist Mist.<\/p>\n"},"status":"1"},{"id":48227,"parent":48226,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-08T23:27:59","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Wir haben nicht gesagt, dass man seine Kritik per PN schicken soll. Man kann aber sachliche und konstruktive Kritik in den Kommentaren verlangen. Siehe auch unsere \u2192 <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewtopic.php?f=189&#038;t=2076\" >Netiquette<\/a><\/p>\n<p>M\u00f6chte man wirklich Dampf ablasen, dann kann man gerne eine E-Mail an &#8222;\/dev\/0&#8220; schicken. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n<p>PS: Bez\u00fcglich den Links ist auch der Kommentar \u2192 <a href=\"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/#comment-48228\">hier<\/a> \u2190 interessant.<\/p>\n"},"status":"1"},{"id":48228,"parent":48223,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-08T23:32:37","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Die Amazon-Links sind bei uns meist Affiliate-Links, da wir durch diese unter anderem auch unsere Server-Kosten decken. Diese Links sind auch so gekennzeichnet, n\u00e4mlich durch das ausgef\u00fcllte K\u00e4stchen mit dem Pfeil. Mehr dazu \u2192 <a href=\"https:\/\/www.deskmodder.de\/blog\/deskmodder-de-team\/#transparenz\">hier<\/a> \u2190. Alle normalen Links, welche unsere Seite verlassen, haben kein ausgef\u00fclltes K\u00e4stchen.<\/p>\n"},"status":"1"},{"id":48229,"parent":48226,"author":0,"author_name":"qwert73","author_email":"galkauskaite@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=96&d=mm&r=g"},"date":"2017-05-08T23:35:18","cld_nonce":"d8513d7dba","content":{"rendered":"<p>ich bin ja nicht zartbeseitet, aber wenn mir f\u00fcr Begriffe wie Jungspund schon mal von offizieller Seite hatespeech vorgeworfen wurde, dann bitte ich doch h\u00f6flichst darum, sich das *Post von birkuli genauer anzuschauen. Danke sch\u00f6n!<br \/>\n<br \/>\n<i>Alle Stellen mit einem * wurden der Netiquette entsprechend eingeschr\u00e4nkt und\/ oder paraphrasiert, sodass der Sinn erhalten bleibt. \u2013 Max<\/i><\/p>\n"},"status":"1"},{"id":48231,"parent":48226,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-08T23:41:17","cld_nonce":"d8513d7dba","content":{"rendered":"<p>@qwert73 Soweit war ich noch nicht.<\/p>\n"},"status":"1"},{"id":48232,"parent":0,"author":0,"author_name":"qwert73","author_email":"galkauskaite@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=96&d=mm&r=g"},"date":"2017-05-08T23:42:48","cld_nonce":"d8513d7dba","content":{"rendered":"<p>MAX, k\u00f6nnt Ihr nicht eine Sparte einrichten, wo alle unzensiert und ungezwungen \u00fcbereinander herfallen k\u00f6nnen, und am Ende derjenige als Sieger hervorgeht, der die derbsten Beleidigungen und Punchlines ausst\u00f6\u00dft?<\/p>\n"},"status":"1"},{"id":48233,"parent":48232,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-08T23:52:34","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Gute Idee&#8230; ich schlage allen interessierten &#8222;e-chat.co&#8220; vor.<\/p>\n"},"status":"1"},{"id":48234,"parent":48226,"author":2371,"author_name":"Birkuli","author_email":"zbk8x@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=96&d=mm&r=g"},"date":"2017-05-08T23:54:54","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Hallo @Ingo,<br \/>\ndas eine oder andere mag aus Sicht des Betrachters ja so sein, aber hier ist weder der Raum noch die Zeit und M\u00f6glichkeit jetzt alle Alternativen zu diesem Produkt aufzulisten, hier ist nicht der \u00f6ffentlich rechtliche Rundfunk wo es bei Nicht Bewusster Werbung auf mehrfach Nennungen hinaus l\u00e4uft oder laufen muss, wenn du Alternativen haben m\u00f6chtest informiere dich gerne auf einschl\u00e4gigen Seiten oder merke in der Kommentarfunktion wie es auch andere User tun Alternativen auf die auch andere interessieren k\u00f6nnten, davon lebt dieses Forum ja auch das alle sachliche und richtige Informationen bereitstellen.<br \/>\nSo sammeln sich Ideen, aber nicht, wenn einige nur unsachlich rummeckern.<br \/>\nInitiierte Werbung ist auch notwendig um die Infrastruktur des Servers und somit auch der gesamten Webpr\u00e4senz von Deskmodder zu erm\u00f6glichen oder sollen es die Redakteure auch noch neben ihrem unerm\u00fcdlichen Engagement zugemutet werden alles aus eigener Tasche zu bezahlen?<br \/>\nMit so einem geringen Budget eine solche Seite aufrecht zu erhalten und der \u00d6ffentlichkeit kostenfrei bereit zu stellen zollt Respekt an jeden einzelnen Redakteur und aller die still im Hintergrund ihren Beitrag dazu leisten und gerade jetzt, genau in diesen Moment ist die M\u00f6glichkeit eine PN zu schreiben an einem Redakteur der wohlgemerkt keine jahrelange Ausbildung genossen hat als Reporter oder staatlich gepr\u00fcfter Produkttester, also wenn dir etwas auff\u00e4llt teile es dem Redakteur in einer PN mit und er hat somit die M\u00f6glichkeit auf die Kritik oder im Besten Fall sogar Verbesserungsvorschl\u00e4ge zu reagieren und diese in den Artikel einflie\u00dfen zu lassen.<br \/>\nWenn es dir so am Herzen liegt @Ingo, kannst du ja gern als freiwilliger \u00fcber die Tipp Box eigene, deinen Anspr\u00fcchen gen\u00fcgende Beitr\u00e4ge einreichen, wir w\u00fcrden uns sicherlich dar\u00fcber freuen.<br \/>\nGru\u00df Birkuli<\/p>\n"},"status":"1"},{"id":48235,"parent":48226,"author":0,"author_name":"qwert73","author_email":"galkauskaite@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=96&d=mm&r=g"},"date":"2017-05-08T23:55:06","cld_nonce":"d8513d7dba","content":{"rendered":"<p>&#8222;Mann, diese meist anonymen Kommentatoren sind sowas von bemitleidenswert, es muss so schrecklich sein im Leben ein v\u00f6lliger Versager und eine absolute Null zu sein!&#8220;<\/p>\n<p>MAX, daran sieht man, wie unterschiedlich wir beide ticken k\u00f6nnen: Den meines Erachtens schlimmsten Satz l\u00e4sst Du stehen, blo\u00df weil er keine Kraftausdr\u00fccke enth\u00e4lt.<\/p>\n<p><i>Kritik aufgenommen und umgesetzt. &#8211; Max<\/i><\/p>\n"},"status":"1"},{"id":48236,"parent":48233,"author":0,"author_name":"qwert73","author_email":"galkauskaite@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=96&d=mm&r=g"},"date":"2017-05-08T23:59:32","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Mein Vorschlag: The Purge!<\/p>\n<p>Wer fair k\u00e4mpft, hat schon verloren!<\/p>\n"},"status":"1"},{"id":48237,"parent":48224,"author":2371,"author_name":"Birkuli","author_email":"zbk8x@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=96&d=mm&r=g"},"date":"2017-05-09T00:08:16","cld_nonce":"d8513d7dba","content":{"rendered":"<p>ok, danke Max, hiermit entschuldige ich mich f\u00fcr meine z\u00fcgellose Wortwahl, auch an alle zartbeseiteten hier, es war nicht so gemeint, eigentlich habe ich mich sogar noch ziemlich gebremmst aus R\u00fccksicht auf evtl. minderj\u00e4hrige Kinder und Jugendliche, ich nehme alles zur\u00fcck und behaupte das Gegenteil.<br \/>\nMein n\u00e4chster Satz \u00fcber solche*** enth\u00e4lt mindestens 200 Sternchen, also erspare ich Max das aussternen und @qwert73 tue ich auch nicht weh.<br \/>\nsch\u00f6ne Gr\u00fc\u00dfe Birkuli<\/p>\n"},"status":"1"},{"id":48239,"parent":48237,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-09T00:13:44","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Danke, nicht dass dann meine Sternchen-Taste klemmt. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":48240,"parent":48236,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-09T00:15:42","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Habe ich noch nie gesehen, ist aber bereits in der Watchliste. Eventuell kommt es ja auch bald im Fernsehen, dann kann ich es via Entertain und HD+ genie\u00dfen. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":48241,"parent":48236,"author":2371,"author_name":"Birkuli","author_email":"zbk8x@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=96&d=mm&r=g"},"date":"2017-05-09T00:19:59","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Hallo @qwert73,<br \/>\nich habe da mal eine frage an dich?<br \/>\nKannst du deinen Namen tanzen?<br \/>\nOder wurde dir beim Wort Pups der Mund mit Seife ausgewaschen?<br \/>\nok, jetzt bin ich wieder lieb, alles nicht so b\u00f6se gemeint aber manchmal brauchen einige *** so eine Ansage, weil die verstehen keine andere Sprache, wenn Mama hups sagt n\u00e4ssen die sich gleich ein.<br \/>\nJetzt kommen wieder 400 Sterne und jetzt ist mir besser.<br \/>\nGru\u00df Birkuli<\/p>\n<p>PS: Ich bin in den Hamburger Slums gro\u00df geworden, ich kann auch sehr, sehr b\u00f6se austeilen aber auch einstecken was die meisten Memmen eben nicht k\u00f6nnen die \u20ac die. ***<\/p>\n<p><i>Alle Stellen mit einem \u20ac wurden der Netiquette entsprechend eingeschr\u00e4nkt und\/ oder paraphrasiert, sodass der Sinn erhalten bleibt. &#8211; Max<\/i><\/p>\n"},"status":"1"},{"id":48243,"parent":0,"author":0,"author_name":"Timo","author_email":"Savefirmmails@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/cf7eaa9590fa5d1eb9d2811ec08cb7e7e3411090e4621d0c7b46a7d7744dfcca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/cf7eaa9590fa5d1eb9d2811ec08cb7e7e3411090e4621d0c7b46a7d7744dfcca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/cf7eaa9590fa5d1eb9d2811ec08cb7e7e3411090e4621d0c7b46a7d7744dfcca?s=96&d=mm&r=g"},"date":"2017-05-09T00:52:34","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Kastration des Receiver! <\/p>\n<p>Also hier fehlen eindeutig die gravierenden Nachteile von HD+!<br \/>\nZum Beispiel ist es nicht m\u00f6glich bei den privaten HD Sendern wie zum Beispiel Pro7 HD, RTL HD, usw. aufzunehmen, timeshift bzw vor oder zur\u00fcck zu sp\u00fclen. HD+ rentiert sich nach meiner Meinung \u00fcberhaupt nicht wenn man dann sowieso nur in SD aufnehmen kann.  Ich hab leider nicht dir Zeit und die Lust zu einer bestimmten Zeit am Fernseher sitzen zu M\u00dcSSEN!<\/p>\n"},"status":"1"},{"id":48244,"parent":48236,"author":0,"author_name":"qwert73","author_email":"galkauskaite@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=96&d=mm&r=g"},"date":"2017-05-09T01:09:19","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Mit solchen Spr\u00fcchen verlierst Du selbst im Kindergarten ein Battle, *!<\/p>\n<p><i>Alle Stellen mit einem * wurden der Netiquette entsprechend eingeschr\u00e4nkt und\/ oder paraphrasiert, sodass der Sinn erhalten bleibt. &#8211; Max<\/i><\/p>\n"},"status":"1"},{"id":48245,"parent":48243,"author":2371,"author_name":"Birkuli","author_email":"zbk8x@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=96&d=mm&r=g"},"date":"2017-05-09T01:09:32","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Hallo @Timo,<br \/>\nist das nicht ein generelles Merkmal bei den privaten HD Programmen auch bei den anderen Anbietern?<br \/>\nIch konnte das weder bei dem HD Paket von Kabel Deutschland\/Vodafone noch bei Magine im Internet oder mit dem Plus Modul per Satellit und ich nehme an es wird auch nicht bei meinem jetzigen Entertain m\u00f6glich sein, auch beim Sky Abo waren diese Dinge nicht mit dem HD Paket m\u00f6glich.<br \/>\nDas ist einfach so in den HDCP Regeln (Kopierschutz) vorgegeben! Bedarf also keiner besonderen Erw\u00e4hnung meiner Meinung nach.<br \/>\nWenn jeder Artikel erstmal in die Grundlagenerkl\u00e4rung gehen soll w\u00fcrde das den Rahmen wohl sprengen.<br \/>\nGru\u00df Birkuli<\/p>\n"},"status":"1"},{"id":48246,"parent":48236,"author":0,"author_name":"qwert73","author_email":"galkauskaite@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6c2ec42ee0d9eac0951d1fb545971dc4a004134365fbc5950821cc2806913881?s=96&d=mm&r=g"},"date":"2017-05-09T01:12:08","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Und wieviel Du einstecken kannst, wei\u00df ich von unserer Diskussion \u00fcber audiophilen Krempel: Nichts!<\/p>\n"},"status":"1"},{"id":48247,"parent":48236,"author":2371,"author_name":"Birkuli","author_email":"zbk8x@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=96&d=mm&r=g"},"date":"2017-05-09T01:21:15","cld_nonce":"d8513d7dba","content":{"rendered":"<p>ok @qwert73,<br \/>\nich beuge mich dieser geballten Macht und ziehe mich ehrfurchtsvoll und devot zur\u00fcck, denn mir gehen bei so harten Worten einfach die Sterne aus, gute Nacht John Boy, m\u00f6ge deine Welt heil sein.<br \/>\nGru\u00df Birkuli<\/p>\n<p>PS: Sobald ich weis wie &#8222;Netiquette&#8220; geschrieben wird, werde ich sofort auf selbige achten.<\/p>\n"},"status":"1"},{"id":48250,"parent":0,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icom.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/963c40fd856480e87f9e1b0dd273a6ea5e334168bc58bb36f67e654e0c32f243?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/963c40fd856480e87f9e1b0dd273a6ea5e334168bc58bb36f67e654e0c32f243?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/963c40fd856480e87f9e1b0dd273a6ea5e334168bc58bb36f67e654e0c32f243?s=96&d=mm&r=g"},"date":"2017-05-09T10:38:19","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Meiner Meinung nach, macht man mit der Hochaufl\u00f6sung neben den \u00fcblichen Geb\u00fchren ein zus\u00e4tzliches Gesch\u00e4ft. Ein Blick zur\u00fcck in die Vergangenheit: Als damals Willy Brandt auf den Roten Knopf dr\u00fcckte und die Bildr\u00f6hre farbig wurde, da wurden keine Zusatzkosten f\u00e4llig. <\/p>\n<p>Heute verlangt man f\u00fcr HD \u00dcbertragung, f\u00fcr 4k und bald auch f\u00fcr 8k Aufl\u00f6sung, eine ziemlich Stange Geld, wenn man noch die Zwangsgeb\u00fchren der \u00d6ffentlich-Rechtlichen hinzunimmt, die Zusatzgeb\u00fchren f\u00fcr die Privaten, die im Sommer diesen Jahres f\u00e4llig werden. Eigentlich hat sich ein un\u00fcbersichtliches Dickicht an Geb\u00fchren und f\u00fcr Zusatz-Features im Fernsehmarkt entwickelt.<\/p>\n"},"status":"1"},{"id":48251,"parent":0,"author":0,"author_name":"Roots","author_email":"jederman@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=96&d=mm&r=g"},"date":"2017-05-09T10:49:43","cld_nonce":"d8513d7dba","content":{"rendered":"<p>HI<br \/>\nDieser Post kommt doch sehr als Werbung her\u00fcber! Man k\u00f6nnte sich fragen, ob der Ersteller auch richtig entlohnt wurde.<\/p>\n<p>Es w\u00e4re sehr sch\u00f6n, wenn ein Kollege von TimboTillo mit Kabelanschluss einen ebenso euphorischen Artikel \u00fcber<br \/>\nUnitymedia oder KabelBW oder was auch immer, schreiben w\u00fcrde!<br \/>\nKlasse w\u00e4re dann, wenn man diese M\u00f6glichkeiten des HD-empfangs dann mit einander Vergleichen w\u00fcrde!!!!<br \/>\nAch, und da gibt es ja auch noch andere Empfangsm\u00f6glichkeiten!<br \/>\nStreamen von Netflix und Amazon, Sky Deutschland in HD oder besser. Was sind da die Vor- und\/oder Nachteile?<\/p>\n<p>Das w\u00e4re mal ein Artikel gewesen!!<\/p>\n"},"status":"1"},{"id":48252,"parent":48250,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-05-09T10:50:14","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Absolutes +1 Peter. Es ist schon irre, mit welchen Mitteln versucht wird Geld zu machen. Immerhin sind es werbefinanzierte Sender (Ausser Sky..) die so noch mehr Geld kassieren wollen.<\/p>\n"},"status":"1"},{"id":48255,"parent":0,"author":0,"author_name":"Oldie","author_email":"Oldie@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1452ac165a0427f576292bb04a6fe8043ecbe0b39ea2b1203cf47b0eb732d31a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1452ac165a0427f576292bb04a6fe8043ecbe0b39ea2b1203cf47b0eb732d31a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1452ac165a0427f576292bb04a6fe8043ecbe0b39ea2b1203cf47b0eb732d31a?s=96&d=mm&r=g"},"date":"2017-05-09T11:14:00","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Moin,<br \/>\nes ist schon erstaunlich, mit welchen Mitteln uns versucht wird, die gute alte Bildqualit\u00e4t eines R\u00f6hrenfernsehers wieder unterzujubeln. Wer die Ehre hat, bei Oma noch mal einen R\u00f6hren-TV bestaunen zu d\u00fcrfen, fragt sich echt, warum heute nicht mehr&#8230;HD; HD+ 4K; 8K usw. und der ganze Quatsch dazu, die Bildqualit\u00e4t war einfach besser (abgesehen mal von Messwerten, die das Auge eh nicht wahr nimmt). Ein riesen Beschiss heutzutage&#8230;.<\/p>\n"},"status":"1"},{"id":48259,"parent":48252,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2017-05-09T11:47:45","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Ich bin ein Anh\u00e4nger (aus volkswirtschaftlichen Gr\u00fcnden) der sozialen Marktwirtschaft. Und \u00fcberall dort. wo sich Privatisierungen wie eine Krake ausbreiten, hinterl\u00e4sst sie zumindest in bestimmten Bereichen der \u00f6ffentlichen Daseinsvorsorge eine Spur der gesellschaftlichen Verw\u00fcstung. Public Partner Privateship (PPP) wird so ein Konstrukt euphemistisch genannt. Imgrunde ein Modell zur Enteignung bzw. ein Abkassierungsmodell, das den B\u00fcrgern als &#8222;freie&#8220; Marktwirtschaft verkauft wird.<br \/>\nEin technisch hochqualitatives Fernsehen und Rundfunk sollte nicht in die H\u00e4nde von Investoren gelegt werden. Genauso wenig Wasserwerke, Stromerzeuger und last but not least der Wohnungsbau. Und auch nicht der Ausbau der Breitbandnetze, der Verkehrswege.<br \/>\nSolche lukrativen Projekte wecken im Kapitalismus Begehrlichkeiten, weil sie hohe Rendite-Versprechen in Aussicht stellen. So kommt es, dass sich hier ein asozial wirkender Markt entwickelt. Nach dem Gesetz der \u00d6konomie eine Umverteilung von unten nach oben, die die verfassungsgerechte soziale Marktwirtschaft konterkariert. So zerst\u00f6rt man Gesellschaften und ihren Zusammenhalt.<\/p>\n"},"status":"1"},{"id":48261,"parent":48251,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-09T12:01:40","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Ich gebe zu, dass meine EntertainTV-Artikel  genauso euphorisch sind und daf\u00fcr zahlt man im Endeffekt noch mehr Geld als f\u00fcr HD+. Wie auch immer, wenn du die Suchfunktion benutzt wirst auch auf zahlreiche weitere Beitr\u00e4ge von uns kommen, in welchen die Qualit\u00e4t der einzelnen \u00dcbertragungswege angesprochen wird.<\/p>\n"},"status":"1"},{"id":48263,"parent":0,"author":2371,"author_name":"Birkuli","author_email":"zbk8x@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=96&d=mm&r=g"},"date":"2017-05-09T12:37:47","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Hallo @Oldie,<br \/>\nwenn es um die Wiedergabe von reinen SD Inhalten geht die nicht schon irgendwie durch den Anbieter Skaliert oder extrem komprimiert sind hat ein klassischer Fernseher der alten Technik eindeutig die Nase vorn, er wurde schlie\u00dflich daf\u00fcr optimiert und erf\u00fcllt dieses mit Bravour.<br \/>\nKommt jedoch HD ins Spiel so sind die M\u00f6glichkeiten der Bildwiedergabe eindeutig limitiert das Bild sieht zwar klarer aus aber es fehlt aufgrund einer v\u00f6llig anderen Matrix die Genauigkeit, ein SD Bild sieht auf einem Flachbildschirm einfach grausig aus da die beiden Formate eigentlich nicht zusammenpassen.<br \/>\nUnd die Top 34 Programme m\u00fcssen ja auch \u00fcberall doppelt und dreifach bezahlt werden und wenn in HD eben nochmal extra da das sogenannte Grundpaket immer mit gebucht werden muss ob man es nutzt oder nicht.<br \/>\nIch zahle mittlerweile den Grundschrott an meinen Vermieter durch einen Koppelvertrag, ca. 8.75\u20ac pro Monat (Kabel), 17.50\u20ac Rundfunkbeitrag (GEZ), 9.75\u20ac an die Telekom f\u00fcr Entertain und 6.50\u20ac f\u00fcr Magine TV f\u00fcr ein und dieselben Programme in unterschiedlicher Qualit\u00e4t, f\u00fcr HD kommen teils nochmal Aufschl\u00e4ge dazu, wenn ich es nutzen m\u00f6chte.<br \/>\nUnd es gibt noch mehr Angebote die sich das alles immer nochmal bezahlen lassen um an zwei drei brauchbare Sender zu gelangen.<br \/>\nGEZ und Kabel gibt es kein Entrinnen, weil die sich die Lizenz zum Gelddrucken gesichert haben.<br \/>\nDa ich hier weder Satellit noch DVBT2 was ja auch mittlerweile an ein ABO bei Freenet gebunden ist nutzen kann muss ich also jeweils den Monopolisten das Geld zahlen.<br \/>\nTja, die Huckleberry Finn Methode zieht immer noch und die Kuh wird gemolken bis sie tot umf\u00e4llt, immer und immer nochmal.<br \/>\nGru\u00df Birkuli<br \/>\nDer Vollst\u00e4ndigkeit halber sei erw\u00e4hnt das es noch viele andere hier nicht erw\u00e4hnte Firmen gibt.<\/p>\n"},"status":"1"},{"id":48266,"parent":48251,"author":2371,"author_name":"Birkuli","author_email":"zbk8x@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=96&d=mm&r=g"},"date":"2017-05-09T13:14:47","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Hallo @ Roots,<br \/>\nkann es sein das du Deskmodder.de mit gro\u00dfen Printmedien versuchst gleichzustellen? Oder verwechselst? Dort arbeiten in der Regel festangestellte Mitarbeiter oder Redakteure auf Honorar Basis die nichts Anderes machen und von vielen Firmen Test und Produktmuster bekommen.<br \/>\nHier \u201earbeiten\u201c technikbegeisterte Menschen unentgeltlich in ihrer Freizeit und erm\u00f6glichen den Zugang zu einem erheblichen Technik &amp; Wissens Fundus der kostenlos genutzt werden kann.<br \/>\nWenn der eine oder andere seine Begeisterung kundtut und andere User das mitteilt ist das eben so,<br \/>\ndie Sponsoren Links sind eindeutig gekennzeichnet und als solche auch zu erkennen.<br \/>\nWenn Tim oder Max \u00fcber einen Profi Fu\u00dfball Klub schreiben, wei\u00df doch wohl jeder das es noch 53 andere Profi Klubs in der Bundesliga gibt oder sollen allen Ernstes in jedem Beitrag alle 54 Bundesliga Klubs erw\u00e4hnt werden?<br \/>\nWas kommt dann? Ich m\u00f6chte jetzt gerne das die Beitr\u00e4ge gentrifiziert werden und dass auch alle Transgender und sonstige Gesellschaftsgruppen erw\u00e4hnt und ber\u00fccksichtigt werden.<br \/>\nSeid doch einfach einmal etwas dankbar und freut euch \u00fcber das kostenlose Angebot und n\u00f6rgelt nicht an allem rum.<br \/>\nEin Weg w\u00e4re z.B. wenn du jetzt ein Paar sinnvolle Verweise zusammengetragen h\u00e4ttest und das in deinem Kommentar f\u00fcr alle interessierten bereit gestellt h\u00e4ttest.<br \/>\nSo, ich haben fertig f\u00fcr den Moment<br \/>\nGru\u00df Birkuli<\/p>\n"},"status":"1"},{"id":48277,"parent":48266,"author":0,"author_name":"Roots","author_email":"jederman@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=96&d=mm&r=g"},"date":"2017-05-09T15:22:25","cld_nonce":"d8513d7dba","content":{"rendered":"<p>@MAX &amp; @Birkuli<\/p>\n<p>Ob die Page privater Natur ist oder Kommerziell l\u00e4sst sich auf den ersten Blick nicht erkennen.<br \/>\nAber dieser Artikel f\u00e4llt definitiv unter die Rubrik &#8222;Werbung&#8220;!<\/p>\n<p>Gut, wenn Kollege TimboTillo von hochaufl\u00f6sendem TV so begeistert ist, h\u00e4tte er es ja auch so beschreiben k\u00f6nnen!<\/p>\n<p>Wie z.B. Hei, habe jetzt HD+. Man ist das toll (geil) &#8230;. usw. etw. Aber TimboTillo reitet so auf HD+, als g\u00e4be es nichts besseres.<br \/>\nUnd an Hand einiger anderer Reaktionen hier im Forum, bin ich ja nicht der Einzige, der diesen Artikel jetzt nicht f\u00fcr so gelungen h\u00e4lt.<br \/>\nNehmt diese Kritik doch einfach mal so an, versucht ein anderes Mal daran zu denken und macht einfach weiter gute &#8222;Nachrichten&#8220;, das macht Ihr ja meist.<\/p>\n"},"status":"1"},{"id":48278,"parent":48245,"author":0,"author_name":"Roots","author_email":"jederman@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=96&d=mm&r=g"},"date":"2017-05-09T15:27:27","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Bei Unitymedia in Hessen kann ich sehr wohl in HD aufnehmen! Einzig bei einigen Sendern kann man nicht vorspulen!<\/p>\n"},"status":"1"},{"id":48281,"parent":48277,"author":0,"author_name":"Roots","author_email":"jederman@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d72971c7a45aa7b4b91099e78d63422db2f250cb8ed3dc98ef97742d3a138a3a?s=96&d=mm&r=g"},"date":"2017-05-09T15:47:13","cld_nonce":"d8513d7dba","content":{"rendered":"<p>So, habe das IMPRESSUM gelesen und auch das DESKMODDER.DE TEAM be\u00e4ugt.<br \/>\nNun wei\u00df ich, es ist Euer Hobby, dass mich meist erfreut. Danke.<\/p>\n<p>Doch auch wenn jemand mal einen Artikel kritisiert, geht nicht gleich mit der Keule auf ihn los.<br \/>\nIch habe mich sehr bem\u00fcht meinen Eindruck kund zu tun und hatte das Gef\u00fchl daf\u00fcr gleich verdroschen zu werden.<\/p>\n<p>Dennoch, macht weiter so und habt Spa\u00df dabei und erfreut mich mit Euren Eindr\u00fccken und Berichten.<\/p>\n"},"status":"1"},{"id":48282,"parent":48277,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-09T16:07:15","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Ich wollte nicht mit der Keule auf dich losgehen, tut mir leid, falls du das so empfunden hast. Aber wenn einer mit Satzzeichen nur so um sich wirft, dann kann man aber auch keine andere Reaktion erwarten. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":48283,"parent":48263,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2017-05-09T16:20:53","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Zumal schon l\u00e4ngst in HD f\u00fcr das Fernsehen produziert wird. Die Kosten f\u00fcr die Kameras sind l\u00e4ngst erwirtschaftet. Auch die Hardware, Bildmischer und Tonmischer, Monitore,  sind nicht das Problem und stehen l\u00e4ngst in den Studios. Avid als Editing-Software hat l\u00e4ngst 8k implementiert.  <\/p>\n<p>Also, prinzipiell sind f\u00fcr uns Produzenten, Postproduzenten, Synchron-Studios wie Fernsehanbieter keine Mehrkosten im Saldo. Was hier gerade von RTL und Co. intendiert wird, dass Mehrkosten durch HD oder UHD entstehen w\u00fcrden, ist wei\u00dfe Salbe, die man den Kunden in die Augen schmiert: In Eintracht mit den Anbietern f\u00fcr die Fernsehkan\u00e4le! Eine regelrechte Entente, ja &#8222;zum Gelddrucken&#8220;, wie Birkuli das zu Recht nennt. Abzocke eben.<\/p>\n"},"status":"1"},{"id":48284,"parent":48283,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-09T16:28:44","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Soweit ich das verstanden habe, kosten vor allem die gr\u00f6\u00dferen \u00dcbertragungskapazit\u00e4ten mehr.<\/p>\n"},"status":"1"},{"id":48288,"parent":48284,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2017-05-09T17:17:59","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Ja&#8230;so wird es kolportiert. Aber die \u00dcbertragungsdaten ben\u00f6tigen keine Neu-Investitionen in die Studio-Hardware, nebst Aufnahmetechnik (die sind schon l\u00e4ngst verf\u00fcgbar), sondern ben\u00f6tigen allenfalls ein fl\u00e4chendeckendes Breitbandnetz. Das ist aber nicht Aufgabe f\u00fcr eine Investitionst\u00e4tigkeit des produzierenden Gewerbes. Die Netzprovider haben sozusagen einen Pakt mit den Programmanbietern geschlossen und sagen: Wir finanzieren den Netzausbau und ihr macht das Programm. Folge: Netzanbieter verdienen, Programmanbieter verdienen; beide an Zuschl\u00e4gen, die noch oben drauf auf die schon bestehenden hinzukommen.<br \/>\nDer Netzausbau m\u00fcsste aber im Sinne einer Teilhabe am techn. Fortschritt allen gleicherma\u00dfen zugute kommen; unabh\u00e4ngig vom Geldbeutel. Und daher ist meiner Meinung nach der Netzausbau eine sozialpolitische Aufgabe der Politik.<\/p>\n"},"status":"1"},{"id":48289,"parent":48263,"author":0,"author_name":"Peter","author_email":"peter_ustinow@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e2f205723a85ef0199def843d3ac8dc13a80f86f026ecb4fb3919a3982c5dbb9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e2f205723a85ef0199def843d3ac8dc13a80f86f026ecb4fb3919a3982c5dbb9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e2f205723a85ef0199def843d3ac8dc13a80f86f026ecb4fb3919a3982c5dbb9?s=96&d=mm&r=g"},"date":"2017-05-09T17:18:37","cld_nonce":"d8513d7dba","content":{"rendered":"<p>DVB-t 2 ist keinesfalls an ein Freenetabo gebunden.<\/p>\n"},"status":"1"},{"id":48292,"parent":48289,"author":2371,"author_name":"Birkuli","author_email":"zbk8x@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a553036c2f7af853278a81ee4aa7477d5f3fb38729d81ed2a701c38fe1a0528c?s=96&d=mm&r=g"},"date":"2017-05-09T18:03:10","cld_nonce":"d8513d7dba","content":{"rendered":"<p>um die privaten und eine Handvoll Randsender zu sehen doch schon, oder? Nur die Grundsender der \u00f6ffentlich rechtlichen sind doch frei empfangbar oder bin ich da falsch informiert?<br \/>\noder tut Freenet nur so als ob es ohne nicht ginge?<\/p>\n"},"status":"1"},{"id":48294,"parent":48292,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2017-05-09T18:05:34","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Ist schon richtig Birkuli. Aber die \u00f6ffentlichen kann man auch ohne Freenet empfangen.<\/p>\n"},"status":"1"},{"id":48296,"parent":48292,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2017-05-09T18:36:17","cld_nonce":"d8513d7dba","content":{"rendered":"<p>So ist es. Und wenn man sich nicht aus den Kabelgeb\u00fchren verabschieden kann, weil man stattdessen DVB-t2 Nutzen m\u00f6chte, dann kommen die Abo-Geb\u00fchren noch oben drauf, zus\u00e4tzlich zu den Geb\u00fchren f\u00fcr das \u00f6ffentlich-rechtliche Angebot. Die Privaten glauben, sie k\u00f6nnten so erwas wie GEZ einf\u00fchren, weil die hohen Marktanteile ihnen das signalisierten.<br \/>\nDer Kunde hat die M\u00f6glichkeit, seine Marktmacht dahingehend auszuspielen, indem er sich den Privaten verweigert und das Soiel nicht mitmacht. Zur Info: 1 Minute Werbezeit bei RTL kosten, je nach Attraktivit\u00e4t des ausgestrahlten Programms, bis zu 100 000\u20ac. Anscheinend reicht die Marge bei den Anbietern nicht.<\/p>\n"},"status":"1"},{"id":48297,"parent":0,"author":0,"author_name":"Kyamidos","author_email":"ingo.leiner@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7f4eb3841ea51c447ea31b63704d2959afb0ebbcbcc817d17ab4d36b18abe31b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7f4eb3841ea51c447ea31b63704d2959afb0ebbcbcc817d17ab4d36b18abe31b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7f4eb3841ea51c447ea31b63704d2959afb0ebbcbcc817d17ab4d36b18abe31b?s=96&d=mm&r=g"},"date":"2017-05-09T18:44:30","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Also wenn ich bef\u00fcrchte das meinem Gehirn gro\u00dfer Schaden zugef\u00fcgt wurde, h\u00f6re ich mir immer die 10. Sinfonie von Robert Simpson an. Da ist dann alles wieder gut; sozusagen eine kleine einsame Klanginsel die das unausl\u00f6schlich Gute im Menschen repr\u00e4sentiert. Ganz uneigenn\u00fctzig liegt sie da im tosenden Ozean, achja &#8230;  <\/p>\n<p>Nein, nichts mehr. Ich bin jetzt da &#8230;<\/p>\n"},"status":"1"},{"id":48302,"parent":48284,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-09T19:43:42","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Das meine ich gar nicht. Ich meine zum Beispiel die Kapazit\u00e4ten auf dem Satelliten, welche je h\u00f6her die Bandbreite wird, auch immer teurer und knapper werden.<\/p>\n"},"status":"1"},{"id":48305,"parent":48278,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-05-09T19:47:55","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Genau aufnehmen ist immer m\u00f6glich, aber nicht vorspulen, weil man ja die Werbung \u00fcberspulen k\u00f6nnte&#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":48370,"parent":0,"author":118,"author_name":"Gumfuzi","author_email":"deskmodder.de@noweb.at","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f1bc2c203701f27d2dde3720ed7f08333a7654f9aa87d73e429ceb3f14076533?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f1bc2c203701f27d2dde3720ed7f08333a7654f9aa87d73e429ceb3f14076533?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f1bc2c203701f27d2dde3720ed7f08333a7654f9aa87d73e429ceb3f14076533?s=96&d=mm&r=g"},"date":"2017-05-10T17:32:34","cld_nonce":"d8513d7dba","content":{"rendered":"<p>1. auf das RTL (&#038; Co)-&#8222;Bildungs&#8220;-fernsehen kann ich gerne verzichten, das wird auch in HD nicht besser&#8230; Werbung in HD, ach wie toll!<br \/>\n2. nicht nur die Pixelanzahl\/Aufl\u00f6sung ist wichtig, sondern auch die Datenrate und wie das Ausgangsmaterial war.<\/p>\n<p>Ich pers\u00f6nlich finde diese &#8222;+&#8220;-Einschr\u00e4nkungen (HD+, CI+, etc.) v\u00f6llig unn\u00f6tig und umst\u00e4ndlich f\u00fcr den Kunden &#8211; aber die Werbung muss man sich ansehen (oder meist eben nicht, weil ein Toilettenbesuch, etc. ansteht). Schade.<\/p>\n<p>Ich gucke lieber via Internet, da gibt es (noch!) nicht so viel bzw. gar keine Werbung.<\/p>\n"},"status":"1"},{"id":49515,"parent":0,"author":0,"author_name":"Winfried Kaempfer","author_email":"winniwinni@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4e900d595b714e320badaeb707c077cfe3f6e2b940a7569eb2d35bebe157420f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4e900d595b714e320badaeb707c077cfe3f6e2b940a7569eb2d35bebe157420f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4e900d595b714e320badaeb707c077cfe3f6e2b940a7569eb2d35bebe157420f?s=96&d=mm&r=g"},"date":"2017-06-08T14:11:00","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Leider sind die Umschaltzeiten bei den verschl\u00fcsselten Sender auf meinem Samsung TV sehr lange!<\/p>\n"},"status":"1"},{"id":49522,"parent":49515,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2017-06-08T17:35:55","cld_nonce":"d8513d7dba","content":{"rendered":"<p>Ja, das liegt an der Verschl\u00fcsselung und den langsamen Prozessoren in vielen SmartTVs. Sollte aber immer besser werden.<\/p>\n"},"status":"1"}],"wp_author":{"id":2650,"name":"TimboTillo","description":"Word, PowerPoint waren meine ersten Erfahrungen mit der Computer-Welt. Immer mehr lernte ich neue M\u00f6glichkeiten und Funktionen kennen. Richtig wohl f\u00fchle ich mich im Netzwerkbereich, mit Windows 11 und ganz viel WLAN :-)!","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g"}},"cld_nonce":"d8513d7dba","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus\" \/>\n<meta property=\"og:description\" content=\"Wer den Fu\u00dfball liebt, der schaut jedes Spiel im Fernsehen. Wer den Sport liebt, freut sich auf Olympia 2018. Und wer Abends gerne einen Blockbuster sehen m\u00f6chte, der schaut RTL, Sat.1 und Co. In der Zeit von 4K oder sogar&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/timwesterhoffnoh\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-08T18:57:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-02T13:21:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1314\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TimboTillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/TimWesterhoff98\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/\"},\"author\":{\"name\":\"TimboTillo\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3ef642d5524caf1553c054f014206d7\"},\"headline\":\"So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus\",\"datePublished\":\"2017-05-08T18:57:39+00:00\",\"dateModified\":\"2019-08-02T13:21:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/\"},\"wordCount\":785,\"commentCount\":58,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/hd.jpg\",\"keywords\":[\"4k\",\"8k\",\"Amazon\",\"CI\",\"fernseher\",\"film\",\"Full\",\"Fu\u00dfball\",\"HD\",\"Netflix\",\"Olympia\",\"RAM\",\"Samsung\",\"Serie\",\"Sony\",\"Streaming\",\"TV\"],\"articleSection\":{\"1\":\"Hardware\",\"2\":\"Software &amp; Updates\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/\",\"name\":\"So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/hd.jpg\",\"datePublished\":\"2017-05-08T18:57:39+00:00\",\"dateModified\":\"2019-08-02T13:21:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/hd.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/hd.jpg\",\"width\":1314,\"height\":507},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/05\\\/08\\\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3ef642d5524caf1553c054f014206d7\",\"name\":\"TimboTillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g\",\"caption\":\"TimboTillo\"},\"description\":\"Word, PowerPoint waren meine ersten Erfahrungen mit der Computer-Welt. Immer mehr lernte ich neue M\u00f6glichkeiten und Funktionen kennen. Richtig wohl f\u00fchle ich mich im Netzwerkbereich, mit Windows 11 und ganz viel WLAN :-)!\",\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/timwesterhoffnoh\",\"https:\\\/\\\/www.instagram.com\\\/tim_westerhoff\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/TimWesterhoff98\"],\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/timbotillo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/","og_locale":"de_DE","og_type":"article","og_title":"So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus","og_description":"Wer den Fu\u00dfball liebt, der schaut jedes Spiel im Fernsehen. Wer den Sport liebt, freut sich auf Olympia 2018. Und wer Abends gerne einen Blockbuster sehen m\u00f6chte, der schaut RTL, Sat.1 und Co. In der Zeit von 4K oder sogar&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_author":"http:\/\/www.facebook.com\/timwesterhoffnoh","article_published_time":"2017-05-08T18:57:39+00:00","article_modified_time":"2019-08-02T13:21:23+00:00","og_image":[{"width":1314,"height":507,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd.jpg","type":"image\/jpeg"}],"author":"TimboTillo","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/TimWesterhoff98","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/"},"author":{"name":"TimboTillo","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3ef642d5524caf1553c054f014206d7"},"headline":"So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus","datePublished":"2017-05-08T18:57:39+00:00","dateModified":"2019-08-02T13:21:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/"},"wordCount":785,"commentCount":58,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd.jpg","keywords":["4k","8k","Amazon","CI","fernseher","film","Full","Fu\u00dfball","HD","Netflix","Olympia","RAM","Samsung","Serie","Sony","Streaming","TV"],"articleSection":{"1":"Hardware","2":"Software &amp; Updates"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/","name":"So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd.jpg","datePublished":"2017-05-08T18:57:39+00:00","dateModified":"2019-08-02T13:21:23+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd.jpg","width":1314,"height":507},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/05\/08\/so-kommen-mit-dem-hd-modul-ueber-50-sender-in-brillanter-hd-qualitaet-ins-haus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"So kommen mit dem HD+ Modul \u00fcber 50 Sender in Full HD- oder UHD-Qualit\u00e4t ins Haus"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3ef642d5524caf1553c054f014206d7","name":"TimboTillo","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g","caption":"TimboTillo"},"description":"Word, PowerPoint waren meine ersten Erfahrungen mit der Computer-Welt. Immer mehr lernte ich neue M\u00f6glichkeiten und Funktionen kennen. Richtig wohl f\u00fchle ich mich im Netzwerkbereich, mit Windows 11 und ganz viel WLAN :-)!","sameAs":["http:\/\/www.facebook.com\/timwesterhoffnoh","https:\/\/www.instagram.com\/tim_westerhoff\/","https:\/\/x.com\/https:\/\/twitter.com\/TimWesterhoff98"],"url":"https:\/\/www.deskmodder.de\/blog\/author\/timbotillo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/hd.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/83050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2650"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=83050"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/83050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/83051"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=83050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=83050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=83050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}