{"id":81071,"date":"2017-03-09T09:21:01","date_gmt":"2017-03-09T08:21:01","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=81071"},"modified":"2017-03-09T09:52:26","modified_gmt":"2017-03-09T08:52:26","slug":"sticky-notes-1-7-1-im-slow-ring-mit-aenderungen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/","title":{"rendered":"Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen"},"content":{"rendered":"<p>Die Fast-Ring Insider sind noch mit der 1.6.2.0 unterwegs aber die Slow-Ring Insider k\u00f6nnen schon die neue Version 1.7.1.0 testen. Die Notizen sind nun mit einem neuen Schatten ausgestattet worden und auch eine hellere Akzentfarbe wurde hinzugef\u00fcgt. Die Farben selber wurden einheitlicher gestaltet und kommen etwas sch\u00e4rfer zur Geltung.<\/p>\n<p>Auch ein Fehler wurde behoben, dass die letzten \u00c4nderungen verlorengegangen sind, wenn man die Notizen geschlossen hatte. Kleine aber feine \u00c4nderungen. Wer weiterhin lieber mit den alten Notizen arbeiten m\u00f6chte, kann dies auch weiterhin. Denn nicht jeder mag die neuen &#8222;modernen&#8220; Haftzettel auf dem Desktop. Auch wenn sie nun schon um einige Funktionen erweitert wurden. Info und Download <a href=\"https:\/\/www.deskmodder.de\/blog\/2016\/07\/21\/windows-10-1607-alte-kurznotizen-sticky-notes-installieren-und-nutzen\/\" target=\"_blank\"><b> HIER<\/b><\/a><\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171.jpg\" rel=\"lightbox[81071]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-500x310.jpg\" alt=\"\" width=\"500\" height=\"310\" class=\"aligncenter size-medium wp-image-81072\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-500x310.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-306x190.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171.jpg 516w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Quelle: Feedback-Hub<\/p>\n<!-- WP-Appbox (Version: 4.5.13 \/\/ Store: microsoftstore \/\/ ID: 9nblggh4qghw) -->\n<div class=\"wpappbox wpappbox-243d8d0436f6f61c34881bf9bdc4e27b microsoftstore simple\">\n\t<div class=\"qrcode\"><img decoding=\"async\" src=\"https:\/\/api.qrserver.com\/v1\/create-qr-code\/?data=https%3A%2F%2Fwww.microsoft.com%2Fde-de%2Fstore%2Fp%2Fapp%2F9nblggh4qghw&size=200x200&ecc=M&margin=0\" alt=\"Microsoft Sticky Notes\" \/><\/div>\n\t<div class=\"appicon\">\n\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/app\/9nblggh4qghw\" aria-label=\"Microsoft Sticky Notes\"><img decoding=\"async\" src=\"\/\/store-images.s-microsoft.com\/image\/apps.62870.13510798887395106.d232eea9-7c05-49ea-9867-26ad069802b8.d560cf38-6023-4e62-ab2c-fd57aa870986?w=180&#038;h=180&#038;q=60\" alt=\"Microsoft Sticky Notes\" \/><\/a>\n\t<\/div>\n\t<div class=\"applinks\">\n\t\t<div class=\"appbuttons\">\n\t\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/app\/9nblggh4qghw\" aria-label=\"Microsoft Sticky Notes\">Download<\/a>\n\t\t\t<span onMouseOver=\"jQuery('.wpappbox-243d8d0436f6f61c34881bf9bdc4e27b .qrcode').show();\" onMouseOut=\"jQuery('.wpappbox-243d8d0436f6f61c34881bf9bdc4e27b .qrcode').hide();\">QR-Code<\/span>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"appdetails\">\n\t\t<div class=\"apptitle\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/app\/9nblggh4qghw\" title=\"Microsoft Sticky Notes\" aria-label=\"Microsoft Sticky Notes\" class=\"apptitle\">Microsoft Sticky Notes<\/a><\/div>\n\t\t<div class=\"developer\">\n\t\t\t<span class=\"label\">Entwickler: <\/span>\n\t\t\t<span class=\"value\">Microsoft Corporation<\/span>\n\t\t<\/div>\n\t\t<div class=\"price\">\n\t\t\t<span class=\"label\">Preis: <\/span>\n\t\t\t<span class=\"value\">Kostenlos<\/span> \n\t\t\t<span class=\"rating\"><div title=\"3.5 von 5 Sternen\" class=\"rating-stars stars-monochrome stars35\"><\/div><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div><!-- \/WP-Appbox -->\n","protected":false},"excerpt":{"rendered":"<p>Die Fast-Ring Insider sind noch mit der 1.6.2.0 unterwegs aber die Slow-Ring Insider k\u00f6nnen schon die neue Version 1.7.1.0 testen. Die Notizen sind nun mit einem neuen Schatten ausgestattet worden und auch eine hellere Akzentfarbe wurde hinzugef\u00fcgt. Die Farben selber&hellip; <\/p>\n","protected":false},"author":134,"featured_media":81072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[16346,5247,12413],"class_list":["post-81071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-1-7-1","tag-changelog","tag-sticky-notes"],"wp_featured_image":{"id":81072,"alt_text":"","description":"","media_type":"image","media_details":{"width":516,"height":320,"file":"2017\/03\/sticky-notes-171.jpg","sizes":{"thumbnail":{"file":"sticky-notes-171-306x190.jpg","width":306,"height":190,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-306x190.jpg"},"medium":{"file":"sticky-notes-171-500x310.jpg","width":500,"height":310,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-500x310.jpg"},"wp_review_large":{"file":"sticky-notes-171-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-320x200.jpg"},"wp_review_small":{"file":"sticky-notes-171-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-65x65.jpg"},"blog-large":{"file":"sticky-notes-171-516x300.jpg","width":516,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-516x300.jpg"},"blog-medium":{"file":"sticky-notes-171-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-306x205.jpg"},"recent-thumb":{"file":"sticky-notes-171-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-350x316.jpg"},"wp_rp_thumbnail":{"file":"sticky-notes-171-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":81071,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen\" \/>\n<meta property=\"og:description\" content=\"Die Fast-Ring Insider sind noch mit der 1.6.2.0 unterwegs aber die Slow-Ring Insider k\u00f6nnen schon die neue Version 1.7.1.0 testen. Die Notizen sind nun mit einem neuen Schatten ausgestattet worden und auch eine hellere Akzentfarbe wurde hinzugef\u00fcgt. Die Farben selber&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-09T08:21:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-09T08:52:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"516\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen\",\"datePublished\":\"2017-03-09T08:21:01+00:00\",\"dateModified\":\"2017-03-09T08:52:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/\"},\"wordCount\":123,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/sticky-notes-171.jpg\",\"keywords\":[\"1.7.1\",\"changelog\",\"Sticky Notes\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/\",\"name\":\"Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/sticky-notes-171.jpg\",\"datePublished\":\"2017-03-09T08:21:01+00:00\",\"dateModified\":\"2017-03-09T08:52:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/sticky-notes-171.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/sticky-notes-171.jpg\",\"width\":516,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2017\\\/03\\\/09\\\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/","og_locale":"de_DE","og_type":"article","og_title":"Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen","og_description":"Die Fast-Ring Insider sind noch mit der 1.6.2.0 unterwegs aber die Slow-Ring Insider k\u00f6nnen schon die neue Version 1.7.1.0 testen. Die Notizen sind nun mit einem neuen Schatten ausgestattet worden und auch eine hellere Akzentfarbe wurde hinzugef\u00fcgt. Die Farben selber&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2017-03-09T08:21:01+00:00","article_modified_time":"2017-03-09T08:52:26+00:00","og_image":[{"width":516,"height":320,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen","datePublished":"2017-03-09T08:21:01+00:00","dateModified":"2017-03-09T08:52:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/"},"wordCount":123,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171.jpg","keywords":["1.7.1","changelog","Sticky Notes"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/","url":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/","name":"Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171.jpg","datePublished":"2017-03-09T08:21:01+00:00","dateModified":"2017-03-09T08:52:26+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171.jpg","width":516,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2017\/03\/09\/sticky-notes-1-7-1-im-slow-ring-mit-aenderungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Sticky Notes 1.7.1 im Slow Ring mit \u00c4nderungen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/sticky-notes-171.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/81071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=81071"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/81071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/81072"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=81071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=81071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=81071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}