{"id":79729,"date":"2018-02-18T09:45:51","date_gmt":"2018-02-18T08:45:51","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=79729"},"modified":"2023-01-14T17:09:34","modified_gmt":"2023-01-14T16:09:34","slug":"app-des-tages-maloud-webseiten-vorlesen-lassen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/","title":{"rendered":"App des Tages: mAloud Webseiten vorlesen lassen"},"content":{"rendered":"<p><strong>[Update 18.02.2018]:<\/strong> Die App ist mal wieder kostenlos im Angebot f\u00fcr knapp 10 Tage. Auch wenn die App ihren Dienst wirklich gut verrichtet, so ist der Ersteller der App AlticaSoft LLC doch ganz sch\u00f6n ausversch\u00e4mt. Eine Preiserh\u00f6hung auf nun 6,09 geht ja gerade noch in Ordnung. Die App dann aber mit Werbung auszuliefern ist einfach nur frech. Wer diese App trotzdem ben\u00f6tigen sollte findet unten den Link.<\/p>\n<p>[Update 12.11.2017]: mAloud ist wieder einmal kostenlos zu haben. Es bleiben noch knapp 10 Tage, um die App ohne Kosten herunterladen zu k\u00f6nnen. Gegen\u00fcber dem alten Artikel hat sich der Preis nun von 1,99 auf mal locker 5,09 Euro erh\u00f6ht, die man nun sparen kann. Laut Angaben im Microsoft Store hat man nun auch die Unterst\u00fctzung f\u00fcr Deutsch hinzugef\u00fcgt.<\/p>\n<p>Bisheriger Text 11.02.2017: Wer Probleme mit dem Lesen hat, oder sich nebenbei den Inhalt von Webseiten vorlesen lassen m\u00f6chte sollte sich die Universal App mAloud einmal anschauen. Die App gibt es noch knapp 3 Tage kostenlos im Microsoft Store. Der normale Preis betr\u00e4gt sonst 1,99$. Die App ist trotz des Preises mit Werbung ausgestattet. Ansonsten macht sie aber das, was man von ihr verlangt. Man gibt die Webseite ein und dr\u00fcckt auf den Play-Button. Die Geschwindigkeit kann man in drei Stufen ausw\u00e4hlen. Vorlesen lassen kann man sich die Seiten von &#8222;Stefan&#8220;, &#8222;Katja&#8220; oder &#8222;Hedda&#8220;. Je nach &#8222;Geschmack&#8220;. Beim Test von einigen Artikeln unserer Seite kann man sich nicht beklagen. Selbst Anleitungen mit Pfaden kamen gut r\u00fcber. Nur sollte man da die Geschwindigkeit heruntersetzen.<\/p>\n<div id='gallery-1' class='gallery galleryid-79729 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg' rel=\"lightbox[79729]\"><img loading=\"lazy\" decoding=\"async\" width=\"223\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-223x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-223x205.jpg 223w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-391x360.jpg 391w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-634x583.jpg 634w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg 858w\" sizes=\"auto, (max-width: 223px) 100vw, 223px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-002.jpg' rel=\"lightbox[79729]\"><img loading=\"lazy\" decoding=\"async\" width=\"223\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-002-223x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-002-223x205.jpg 223w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-002-392x360.jpg 392w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-002-634x583.jpg 634w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-002.jpg 857w\" sizes=\"auto, (max-width: 223px) 100vw, 223px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-003.jpg' rel=\"lightbox[79729]\"><img loading=\"lazy\" decoding=\"async\" width=\"224\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-003-224x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-003-224x205.jpg 224w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-003-393x360.jpg 393w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-003-636x583.jpg 636w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-003.jpg 859w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Ansonsten ist die App sehr einfach aufgebaut. Beim der \u00dcbersetzung im Men\u00fc sollte man nicht genau hinschauen. Aktie \u00f6ffnet das Freigeben-Men\u00fc. Aber damit kann man leben. Die App ist unter Windows 10 und Mobile, sowie Windows 8.1 einsetzbar.<\/p>\n<p>Wer sie einmal testen m\u00f6chte:<\/p>\n<p><!-- WP-Appbox (Version: 4.5.13 \/\/ Store: microsoftstore \/\/ ID: 9wzdncrfjhmg) -->\n<div class=\"wpappbox wpappbox-c78629b1d8516abe247ca0dbe04cfbc8 microsoftstore simple\">\n\t<div class=\"qrcode\"><img decoding=\"async\" src=\"https:\/\/api.qrserver.com\/v1\/create-qr-code\/?data=https%3A%2F%2Fwww.microsoft.com%2Fde-de%2Fstore%2Fp%2Fapp%2F9wzdncrfjhmg&size=200x200&ecc=M&margin=0\" alt=\"mAloud\" \/><\/div>\n\t<div class=\"appicon\">\n\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/app\/9wzdncrfjhmg\" aria-label=\"mAloud\"><img decoding=\"async\" src=\"\/\/store-images.s-microsoft.com\/image\/apps.31431.9007199266263123.14abe257-7ae0-4ff8-8ff6-fd2b9c57b769.d9baf4d4-34ce-43d7-b18c-d2cd6e22df2d?w=180&#038;h=180&#038;q=60\" alt=\"mAloud\" \/><\/a>\n\t<\/div>\n\t<div class=\"applinks\">\n\t\t<div class=\"appbuttons\">\n\t\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/app\/9wzdncrfjhmg\" aria-label=\"mAloud\">Download<\/a>\n\t\t\t<span onMouseOver=\"jQuery('.wpappbox-c78629b1d8516abe247ca0dbe04cfbc8 .qrcode').show();\" onMouseOut=\"jQuery('.wpappbox-c78629b1d8516abe247ca0dbe04cfbc8 .qrcode').hide();\">QR-Code<\/span>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"appdetails\">\n\t\t<div class=\"apptitle\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/app\/9wzdncrfjhmg\" title=\"mAloud\" aria-label=\"mAloud\" class=\"apptitle\">mAloud<\/a><\/div>\n\t\t<div class=\"developer\">\n\t\t\t<span class=\"label\">Entwickler: <\/span>\n\t\t\t<span class=\"value\">AlticaSoft LLC<\/span>\n\t\t<\/div>\n\t\t<div class=\"price\">\n\t\t\t<span class=\"label\">Preis: <\/span>\n\t\t\t<span class=\"value\">1,99 \u20ac<sup>+<\/sup><\/span> \n\t\t\t<span class=\"rating\"><div title=\"0 von 5 Sternen\" class=\"rating-stars stars-monochrome stars00\"><\/div><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div><!-- \/WP-Appbox --><br \/>\n<a href=\"https:\/\/www.microsoft.com\/de-de\/store\/p\/maloud\/9wzdncrfjhmg\" rel=\"noopener\" target=\"_blank\">https:\/\/www.microsoft.com\/de-de\/store\/p\/maloud\/9wzdncrfjhmg<\/a><\/p>\n<p>myappfree<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[Update 18.02.2018]: Die App ist mal wieder kostenlos im Angebot f\u00fcr knapp 10 Tage. Auch wenn die App ihren Dienst wirklich gut verrichtet, so ist der Ersteller der App AlticaSoft LLC doch ganz sch\u00f6n ausversch\u00e4mt. Eine Preiserh\u00f6hung auf nun 6,09&hellip; <\/p>\n","protected":false},"author":134,"featured_media":79730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689,11,3999],"tags":[16052,16053,9751,7485],"class_list":["post-79729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","category-windows","category-windos-phone","tag-maloud","tag-webseiten-vorlesen-lassen","tag-windows-10","tag-windows-10-mobile"],"wp_featured_image":{"id":79730,"alt_text":"","description":"","media_type":"image","media_details":{"width":858,"height":789,"file":"2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg","sizes":{"thumbnail":{"file":"maloud-webseiten-vorlesen-lassen-windows-10-001-223x205.jpg","width":223,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-223x205.jpg"},"medium":{"file":"maloud-webseiten-vorlesen-lassen-windows-10-001-391x360.jpg","width":391,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-391x360.jpg"},"large":{"file":"maloud-webseiten-vorlesen-lassen-windows-10-001-634x583.jpg","width":634,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-634x583.jpg"},"wp_review_large":{"file":"maloud-webseiten-vorlesen-lassen-windows-10-001-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-320x200.jpg"},"wp_review_small":{"file":"maloud-webseiten-vorlesen-lassen-windows-10-001-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-65x65.jpg"},"blog-large":{"file":"maloud-webseiten-vorlesen-lassen-windows-10-001-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-642x300.jpg"},"blog-medium":{"file":"maloud-webseiten-vorlesen-lassen-windows-10-001-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-306x205.jpg"},"recent-thumb":{"file":"maloud-webseiten-vorlesen-lassen-windows-10-001-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-350x316.jpg"},"service-featured":{"file":"maloud-webseiten-vorlesen-lassen-windows-10-001-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-600x330.jpg"},"wp_rp_thumbnail":{"file":"maloud-webseiten-vorlesen-lassen-windows-10-001-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":79729,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg"},"commentcount":6,"wp_comments":[{"id":43340,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-02-11T12:26:16","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8222;Wer Probleme mit dem Lesen hat, oder sich nebenbei den Inhalt von Webseiten vorlesen lassen m\u00f6chte&#8220;<\/p>\n<p>&#8211; wenn einer \u00fcberhaupt nicht lesen kann, warum auch immer &#8211; na ja<\/p>\n<p>&#8211; &#8222;nebenbei&#8220;? Da sei Gott vor &#8211; dieser monotone Singsang ist doch kaum zu ertragen<\/p>\n<p>&#8222;Die App ist trotz des Preises mit Werbung ausgestattet&#8220;<\/p>\n<p>Sehr fein ausgedr\u00fcckt, grins! Selbst bei Preis 0,- nervt die Blinki-Werbung. Ich will aber nicht nur meckern: einen Artikel von mir hat sie korrekt vorgelesen, mein &#8222;\u00c4\u00e4\u00e4h!&#8220; und &#8222;Herr Hugo&#8220; waren klar zu h\u00f6ren. Probs hat die App \u00b4n bi\u00dfchen, wenn im deutschen Text englische W\u00f6rter vorkommen.<\/p>\n"},"status":"1"},{"id":43356,"parent":0,"author":0,"author_name":"Thomas Bauer","author_email":"thomas.bauer1967@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b543c356018d1eae65a01e24901f591e8d1eeb364b94c1b9a79847abaf75beec?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b543c356018d1eae65a01e24901f591e8d1eeb364b94c1b9a79847abaf75beec?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b543c356018d1eae65a01e24901f591e8d1eeb364b94c1b9a79847abaf75beec?s=96&d=mm&r=g"},"date":"2017-02-11T18:12:31","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich f\u00e4nds besser wenn die App eine Erweiterung von Edge w\u00e4re oder zumindest die Favoriten verwenden w\u00fcrde. WIndows 10 ist echt ein Flickenteppich. Warum kann man Cortana nicht zum Vorlesen benutzen<\/p>\n"},"status":"1"},{"id":43367,"parent":43356,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2017-02-12T00:08:54","cld_nonce":"82f011626f","content":{"rendered":"<p>Das w\u00e4re nur ein Zusatzgrund, die App nicht zu nutzen. Edge &amp; Cortana &amp; die App &#8211; Feind(e)\u00b3 f\u00fcr Herrn Hugo. Sowas bewu\u00dft nicht zu nutzen macht mir fast schon Spa\u00df. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":59614,"parent":0,"author":2616,"author_name":"Henry Earth","author_email":"j-gieseke@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/49981eb5b27871570eadce104491cdfdc70523fbdf172c33b47a4dc90ddfc2f1?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/49981eb5b27871570eadce104491cdfdc70523fbdf172c33b47a4dc90ddfc2f1?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/49981eb5b27871570eadce104491cdfdc70523fbdf172c33b47a4dc90ddfc2f1?s=96&d=mm&r=g"},"date":"2017-11-12T13:57:01","cld_nonce":"82f011626f","content":{"rendered":"<p>Spielerei in meinen Augen , vor allem wenn ich nicht alles lesen oder gar h\u00f6ren will<\/p>\n"},"status":"1"},{"id":59616,"parent":0,"author":0,"author_name":"Manuel","author_email":"Manuel.Appelhoff@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6c6a537e2ce1e945d278bc43d3d55e9865f8514af142589623b5422951559576?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6c6a537e2ce1e945d278bc43d3d55e9865f8514af142589623b5422951559576?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6c6a537e2ce1e945d278bc43d3d55e9865f8514af142589623b5422951559576?s=96&d=mm&r=g"},"date":"2017-11-12T15:03:27","cld_nonce":"82f011626f","content":{"rendered":"<p>Seit dem Fall Creators Update kann Edge das von alleine ohne App\/Erweiterung.<br \/>\n+ kostenlos<br \/>\n+ mit der Geschwindigkeitsregelung<br \/>\n+ mit den genannten drei Stimmen<br \/>\n+ man kann den vorzulesenden Text markieren<br \/>\n&#8211; nur nicht f\u00fcr W10m und WP<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":59617,"parent":43356,"author":0,"author_name":"Manuel","author_email":"Manuel.Appelhoff@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6c6a537e2ce1e945d278bc43d3d55e9865f8514af142589623b5422951559576?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6c6a537e2ce1e945d278bc43d3d55e9865f8514af142589623b5422951559576?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6c6a537e2ce1e945d278bc43d3d55e9865f8514af142589623b5422951559576?s=96&d=mm&r=g"},"date":"2017-11-12T15:04:38","cld_nonce":"82f011626f","content":{"rendered":"<p>siehe meinen Kommentar <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>App des Tages: mAloud Webseiten vorlesen lassen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"App des Tages: mAloud Webseiten vorlesen lassen\" \/>\n<meta property=\"og:description\" content=\"[Update 18.02.2018]: Die App ist mal wieder kostenlos im Angebot f\u00fcr knapp 10 Tage. Auch wenn die App ihren Dienst wirklich gut verrichtet, so ist der Ersteller der App AlticaSoft LLC doch ganz sch\u00f6n ausversch\u00e4mt. Eine Preiserh\u00f6hung auf nun 6,09&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-18T08:45:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-14T16:09:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"858\" \/>\n\t<meta property=\"og:image:height\" content=\"789\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"App des Tages: mAloud Webseiten vorlesen lassen\",\"datePublished\":\"2018-02-18T08:45:51+00:00\",\"dateModified\":\"2023-01-14T16:09:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/\"},\"wordCount\":321,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg\",\"keywords\":[\"mAloud\",\"Webseiten vorlesen lassen\",\"Windows 10\",\"Windows 10 Mobile\"],\"articleSection\":[\"Windows 10\",\"Windows \u00e4lter\",\"Windows Mobile\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/\",\"name\":\"App des Tages: mAloud Webseiten vorlesen lassen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg\",\"datePublished\":\"2018-02-18T08:45:51+00:00\",\"dateModified\":\"2023-01-14T16:09:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg\",\"width\":858,\"height\":789},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/02\\\/18\\\/app-des-tages-maloud-webseiten-vorlesen-lassen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"App des Tages: mAloud Webseiten vorlesen lassen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"App des Tages: mAloud Webseiten vorlesen lassen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/","og_locale":"de_DE","og_type":"article","og_title":"App des Tages: mAloud Webseiten vorlesen lassen","og_description":"[Update 18.02.2018]: Die App ist mal wieder kostenlos im Angebot f\u00fcr knapp 10 Tage. Auch wenn die App ihren Dienst wirklich gut verrichtet, so ist der Ersteller der App AlticaSoft LLC doch ganz sch\u00f6n ausversch\u00e4mt. Eine Preiserh\u00f6hung auf nun 6,09&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-02-18T08:45:51+00:00","article_modified_time":"2023-01-14T16:09:34+00:00","og_image":[{"width":858,"height":789,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"App des Tages: mAloud Webseiten vorlesen lassen","datePublished":"2018-02-18T08:45:51+00:00","dateModified":"2023-01-14T16:09:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/"},"wordCount":321,"commentCount":6,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg","keywords":["mAloud","Webseiten vorlesen lassen","Windows 10","Windows 10 Mobile"],"articleSection":["Windows 10","Windows \u00e4lter","Windows Mobile"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/","name":"App des Tages: mAloud Webseiten vorlesen lassen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg","datePublished":"2018-02-18T08:45:51+00:00","dateModified":"2023-01-14T16:09:34+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg","width":858,"height":789},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/02\/18\/app-des-tages-maloud-webseiten-vorlesen-lassen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"App des Tages: mAloud Webseiten vorlesen lassen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/02\/maloud-webseiten-vorlesen-lassen-windows-10-001.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/79729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=79729"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/79729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/79730"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=79729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=79729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=79729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}