{"id":73087,"date":"2016-10-05T14:29:55","date_gmt":"2016-10-05T12:29:55","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=73087"},"modified":"2016-10-05T14:29:55","modified_gmt":"2016-10-05T12:29:55","slug":"facebook-stellt-lite-version-seines-messengers-bereit","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/","title":{"rendered":"Facebook stellt Lite-Version seines Messengers bereit"},"content":{"rendered":"<p>Ich bin kein Facebook-User und werde es wohl auch nicht mehr werden. Trotzdem einmal kurz dar\u00fcber informiert, dass Facebook diese Woche eine Lite-Version seines Messengers ver\u00f6ffentlicht hat. Die abgespeckte Version kann Nachrichten, Bilder, Links und Sticker senden und empfangen. Gegen\u00fcber der Vollversion ben\u00f6tigt der Lite Messenger aber geringere Hardware-Anforderungen. So ist die App selbst nur 10 MB gro\u00df (im Gegensatz zur Vollversion mit 50 MB) und ben\u00f6tigt auch sonst weniger Hardware-Ressourcen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-73091\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-777x583.png\" alt=\"mlite-staticnwsrm-final\" width=\"777\" height=\"583\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-777x583.png 777w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-273x205.png 273w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-480x360.png 480w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final.png 1368w\" sizes=\"auto, (max-width: 777px) 100vw, 777px\" \/><\/p>\n<p>Lite- und Vollversion sind miteinander kompatibel sofern man keine Funktion der Vollversion nutzt, welche die Lite-Ausgabe nicht unterst\u00fctzt. Gedacht ist der Messenger f\u00fcr Schwellenl\u00e4nder, in welchen schnelles Internet noch nicht \u00fcberall vorhanden ist. Aktuell verf\u00fcgbar ist der Facebook Messenger Lite in\u00a0Kenia, Tunesien, Malaysia, Sri Lanka und Venezuela. Nach und nach sollen weitere L\u00e4nder folgen.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"http:\/\/newsroom.fb.com\/news\/2016\/10\/empowering-the-world-to-stay-connected-introducing-messenger-lite\/\" target=\"_blank\">Facebook<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ich bin kein Facebook-User und werde es wohl auch nicht mehr werden. Trotzdem einmal kurz dar\u00fcber informiert, dass Facebook diese Woche eine Lite-Version seines Messengers ver\u00f6ffentlicht hat. Die abgespeckte Version kann Nachrichten, Bilder, Links und Sticker senden und empfangen. Gegen\u00fcber&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":73091,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,152],"tags":[14654],"class_list":["post-73087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-software","tag-facebook-messenger-lite"],"wp_featured_image":{"id":73091,"alt_text":"","description":"","media_type":"image","media_details":{"width":1368,"height":1026,"file":"2016\/10\/mlite-staticnwsrm-final.png","sizes":{"thumbnail":{"file":"mlite-staticnwsrm-final-273x205.png","width":273,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-273x205.png"},"medium":{"file":"mlite-staticnwsrm-final-480x360.png","width":480,"height":360,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-480x360.png"},"large":{"file":"mlite-staticnwsrm-final-777x583.png","width":777,"height":583,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-777x583.png"},"wp_review_large":{"file":"mlite-staticnwsrm-final-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-320x200.png"},"wp_review_small":{"file":"mlite-staticnwsrm-final-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-65x65.png"},"blog-large":{"file":"mlite-staticnwsrm-final-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-642x300.png"},"blog-medium":{"file":"mlite-staticnwsrm-final-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-306x205.png"},"recent-thumb":{"file":"mlite-staticnwsrm-final-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-350x316.png"},"service-featured":{"file":"mlite-staticnwsrm-final-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-600x330.png"},"wp_rp_thumbnail":{"file":"mlite-staticnwsrm-final-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":73087,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final.png"},"commentcount":2,"wp_comments":[{"id":29525,"parent":0,"author":0,"author_name":"Dave 1985","author_email":"dave@aol.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e7338e02f01656648a222c99078a1fe83fdb1a9da351cda8ded2fb4dfc4f54f6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e7338e02f01656648a222c99078a1fe83fdb1a9da351cda8ded2fb4dfc4f54f6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e7338e02f01656648a222c99078a1fe83fdb1a9da351cda8ded2fb4dfc4f54f6?s=96&d=mm&r=g"},"date":"2016-10-05T14:51:55","cld_nonce":"82f011626f","content":{"rendered":"<p>Download APK<\/p>\n<p><a href=\"http:\/\/beste-apps.chip.de\/android\/getfile\/cxo.100979577\/\" rel=\"nofollow ugc\">http:\/\/beste-apps.chip.de\/android\/getfile\/cxo.100979577\/<\/a><\/p>\n"},"status":"1"},{"id":29528,"parent":0,"author":0,"author_name":"Thomas Bauer","author_email":"thomas.bauer1967@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b543c356018d1eae65a01e24901f591e8d1eeb364b94c1b9a79847abaf75beec?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b543c356018d1eae65a01e24901f591e8d1eeb364b94c1b9a79847abaf75beec?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b543c356018d1eae65a01e24901f591e8d1eeb364b94c1b9a79847abaf75beec?s=96&d=mm&r=g"},"date":"2016-10-05T15:42:30","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich hatte vor einiger Zeit mal die Beta Version von Facebook Lite getestet. Leider unterst\u00fctzte die Lite-Version keinen Landscape Mode f\u00fcr Tablets oder Smartphones. Oder wurde da nachgebessert? Wei\u00df da jemand n\u00e4heres?<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Facebook stellt Lite-Version seines Messengers bereit - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facebook stellt Lite-Version seines Messengers bereit\" \/>\n<meta property=\"og:description\" content=\"Ich bin kein Facebook-User und werde es wohl auch nicht mehr werden. Trotzdem einmal kurz dar\u00fcber informiert, dass Facebook diese Woche eine Lite-Version seines Messengers ver\u00f6ffentlicht hat. Die abgespeckte Version kann Nachrichten, Bilder, Links und Sticker senden und empfangen. Gegen\u00fcber&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-05T12:29:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1368\" \/>\n\t<meta property=\"og:image:height\" content=\"1026\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Facebook stellt Lite-Version seines Messengers bereit\",\"datePublished\":\"2016-10-05T12:29:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/\"},\"wordCount\":144,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/mlite-staticnwsrm-final.png\",\"keywords\":[\"Facebook Messenger Lite\"],\"articleSection\":{\"1\":\"Software &amp; Updates\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/\",\"name\":\"Facebook stellt Lite-Version seines Messengers bereit - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/mlite-staticnwsrm-final.png\",\"datePublished\":\"2016-10-05T12:29:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/mlite-staticnwsrm-final.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/mlite-staticnwsrm-final.png\",\"width\":1368,\"height\":1026},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/10\\\/05\\\/facebook-stellt-lite-version-seines-messengers-bereit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facebook stellt Lite-Version seines Messengers bereit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Facebook stellt Lite-Version seines Messengers bereit - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/","og_locale":"de_DE","og_type":"article","og_title":"Facebook stellt Lite-Version seines Messengers bereit","og_description":"Ich bin kein Facebook-User und werde es wohl auch nicht mehr werden. Trotzdem einmal kurz dar\u00fcber informiert, dass Facebook diese Woche eine Lite-Version seines Messengers ver\u00f6ffentlicht hat. Die abgespeckte Version kann Nachrichten, Bilder, Links und Sticker senden und empfangen. Gegen\u00fcber&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2016-10-05T12:29:55+00:00","og_image":[{"width":1368,"height":1026,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final.png","type":"image\/png"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Facebook stellt Lite-Version seines Messengers bereit","datePublished":"2016-10-05T12:29:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/"},"wordCount":144,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final.png","keywords":["Facebook Messenger Lite"],"articleSection":{"1":"Software &amp; Updates"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/","url":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/","name":"Facebook stellt Lite-Version seines Messengers bereit - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final.png","datePublished":"2016-10-05T12:29:55+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final.png","width":1368,"height":1026},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/10\/05\/facebook-stellt-lite-version-seines-messengers-bereit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Facebook stellt Lite-Version seines Messengers bereit"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/10\/mlite-staticnwsrm-final.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/73087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=73087"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/73087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/73091"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=73087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=73087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=73087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}