{"id":70771,"date":"2016-08-25T20:35:25","date_gmt":"2016-08-25T18:35:25","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=70771"},"modified":"2016-08-25T20:35:25","modified_gmt":"2016-08-25T18:35:25","slug":"sony-xperia-x-compact-erstes-bild-geleakt","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/","title":{"rendered":"Sony Xperia X Compact: Erstes Bild geleakt"},"content":{"rendered":"<p>Spricht man heute von kompakten Smartphones besitzen diese immer noch ein Display ab 4,5 Zoll. Vor einigen Jahren hatten diese Gr\u00f6\u00dfe ausschlie\u00dflich die Highend-Ger\u00e4te. Ebenso sparen viele Hersteller gerade bei den kompakten Ausgaben ihrer Smartphones nicht nur beim Display sondern auch bei der verbauten Hardware. Positiv ist hier aber Sony zu nennen, welche bislang bei ihren Xperia Compact-Ausgaben gute Hardware verbaut hatten. Um so sch\u00f6ner ist nun zu lesen, dass Sony seine Compact-Reihe mit einem <strong>Xperia X Compact<\/strong> fortsetzen wird. Ein erstes Bild vom Smartphone wurde nun von Evleaks gepostet.<\/p>\n<div class=\"video-container\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\">Sony Xperia X Compact <a href=\"https:\/\/t.co\/q2GKddYUqh\">pic.twitter.com\/q2GKddYUqh<\/a><\/p>\n<p>&mdash; Evan Blass (@evleaks) <a href=\"https:\/\/twitter.com\/evleaks\/status\/768782671707148288\">August 25, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Angaben zur Gr\u00f6\u00dfe und Co. wurden hier noch nicht gemacht. Und auch beim Design gibt&#8217;s keine gro\u00dfen \u00dcberraschungen. Pers\u00f6nlich gehe ich nicht davon aus, dass Sony das Xperia X Compact mit nach Berlin zur IFA 2016 bringen wird. Hier gehe ich eher von der Vorstellung eines neuen Highend-Smartphones aus.<\/p>\n<p>Mal schauen ob es die n\u00e4chsten Tage weitere Informationen geben wird. Sony schweigt bislang dazu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spricht man heute von kompakten Smartphones besitzen diese immer noch ein Display ab 4,5 Zoll. Vor einigen Jahren hatten diese Gr\u00f6\u00dfe ausschlie\u00dflich die Highend-Ger\u00e4te. Ebenso sparen viele Hersteller gerade bei den kompakten Ausgaben ihrer Smartphones nicht nur beim Display sondern&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":70773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286],"tags":[14164],"class_list":["post-70771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","tag-sony-xperia-x-compact"],"wp_featured_image":{"id":70773,"alt_text":"","description":"","media_type":"image","media_details":{"width":254,"height":500,"file":"2016\/08\/IMG_20160825_203110.jpg","sizes":{"thumbnail":{"file":"IMG_20160825_203110-104x205.jpg","width":104,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110-104x205.jpg"},"medium":{"file":"IMG_20160825_203110-183x360.jpg","width":183,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110-183x360.jpg"},"wp_review_large":{"file":"IMG_20160825_203110-254x200.jpg","width":254,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110-254x200.jpg"},"wp_review_small":{"file":"IMG_20160825_203110-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110-65x65.jpg"},"blog-large":{"file":"IMG_20160825_203110-254x300.jpg","width":254,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110-254x300.jpg"},"blog-medium":{"file":"IMG_20160825_203110-254x205.jpg","width":254,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110-254x205.jpg"},"recent-thumb":{"file":"IMG_20160825_203110-254x316.jpg","width":254,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110-254x316.jpg"},"service-featured":{"file":"IMG_20160825_203110-254x330.jpg","width":254,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110-254x330.jpg"},"wp_rp_thumbnail":{"file":"IMG_20160825_203110-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":70771,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110.jpg"},"commentcount":2,"wp_comments":[{"id":25019,"parent":0,"author":0,"author_name":"Olaf Weidlich","author_email":"oweidlich29@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c3f1e9e3c8786e9a13ebe312172fee3b4ea0c8f0aa6647d797c8687c7c8f9659?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c3f1e9e3c8786e9a13ebe312172fee3b4ea0c8f0aa6647d797c8687c7c8f9659?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c3f1e9e3c8786e9a13ebe312172fee3b4ea0c8f0aa6647d797c8687c7c8f9659?s=96&d=mm&r=g"},"date":"2016-08-26T12:31:39","cld_nonce":"82f011626f","content":{"rendered":"<p>Hoffentlich verbaut Sony dieses mal einen besseren Akku als bei dem XA ode X.<br \/>\nEin Akku der nur noch Saft f\u00fcr 8 Stunden bei normaler Nutzung bietet ist nicht akzeptabel.<br \/>\nWenn ich an das Z3 oder Z5 zur\u00fcck denke, hatte Sony sich mit der X Serie ein Eigentor geschossen.<\/p>\n"},"status":"1"},{"id":25031,"parent":25019,"author":2020,"author_name":"Mike","author_email":"beatmasters.winlite.blog@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"},"date":"2016-08-26T15:24:36","cld_nonce":"82f011626f","content":{"rendered":"<p>Xperia X Compact wird wohl doch auf der IFA vorgestellt werden. Der Akku soll 2.700 mAh liefern.<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sony Xperia X Compact: Erstes Bild geleakt - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sony Xperia X Compact: Erstes Bild geleakt\" \/>\n<meta property=\"og:description\" content=\"Spricht man heute von kompakten Smartphones besitzen diese immer noch ein Display ab 4,5 Zoll. Vor einigen Jahren hatten diese Gr\u00f6\u00dfe ausschlie\u00dflich die Highend-Ger\u00e4te. Ebenso sparen viele Hersteller gerade bei den kompakten Ausgaben ihrer Smartphones nicht nur beim Display sondern&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-25T18:35:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"254\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Sony Xperia X Compact: Erstes Bild geleakt\",\"datePublished\":\"2016-08-25T18:35:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/\"},\"wordCount\":173,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/IMG_20160825_203110.jpg\",\"keywords\":[\"Sony Xperia X Compact\"],\"articleSection\":[\"Hardware\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/\",\"name\":\"Sony Xperia X Compact: Erstes Bild geleakt - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/IMG_20160825_203110.jpg\",\"datePublished\":\"2016-08-25T18:35:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/IMG_20160825_203110.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/IMG_20160825_203110.jpg\",\"width\":254,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/08\\\/25\\\/sony-xperia-x-compact-erstes-bild-geleakt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sony Xperia X Compact: Erstes Bild geleakt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sony Xperia X Compact: Erstes Bild geleakt - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/","og_locale":"de_DE","og_type":"article","og_title":"Sony Xperia X Compact: Erstes Bild geleakt","og_description":"Spricht man heute von kompakten Smartphones besitzen diese immer noch ein Display ab 4,5 Zoll. Vor einigen Jahren hatten diese Gr\u00f6\u00dfe ausschlie\u00dflich die Highend-Ger\u00e4te. Ebenso sparen viele Hersteller gerade bei den kompakten Ausgaben ihrer Smartphones nicht nur beim Display sondern&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2016-08-25T18:35:25+00:00","og_image":[{"width":254,"height":500,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Sony Xperia X Compact: Erstes Bild geleakt","datePublished":"2016-08-25T18:35:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/"},"wordCount":173,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110.jpg","keywords":["Sony Xperia X Compact"],"articleSection":["Hardware"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/","url":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/","name":"Sony Xperia X Compact: Erstes Bild geleakt - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110.jpg","datePublished":"2016-08-25T18:35:25+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110.jpg","width":254,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/08\/25\/sony-xperia-x-compact-erstes-bild-geleakt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Sony Xperia X Compact: Erstes Bild geleakt"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/08\/IMG_20160825_203110.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/70771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=70771"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/70771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/70773"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=70771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=70771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=70771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}