{"id":67692,"date":"2016-07-06T14:49:35","date_gmt":"2016-07-06T12:49:35","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=67692"},"modified":"2016-07-06T15:36:10","modified_gmt":"2016-07-06T13:36:10","slug":"avm-veroeffentlicht-fritzos-6-60","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/","title":{"rendered":"AVM ver\u00f6ffentlicht FRITZ!OS 6.60"},"content":{"rendered":"<p>Nachdem die FRITZ!OS Version 6.60 Langezeit getestet wurde, ist sie nun endlich final und wird ab sofort an die FRITZ!Box 7490 und die FRITZ!Box 6490 Cable verteilt, wobei weitere FRITZ!Boxen folgen sollen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-57874\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/12\/FRITZBox-7490.jpg\" alt=\"FRITZ!Box 7490\" width=\"774\" height=\"467\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/12\/FRITZBox-7490.jpg 774w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/12\/FRITZBox-7490-250x151.jpg 250w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/12\/FRITZBox-7490-500x302.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/12\/FRITZBox-7490-700x422.jpg 700w\" sizes=\"auto, (max-width: 774px) 100vw, 774px\" \/><\/p>\n<p>Nachfolgend f\u00fcr euch alle Neuerungen, Fehlerbehebungen und Verbesserungen bei FRITZ!OS 6.60:<\/p>\n<ul>\n<li>WLAN:\n<ul>\n<li>NEU &#8211; FRITZ!Hotspot: der WLAN-Gastzugang mit Zusatzfunktionen f\u00fcr Caf\u00e9, Laden oder Praxis: Vorschaltseite mit eigenem Logo, Text und Link auf eigene Homepage<br \/>\nDetails unter https:\/\/avm.de\/ratgeber\/praktische-wlan-features\/der-fritz-hotspot-fuer-gaeste\/<\/li>\n<li>Verbesserung &#8211; Einstellen der Zeitschaltung an Smartphone und Tablet optimiert<\/li>\n<li>Verbesserung \u0096- Stabilit\u00e4t verbessert<\/li>\n<\/ul>\n<\/li>\n<li>Internet:\n<ul>\n<li>Verbesserung &#8211; schneller Surfen durch optimierte Behandlung von DNS-Anfragen<\/li>\n<li>Verbesserung \u0096- Stabilit\u00e4t von IPTV bei gleichzeitiger Nutzung \u00fcber LAN und WLAN<\/li>\n<\/ul>\n<\/li>\n<li>Telefonie:\n<ul>\n<li>Verbesserung &#8211; h\u00f6here Sprachqualit\u00e4t bei Internettelefonie durch verz\u00f6gerungsarme Sprach\u00fcbertragung<\/li>\n<li>Verbesserung &#8211; schnellerer Verbindungsaufbau bei Internettelefonie bei gleichzeitiger Daten\u00fcbertragung<\/li>\n<li>Verbesserung &#8211; h\u00f6here Sprachqualit\u00e4t bei Internettelefonie auch bei gleichzeitiger Daten\u00fcbertragung beim Anbieter Deutsche Telekom<\/li>\n<li>Verbesserung \u0096- Einstellen der Zeitschaltung des Anrufbeantworters an Smartphone und Tablet optimiert<\/li>\n<li>Verbesserung \u0096- Anpassungen f\u00fcr Internettelefonie-Anbieter Personal-VoIP<\/li>\n<li>Verbesserung \u0096- Internettelefonie-Anbieter &#8222;Anderer Anbieter&#8220;, &#8222;SIP-Anlagenanschluss&#8220; und &#8222;SIP-Trunking&#8220; bieten Einstellung der Paketgr\u00f6\u00dfe<\/li>\n<li>Verbesserung \u0096- Interoperabilit\u00e4t der Nachrichten\u00fcbertragung (MWI) zu angeschlossenen IP-Telefonen<\/li>\n<li>Verbesserung \u0096- Interoperabilit\u00e4t der \u00dcbertragung von Faxnachrichten \u00fcber das Internet (Protokoll T.38)<\/li>\n<li>Behoben -\u0096 in seltenen F\u00e4llen m\u00f6gliche Gespr\u00e4chsabbr\u00fcche beim Halten\/Makeln<\/li>\n<li>\u00c4nderung -\u0096 Anforderung f\u00fcr Kennw\u00f6rter von IP-Telefonen weiter erh\u00f6ht<\/li>\n<li>\u00c4nderung -\u0096 Anpassung an ver\u00e4nderte Netzbedingungen, in deren Folge Rufe von Anschl\u00fcssen der Telekom, easybell und Alice in das Netz von UnityMedia\/Kabel-BW scheitern konnten<\/li>\n<\/ul>\n<\/li>\n<li>Mediaserver:\n<ul>\n<li>Verbesserung &#8211; MagentaCLOUD als Quelle f\u00fcr den FRITZ!Mediaserver unterst\u00fctzt (ehemals T-Mediencenter)<\/li>\n<\/ul>\n<\/li>\n<li>DECT:\n<ul>\n<li>Behoben -\u0096 Telefonbucheintr\u00e4ge mit mehreren Rufnummern wurden gelegentlich nicht vollst\u00e4ndig \u00fcbernommen<\/li>\n<\/ul>\n<\/li>\n<li>Heimnetz:\n<ul>\n<li>Behoben -\u0096 Entfernen ungenutzter Ger\u00e4te in Heimnetzliste entfernte auch VPN-Verbindungen<\/li>\n<\/ul>\n<\/li>\n<li>USB\/UMTS:\n<ul>\n<li>Verbesserung -\u0096 Unterst\u00fctzung f\u00fcr einige Mobilfunk-Sticks von Huawei optimiert (u.a. f\u00fcr K3715, E173, E176)<\/li>\n<li>Verbesserung \u0096- Unterst\u00fctzung f\u00fcr Mobilfunk-Stick (LTE) Huawei K5150 (Tethering-Mode)<\/li>\n<li>Behoben -\u0096 keine Erkennung der Telefonie-Unterst\u00fctzung bei Mobilfunk-Sticks von Huawei<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Die Software sollte die Nutzer\u00a0von freien\u00a0Ger\u00e4te bereits erreichen, alle anderen mit vom Provider angepassten FRITZ!Boxen (ausgenommen 1&amp;1, denn diese setzen nur optisch ver\u00e4nderte FRITZ!Boxen ein) m\u00fcssen sich wahrscheinlich noch ein wenig gedulden.<\/p>\n<div class=\"quellenzeile\"><div class=\"quelle\">Quelle: <a href=\"https:\/\/avm.de\/service\/downloads\/download\/show\/18492\/\">AVM<\/a><\/div><div class=\"viaquelle\">Via: <a href=\"https:\/\/www.mobiflip.de\/avm-fritzos-6-60-ist-da\/\">mobiFlip<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem die FRITZ!OS Version 6.60 Langezeit getestet wurde, ist sie nun endlich final und wird ab sofort an die FRITZ!Box 7490 und die FRITZ!Box 6490 Cable verteilt, wobei weitere FRITZ!Boxen folgen sollen. Nachfolgend f\u00fcr euch alle Neuerungen, Fehlerbehebungen und Verbesserungen&hellip; <\/p>\n","protected":false},"author":2550,"featured_media":36563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286],"tags":[13533,12181,3449,6742,2794,3996,13534,317,2643,7256],"class_list":["post-67692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","tag-cable","tag-dsl","tag-fritzbox","tag-fritzbox-6490","tag-fritzbox-7490","tag-fritzos","tag-fritzos-6-60","tag-internet","tag-router","tag-vdsl"],"wp_featured_image":{"id":36563,"alt_text":"","description":"","media_type":"image","media_details":{"width":3000,"height":2200,"file":"2015\/01\/AVM_FRITZBox_3490_freigestellt.png","sizes":{"thumbnail":{"file":"AVM_FRITZBox_3490_freigestellt-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt-150x150.png"},"medium":{"file":"AVM_FRITZBox_3490_freigestellt-150x110.png","width":150,"height":110,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt-150x110.png"},"large":{"file":"AVM_FRITZBox_3490_freigestellt-500x367.png","width":500,"height":367,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt-500x367.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":34772,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt.png"},"commentcount":5,"wp_comments":[{"id":22294,"parent":0,"author":2213,"author_name":"KnorxThieus","author_email":"knorxthieus@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=96&d=mm&r=g"},"date":"2016-07-06T16:14:36","cld_nonce":"82f011626f","content":{"rendered":"<p>Wow, da kann ich meinen Gewinn aus der Weihnachtszeit von euch ja mal updaten <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><br \/>\nKlingt gut, nun fehlt uns nur noch der l\u00e4ngst \u00fcberf\u00e4llige VoIP-Vertrag &#8230;<\/p>\n"},"status":"1"},{"id":22295,"parent":22294,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2016-07-06T16:30:43","cld_nonce":"82f011626f","content":{"rendered":"<p>Woran scheitert der VoIP-Vertrag denn?<\/p>\n"},"status":"1"},{"id":22414,"parent":22295,"author":2213,"author_name":"KnorxThieus","author_email":"knorxthieus@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9eb405a525ffc0e1e71260e73871947087f4ff1a371d4741ffd696ae6782e04d?s=96&d=mm&r=g"},"date":"2016-07-09T23:25:24","cld_nonce":"82f011626f","content":{"rendered":"<p>An der Zeit und am geeigneten Vertrag <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><br \/>\nJetzt rennt uns Alice mit Forderungen wie &#8222;Nimm unseren Router oder vergiss VoIP mit uns&#8220; ins Haus &#8230; kenne mich auf dem Gebiet aber nicht wirklich aus.<\/p>\n"},"status":"1"},{"id":22416,"parent":22414,"author":2550,"author_name":"MAX","author_email":"maxstahl@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/baa8420b54a519e302878331460593a8692483d5d41187ec53ed72d7d8fc4aa4?s=96&d=mm&r=g"},"date":"2016-07-10T01:32:25","cld_nonce":"82f011626f","content":{"rendered":"<p>Alice, was im \u00dcbrigen zu O2 geh\u00f6rt, ist damit ganz sch\u00f6n dreist&#8230; Hast du die Chance zu einem anderen Anbieter zu wechseln?<\/p>\n"},"status":"1"},{"id":22424,"parent":22414,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2016-07-10T08:26:01","cld_nonce":"82f011626f","content":{"rendered":"<p>@KnorxThieus<br \/>\ngeht mir genau so. Hab es bisher aber ignoriert.<\/p>\n"},"status":"1"}],"wp_author":{"id":2550,"name":"MAX","description":"Begeisterter Technik-Enthusiast, der aktuell zwei Welten vereint. Windows auf PC sowie Xbox und iOS auf dem iPhone, als auch auf dem iPad. Gespaltene Pers\u00f6nlichkeit w\u00fcrde ich sagen. ;)","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AVM ver\u00f6ffentlicht FRITZ!OS 6.60 - Deskmodder.de<\/title>\n<meta name=\"description\" content=\"AVM ver\u00f6ffentlicht f\u00fcr die FRITZ!Box 7490 und die FRITZ!Box 6490 Cable die FRITZ!OS Version 6.60, die mit zahlreichen Neuerungen und Verbesserungen kommt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVM ver\u00f6ffentlicht FRITZ!OS 6.60\" \/>\n<meta property=\"og:description\" content=\"AVM ver\u00f6ffentlicht f\u00fcr die FRITZ!Box 7490 und die FRITZ!Box 6490 Cable die FRITZ!OS Version 6.60, die mit zahlreichen Neuerungen und Verbesserungen kommt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-06T12:49:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-06T13:36:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt-500x367.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"MAX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@themximum\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/\"},\"author\":{\"name\":\"MAX\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/bd4b9506e83c661f1de1af925c726d7c\"},\"headline\":\"AVM ver\u00f6ffentlicht FRITZ!OS 6.60\",\"datePublished\":\"2016-07-06T12:49:35+00:00\",\"dateModified\":\"2016-07-06T13:36:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/\"},\"wordCount\":403,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/AVM_FRITZBox_3490_freigestellt.png\",\"keywords\":[\"Cable\",\"DSL\",\"Fritz!Box\",\"Fritz!Box 6490\",\"FRITZ!Box 7490\",\"Fritz!OS\",\"FRITZ!OS 6.60\",\"Internet\",\"Router\",\"VDSL\"],\"articleSection\":[\"Hardware\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/\",\"name\":\"AVM ver\u00f6ffentlicht FRITZ!OS 6.60 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/AVM_FRITZBox_3490_freigestellt.png\",\"datePublished\":\"2016-07-06T12:49:35+00:00\",\"dateModified\":\"2016-07-06T13:36:10+00:00\",\"description\":\"AVM ver\u00f6ffentlicht f\u00fcr die FRITZ!Box 7490 und die FRITZ!Box 6490 Cable die FRITZ!OS Version 6.60, die mit zahlreichen Neuerungen und Verbesserungen kommt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/AVM_FRITZBox_3490_freigestellt.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/AVM_FRITZBox_3490_freigestellt.png\",\"width\":3000,\"height\":2200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/07\\\/06\\\/avm-veroeffentlicht-fritzos-6-60\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVM ver\u00f6ffentlicht FRITZ!OS 6.60\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/bd4b9506e83c661f1de1af925c726d7c\",\"name\":\"MAX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g\",\"caption\":\"MAX\"},\"description\":\"Begeisterter Technik-Enthusiast, der aktuell zwei Welten vereint. Windows auf PC sowie Xbox und iOS auf dem iPhone, als auch auf dem iPad. Gespaltene Pers\u00f6nlichkeit w\u00fcrde ich sagen. ;)\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/themximum\\\/\",\"https:\\\/\\\/x.com\\\/themximum\"],\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/max\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AVM ver\u00f6ffentlicht FRITZ!OS 6.60 - Deskmodder.de","description":"AVM ver\u00f6ffentlicht f\u00fcr die FRITZ!Box 7490 und die FRITZ!Box 6490 Cable die FRITZ!OS Version 6.60, die mit zahlreichen Neuerungen und Verbesserungen kommt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/","og_locale":"de_DE","og_type":"article","og_title":"AVM ver\u00f6ffentlicht FRITZ!OS 6.60","og_description":"AVM ver\u00f6ffentlicht f\u00fcr die FRITZ!Box 7490 und die FRITZ!Box 6490 Cable die FRITZ!OS Version 6.60, die mit zahlreichen Neuerungen und Verbesserungen kommt.","og_url":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2016-07-06T12:49:35+00:00","article_modified_time":"2016-07-06T13:36:10+00:00","og_image":[{"width":500,"height":367,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt-500x367.png","type":"image\/png"}],"author":"MAX","twitter_card":"summary_large_image","twitter_creator":"@themximum","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/"},"author":{"name":"MAX","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/bd4b9506e83c661f1de1af925c726d7c"},"headline":"AVM ver\u00f6ffentlicht FRITZ!OS 6.60","datePublished":"2016-07-06T12:49:35+00:00","dateModified":"2016-07-06T13:36:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/"},"wordCount":403,"commentCount":5,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt.png","keywords":["Cable","DSL","Fritz!Box","Fritz!Box 6490","FRITZ!Box 7490","Fritz!OS","FRITZ!OS 6.60","Internet","Router","VDSL"],"articleSection":["Hardware"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/","url":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/","name":"AVM ver\u00f6ffentlicht FRITZ!OS 6.60 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt.png","datePublished":"2016-07-06T12:49:35+00:00","dateModified":"2016-07-06T13:36:10+00:00","description":"AVM ver\u00f6ffentlicht f\u00fcr die FRITZ!Box 7490 und die FRITZ!Box 6490 Cable die FRITZ!OS Version 6.60, die mit zahlreichen Neuerungen und Verbesserungen kommt.","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt.png","width":3000,"height":2200},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/07\/06\/avm-veroeffentlicht-fritzos-6-60\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"AVM ver\u00f6ffentlicht FRITZ!OS 6.60"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/bd4b9506e83c661f1de1af925c726d7c","name":"MAX","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g","caption":"MAX"},"description":"Begeisterter Technik-Enthusiast, der aktuell zwei Welten vereint. Windows auf PC sowie Xbox und iOS auf dem iPhone, als auch auf dem iPad. Gespaltene Pers\u00f6nlichkeit w\u00fcrde ich sagen. ;)","sameAs":["https:\/\/www.instagram.com\/themximum\/","https:\/\/x.com\/themximum"],"url":"https:\/\/www.deskmodder.de\/blog\/author\/max\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/AVM_FRITZBox_3490_freigestellt.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/67692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2550"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=67692"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/67692\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/36563"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=67692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=67692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=67692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}