{"id":64879,"date":"2016-05-19T07:17:58","date_gmt":"2016-05-19T05:17:58","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=64879"},"modified":"2016-05-19T07:17:58","modified_gmt":"2016-05-19T05:17:58","slug":"amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/","title":{"rendered":"Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD"},"content":{"rendered":"<p>Kurzinfo f\u00fcr die User eines Fire TV von Amazon. Denn m\u00f6glicherweise steht demn\u00e4chst f\u00fcr euch wieder ein kleines Systemupdate bereit. Zumindest gibt Amazon in den USA das per <a href=\"http:\/\/phx.corporate-ir.net\/phoenix.zhtml?c=176060&amp;p=irol-newsArticle&amp;ID=2168940\" target=\"_blank\">Pressemitteilung<\/a> bekannt. Hauptthema bzw. Inhalt des Updates wird die Integration des Assistenten &#8222;Alexa&#8220; sein, welchen wir hierzulande aber nicht sehen werden. Weiterer Inhalt des Updates soll laut Pressemitteilung aber auch die Unterst\u00fctzung der Wiedergabe von YouTube in 4K UltraHD sein.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-50566\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv-700x504.jpg\" alt=\"amazon-fire-tv\" width=\"700\" height=\"504\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv-700x504.jpg 700w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv-250x180.jpg 250w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv-500x360.jpg 500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><br \/>\n<blockquote class=\"quote_border_top\">\"<\/p>\n<ul>\n<li class=\"bwlistitemmargb\">YouTube 4K Ultra HD\u2014Access YouTube\u2019s full 4K library via the YouTube.com app on Amazon Fire TV when connected to a UHD-compatible TV<\/li>\n<\/ul>\n<p>\"<\/blockquote><br \/>\nWann das Update dann auch bei uns zur Verf\u00fcgung stehen wird, ist noch nicht bekannt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kurzinfo f\u00fcr die User eines Fire TV von Amazon. Denn m\u00f6glicherweise steht demn\u00e4chst f\u00fcr euch wieder ein kleines Systemupdate bereit. Zumindest gibt Amazon in den USA das per Pressemitteilung bekannt. Hauptthema bzw. Inhalt des Updates wird die Integration des Assistenten&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":50566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286,152],"tags":[6739,12986,12987],"class_list":["post-64879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","category-software","tag-amazon-fire-tv","tag-fire-tv-update","tag-youtube-4k-video"],"wp_featured_image":{"id":50566,"alt_text":"","description":"","media_type":"image","media_details":{"width":1000,"height":1000,"file":"2015\/08\/amazon-fire-tv.jpg","sizes":{"thumbnail":{"file":"amazon-fire-tv-250x180.jpg","width":250,"height":180,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv-250x180.jpg"},"medium":{"file":"amazon-fire-tv-500x360.jpg","width":500,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv-500x360.jpg"},"large":{"file":"amazon-fire-tv-700x504.jpg","width":700,"height":504,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv-700x504.jpg"},"wp_rp_thumbnail":{"file":"amazon-fire-tv-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv-150x150.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":50562,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv.jpg"},"commentcount":1,"wp_comments":[{"id":20905,"parent":0,"author":0,"author_name":"Sandro","author_email":"sandrchud@freenet.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9ee3716bac0b374b2eadc57718fd7ef0b673f56ce494e327c860668ad3af728c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9ee3716bac0b374b2eadc57718fd7ef0b673f56ce494e327c860668ad3af728c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9ee3716bac0b374b2eadc57718fd7ef0b673f56ce494e327c860668ad3af728c?s=96&d=mm&r=g"},"date":"2016-05-19T17:29:35","cld_nonce":"82f011626f","content":{"rendered":"<p>Wird das f\u00fcr beide Generationen sein oder nur die zweite, sprich neuere?<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD\" \/>\n<meta property=\"og:description\" content=\"Kurzinfo f\u00fcr die User eines Fire TV von Amazon. Denn m\u00f6glicherweise steht demn\u00e4chst f\u00fcr euch wieder ein kleines Systemupdate bereit. Zumindest gibt Amazon in den USA das per Pressemitteilung bekannt. Hauptthema bzw. Inhalt des Updates wird die Integration des Assistenten&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-19T05:17:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD\",\"datePublished\":\"2016-05-19T05:17:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/\"},\"wordCount\":133,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/amazon-fire-tv.jpg\",\"keywords\":[\"Amazon Fire TV\",\"Fire TV Update\",\"YouTube 4k Video\"],\"articleSection\":{\"1\":\"Hardware\",\"2\":\"Software &amp; Updates\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/\",\"name\":\"Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/amazon-fire-tv.jpg\",\"datePublished\":\"2016-05-19T05:17:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/amazon-fire-tv.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/amazon-fire-tv.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/05\\\/19\\\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/","og_locale":"de_DE","og_type":"article","og_title":"Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD","og_description":"Kurzinfo f\u00fcr die User eines Fire TV von Amazon. Denn m\u00f6glicherweise steht demn\u00e4chst f\u00fcr euch wieder ein kleines Systemupdate bereit. Zumindest gibt Amazon in den USA das per Pressemitteilung bekannt. Hauptthema bzw. Inhalt des Updates wird die Integration des Assistenten&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2016-05-19T05:17:58+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD","datePublished":"2016-05-19T05:17:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/"},"wordCount":133,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv.jpg","keywords":["Amazon Fire TV","Fire TV Update","YouTube 4k Video"],"articleSection":{"1":"Hardware","2":"Software &amp; Updates"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/","url":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/","name":"Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv.jpg","datePublished":"2016-05-19T05:17:58+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/05\/19\/amazon-fire-tv-kommendes-update-liefert-unterstuetzung-fuer-youtube-in-ultra-hd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Amazon Fire TV: Kommendes Update liefert Unterst\u00fctzung f\u00fcr YouTube in Ultra HD"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/08\/amazon-fire-tv.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/64879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=64879"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/64879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/50566"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=64879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=64879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=64879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}