{"id":63796,"date":"2016-04-27T05:02:34","date_gmt":"2016-04-27T03:02:34","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=63796"},"modified":"2016-04-27T05:03:11","modified_gmt":"2016-04-27T03:03:11","slug":"detailszum-kommenden-honor-v8","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/","title":{"rendered":"Details zum kommenden &#8222;Honor V8&#8220;"},"content":{"rendered":"<p>Bereits in der letzten Woche gab es einen ersten <a href=\"http:\/\/www.deskmodder.de\/blog\/2016\/04\/21\/honor-v8-erster-teaser-gibt-hinweis-auf-dual-kamera\/\">Teaser zum Honor V8<\/a> von Huawei, welcher auf eine Dual-Kamera hindeutete. Nun verr\u00e4t uns die\u00a0<a href=\"http:\/\/shouji.tenaa.com.cn\/mobile\/MobileDetail.aspx?code=rraknvfTEOUDXfLZ33FYpAuMSsCV%2bXBU\">chinesische Zulassungsbeh\u00f6rde TENAA<\/a> deutliche mehr zum Honor V8. Dieses soll in einer Basisversion und Premiumversion kommen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63800\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b.jpg\" alt=\"16021339-b\" width=\"480\" height=\"640\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b.jpg 480w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-135x180.jpg 135w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-270x360.jpg 270w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-378x504.jpg 378w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>Das &#8222;normale&#8220; Honor V8 wird demnach ein doch relativ gro\u00dfes 5,7 Zoll FullHD-Display mit einer Aufl\u00f6sung von 1920 x 1080 Pixeln besitzen und kann somit eigentlich schon als Phablet bezeichnet werden. Beim Prozessor d\u00fcrfte es sich um den Kirin 950 Achtkern-Prozessor handeln. Zumindest soll es sich um einen Achkern-Chip mit 2,3 GHz je Kern handeln. Dieser wird von 4GB RAM unterst\u00fctzt. Der per MicroSD-Karte erweiterbare, interne Speicher betr\u00e4gt 32GB. Bei der R\u00fcckseitenkamera soll es sich wie angeteasert um eine Dual-Kamera handeln, wobei beide Objektive eine Aufl\u00f6sung von 12MP bieten. Ob auch beim Honor V8 Leica Objektive verbaut worden sind, ist nicht bekannt. Die Frontkamera bietet 8MP. Der Akku ist mit 3.400 mAh gut dimensioniert. Vorinstalliert ist Android 6 Marshmallow.<\/p>\n<p>Das Premiummodell vom Honor V8 unterscheidet sich haupts\u00e4chlich beim Display und beim internen Speicher. Auch hier wird ein 5,7 Zoll Display verbaut sein. Doch dieses soll dann QHD-Aufl\u00f6sung bieten bzw. 2560 x 1440 Pixel. Auch hier soll der Kirin 950 Prozessor verbaut sein, welcher mit 2,5 GHz aber etwas h\u00f6her getaktet sein soll. Ebenfalls gibt&#8217;s 4GB RAM und die oben genannten Kameras. Beim internen Speicher gibt&#8217;s beim Premiummodell aber satte 64GB, welcher ebenfalls erweiterbar ist.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63801\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-z.jpg\" alt=\"16021339-z\" width=\"480\" height=\"640\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-z.jpg 480w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-z-135x180.jpg 135w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-z-270x360.jpg 270w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-z-378x504.jpg 378w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>Am 10.Mai wird laut Teaser das Honor V8 dann offiziell vorgestellt werden. Fraglich ist bislang nur, ob das Ger\u00e4t auch nach Deutschland kommen wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bereits in der letzten Woche gab es einen ersten Teaser zum Honor V8 von Huawei, welcher auf eine Dual-Kamera hindeutete. Nun verr\u00e4t uns die\u00a0chinesische Zulassungsbeh\u00f6rde TENAA deutliche mehr zum Honor V8. Dieses soll in einer Basisversion und Premiumversion kommen. Das&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":63800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286],"tags":[12679],"class_list":["post-63796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","tag-honor-v8"],"wp_featured_image":{"id":63800,"alt_text":"","description":"","media_type":"image","media_details":{"width":480,"height":640,"file":"2016\/04\/16021339-b.jpg","sizes":{"thumbnail":{"file":"16021339-b-135x180.jpg","width":135,"height":180,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-135x180.jpg"},"medium":{"file":"16021339-b-270x360.jpg","width":270,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-270x360.jpg"},"large":{"file":"16021339-b-378x504.jpg","width":378,"height":504,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-378x504.jpg"},"wp_review_large":{"file":"16021339-b-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-320x200.jpg"},"wp_review_small":{"file":"16021339-b-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-65x65.jpg"},"blog-large":{"file":"16021339-b-480x300.jpg","width":480,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-480x300.jpg"},"blog-medium":{"file":"16021339-b-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-306x205.jpg"},"recent-thumb":{"file":"16021339-b-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-350x316.jpg"},"service-featured":{"file":"16021339-b-480x330.jpg","width":480,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-480x330.jpg"},"wp_rp_thumbnail":{"file":"16021339-b-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":63796,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Details zum kommenden &quot;Honor V8&quot; - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Details zum kommenden &quot;Honor V8&quot;\" \/>\n<meta property=\"og:description\" content=\"Bereits in der letzten Woche gab es einen ersten Teaser zum Honor V8 von Huawei, welcher auf eine Dual-Kamera hindeutete. Nun verr\u00e4t uns die\u00a0chinesische Zulassungsbeh\u00f6rde TENAA deutliche mehr zum Honor V8. Dieses soll in einer Basisversion und Premiumversion kommen. Das&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-27T03:02:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-27T03:03:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Details zum kommenden &#8222;Honor V8&#8220;\",\"datePublished\":\"2016-04-27T03:02:34+00:00\",\"dateModified\":\"2016-04-27T03:03:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/16021339-b.jpg\",\"keywords\":[\"Honor V8\"],\"articleSection\":[\"Hardware\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/\",\"name\":\"Details zum kommenden \\\"Honor V8\\\" - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/16021339-b.jpg\",\"datePublished\":\"2016-04-27T03:02:34+00:00\",\"dateModified\":\"2016-04-27T03:03:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/16021339-b.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/16021339-b.jpg\",\"width\":480,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/27\\\/detailszum-kommenden-honor-v8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Details zum kommenden &#8222;Honor V8&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Details zum kommenden \"Honor V8\" - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/","og_locale":"de_DE","og_type":"article","og_title":"Details zum kommenden \"Honor V8\"","og_description":"Bereits in der letzten Woche gab es einen ersten Teaser zum Honor V8 von Huawei, welcher auf eine Dual-Kamera hindeutete. Nun verr\u00e4t uns die\u00a0chinesische Zulassungsbeh\u00f6rde TENAA deutliche mehr zum Honor V8. Dieses soll in einer Basisversion und Premiumversion kommen. Das&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2016-04-27T03:02:34+00:00","article_modified_time":"2016-04-27T03:03:11+00:00","og_image":[{"width":480,"height":640,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Details zum kommenden &#8222;Honor V8&#8220;","datePublished":"2016-04-27T03:02:34+00:00","dateModified":"2016-04-27T03:03:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b.jpg","keywords":["Honor V8"],"articleSection":["Hardware"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/","url":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/","name":"Details zum kommenden \"Honor V8\" - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b.jpg","datePublished":"2016-04-27T03:02:34+00:00","dateModified":"2016-04-27T03:03:11+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b.jpg","width":480,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/27\/detailszum-kommenden-honor-v8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Details zum kommenden &#8222;Honor V8&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/16021339-b.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/63796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=63796"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/63796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/63800"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=63796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=63796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=63796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}