{"id":63051,"date":"2016-04-12T13:38:49","date_gmt":"2016-04-12T11:38:49","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=63051"},"modified":"2016-04-12T13:38:49","modified_gmt":"2016-04-12T11:38:49","slug":"kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/","title":{"rendered":"Kindle Oasis: Das soll der kommende eReader von Amazon sein"},"content":{"rendered":"<p>Bereits in der letzten Woche berichteten wir, dass Amazon in dieser Woche einen neuen Kindle eReader vorstellen m\u00f6chte. Bislang war nicht viel bekannt, au\u00dfer dass das Ger\u00e4t d\u00fcnner wird und mit neuer Akku-Technik ausgestattet sein soll. Nun zeigt uns ein Leak den kommenden eReader. Und hierbei soll es sich um den Kindle Oasis handeln. Und wie die Bilder zeigen, gibt&#8217;s ein komplett \u00fcberarbeitetes Design.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63064\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg\" alt=\"oasis_00\" width=\"637\" height=\"535\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg 637w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-214x180.jpg 214w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-429x360.jpg 429w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-600x504.jpg 600w\" sizes=\"auto, (max-width: 637px) 100vw, 637px\" \/><\/p>\n<p>Ebenso zeigt sich die neue H\u00fclle, welche mittels Magneten befestigt wird. Das Cover bietet dann nicht nur Schutz sondern dient auch als Speicher f\u00fcr Strom. Laut den Spezifikationen soll der Kindle Oasis an der dicksten Stelle 8,5mm und an der d\u00fcnnsten Stelle nur 3,4mm sein. Weiterhin gibt&#8217;s 60% mehr Helligkeit, 300ppi und LED-Backlight. Das\u00a0Gewicht soll bei 131 Gramm liegen.<\/p>\n<div id='gallery-1' class='gallery galleryid-63051 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"180\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-214x180.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-214x180.jpg 214w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-429x360.jpg 429w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-600x504.jpg 600w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg 637w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_01.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"119\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_01-250x119.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_01-250x119.jpg 250w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_01-500x239.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_01.jpg 680w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_02.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"173\" height=\"180\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_02-173x180.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_02-173x180.jpg 173w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_02.jpg 329w\" sizes=\"auto, (max-width: 173px) 100vw, 173px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_03.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"136\" height=\"180\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_03-136x180.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_03-136x180.jpg 136w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_03-273x360.jpg 273w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_03-382x504.jpg 382w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_03.jpg 530w\" sizes=\"auto, (max-width: 136px) 100vw, 136px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_04.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"165\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_04-250x165.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_04-250x165.jpg 250w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_04-500x329.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_04.jpg 680w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_05.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"172\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_05-250x172.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_05-250x172.jpg 250w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_05-500x343.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_05.jpg 680w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_06.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"198\" height=\"180\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_06-198x180.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_06-198x180.jpg 198w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_06-396x360.jpg 396w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_06-554x504.jpg 554w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_06-350x316.jpg 350w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_06.jpg 700w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_07.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"198\" height=\"180\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_07-198x180.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_07-198x180.jpg 198w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_07-395x360.jpg 395w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_07-350x316.jpg 350w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_07.jpg 549w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_08.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"174\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_08-250x174.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_08-250x174.jpg 250w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_08-500x348.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_08.jpg 680w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_09.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"227\" height=\"180\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_09-227x180.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_09-227x180.jpg 227w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_09-454x360.jpg 454w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_09-636x504.jpg 636w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_09.jpg 680w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/kindle-oasis.jpg' rel=\"lightbox[63051]\"><img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"180\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/kindle-oasis-174x180.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/kindle-oasis-174x180.jpg 174w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/kindle-oasis-348x360.jpg 348w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/kindle-oasis.jpg 483w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Klingt alles nicht schlecht. Mal schauen wo der Preis liegen wird.<\/p>\n<div class=\"viaquelle\">via <a href=\"http:\/\/liliputing.com\/2016\/04\/amazon-kindle-oasis-leaks-suggest-a-radically-new-ereader-design.html\" target=\"_blank\">Liliputing<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bereits in der letzten Woche berichteten wir, dass Amazon in dieser Woche einen neuen Kindle eReader vorstellen m\u00f6chte. Bislang war nicht viel bekannt, au\u00dfer dass das Ger\u00e4t d\u00fcnner wird und mit neuer Akku-Technik ausgestattet sein soll. Nun zeigt uns ein&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":63064,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286],"tags":[12568,12515],"class_list":["post-63051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","tag-amazon-kindle-oasis","tag-kindle-ereader"],"wp_featured_image":{"id":63064,"alt_text":"","description":"","media_type":"image","media_details":{"width":637,"height":535,"file":"2016\/04\/oasis_00.jpg","sizes":{"thumbnail":{"file":"oasis_00-214x180.jpg","width":214,"height":180,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-214x180.jpg"},"medium":{"file":"oasis_00-429x360.jpg","width":429,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-429x360.jpg"},"large":{"file":"oasis_00-600x504.jpg","width":600,"height":504,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-600x504.jpg"},"wp_review_large":{"file":"oasis_00-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-320x200.jpg"},"wp_review_small":{"file":"oasis_00-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-65x65.jpg"},"blog-large":{"file":"oasis_00-637x300.jpg","width":637,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-637x300.jpg"},"blog-medium":{"file":"oasis_00-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-306x205.jpg"},"recent-thumb":{"file":"oasis_00-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-350x316.jpg"},"service-featured":{"file":"oasis_00-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-600x330.jpg"},"wp_rp_thumbnail":{"file":"oasis_00-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":63051,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kindle Oasis: Das soll der kommende eReader von Amazon sein - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kindle Oasis: Das soll der kommende eReader von Amazon sein\" \/>\n<meta property=\"og:description\" content=\"Bereits in der letzten Woche berichteten wir, dass Amazon in dieser Woche einen neuen Kindle eReader vorstellen m\u00f6chte. Bislang war nicht viel bekannt, au\u00dfer dass das Ger\u00e4t d\u00fcnner wird und mit neuer Akku-Technik ausgestattet sein soll. Nun zeigt uns ein&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-12T11:38:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"637\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Kindle Oasis: Das soll der kommende eReader von Amazon sein\",\"datePublished\":\"2016-04-12T11:38:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/\"},\"wordCount\":160,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/oasis_00.jpg\",\"keywords\":[\"Amazon Kindle Oasis\",\"Kindle eReader\"],\"articleSection\":[\"Hardware\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/\",\"name\":\"Kindle Oasis: Das soll der kommende eReader von Amazon sein - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/oasis_00.jpg\",\"datePublished\":\"2016-04-12T11:38:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/oasis_00.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/oasis_00.jpg\",\"width\":637,\"height\":535},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2016\\\/04\\\/12\\\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kindle Oasis: Das soll der kommende eReader von Amazon sein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kindle Oasis: Das soll der kommende eReader von Amazon sein - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/","og_locale":"de_DE","og_type":"article","og_title":"Kindle Oasis: Das soll der kommende eReader von Amazon sein","og_description":"Bereits in der letzten Woche berichteten wir, dass Amazon in dieser Woche einen neuen Kindle eReader vorstellen m\u00f6chte. Bislang war nicht viel bekannt, au\u00dfer dass das Ger\u00e4t d\u00fcnner wird und mit neuer Akku-Technik ausgestattet sein soll. Nun zeigt uns ein&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2016-04-12T11:38:49+00:00","og_image":[{"width":637,"height":535,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Kindle Oasis: Das soll der kommende eReader von Amazon sein","datePublished":"2016-04-12T11:38:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/"},"wordCount":160,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg","keywords":["Amazon Kindle Oasis","Kindle eReader"],"articleSection":["Hardware"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/","url":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/","name":"Kindle Oasis: Das soll der kommende eReader von Amazon sein - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg","datePublished":"2016-04-12T11:38:49+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg","width":637,"height":535},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2016\/04\/12\/kindle-oasis-das-soll-der-kommende-ereader-von-amazon-sein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Kindle Oasis: Das soll der kommende eReader von Amazon sein"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/04\/oasis_00.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/63051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=63051"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/63051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/63064"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=63051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=63051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=63051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}