{"id":46361,"date":"2015-06-15T16:30:07","date_gmt":"2015-06-15T14:30:07","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=46361"},"modified":"2023-06-25T14:05:49","modified_gmt":"2023-06-25T12:05:49","slug":"windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/","title":{"rendered":"Windows Firewall Notifier 2.0 Portable erschienen &#8211; Datenverbindungen \u00fcberwachen"},"content":{"rendered":"<p>Das Tool Windows Firewall Notifier in der Version 1.9 werden einige von euch sicherlich kennen. Ein kleines Programm, welches sich in die windowseigene Firewall einklinkt und man so die Kontrolle hat, welche Programme eine Verbindung zum Internet herstellen wollen. Dies kann man dann zulassen oder blockieren. Mit der Windows Firewall direkt ist dieses Unterfangen sehr schwierig.<br \/>\nJetzt steht die Version 2.0 in einer Alpha Version zur Verf\u00fcgung und wurde vom Design her komplett \u00fcberarbeitet und verwendet jetzt Microsoft .NET 4.5. Sie ist f\u00fcr alle Windows Versionen. Ich hab sie mal unter Windows 10 getestet.<br \/>\n<a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001.jpg\" rel=\"lightbox[46361]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-46362\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001-500x360.jpg\" alt=\"Windows Firewall Notifier-001\" width=\"500\" height=\"360\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001-250x180.jpg 250w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001-700x504.jpg 700w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><br \/>\nIst die Datei entpackt wurden muss nur die WFN.exe als Administrator ausgef\u00fchrt werden. Sollte dann trotzdem oben im Bild erscheinen, dass man es als Administrator ausf\u00fchren muss, dann einfach darauf klicken.<br \/>\nIn der \u00dcbersicht hat man nun die Verbindungen die aktiv sind mit einem Haken.<\/p>\n<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-002.jpg\" rel=\"lightbox[46361]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-46363\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-002-500x360.jpg\" alt=\"Windows Firewall Notifier-002\" width=\"500\" height=\"360\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-002-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-002-250x180.jpg 250w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-002-700x504.jpg 700w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><br \/>\nInteressant ist die Einstellung Map. Die zeigt wohin die Reise der Daten geht.<\/p>\n<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-005.jpg\" rel=\"lightbox[46361]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-46364\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-005-500x360.jpg\" alt=\"Windows Firewall Notifier-005\" width=\"500\" height=\"360\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-005-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-005-250x180.jpg 250w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-005-700x504.jpg 700w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>In den Einstellungen hat man nun die M\u00f6glichkeit, die Benachrichtigungen anzeigen zu lassen, wenn ein Programm ins Netz gehen will.<\/p>\n<p>Dies sieht dann so aus:<br \/>\n<a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-003.jpg\" rel=\"lightbox[46361]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-46365\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-003.jpg\" alt=\"Windows Firewall Notifier-003\" width=\"486\" height=\"293\" \/><\/a><\/p>\n<p>Hier kann man nun die Verbindung blocken oder zulassen.<\/p>\n<p>Falls euch die Windows Firewall Notifier 2.0 dann doch nicht so zusagt, dann <strong>bitte nicht einfach den Ordner l\u00f6schen<\/strong>. Erst muss die DisableWFN.cmd als Administrator ausgef\u00fchrt werden. Die entfernt alle Einstellungen, die sich in die Windowseigene Firewall eingeklinkt haben.<\/p>\n<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-006.jpg\" rel=\"lightbox[46361]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-46367\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-006-500x360.jpg\" alt=\"Windows Firewall Notifier-006\" width=\"500\" height=\"360\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-006-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-006-250x180.jpg 250w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-006-700x504.jpg 700w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><strong>Weitere Infos unter:<\/strong> <a href=\"https:\/\/wfn.codeplex.com\/\" target=\"_blank\" rel=\"noopener\">wfn.codeplex.com<\/a> bzw. <a href=\"http:\/\/wfn.codeplex.com\/releases\/view\/615670\" target=\"_blank\" rel=\"noopener\">wfn.codeplex.com\/releases<\/a><br \/>\n&#8211; Und: <a href=\"https:\/\/github.com\/wokhan\/WFN\/releases\" rel=\"noopener\" target=\"_blank\">github.com\/WFN\/releases<\/a><\/p>\n<p><strong>Auch interessant:<\/strong> <a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Firewall_deaktivieren_aktivieren_Einstellungen\" target=\"_blank\" rel=\"noopener\">Windows 10 Firewall deaktivieren aktivieren Einstellungen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Tool Windows Firewall Notifier in der Version 1.9 werden einige von euch sicherlich kennen. Ein kleines Programm, welches sich in die windowseigene Firewall einklinkt und man so die Kontrolle hat, welche Programme eine Verbindung zum Internet herstellen wollen. Dies&hellip; <\/p>\n","protected":false},"author":134,"featured_media":46362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[152,2689,11],"tags":[5181,9002,22,9001,9003,9004],"class_list":["post-46361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software","category-windows-10","category-windows","tag-2-0","tag-firewallzusatz","tag-freeware","tag-portable","tag-verbindungen-blocken","tag-windows-firewall-notifier"],"wp_featured_image":{"id":46362,"alt_text":"","description":"","media_type":"image","media_details":{"width":933,"height":681,"file":"2015\/06\/Windows-Firewall-Notifier-001.jpg","sizes":{"thumbnail":{"file":"Windows-Firewall-Notifier-001-250x180.jpg","width":250,"height":180,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001-250x180.jpg"},"medium":{"file":"Windows-Firewall-Notifier-001-500x360.jpg","width":500,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001-500x360.jpg"},"large":{"file":"Windows-Firewall-Notifier-001-700x504.jpg","width":700,"height":504,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001-700x504.jpg"},"wp_rp_thumbnail":{"file":"Windows-Firewall-Notifier-001-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001-150x150.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":46361,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001.jpg"},"commentcount":4,"wp_comments":[{"id":242160,"parent":0,"author":0,"author_name":"Max","author_email":"XXX@XXX.xxx","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7dfd10b96f8323aa474196963342ec4f8732309710279bec2867b05a712b0a45?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7dfd10b96f8323aa474196963342ec4f8732309710279bec2867b05a712b0a45?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7dfd10b96f8323aa474196963342ec4f8732309710279bec2867b05a712b0a45?s=96&d=mm&r=g"},"date":"2023-06-25T13:17:40","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8230; die Links zum Hersteller gehn nicht mehr, weil das Projekt &#8222;Windows Firewall Notifier&#8220; l\u00e4ngst eingestellt wurde und sich somit das Tool nicht mehr herunterladen l\u00e4sst.<\/p>\n"},"status":"1"},{"id":242162,"parent":0,"author":0,"author_name":"Max","author_email":"XXX@XXX.xx","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/93bfbc9ae985e2f2e3445499dc1f095e49fb86809196e6332e2e48cd85d632b5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/93bfbc9ae985e2f2e3445499dc1f095e49fb86809196e6332e2e48cd85d632b5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/93bfbc9ae985e2f2e3445499dc1f095e49fb86809196e6332e2e48cd85d632b5?s=96&d=mm&r=g"},"date":"2023-06-25T13:23:10","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8230; warum l\u00f6scht ihr hinweise, wenn eure links nicht mehr gehn oder firmen die entwicklung l\u00e4ngst eingestellt haben wie vom oben genannten probramm  ? soll mit falschen oder veralteteten link eure seite &#8222;voller&#8220; und &#8222;intressanter&#8220; aussehn  ? ihr verbreitet aber falsche und f\u00fcr nutzer \u00e4rgerliche informationen, wenn diese nicht stimmen oder es diese genannten tools garnicht mehr vorhanden sind.<\/p>\n"},"status":"1"},{"id":242163,"parent":242162,"author":0,"author_name":"Max","author_email":"XXX@XXX.xxx","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7dfd10b96f8323aa474196963342ec4f8732309710279bec2867b05a712b0a45?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7dfd10b96f8323aa474196963342ec4f8732309710279bec2867b05a712b0a45?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7dfd10b96f8323aa474196963342ec4f8732309710279bec2867b05a712b0a45?s=96&d=mm&r=g"},"date":"2023-06-25T13:24:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8230; dieser Eintrag sollte nicht rein, weil ich dachte, ihr habt den ersten Eintrag gel\u00f6scht <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/> SORRY !<\/p>\n"},"status":"1"},{"id":242164,"parent":242163,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2023-06-25T13:39:37","cld_nonce":"b6d6726996","content":{"rendered":"<p>Warum sollten wir ihn l\u00f6schen?<br \/>\nDer Beitrag ist von 2015, da kann so etwas schon mal vorkommen, dass es ein Tool nicht mehr gibt.<\/p>\n<p>Hab oben mal einen GitHub-Link hinzugef\u00fcgt<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windows Firewall Notifier 2.0 Portable erschienen - Datenverbindungen \u00fcberwachen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows Firewall Notifier 2.0 Portable erschienen - Datenverbindungen \u00fcberwachen\" \/>\n<meta property=\"og:description\" content=\"Das Tool Windows Firewall Notifier in der Version 1.9 werden einige von euch sicherlich kennen. Ein kleines Programm, welches sich in die windowseigene Firewall einklinkt und man so die Kontrolle hat, welche Programme eine Verbindung zum Internet herstellen wollen. Dies&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-15T14:30:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-25T12:05:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"933\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Windows Firewall Notifier 2.0 Portable erschienen &#8211; Datenverbindungen \u00fcberwachen\",\"datePublished\":\"2015-06-15T14:30:07+00:00\",\"dateModified\":\"2023-06-25T12:05:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/\"},\"wordCount\":261,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Windows-Firewall-Notifier-001.jpg\",\"keywords\":[\"2.0\",\"Firewallzusatz\",\"Freeware\",\"portable\",\"Verbindungen blocken\",\"Windows Firewall Notifier\"],\"articleSection\":[\"Software &amp; Updates\",\"Windows 10\",\"Windows \u00e4lter\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/#respond\"]}],\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/\",\"name\":\"Windows Firewall Notifier 2.0 Portable erschienen - Datenverbindungen \u00fcberwachen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Windows-Firewall-Notifier-001.jpg\",\"datePublished\":\"2015-06-15T14:30:07+00:00\",\"dateModified\":\"2023-06-25T12:05:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Windows-Firewall-Notifier-001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Windows-Firewall-Notifier-001.jpg\",\"width\":933,\"height\":681},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/06\\\/15\\\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows Firewall Notifier 2.0 Portable erschienen &#8211; Datenverbindungen \u00fcberwachen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windows Firewall Notifier 2.0 Portable erschienen - Datenverbindungen \u00fcberwachen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/","og_locale":"de_DE","og_type":"article","og_title":"Windows Firewall Notifier 2.0 Portable erschienen - Datenverbindungen \u00fcberwachen","og_description":"Das Tool Windows Firewall Notifier in der Version 1.9 werden einige von euch sicherlich kennen. Ein kleines Programm, welches sich in die windowseigene Firewall einklinkt und man so die Kontrolle hat, welche Programme eine Verbindung zum Internet herstellen wollen. Dies&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2015-06-15T14:30:07+00:00","article_modified_time":"2023-06-25T12:05:49+00:00","og_image":[{"width":933,"height":681,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Windows Firewall Notifier 2.0 Portable erschienen &#8211; Datenverbindungen \u00fcberwachen","datePublished":"2015-06-15T14:30:07+00:00","dateModified":"2023-06-25T12:05:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/"},"wordCount":261,"commentCount":4,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001.jpg","keywords":["2.0","Firewallzusatz","Freeware","portable","Verbindungen blocken","Windows Firewall Notifier"],"articleSection":["Software &amp; Updates","Windows 10","Windows \u00e4lter"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/#respond"]}],"copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/","url":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/","name":"Windows Firewall Notifier 2.0 Portable erschienen - Datenverbindungen \u00fcberwachen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001.jpg","datePublished":"2015-06-15T14:30:07+00:00","dateModified":"2023-06-25T12:05:49+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001.jpg","width":933,"height":681},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/06\/15\/windows-firewall-notifier-2-0-portable-erschienen-datenverbindungen-ueberwachen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows Firewall Notifier 2.0 Portable erschienen &#8211; Datenverbindungen \u00fcberwachen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/06\/Windows-Firewall-Notifier-001.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/46361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=46361"}],"version-history":[{"count":1,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/46361\/revisions"}],"predecessor-version":[{"id":179529,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/46361\/revisions\/179529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/46362"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=46361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=46361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=46361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}