{"id":39072,"date":"2015-02-17T08:47:17","date_gmt":"2015-02-17T07:47:17","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=39072"},"modified":"2015-02-17T08:47:17","modified_gmt":"2015-02-17T07:47:17","slug":"asus-demnaechst-mit-smartwatch-ohne-android-wear","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/","title":{"rendered":"Asus demn\u00e4chst mit Smartwatch ohne Android Wear ?"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/09\/Asus-ZenWatch-Front_1.jpg\" rel=\"lightbox[39072]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-31305\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/09\/Asus-ZenWatch-Front_1-150x150.jpg\" alt=\"Asus-ZenWatch-Front_1\" width=\"150\" height=\"150\" \/><\/a>Auch in diesem Jahr werden wir wohl die ein oder andere Smartwatch diverser Hersteller zu sehen bekommen. Auch Asus wird mit an Bord sein &#8211; doch auch f\u00fcr die Zukunft scheint man schon Pl\u00e4ne zu haben.<\/p>\n<p>Denn offensichtlich scheint Asus mit Android Wear unzufrieden zu sein und plant eine Smartwatch unabh\u00e4ngig vom System aus dem Hause Google zu produzieren.<\/p>\n<p><!--more--><\/p>\n<p>Genaue Angaben gibt es noch nicht. Doch soll das System generell schonender mit dem Akku umgehen, leistungstechnisch aber stark genug sein. M\u00f6glicherweise wird man hier auf einen Chip aus dem Hause MediaTek setzen.<\/p>\n<p>Man kann gespannt sein. Vom Design her gefallen mit die bisherigen Exemplare von Asus zumindest gut.<\/p>\n<div class=\"viaquelle\">via <a href=\"http:\/\/pocketnow.com\/2015\/02\/16\/asus-smartwatch-strategy\" target=\"_blank\">Pocketnow<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Auch in diesem Jahr werden wir wohl die ein oder andere Smartwatch diverser Hersteller zu sehen bekommen. Auch Asus wird mit an Bord sein &#8211; doch auch f\u00fcr die Zukunft scheint man schon Pl\u00e4ne zu haben. Denn offensichtlich scheint Asus&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":43721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[2146,2747,6454],"class_list":["post-39072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-asus","tag-smartwatch","tag-zenwatch"],"wp_featured_image":{"id":43721,"alt_text":"","description":"","media_type":"image","media_details":{"width":150,"height":150,"file":"2015\/02\/Asus-ZenWatch-Front_1-150x150.jpg","sizes":{"thumbnail":{"file":"Asus-ZenWatch-Front_1-150x150-250x180.jpg","width":250,"height":180,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150-250x180.jpg"},"medium":{"file":"Asus-ZenWatch-Front_1-150x150-500x360.jpg","width":500,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150-500x360.jpg"},"large":{"file":"Asus-ZenWatch-Front_1-150x150-700x504.jpg","width":700,"height":504,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150-700x504.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":39072,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150.jpg"},"commentcount":1,"wp_comments":[{"id":9194,"parent":0,"author":0,"author_name":"Andreas","author_email":"andy_g1409@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5c4109f2dfb7d547d022d0300f6b7285b1355edd52e9122cb9b48843ae5bd466?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5c4109f2dfb7d547d022d0300f6b7285b1355edd52e9122cb9b48843ae5bd466?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5c4109f2dfb7d547d022d0300f6b7285b1355edd52e9122cb9b48843ae5bd466?s=96&d=mm&r=g"},"date":"2015-02-17T12:58:10","cld_nonce":"82f011626f","content":{"rendered":"<p>Gab es nicht letztens eine Meldung zu einer Asus-Smartwatch mit &#8222;Vivo&#8220; im Namen? &#8222;Vivo&#8220; sind ja bisher Windows-Systeme.<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Asus demn\u00e4chst mit Smartwatch ohne Android Wear ? - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asus demn\u00e4chst mit Smartwatch ohne Android Wear ?\" \/>\n<meta property=\"og:description\" content=\"Auch in diesem Jahr werden wir wohl die ein oder andere Smartwatch diverser Hersteller zu sehen bekommen. Auch Asus wird mit an Bord sein &#8211; doch auch f\u00fcr die Zukunft scheint man schon Pl\u00e4ne zu haben. Denn offensichtlich scheint Asus&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-17T07:47:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Asus demn\u00e4chst mit Smartwatch ohne Android Wear ?\",\"datePublished\":\"2015-02-17T07:47:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/\"},\"wordCount\":124,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Asus-ZenWatch-Front_1-150x150.jpg\",\"keywords\":[\"Asus\",\"Smartwatch\",\"ZenWatch\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/#respond\"]}],\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/\",\"name\":\"Asus demn\u00e4chst mit Smartwatch ohne Android Wear ? - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Asus-ZenWatch-Front_1-150x150.jpg\",\"datePublished\":\"2015-02-17T07:47:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Asus-ZenWatch-Front_1-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Asus-ZenWatch-Front_1-150x150.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/17\\\/asus-demnaechst-mit-smartwatch-ohne-android-wear\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asus demn\u00e4chst mit Smartwatch ohne Android Wear ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Asus demn\u00e4chst mit Smartwatch ohne Android Wear ? - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/","og_locale":"de_DE","og_type":"article","og_title":"Asus demn\u00e4chst mit Smartwatch ohne Android Wear ?","og_description":"Auch in diesem Jahr werden wir wohl die ein oder andere Smartwatch diverser Hersteller zu sehen bekommen. Auch Asus wird mit an Bord sein &#8211; doch auch f\u00fcr die Zukunft scheint man schon Pl\u00e4ne zu haben. Denn offensichtlich scheint Asus&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2015-02-17T07:47:17+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Asus demn\u00e4chst mit Smartwatch ohne Android Wear ?","datePublished":"2015-02-17T07:47:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/"},"wordCount":124,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150.jpg","keywords":["Asus","Smartwatch","ZenWatch"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/#respond"]}],"copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/","url":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/","name":"Asus demn\u00e4chst mit Smartwatch ohne Android Wear ? - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150.jpg","datePublished":"2015-02-17T07:47:17+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/17\/asus-demnaechst-mit-smartwatch-ohne-android-wear\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Asus demn\u00e4chst mit Smartwatch ohne Android Wear ?"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/Asus-ZenWatch-Front_1-150x150.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/39072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=39072"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/39072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/43721"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=39072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=39072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=39072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}