{"id":39026,"date":"2015-02-15T13:56:07","date_gmt":"2015-02-15T12:56:07","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=39026"},"modified":"2015-02-15T13:56:50","modified_gmt":"2015-02-15T12:56:50","slug":"htc-one-m8i-technische-daten-geleakt","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/","title":{"rendered":"HTC One M8i &#8211; Technische Daten geleakt"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2.jpg\" rel=\"lightbox[39026]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-38857\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2-150x150.jpg\" alt=\"htc one m8 hima konzept (2)\" width=\"150\" height=\"150\" \/><\/a>Mit dem HTC One M9 wird uns HTC auf dem Mobile World Congress 2015 sein neues Smartphone-Flaggschiff pr\u00e4sentieren. Aber offensichtlich plant man auch ein neues Mittelklasse-Smartphone zu pr\u00e4sentieren, welches die Bezeichnung <strong>HTC One M8i<\/strong> tragen und auf dem One M8 basieren soll.<\/p>\n<p>Nun hat User <a href=\"http:\/\/upleaks.info\/2015\/02\/15\/htc-one-m8im8_ql\/\" target=\"_blank\">Upleaks<\/a> die technischen Daten ver\u00f6ffentlicht, welche f\u00fcr ein Ger\u00e4t der Mittelklasse nicht schlecht sind.<\/p>\n<p><!--more--><\/p>\n<p><span style=\"text-decoration: underline;\">Hier einmal die Daten im \u00dcberblick:<\/span><\/p>\n<ul>\n<li>0PKV series<\/li>\n<li>In almost same dimension\/weight as M8<\/li>\n<li>Qualcomm Snapdragon 615 MSM8939 1.7GHz*4 + 1.0GHz*4<\/li>\n<li>5\u2033 FHD Display<\/li>\n<li>2GB DDR3 RAM<\/li>\n<li>16GB ROM<\/li>\n<li>Android 5.0 with Desire Sense 7.0<\/li>\n<li>13MP + 2MP Main DuoCamera with Dual LED flash<\/li>\n<li>5MP Front Camera optimized to Selfie<\/li>\n<li>BoomSound<\/li>\n<li>NFC<\/li>\n<li>Bluetooth 4.1<\/li>\n<li>microSD slot<\/li>\n<li>Battery less than 3000mAh<\/li>\n<\/ul>\n<p>Da das One M8i mit Sense 7.0 ausgeliefert werden soll, wird es auch erst nach dem HTC One M9 pr\u00e4sentiert werden. Ein m\u00f6glicher Preis ist noch nicht bekannt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit dem HTC One M9 wird uns HTC auf dem Mobile World Congress 2015 sein neues Smartphone-Flaggschiff pr\u00e4sentieren. Aber offensichtlich plant man auch ein neues Mittelklasse-Smartphone zu pr\u00e4sentieren, welches die Bezeichnung HTC One M8i tragen und auf dem One M8&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":72515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[7866],"class_list":["post-39026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-htc-one-m8i"],"wp_featured_image":{"id":72515,"alt_text":"","description":"","media_type":"image","media_details":{"width":150,"height":150,"file":"2015\/02\/htc-one-m8-hima-konzept-2-150x150-1.jpg","sizes":{"wp_review_small":{"file":"htc-one-m8-hima-konzept-2-150x150-1-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2-150x150-1-65x65.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":39026,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2-150x150-1.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>HTC One M8i - Technische Daten geleakt - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HTC One M8i - Technische Daten geleakt\" \/>\n<meta property=\"og:description\" content=\"Mit dem HTC One M9 wird uns HTC auf dem Mobile World Congress 2015 sein neues Smartphone-Flaggschiff pr\u00e4sentieren. Aber offensichtlich plant man auch ein neues Mittelklasse-Smartphone zu pr\u00e4sentieren, welches die Bezeichnung HTC One M8i tragen und auf dem One M8&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-15T12:56:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-02-15T12:56:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2-150x150-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"HTC One M8i &#8211; Technische Daten geleakt\",\"datePublished\":\"2015-02-15T12:56:07+00:00\",\"dateModified\":\"2015-02-15T12:56:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/\"},\"wordCount\":156,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/htc-one-m8-hima-konzept-2-150x150-1.jpg\",\"keywords\":[\"HTC One M8i\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/#respond\"]}],\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/\",\"name\":\"HTC One M8i - Technische Daten geleakt - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/htc-one-m8-hima-konzept-2-150x150-1.jpg\",\"datePublished\":\"2015-02-15T12:56:07+00:00\",\"dateModified\":\"2015-02-15T12:56:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/htc-one-m8-hima-konzept-2-150x150-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/htc-one-m8-hima-konzept-2-150x150-1.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/02\\\/15\\\/htc-one-m8i-technische-daten-geleakt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HTC One M8i &#8211; Technische Daten geleakt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"HTC One M8i - Technische Daten geleakt - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/","og_locale":"de_DE","og_type":"article","og_title":"HTC One M8i - Technische Daten geleakt","og_description":"Mit dem HTC One M9 wird uns HTC auf dem Mobile World Congress 2015 sein neues Smartphone-Flaggschiff pr\u00e4sentieren. Aber offensichtlich plant man auch ein neues Mittelklasse-Smartphone zu pr\u00e4sentieren, welches die Bezeichnung HTC One M8i tragen und auf dem One M8&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2015-02-15T12:56:07+00:00","article_modified_time":"2015-02-15T12:56:50+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2-150x150-1.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"HTC One M8i &#8211; Technische Daten geleakt","datePublished":"2015-02-15T12:56:07+00:00","dateModified":"2015-02-15T12:56:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/"},"wordCount":156,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2-150x150-1.jpg","keywords":["HTC One M8i"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/#respond"]}],"copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/","url":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/","name":"HTC One M8i - Technische Daten geleakt - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2-150x150-1.jpg","datePublished":"2015-02-15T12:56:07+00:00","dateModified":"2015-02-15T12:56:50+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2-150x150-1.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2-150x150-1.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/02\/15\/htc-one-m8i-technische-daten-geleakt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"HTC One M8i &#8211; Technische Daten geleakt"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/02\/htc-one-m8-hima-konzept-2-150x150-1.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/39026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=39026"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/39026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/72515"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=39026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=39026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=39026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}