{"id":38050,"date":"2015-01-29T16:22:09","date_gmt":"2015-01-29T15:22:09","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=38050"},"modified":"2015-01-29T16:22:47","modified_gmt":"2015-01-29T15:22:47","slug":"lg-mit-weiterem-fortschritt-bei-flexiblen-displays","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/","title":{"rendered":"LG mit weiterem Fortschritt bei flexiblen Displays"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel.jpg\" rel=\"lightbox[38050]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-38054\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel-150x108.jpg\" alt=\"flexible-oled-lighting-panel\" width=\"150\" height=\"108\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel-150x108.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel.jpg 545w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Auf der CES 2015 hat uns LG mit dem LG G Flex 2 sein zweites Smartphone mit einem gebogenem bzw. flexiblem Display vorgestellt. Bereits im letzten Jahr konnten wir mitverfolgen wie weit die Entwicklung der flexiblen Displays bei LG ist und nun vermeldet man einen weiteren Fortschritt.<\/p>\n<p>Denn die nun vorliegenden Displays k\u00f6nnen bis zu 30% gebogen werden und sind somit schon fast faltbar.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/LG-Chem-Plastic-Based-Truly-Flexible-OLED-Light-Panel.jpg\" rel=\"lightbox[38050]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-38055\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/LG-Chem-Plastic-Based-Truly-Flexible-OLED-Light-Panel.jpg\" alt=\"LG-Chem-Plastic-Based-Truly-Flexible-OLED-Light-Panel\" width=\"513\" height=\"512\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/LG-Chem-Plastic-Based-Truly-Flexible-OLED-Light-Panel.jpg 513w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/LG-Chem-Plastic-Based-Truly-Flexible-OLED-Light-Panel-150x150.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/LG-Chem-Plastic-Based-Truly-Flexible-OLED-Light-Panel-500x500.jpg 500w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/><\/a><\/p>\n<p>Gerade im TV-Bereich aber auch bei Smartwatches oder bei Lampen sieht LG Anwendungsgebiete. Und mal schauen wann wir dann wirklich das erste faltbare Tablet oder Smartphone sehen werden.<\/p>\n<div class=\"quelle\"><a href=\"http:\/\/news.oled-display.net\/lg-chem-new-flexible-plastic-oled-lighting-panels-2015\/\" target=\"_blank\">Quelle<\/a> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Auf der CES 2015 hat uns LG mit dem LG G Flex 2 sein zweites Smartphone mit einem gebogenem bzw. flexiblem Display vorgestellt. Bereits im letzten Jahr konnten wir mitverfolgen wie weit die Entwicklung der flexiblen Displays bei LG ist&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":38054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[2213,630,7676,3082,7677,2184,7678,2747],"class_list":["post-38050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-display","tag-entwicklung","tag-faltbare-displays","tag-flexible-displays","tag-fortschritt","tag-lg","tag-smartphine","tag-smartwatch"],"wp_featured_image":{"id":38054,"alt_text":"","description":"","media_type":"image","media_details":{"width":545,"height":392,"file":"2015\/01\/flexible-oled-lighting-panel.jpg","sizes":{"thumbnail":{"file":"flexible-oled-lighting-panel-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel-150x150.jpg"},"medium":{"file":"flexible-oled-lighting-panel-150x108.jpg","width":150,"height":108,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel-150x108.jpg"},"large":{"file":"flexible-oled-lighting-panel-500x360.jpg","width":500,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel-500x360.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":38050,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LG mit weiterem Fortschritt bei flexiblen Displays - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LG mit weiterem Fortschritt bei flexiblen Displays\" \/>\n<meta property=\"og:description\" content=\"Auf der CES 2015 hat uns LG mit dem LG G Flex 2 sein zweites Smartphone mit einem gebogenem bzw. flexiblem Display vorgestellt. Bereits im letzten Jahr konnten wir mitverfolgen wie weit die Entwicklung der flexiblen Displays bei LG ist&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-29T15:22:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-29T15:22:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"545\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"LG mit weiterem Fortschritt bei flexiblen Displays\",\"datePublished\":\"2015-01-29T15:22:09+00:00\",\"dateModified\":\"2015-01-29T15:22:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/\"},\"wordCount\":100,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/flexible-oled-lighting-panel.jpg\",\"keywords\":[\"Display\",\"entwicklung\",\"faltbare Displays\",\"flexible Displays\",\"Fortschritt\",\"LG\",\"Smartphine\",\"Smartwatch\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/#respond\"]}],\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/\",\"name\":\"LG mit weiterem Fortschritt bei flexiblen Displays - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/flexible-oled-lighting-panel.jpg\",\"datePublished\":\"2015-01-29T15:22:09+00:00\",\"dateModified\":\"2015-01-29T15:22:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/flexible-oled-lighting-panel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/flexible-oled-lighting-panel.jpg\",\"width\":545,\"height\":392},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/29\\\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LG mit weiterem Fortschritt bei flexiblen Displays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LG mit weiterem Fortschritt bei flexiblen Displays - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/","og_locale":"de_DE","og_type":"article","og_title":"LG mit weiterem Fortschritt bei flexiblen Displays","og_description":"Auf der CES 2015 hat uns LG mit dem LG G Flex 2 sein zweites Smartphone mit einem gebogenem bzw. flexiblem Display vorgestellt. Bereits im letzten Jahr konnten wir mitverfolgen wie weit die Entwicklung der flexiblen Displays bei LG ist&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2015-01-29T15:22:09+00:00","article_modified_time":"2015-01-29T15:22:47+00:00","og_image":[{"width":545,"height":392,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"LG mit weiterem Fortschritt bei flexiblen Displays","datePublished":"2015-01-29T15:22:09+00:00","dateModified":"2015-01-29T15:22:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/"},"wordCount":100,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel.jpg","keywords":["Display","entwicklung","faltbare Displays","flexible Displays","Fortschritt","LG","Smartphine","Smartwatch"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/#respond"]}],"copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/","url":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/","name":"LG mit weiterem Fortschritt bei flexiblen Displays - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel.jpg","datePublished":"2015-01-29T15:22:09+00:00","dateModified":"2015-01-29T15:22:47+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel.jpg","width":545,"height":392},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/29\/lg-mit-weiterem-fortschritt-bei-flexiblen-displays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"LG mit weiterem Fortschritt bei flexiblen Displays"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/flexible-oled-lighting-panel.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/38050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=38050"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/38050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/38054"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=38050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=38050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=38050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}