{"id":37188,"date":"2015-01-14T16:40:26","date_gmt":"2015-01-14T15:40:26","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=37188"},"modified":"2015-01-14T16:40:26","modified_gmt":"2015-01-14T15:40:26","slug":"screenshots-vom-ablauf-der-windows-10-technical-preview-installation","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/","title":{"rendered":"Screenshots vom Ablauf der  Windows 10 Technical Preview Installation"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1.jpg\" rel=\"lightbox[37188]\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1-150x106.jpg\" alt=\"win-10-upgrade-screenshots-1\" width=\"150\" height=\"106\" class=\"alignleft size-medium wp-image-37189\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1-150x106.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1-500x355.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1.jpg 915w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Painter hat heute Screenshots ver\u00f6ffentlicht, die zeigen wie die Windows 10 Technical Preview vom Januar installiert wird.<\/p>\n<p>Diese Screenshots werden dann wohl die Windows 7 und Windows 8.1 Benutzer zu sehen bekommen, wenn sie ihr System auf die neue Windows 10 TP upgraden.<br \/>\nAber hier sei noch einmal gesagt: Wenn es soweit ist, macht vorab ein Backup von eurem Betriebssystem. Ansonsten d\u00fcrft ihr neu installieren. Denn ein Zur\u00fcck gibt es nicht.<br \/>\nSiehe: <a href='http:\/\/www.deskmodder.de\/wiki\/index.php?title=Sicherung_erstellen_Backup_anlegen_Windows_8.1'\" target=\"_blank\"'>Sicherung erstellen Backup anlegen Windows 8.1<\/a><!--more--><br class=\"clear\" \/><\/p>\n<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-2.jpg\" rel=\"lightbox[37188]\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-2-150x106.jpg\" alt=\"win-10-upgrade-screenshots-2\" width=\"150\" height=\"106\" class=\"alignleft size-medium wp-image-37191\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-2-150x106.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-2-500x355.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-2.jpg 915w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Bevor es wirklich los geht, fragt der Installer, ob ihr wirklich upgraden m\u00f6chtet.<br class=\"clear\" \/><br \/>\n<a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-3.jpg\" rel=\"lightbox[37188]\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-3-150x106.jpg\" alt=\"win-10-upgrade-screenshots-3\" width=\"150\" height=\"106\" class=\"alignleft size-medium wp-image-37192\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-3-150x106.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-3-500x355.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-3.jpg 915w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Solltet ihr installieren, pr\u00fcft der Installer das System, ob ein Upgrade wirklich m\u00f6glich ist. <br class=\"clear\" \/><br \/>\n<a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-4.jpg\" rel=\"lightbox[37188]\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-4-150x98.jpg\" alt=\"win-10-upgrade-screenshots-4\" width=\"150\" height=\"98\" class=\"alignleft size-medium wp-image-37193\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-4-150x98.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-4-500x327.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-4.jpg 752w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Falls es dann doch daneben gehen sollte und irgendetwas mit eurem System nicht stimmt, dann kommt dieser Screen, den Roman getwittert hat.<\/p>\n<p>Bis zum 21.Januar ist  es ja noch ein paar Tage hin.<br \/>\nOb man dann Windows 10 mit einem lokalen oder Microsoft-Konto installiert, muss jeder selbst entscheiden.<br \/>\nWir haben beide Methoden schon einmal im Wiki als Tutorial bereitgestellt:<br \/>\n\u25aa <a href='http:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_richtig_installieren_mit_einem_Microsoft_oder_lokalem_Konto'\" target=\"_blank\"'>Windows 10 richtig installieren mit einem Microsoft oder lokalem Konto<\/a><\/p>\n<p>Wer schon mal bei uns im Wiki bei den Tutorials f\u00fcr Windows 10 schn\u00f6kern m\u00f6chte:<\/p>\n<p><br class=\"clear\" \/><br class=\"clear\" \/><\/p>\n<p><strong>Alle Tutorials f\u00fcr Windows 10<\/strong> findet ihr bei uns im Wiki im:<br \/>\n\u25aa <a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Portal:Windows_10\" target=\"_blank\"><strong>Portal:Windows 10<\/strong><\/a> in einer \u00dcbersicht.<br \/>\n\u25aa <a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" target=\"_blank\"><span style=\"text-decoration: underline;\"><strong>Kategorie:Windows 10<\/strong><\/span><\/a> Alle Tutorials.<\/p>\n<p>Sowie geordnet in:<\/p>\n<p><center><\/p>\n<table style=\"height: 143px;\" width=\"692\">\n<tbody>\n<tr>\n<td>\n<p><a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10_Allgemein\" target=\"_blank\">Windows 10 Allgemein<\/a><\/td>\n<td>\n<p><a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10_Design\" target=\"_blank\">Windows 10 Design<\/a><\/td>\n<td>\n<p><a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10_Desktop_Explorer\" target=\"_blank\">Windows 10 Desktop Explorer<\/a><\/td>\n<\/tr>\n<tr>\n<td>\n<p><a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10_Fehlermeldungen\" target=\"_blank\">Windows 10 Fehlermeldungen<\/a><\/td>\n<td>\n<p><a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10_Login_Boot\" target=\"_blank\">Windows 10 Login Boot<\/a><\/td>\n<td>\n<p><a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10_ModernUI_und_Apps\" target=\"_blank\">Windows 10 ModernUI und Apps<\/a><\/td>\n<\/tr>\n<tr>\n<td>\n<p><a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10_OneDrive_Sicherheit_Internet\" target=\"_blank\">Windows 10 OneDrive Sicherheit Internet<\/a><\/td>\n<td>\n<p><a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10_Sicherung_Reparatur_Backup\" target=\"_blank\">Windows 10 Sicherung Reparatur Backup<\/a><\/td>\n<td>\n<p><a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10_System_Tweaks\" target=\"_blank\">Windows 10 System Tweaks<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/center><\/p>\n<div class=\"quelle\">Quelle: <a href='http:\/\/pcportal.org.ru\/forum\/60-6328-7#117157'\" target=\"_blank\"'>pcportal.org.ru<\/a> und <a href='https:\/\/twitter.com\/rlinev\/status\/555119406872014848\/photo\/1'\" target=\"_blank\"'>twitter.com\/rlinev<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Painter hat heute Screenshots ver\u00f6ffentlicht, die zeigen wie die Windows 10 Technical Preview vom Januar installiert wird. Diese Screenshots werden dann wohl die Windows 7 und Windows 8.1 Benutzer zu sehen bekommen, wenn sie ihr System auf die neue Windows&hellip; <\/p>\n","protected":false},"author":134,"featured_media":37189,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[1724,602,9751],"class_list":["post-37188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-screenshots","tag-upgrade","tag-windows-10"],"wp_featured_image":{"id":37189,"alt_text":"","description":"","media_type":"image","media_details":{"width":915,"height":649,"file":"2015\/01\/win-10-upgrade-screenshots-1.jpg","sizes":{"thumbnail":{"file":"win-10-upgrade-screenshots-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1-150x150.jpg"},"medium":{"file":"win-10-upgrade-screenshots-1-150x106.jpg","width":150,"height":106,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1-150x106.jpg"},"large":{"file":"win-10-upgrade-screenshots-1-500x355.jpg","width":500,"height":355,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1-500x355.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":37188,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1.jpg"},"commentcount":1,"wp_comments":[{"id":8623,"parent":0,"author":0,"author_name":"MarcSenn","author_email":"marcsenn@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=96&d=mm&r=g"},"date":"2015-01-15T01:09:50","cld_nonce":"82f011626f","content":{"rendered":"<p>Wer installiert \u00fcber eine vorb version die win 10 consumer version. Und den wider \u00fcber MS Meckern weil die den so schlecht leuft. Freu mich auf den complet umstieg von win 8.1 nach win 10 am 21.1<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Screenshots vom Ablauf der Windows 10 Technical Preview Installation - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Screenshots vom Ablauf der Windows 10 Technical Preview Installation\" \/>\n<meta property=\"og:description\" content=\"Painter hat heute Screenshots ver\u00f6ffentlicht, die zeigen wie die Windows 10 Technical Preview vom Januar installiert wird. Diese Screenshots werden dann wohl die Windows 7 und Windows 8.1 Benutzer zu sehen bekommen, wenn sie ihr System auf die neue Windows&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-14T15:40:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"915\" \/>\n\t<meta property=\"og:image:height\" content=\"649\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Screenshots vom Ablauf der Windows 10 Technical Preview Installation\",\"datePublished\":\"2015-01-14T15:40:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/\"},\"wordCount\":79,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/win-10-upgrade-screenshots-1.jpg\",\"keywords\":[\"Screenshots\",\"Upgrade\",\"Windows 10\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/#respond\"]}],\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/\",\"name\":\"Screenshots vom Ablauf der Windows 10 Technical Preview Installation - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/win-10-upgrade-screenshots-1.jpg\",\"datePublished\":\"2015-01-14T15:40:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/win-10-upgrade-screenshots-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/win-10-upgrade-screenshots-1.jpg\",\"width\":915,\"height\":649},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/14\\\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Screenshots vom Ablauf der Windows 10 Technical Preview Installation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Screenshots vom Ablauf der Windows 10 Technical Preview Installation - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/","og_locale":"de_DE","og_type":"article","og_title":"Screenshots vom Ablauf der Windows 10 Technical Preview Installation","og_description":"Painter hat heute Screenshots ver\u00f6ffentlicht, die zeigen wie die Windows 10 Technical Preview vom Januar installiert wird. Diese Screenshots werden dann wohl die Windows 7 und Windows 8.1 Benutzer zu sehen bekommen, wenn sie ihr System auf die neue Windows&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2015-01-14T15:40:26+00:00","og_image":[{"width":915,"height":649,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Screenshots vom Ablauf der Windows 10 Technical Preview Installation","datePublished":"2015-01-14T15:40:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/"},"wordCount":79,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1.jpg","keywords":["Screenshots","Upgrade","Windows 10"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/#respond"]}],"copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/","url":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/","name":"Screenshots vom Ablauf der Windows 10 Technical Preview Installation - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1.jpg","datePublished":"2015-01-14T15:40:26+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1.jpg","width":915,"height":649},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/14\/screenshots-vom-ablauf-der-windows-10-technical-preview-installation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Screenshots vom Ablauf der Windows 10 Technical Preview Installation"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/01\/win-10-upgrade-screenshots-1.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/37188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=37188"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/37188\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/37189"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=37188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=37188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=37188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}