{"id":36675,"date":"2015-01-05T15:31:53","date_gmt":"2015-01-05T14:31:53","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=36675"},"modified":"2015-01-05T15:31:53","modified_gmt":"2015-01-05T14:31:53","slug":"ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/","title":{"rendered":"[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo.png\" rel=\"lightbox[36675]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-10125\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo-150x67.png\" alt=\"LG-Logo\" width=\"150\" height=\"67\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo-150x67.png 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo-500x225.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo.png 795w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Kurz noch notiert, was von LG grad noch per Pressemitteilung in meinem Postfach gelandet ist. Ab 17 Uhr gibt&#8217;s die Pressekonferenz von der CES 2015 Als Livestream zu verfolgen.<\/p>\n<p>Neben dem G Flex 2 erwartet man auch das neue LG G4. <a href=\"http:\/\/ces2015.lgnewsroom.com\" target=\"_blank\">HIER<\/a> geht&#8217;s zum Liestream.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kurz noch notiert, was von LG grad noch per Pressemitteilung in meinem Postfach gelandet ist. Ab 17 Uhr gibt&#8217;s die Pressekonferenz von der CES 2015 Als Livestream zu verfolgen. Neben dem G Flex 2 erwartet man auch das neue LG&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[7331,2184,1137],"class_list":["post-36675","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-ces-2015","tag-lg","tag-livestream"],"wp_featured_image":null,"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr\" \/>\n<meta property=\"og:description\" content=\"Kurz noch notiert, was von LG grad noch per Pressemitteilung in meinem Postfach gelandet ist. Ab 17 Uhr gibt&#8217;s die Pressekonferenz von der CES 2015 Als Livestream zu verfolgen. Neben dem G Flex 2 erwartet man auch das neue LG&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-05T14:31:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo-150x67.png\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr\",\"datePublished\":\"2015-01-05T14:31:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/\"},\"wordCount\":52,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/LG-Logo-150x67.png\",\"keywords\":[\"ces 2015\",\"LG\",\"LiveStream\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/#respond\"]}],\"copyrightYear\":\"2015\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/\",\"name\":\"[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/LG-Logo-150x67.png\",\"datePublished\":\"2015-01-05T14:31:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/LG-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/LG-Logo.png\",\"width\":795,\"height\":358},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2015\\\/01\\\/05\\\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/","og_locale":"de_DE","og_type":"article","og_title":"[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr","og_description":"Kurz noch notiert, was von LG grad noch per Pressemitteilung in meinem Postfach gelandet ist. Ab 17 Uhr gibt&#8217;s die Pressekonferenz von der CES 2015 Als Livestream zu verfolgen. Neben dem G Flex 2 erwartet man auch das neue LG&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2015-01-05T14:31:53+00:00","og_image":[{"url":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo-150x67.png","type":"","width":"","height":""}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr","datePublished":"2015-01-05T14:31:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/"},"wordCount":52,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/#primaryimage"},"thumbnailUrl":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo-150x67.png","keywords":["ces 2015","LG","LiveStream"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/#respond"]}],"copyrightYear":"2015","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/","url":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/","name":"[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/#primaryimage"},"thumbnailUrl":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo-150x67.png","datePublished":"2015-01-05T14:31:53+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/08\/LG-Logo.png","width":795,"height":358},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2015\/01\/05\/ces-2015-lg-mit-livestream-der-pressekonferenz-ab-17-uhr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"[CES 2015] LG mit Livestream der Pressekonferenz ab 17 Uhr"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/36675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=36675"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/36675\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=36675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=36675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=36675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}