{"id":23214,"date":"2014-03-28T06:03:44","date_gmt":"2014-03-28T05:03:44","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=23214"},"modified":"2014-03-28T06:07:32","modified_gmt":"2014-03-28T05:07:32","slug":"amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/","title":{"rendered":"Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an &#8211; Sehen wir dort den Chromecast-Konkurrenten ?"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1.jpg\" rel=\"lightbox[23214]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-23216\" alt=\"amazon-video-event_1\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1-150x132.jpg\" width=\"150\" height=\"132\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1-150x132.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1.jpg 435w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Die Spekulationen rund um einen Streamingstick von Amazon \u00e4hnlich dem Chromecast von Google, sind nicht neu. Genaues zu diesem Stick ist nicht bekannt und wann Amazon diesen pr\u00e4sentieren will ebenso wenig.<\/p>\n<p>Doch offenbar k\u00f6nnte es schon n\u00e4chste Woche soweit sein. Denn Amazon hat nun ein Presse-Event f\u00fcr den 02.April angek\u00fcndigt. <!--more--><\/p>\n<p>&#8222;Please join us for an update of our video business&#8220; ist dort zu lesen, was man doch als deutlichen Hinweis deuten kann.<\/p>\n<p>Neben dem normalen Streamen von Medieninhalten an den Amazon Stick soll aber auch das Streamen von Games m\u00f6glich werden.<\/p>\n<p>Ich bin gespannt, ob der Amazon-Stick den aktuellen Verkaufsrenner Konkurrenz machen kann.<\/p>\n<p>[<a href=\"http:\/\/gigaom.com\/2014\/03\/27\/amazon-press-event-hints-at-release-of-tv-streaming-device\/\" target=\"_blank\">via<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Spekulationen rund um einen Streamingstick von Amazon \u00e4hnlich dem Chromecast von Google, sind nicht neu. Genaues zu diesem Stick ist nicht bekannt und wann Amazon diesen pr\u00e4sentieren will ebenso wenig. Doch offenbar k\u00f6nnte es schon n\u00e4chste Woche soweit sein.&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":23216,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[5058,2767,2431],"class_list":["post-23214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-amazon-stick","tag-chromecast","tag-streaming"],"wp_featured_image":{"id":23216,"alt_text":"","description":"","media_type":"image","media_details":{"width":435,"height":383,"file":"2014\/03\/amazon-video-event_1.jpg","sizes":{"thumbnail":{"file":"amazon-video-event_1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1-150x150.jpg"},"medium":{"file":"amazon-video-event_1-150x132.jpg","width":150,"height":132,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1-150x132.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":1395986321,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":23214,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an - Sehen wir dort den Chromecast-Konkurrenten ? - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an - Sehen wir dort den Chromecast-Konkurrenten ?\" \/>\n<meta property=\"og:description\" content=\"Die Spekulationen rund um einen Streamingstick von Amazon \u00e4hnlich dem Chromecast von Google, sind nicht neu. Genaues zu diesem Stick ist nicht bekannt und wann Amazon diesen pr\u00e4sentieren will ebenso wenig. Doch offenbar k\u00f6nnte es schon n\u00e4chste Woche soweit sein.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-28T05:03:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-28T05:07:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"383\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an &#8211; Sehen wir dort den Chromecast-Konkurrenten ?\",\"datePublished\":\"2014-03-28T05:03:44+00:00\",\"dateModified\":\"2014-03-28T05:07:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/\"},\"wordCount\":125,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/amazon-video-event_1.jpg\",\"keywords\":[\"Amazon Stick\",\"Chromecast\",\"Streaming\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/#respond\"]}],\"copyrightYear\":\"2014\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/\",\"name\":\"Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an - Sehen wir dort den Chromecast-Konkurrenten ? - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/amazon-video-event_1.jpg\",\"datePublished\":\"2014-03-28T05:03:44+00:00\",\"dateModified\":\"2014-03-28T05:07:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/amazon-video-event_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/amazon-video-event_1.jpg\",\"width\":435,\"height\":383},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2014\\\/03\\\/28\\\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an &#8211; Sehen wir dort den Chromecast-Konkurrenten ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an - Sehen wir dort den Chromecast-Konkurrenten ? - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/","og_locale":"de_DE","og_type":"article","og_title":"Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an - Sehen wir dort den Chromecast-Konkurrenten ?","og_description":"Die Spekulationen rund um einen Streamingstick von Amazon \u00e4hnlich dem Chromecast von Google, sind nicht neu. Genaues zu diesem Stick ist nicht bekannt und wann Amazon diesen pr\u00e4sentieren will ebenso wenig. Doch offenbar k\u00f6nnte es schon n\u00e4chste Woche soweit sein.&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2014-03-28T05:03:44+00:00","article_modified_time":"2014-03-28T05:07:32+00:00","og_image":[{"width":435,"height":383,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an &#8211; Sehen wir dort den Chromecast-Konkurrenten ?","datePublished":"2014-03-28T05:03:44+00:00","dateModified":"2014-03-28T05:07:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/"},"wordCount":125,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1.jpg","keywords":["Amazon Stick","Chromecast","Streaming"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/#respond"]}],"copyrightYear":"2014","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/","url":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/","name":"Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an - Sehen wir dort den Chromecast-Konkurrenten ? - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1.jpg","datePublished":"2014-03-28T05:03:44+00:00","dateModified":"2014-03-28T05:07:32+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1.jpg","width":435,"height":383},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2014\/03\/28\/amazon-kuendibt-presse-event-fuer-den-02-april-an-sehen-wir-dort-den-chromecast-konkurrenten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Amazon k\u00fcndigt Presse-Event f\u00fcr den 02.April an &#8211; Sehen wir dort den Chromecast-Konkurrenten ?"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2014\/03\/amazon-video-event_1.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/23214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=23214"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/23214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/23216"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=23214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=23214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=23214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}