{"id":211202,"date":"2026-04-11T08:24:36","date_gmt":"2026-04-11T06:24:36","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=211202"},"modified":"2026-04-11T09:34:55","modified_gmt":"2026-04-11T07:34:55","slug":"kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/","title":{"rendered":"KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende"},"content":{"rendered":"<p>Microsoft stellt heute zum Insider-Marathon eine weitere Beta Insider bereit. Die KB 5083635 erh\u00f6ht die Versionsnummer auf die Windows 11 25H2 26220.8165. Zus\u00e4tzlich zu den Insider-Updates wurde gestern auch ein Wechsel der Insider-Kan\u00e4le angek\u00fcndigt. Man will dadurch mehr \u00dcbersicht schaffen.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta.png\" rel=\"lightbox[211202]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-500x299.png\" alt=\"\" width=\"500\" height=\"299\" class=\"aligncenter size-medium wp-image-170916\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-500x299.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-810x484.png 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-306x183.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta.png 978w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Wir haben <a href=\"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/windows-11-experimentell-und-beta-die-neue-insider-struktur\/\" target=\"_blank\">hier dar\u00fcber berichtet.<\/a> Man hat also darauf reagiert, dass die Beta und Dev sehr oft mit einer identischen Release Notes ver\u00f6ffentlicht wurde. So wie auch heute wieder.<\/p>\n<h3>Bekannte Probleme durch die KB5083635<\/h3>\n<ul>\n<li>Keine beschrieben.<\/li>\n<\/ul>\n<h3>Korrekturen und Verbesserungen durch die KB5083635<\/h3>\n<ul>\n<li><strong>Speicher<\/strong> <\/li>\n<li>Wir erh\u00f6hen die Gr\u00f6\u00dfenbeschr\u00e4nkung f\u00fcr die Formatierung von FAT32-Volumes \u00fcber die Befehlszeile <strong>von 32 GB auf 2 TB<\/strong>.<\/li>\n<li>Die Leistung beim Anzeigen des Speicherinhalts auf gro\u00dfen Volumes \u00fcber \u201eEinstellungen > System > Speicher > Erweiterte Speichereinstellungen > Festplatten und Volumes\u201c wurde verbessert.<\/li>\n<li>\u201eEinstellungen > System > Speicher\u201c wurde aktualisiert, sodass die UAC-Eingabeaufforderung nicht mehr sofort beim Aufrufen der Seite angezeigt wird, sondern erst, wenn Sie tempor\u00e4re Dateien anzeigen m\u00f6chten.<\/li>\n<li><strong>Netzwerk<\/strong> Ein Problem wurde behoben, das in den letzten Insider-Builds dazu f\u00fchrte, dass unter \u201eEinstellungen > Netzwerk &amp; Internet > Datennutzung\u201c unrealistisch hohe Werte angezeigt wurden.<\/li>\n<li><strong>Windows-Sicherheits-App<\/strong> Wir haben k\u00fcrzlich damit begonnen, Verbesserungen an der Windows-Sicherheits-App > Ger\u00e4tesicherheit > Secure Boot-Erfahrung einzuf\u00fchren, die gr\u00fcne, gelbe und rote Symbolmarkierungen sowie neuen Text anzeigt, der den Secure Boot-Status und den Zertifikatsstatus Ihres Ger\u00e4ts widerspiegelt. Microsoft aktualisiert Secure Boot-Zertifikate auf Verbraucherger\u00e4ten und einigen Business-PCs, und Sie k\u00f6nnen Ihren Zertifikatsstatus nun mit dieser neuen Funktion \u00fcberpr\u00fcfen. <em>Diese Funktion ist standardm\u00e4\u00dfig auf von der Unternehmens-IT verwalteten Ger\u00e4ten und Servern deaktiviert.<\/em><\/li>\n<li><a href=\"https:\/\/blogs.windows.com\/windows-insider\/2026\/04\/10\/announcing-windows-11-insider-preview-build-26220-8165-beta-channel\/\" target=\"_blank\">blogs.windows<\/a><\/li>\n<\/ul>\n<h3>Manueller Download der KB5083635<\/h3>\n<ul>\n<li><a href=\"https:\/\/t1p.de\/ldsxw\" target=\"_blank\">Windows11.0-KB5083635-x64.msu<\/a> <\/li>\n<li>ARM: <a href=\"https:\/\/t1p.de\/6rmgb\" target=\"_blank\">Windows11.0-KB5083635-arm64.msu<\/a><\/li>\n<\/ul>\n<h3>Manueller Download der KB5066383 als Enablement Packages f\u00fcr die 26220 Neu ab 27.02.2026<\/h3>\n<ul>\n<li><a href=\"https:\/\/t1p.de\/fbl0h\" target=\"_blank\">Windows11.0-KB5066383-x64.msu<\/a><\/li>\n<li>ARM <a href=\"https:\/\/t1p.de\/1czn7\" target=\"_blank\">Windows11.0-KB5066383-arm64.msu<\/a><\/li>\n<\/ul>\n<h3>Windows 11 Tutorials und Hilfe<\/h3>\n<ul>\n<li>In unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 11 Wiki<\/a> findet ihr sehr viele hilfreiche Tipps und Tricks.<\/li>\n<li>Falls ihr Fragen habt, dann stellt diese ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=353\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Forum<\/strong><\/a>.<\/li>\n<li><strong>Installationsmedien:<\/strong> Aktuelle Windows 11 ISOs findet ihr hier: <a href=\"https:\/\/www.deskmodder.de\/blog\/2025\/06\/28\/windows-11-25h2-26200-iso-esd-deutsch-english\/\" rel=\"noopener\" target=\"_blank\">25H2 26200<\/a>. Ansonsten <a href=\"https:\/\/www.deskmodder.de\/blog\/#:~:text=l%C3%A4dt%20die%2019045.3803-,Download%2DBereich,-Windows%2011%20ISO\" rel=\"noopener\" target=\"_blank\">immer in der rechten Sidebar<\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_neu_clean_installieren_Tipps_und_Tricks\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 neu clean installieren Tipps und Tricks<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_auch_ohne_TPM_und_Secure_Boot_installieren\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 auch ohne TPM und Secure Boot installieren<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_mit_einem_lokalen_oder_Microsoft_Konto_installieren\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 mit lokalem Konto auch Offline installieren<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_Inplace_Upgrade_Reparatur_oder_Feature_Update\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 Inplace Upgrade Reparatur oder Feature Update<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Automatisch_anmelden_Pin_entfernen_Windows_11\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Automatisch anmelden Pin entfernen Windows 11<\/strong><\/a>.<\/li>\n<li>Alle Beitr\u00e4ge zu Windows 11 im Blog findet ihr <a href=\"https:\/\/www.deskmodder.de\/blog\/category\/windows-11\/\" rel=\"noopener\" target=\"_blank\">\u00fcber diese Seite<\/a>. Wobei auch <a href=\"https:\/\/www.deskmodder.de\/blog\/\" rel=\"noopener\" target=\"_blank\">alle anderen Artikel<\/a> interessant sein k\u00f6nnen.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft stellt heute zum Insider-Marathon eine weitere Beta Insider bereit. Die KB 5083635 erh\u00f6ht die Versionsnummer auf die Windows 11 25H2 26220.8165. Zus\u00e4tzlich zu den Insider-Updates wurde gestern auch ein Wechsel der Insider-Kan\u00e4le angek\u00fcndigt. Man will dadurch mehr \u00dcbersicht schaffen.&hellip; <\/p>\n","protected":false},"author":134,"featured_media":170916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[80310],"tags":[96194,96193,96192,89392],"class_list":["post-211202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-11","tag-26220-8165","tag-kb-5083635","tag-kb5083635","tag-windows-11-25h2"],"wp_featured_image":{"id":170916,"alt_text":"","description":"","media_type":"image","media_details":{"width":978,"height":584,"file":"2022\/10\/update-logo-beta.png","filesize":179627,"sizes":{"medium":{"file":"update-logo-beta-500x299.png","width":500,"height":299,"mime-type":"image\/png","filesize":63356,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-500x299.png"},"large":{"file":"update-logo-beta-810x484.png","width":810,"height":484,"mime-type":"image\/png","filesize":130834,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-810x484.png"},"thumbnail":{"file":"update-logo-beta-306x183.png","width":306,"height":183,"mime-type":"image\/png","filesize":30072,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-306x183.png"},"blog-large":{"file":"update-logo-beta-642x300.png","width":642,"height":300,"mime-type":"image\/png","filesize":75226,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-642x300.png"},"blog-medium":{"file":"update-logo-beta-306x205.png","width":306,"height":205,"mime-type":"image\/png","filesize":35495,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-306x205.png"},"recent-thumb":{"file":"update-logo-beta-350x316.png","width":350,"height":316,"mime-type":"image\/png","filesize":65807,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-350x316.png"},"service-featured":{"file":"update-logo-beta-600x330.png","width":600,"height":330,"mime-type":"image\/png","filesize":76061,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta-600x330.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":181692,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta.png"},"commentcount":6,"wp_comments":[{"id":333244,"parent":0,"author":9151,"author_name":"gorzmorz","author_email":"gorzi@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e7e8cd96f95f0f18e1dc745a7b104a857e06e948afb5d067be5ef4e985f0ab6b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e7e8cd96f95f0f18e1dc745a7b104a857e06e948afb5d067be5ef4e985f0ab6b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e7e8cd96f95f0f18e1dc745a7b104a857e06e948afb5d067be5ef4e985f0ab6b?s=96&d=mm&r=g"},"date":"2026-04-11T10:26:01","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>\u201eEinstellungen &gt; System &gt; Speicher\u201c wurde aktualisiert, sodass die UAC-Eingabeaufforderung nicht mehr sofort beim Aufrufen der Seite angezeigt wird, sondern erst, wenn Sie tempor\u00e4re Dateien anzeigen m\u00f6chten.<\/p>\n<p>Kommt bei mir gar nicht. Bereinigung ohne UAC m\u00f6glich. Es gibt aber einen neuen Button &#8222;Cleanup System Files&#8220; und wenn man den dr\u00fcckt, poppt die UAC auf.<br \/>\nBin allerdings auch als Administrator unterwegs.<\/p>\n"},"status":"1"},{"id":333246,"parent":333244,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2026-04-11T10:33:18","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Ja, so soll das ja jetzt auch sein. Ist im Grunde genommen dasselbe verhalten wie bei der klassischen Bereinigung. Die Bereinigung ist jetzt unterteilt in User (ohne UAC-Aufruf) und System (mit UAC-Aufruf).<\/p>\n"},"status":"1"},{"id":333248,"parent":0,"author":9151,"author_name":"gorzmorz","author_email":"gorzi@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e7e8cd96f95f0f18e1dc745a7b104a857e06e948afb5d067be5ef4e985f0ab6b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e7e8cd96f95f0f18e1dc745a7b104a857e06e948afb5d067be5ef4e985f0ab6b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e7e8cd96f95f0f18e1dc745a7b104a857e06e948afb5d067be5ef4e985f0ab6b?s=96&d=mm&r=g"},"date":"2026-04-11T10:38:59","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Ja ist klar. Aber im Beitrag steht von MS, UAC kommt schon, wenn man die tempor\u00e4ren Dateien anklickt. Die lassen sich aber ohne UAC bereinigen. Erst bei Systemdateien kommt die UAC.<\/p>\n"},"status":"1"},{"id":333292,"parent":0,"author":0,"author_name":"J\u00fcrgen Klein","author_email":"edv.kleini@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/2628305da85fe98acd46cbccf7289ec99c3e8c3b760fe73a7f3d3c1604734a92?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/2628305da85fe98acd46cbccf7289ec99c3e8c3b760fe73a7f3d3c1604734a92?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/2628305da85fe98acd46cbccf7289ec99c3e8c3b760fe73a7f3d3c1604734a92?s=96&d=mm&r=g"},"date":"2026-04-11T18:55:25","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Also<br \/>\nWenn ich das richtig verstehe, dann geht es um die UAC User Accounts Control.<br \/>\nWas passiert denn, wenn ich diese in der Registry bzw. in den Einstellungen komplett deaktiviere?<br \/>\nDas w\u00e4re mal interessant.<\/p>\n"},"status":"1"},{"id":333313,"parent":0,"author":4513,"author_name":"Balu66","author_email":"rainer@artelt-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ba06443940aceaad52f5d4fbac7ab2ea0ebf5508e04df74dd978a96ca2e4f8e2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ba06443940aceaad52f5d4fbac7ab2ea0ebf5508e04df74dd978a96ca2e4f8e2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ba06443940aceaad52f5d4fbac7ab2ea0ebf5508e04df74dd978a96ca2e4f8e2?s=96&d=mm&r=g"},"date":"2026-04-12T09:24:53","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Moin,<br \/>\nhabe das update installiert. Nach Neustart kommt diesmal kein Hinweis aauf die Installation der updates.<br \/>\nMit winver wird nach wie vor die Vers.  &#8230;..48 angezeigt. Noch nie vorher ein solches Verhalten gehabt.<br \/>\nWasa bedeutet das?<\/p>\n"},"status":"1"},{"id":333316,"parent":0,"author":4513,"author_name":"Balu66","author_email":"rainer@artelt-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ba06443940aceaad52f5d4fbac7ab2ea0ebf5508e04df74dd978a96ca2e4f8e2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ba06443940aceaad52f5d4fbac7ab2ea0ebf5508e04df74dd978a96ca2e4f8e2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ba06443940aceaad52f5d4fbac7ab2ea0ebf5508e04df74dd978a96ca2e4f8e2?s=96&d=mm&r=g"},"date":"2026-04-12T09:39:21","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Moin,<br \/>\nhat sich erledigt. 2.Durchlauf gestartet und alles O.K.<br \/>\nMein System war wohl noch nicht auf Touren.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"af1c80fd5f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende\" \/>\n<meta property=\"og:description\" content=\"Microsoft stellt heute zum Insider-Marathon eine weitere Beta Insider bereit. Die KB 5083635 erh\u00f6ht die Versionsnummer auf die Windows 11 25H2 26220.8165. Zus\u00e4tzlich zu den Insider-Updates wurde gestern auch ein Wechsel der Insider-Kan\u00e4le angek\u00fcndigt. Man will dadurch mehr \u00dcbersicht schaffen.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-11T06:24:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-11T07:34:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta.png\" \/>\n\t<meta property=\"og:image:width\" content=\"978\" \/>\n\t<meta property=\"og:image:height\" content=\"584\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende\",\"datePublished\":\"2026-04-11T06:24:36+00:00\",\"dateModified\":\"2026-04-11T07:34:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/\"},\"wordCount\":403,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/update-logo-beta.png\",\"keywords\":[\"26220.8165\",\"KB 5083635\",\"KB5083635\",\"Windows 11 25H2\"],\"articleSection\":[\"Windows 11\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/\",\"name\":\"KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/update-logo-beta.png\",\"datePublished\":\"2026-04-11T06:24:36+00:00\",\"dateModified\":\"2026-04-11T07:34:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/update-logo-beta.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/update-logo-beta.png\",\"width\":978,\"height\":584},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/04\\\/11\\\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/","og_locale":"de_DE","og_type":"article","og_title":"KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende","og_description":"Microsoft stellt heute zum Insider-Marathon eine weitere Beta Insider bereit. Die KB 5083635 erh\u00f6ht die Versionsnummer auf die Windows 11 25H2 26220.8165. Zus\u00e4tzlich zu den Insider-Updates wurde gestern auch ein Wechsel der Insider-Kan\u00e4le angek\u00fcndigt. Man will dadurch mehr \u00dcbersicht schaffen.&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2026-04-11T06:24:36+00:00","article_modified_time":"2026-04-11T07:34:55+00:00","og_image":[{"width":978,"height":584,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende","datePublished":"2026-04-11T06:24:36+00:00","dateModified":"2026-04-11T07:34:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/"},"wordCount":403,"commentCount":6,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta.png","keywords":["26220.8165","KB 5083635","KB5083635","Windows 11 25H2"],"articleSection":["Windows 11"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/","url":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/","name":"KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta.png","datePublished":"2026-04-11T06:24:36+00:00","dateModified":"2026-04-11T07:34:55+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta.png","width":978,"height":584},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/04\/11\/kb5083635-windows-11-25h2-manueller-download-neues-update-im-beta-kanal-zum-wochenende\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"KB5083635 Windows 11 25H2 [Manueller Download] neues Update im Beta Kanal zum Wochenende"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/10\/update-logo-beta.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/211202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=211202"}],"version-history":[{"count":3,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/211202\/revisions"}],"predecessor-version":[{"id":211225,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/211202\/revisions\/211225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/170916"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=211202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=211202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=211202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}