{"id":210532,"date":"2026-03-20T09:57:37","date_gmt":"2026-03-20T08:57:37","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=210532"},"modified":"2026-03-20T09:59:22","modified_gmt":"2026-03-20T08:59:22","slug":"google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/","title":{"rendered":"Google Chrome 146.0.7680.153 \/ 154 korrigiert 3 kritische L\u00fccken und 23 andere"},"content":{"rendered":"<p>Google ist auch gut, stellt am 18.03. die Meldung rein, dass der Chrome-Browser 146.0.7680.153\/ 146.0.7680.154 ver\u00f6ffentlicht wird. Nichts weiter. Jetzt tauchen aber die Sicherheitsl\u00fccken auf, die Google korrigiert hat. Und das sind insgesamt 26. Drei davon wurden als kritisch eingestuft.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png\" rel=\"lightbox[210532]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-500x333.png\" alt=\"\" width=\"500\" height=\"333\" class=\"aligncenter size-medium wp-image-162181\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-500x333.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-306x205.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png 600w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Bis auf eine weitere Korrektur (Medium) wurden alle anderen mit &#8222;High&#8220; eingestuft. Also doch ein heftiges Update. <em>(So sah <a href=\"https:\/\/web.archive.org\/web\/20260319060808\/https:\/\/chromereleases.googleblog.com\/\" target=\"_blank\">die Release Notes<\/a> gestern noch aus).<\/em><\/p>\n<p>Dementsprechend wurde auch die Android-Version auf die 146.0.76380.153 aktualisiert, bzw. wird in den kommenden Tagen aktualisiert, wie Google es in den Release Notes schreibt. Hier wurden dieselben Sicherheitsl\u00fccken geschlossen, wie auch in der Desktop-Version.<\/p>\n<h3>Info und Download:<\/h3>\n<ul>\n<li><a href=\"https:\/\/chromereleases.googleblog.com\/2026\/03\/stable-channel-update-for-desktop_18.html\" target=\"_blank\">googleblog.com\/stable-channel-update-for-desktop<\/a><\/li>\n<li><a href=\"https:\/\/chromereleases.googleblog.com\/2026\/03\/chrome-for-android-update_18.html\" target=\"_blank\">googleblog.com\/chrome-for-android-update<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Google ist auch gut, stellt am 18.03. die Meldung rein, dass der Chrome-Browser 146.0.7680.153\/ 146.0.7680.154 ver\u00f6ffentlicht wird. Nichts weiter. Jetzt tauchen aber die Sicherheitsl\u00fccken auf, die Google korrigiert hat. Und das sind insgesamt 26. Drei davon wurden als kritisch eingestuft.&hellip; <\/p>\n","protected":false},"author":134,"featured_media":162181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166],"tags":[95989,95988],"class_list":["post-210532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","tag-google-chrome-146-0-7680-153","tag-google-chrome-146-0-7680-154"],"wp_featured_image":{"id":162181,"alt_text":"","description":"","media_type":"image","media_details":{"width":600,"height":400,"file":"2022\/02\/google-chrome-logo-neu.png","sizes":{"medium":{"file":"google-chrome-logo-neu-500x333.png","width":500,"height":333,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-500x333.png"},"thumbnail":{"file":"google-chrome-logo-neu-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-306x205.png"},"blog-large":{"file":"google-chrome-logo-neu-600x300.png","width":600,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-600x300.png"},"blog-medium":{"file":"google-chrome-logo-neu-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-306x205.png"},"recent-thumb":{"file":"google-chrome-logo-neu-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-350x316.png"},"service-featured":{"file":"google-chrome-logo-neu-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-600x330.png"},"wp_rp_thumbnail":{"file":"google-chrome-logo-neu-50x50.png","width":50,"height":50,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-50x50.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":162618,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png"},"commentcount":5,"wp_comments":[{"id":331165,"parent":0,"author":3001,"author_name":"Janami25","author_email":"mirovb23@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/48f569d8dec591ae29df498900efdc8c685094a1d3f8d8df5fced7f0c075771a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/48f569d8dec591ae29df498900efdc8c685094a1d3f8d8df5fced7f0c075771a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/48f569d8dec591ae29df498900efdc8c685094a1d3f8d8df5fced7f0c075771a?s=96&d=mm&r=g"},"date":"2026-03-20T10:10:55","cld_nonce":"82f011626f","content":{"rendered":"<p>Mittlerweile gibt es gef\u00fchlt jeden 2. Tag eine neue Chrome Version&#8230;<\/p>\n"},"status":"1"},{"id":331168,"parent":331165,"author":10684,"author_name":"Sinnvoller Beitrag","author_email":"teamdjs@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fca52af40a3bd7694ea31ae294696d1737d18a31181dff02e46217744766b3fe?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fca52af40a3bd7694ea31ae294696d1737d18a31181dff02e46217744766b3fe?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fca52af40a3bd7694ea31ae294696d1737d18a31181dff02e46217744766b3fe?s=96&d=mm&r=g"},"date":"2026-03-20T10:42:35","cld_nonce":"82f011626f","content":{"rendered":"<p>Das ist immer noch besser, als alles einmal im Monat in einem Paket zu b\u00fcndeln. Ich m\u00f6chte nicht wochenlang mit einem ungepatchten Browser surfen. Vor allem nicht, wenn ich weiss, dass er Sicherheitsl\u00fccken enth\u00e4lt, die aktiv ausgenutzt werden. Von mir aus kann es ruhig t\u00e4glich Updates geben, solange sichergestellt ist, dass a) die bekannten L\u00fccken geschlossen wurden und b) das Ding stabil und zuverl\u00e4ssig funktioniert.<\/p>\n"},"status":"1"},{"id":331181,"parent":331168,"author":0,"author_name":"Vectorprime","author_email":"reinfeld@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=96&d=mm&r=g"},"date":"2026-03-20T14:24:00","cld_nonce":"82f011626f","content":{"rendered":"<p>da bin ich zu 100% deiner Meinung  <\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/apps.apple.com\/de\/app\/deskmodder\/id1478451921?l=de\" rel=\"nofollow ugc\">Deskmodder.de-App f\u00fcr iOS<\/a><\/i><\/p>\n"},"status":"1"},{"id":331333,"parent":331168,"author":6555,"author_name":"Unbreakable44","author_email":"sascha.renneberg@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/102ef2b6fcfdbf073835e881a4a94f7e888aee6f04c516edfce9463f0ddb667d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/102ef2b6fcfdbf073835e881a4a94f7e888aee6f04c516edfce9463f0ddb667d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/102ef2b6fcfdbf073835e881a4a94f7e888aee6f04c516edfce9463f0ddb667d?s=96&d=mm&r=g"},"date":"2026-03-23T00:10:15","cld_nonce":"82f011626f","content":{"rendered":"<p>ich will aber noch nicht jeden 2 tag mein browser neustarten. ich will doch damit arbeiten?<\/p>\n"},"status":"1"},{"id":331441,"parent":0,"author":2483,"author_name":"MrX1980","author_email":"dfinken@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/14d16a4a4d8343b8eae9de25d7c303406db1f32cd99c34fe0147c9c71261fcfa?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/14d16a4a4d8343b8eae9de25d7c303406db1f32cd99c34fe0147c9c71261fcfa?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/14d16a4a4d8343b8eae9de25d7c303406db1f32cd99c34fe0147c9c71261fcfa?s=96&d=mm&r=g"},"date":"2026-03-23T21:55:05","cld_nonce":"82f011626f","content":{"rendered":"<p>Und schon die n\u00e4chste Version.<br \/>\nVersion 146.0.7680.165 (Windows)<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Google Chrome 146.0.7680.153 \/ 154 korrigiert 3 kritische L\u00fccken und 23 andere - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Chrome 146.0.7680.153 \/ 154 korrigiert 3 kritische L\u00fccken und 23 andere\" \/>\n<meta property=\"og:description\" content=\"Google ist auch gut, stellt am 18.03. die Meldung rein, dass der Chrome-Browser 146.0.7680.153\/ 146.0.7680.154 ver\u00f6ffentlicht wird. Nichts weiter. Jetzt tauchen aber die Sicherheitsl\u00fccken auf, die Google korrigiert hat. Und das sind insgesamt 26. Drei davon wurden als kritisch eingestuft.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T08:57:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T08:59:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Google Chrome 146.0.7680.153 \\\/ 154 korrigiert 3 kritische L\u00fccken und 23 andere\",\"datePublished\":\"2026-03-20T08:57:37+00:00\",\"dateModified\":\"2026-03-20T08:59:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/\"},\"wordCount\":114,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/google-chrome-logo-neu.png\",\"keywords\":[\"Google Chrome 146.0.7680.153\",\"Google Chrome 146.0.7680.154\"],\"articleSection\":[\"Browser\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/\",\"name\":\"Google Chrome 146.0.7680.153 \\\/ 154 korrigiert 3 kritische L\u00fccken und 23 andere - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/google-chrome-logo-neu.png\",\"datePublished\":\"2026-03-20T08:57:37+00:00\",\"dateModified\":\"2026-03-20T08:59:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/google-chrome-logo-neu.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/google-chrome-logo-neu.png\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/03\\\/20\\\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google Chrome 146.0.7680.153 \\\/ 154 korrigiert 3 kritische L\u00fccken und 23 andere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Google Chrome 146.0.7680.153 \/ 154 korrigiert 3 kritische L\u00fccken und 23 andere - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/","og_locale":"de_DE","og_type":"article","og_title":"Google Chrome 146.0.7680.153 \/ 154 korrigiert 3 kritische L\u00fccken und 23 andere","og_description":"Google ist auch gut, stellt am 18.03. die Meldung rein, dass der Chrome-Browser 146.0.7680.153\/ 146.0.7680.154 ver\u00f6ffentlicht wird. Nichts weiter. Jetzt tauchen aber die Sicherheitsl\u00fccken auf, die Google korrigiert hat. Und das sind insgesamt 26. Drei davon wurden als kritisch eingestuft.&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2026-03-20T08:57:37+00:00","article_modified_time":"2026-03-20T08:59:22+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Google Chrome 146.0.7680.153 \/ 154 korrigiert 3 kritische L\u00fccken und 23 andere","datePublished":"2026-03-20T08:57:37+00:00","dateModified":"2026-03-20T08:59:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/"},"wordCount":114,"commentCount":5,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","keywords":["Google Chrome 146.0.7680.153","Google Chrome 146.0.7680.154"],"articleSection":["Browser"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/","url":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/","name":"Google Chrome 146.0.7680.153 \/ 154 korrigiert 3 kritische L\u00fccken und 23 andere - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","datePublished":"2026-03-20T08:57:37+00:00","dateModified":"2026-03-20T08:59:22+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/03\/20\/google-chrome-146-0-7680-153-154-korrigiert-3-kritische-luecken-und-23-andere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Google Chrome 146.0.7680.153 \/ 154 korrigiert 3 kritische L\u00fccken und 23 andere"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/210532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=210532"}],"version-history":[{"count":1,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/210532\/revisions"}],"predecessor-version":[{"id":210533,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/210532\/revisions\/210533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/162181"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=210532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=210532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=210532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}