{"id":209109,"date":"2026-02-10T18:25:05","date_gmt":"2026-02-10T17:25:05","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=209109"},"modified":"2026-02-10T18:25:49","modified_gmt":"2026-02-10T17:25:49","slug":"was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/","title":{"rendered":"Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen?"},"content":{"rendered":"<p>Microsoft hat heute einen Supportbeitrag und auch einen Blogbeitrag zum Thema Secure Boot Zertifikate ver\u00f6ffentlicht. Dabei geht es um die im Juni 2026 auslaufenden Secure Boot Zertifikate von 2011. Bis dahin werden die neuen Secure Boot Zertifikate von 2023 den Dienst \u00fcbernehmen.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/08\/cyber-security-3400657-1920.jpg\" rel=\"lightbox[209109]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/08\/cyber-security-3400657-1920-500x300.jpg\" alt=\"\" width=\"500\" height=\"300\" class=\"aligncenter size-medium wp-image-106512\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/08\/cyber-security-3400657-1920-500x300.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/08\/cyber-security-3400657-1920-306x184.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/08\/cyber-security-3400657-1920-810x486.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/08\/cyber-security-3400657-1920.jpg 1920w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Wir haben \u00fcber das <a href=\"https:\/\/www.deskmodder.de\/blog\/2026\/01\/14\/windows-secure-boot-zertifikate-laufen-2026-ab-alte-zertifikate-werden-ersetzt\/\" target=\"_blank\">Thema schon berichtet<\/a>. Wichtig zu wissen ist, dass der Wechsel der Zertifikate im Gro\u00dfen und Ganzen automatisch ablaufen wird. Einige haben in der letzten Zeit schon ein Update daf\u00fcr erhalten. Man muss also nichts unternehmen.<\/p>\n<p>Nur in Einzelf\u00e4llen ist ein BIOS-Update vom Ger\u00e4tehersteller notwendig. Aber da arbeitet Microsoft eng mit den OEMs zusammen. Auch wenn der Wechsel der Zertifikate nicht stattfinden sollte, kann das Ger\u00e4t weiterhin genutzt werden. Einzig die Updates f\u00fcr die Boot-bezogenen Sicherheitsupdates werden nicht installiert.<\/p>\n<p>Man sollte jetzt aber nicht in Panik verfallen. Es <a href=\"https:\/\/github.com\/cjee21\/Check-UEFISecureBootVariables\" target=\"_blank\">gibt auf GitHub ein Skript<\/a>, mit dem man den derzeitigen &#8222;Zustand&#8220; pr\u00fcfen kann. Einfach auf Code klicken und Download ZIP herunterladen und entpacken.<\/p>\n<p>\u00dcber die Check UEFI PK, KEK, DB and DBX.cmd kann man dann die Abfrage per Rechtsklick als Administrator starten. Das k\u00f6nnte dann so aussehen.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2026\/02\/secure-boot-zertifikate-pruefen-cmd-check-uefisecurebootvariables.jpg\" rel=\"lightbox[209109]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2026\/02\/secure-boot-zertifikate-pruefen-cmd-check-uefisecurebootvariables-500x297.jpg\" alt=\"\" width=\"500\" height=\"297\" class=\"aligncenter size-medium wp-image-209110\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2026\/02\/secure-boot-zertifikate-pruefen-cmd-check-uefisecurebootvariables-500x297.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2026\/02\/secure-boot-zertifikate-pruefen-cmd-check-uefisecurebootvariables-810x481.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2026\/02\/secure-boot-zertifikate-pruefen-cmd-check-uefisecurebootvariables-306x182.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2026\/02\/secure-boot-zertifikate-pruefen-cmd-check-uefisecurebootvariables.jpg 1429w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/support.microsoft.com\/en-us\/topic\/when-secure-boot-certificates-expire-on-windows-devices-c83b6afd-a2b6-43c6-938e-57046c80c1c2\" target=\"_blank\">support.microsoft<\/a><\/div>\n<p>Den Blogbeitrag findet ihr unter diesem Link<\/p>\n<ul>\n<li><a href=\"https:\/\/blogs.windows.com\/windowsexperience\/2026\/02\/10\/refreshing-the-root-of-trust-industry-collaboration-on-secure-boot-certificate-updates\/\" target=\"_blank\">blogs.windows.com\/refreshing-the-root-of-trust-industry-collaboration-on-secure-boot-certificate-updates<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft hat heute einen Supportbeitrag und auch einen Blogbeitrag zum Thema Secure Boot Zertifikate ver\u00f6ffentlicht. Dabei geht es um die im Juni 2026 auslaufenden Secure Boot Zertifikate von 2011. Bis dahin werden die neuen Secure Boot Zertifikate von 2023 den&hellip; <\/p>\n","protected":false},"author":134,"featured_media":92066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689,80310],"tags":[],"class_list":["post-209109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","category-windows-11"],"wp_featured_image":{"id":92066,"alt_text":"http:\/\/www.stockvault.net\/photo\/174251\/cyber-security-concept","description":"","media_type":"image","media_details":{"width":1205,"height":927,"file":"2017\/10\/stockvault-cyber-security-concept174251.jpg","sizes":{"thumbnail":{"file":"stockvault-cyber-security-concept174251-266x205.jpg","width":266,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-266x205.jpg"},"medium":{"file":"stockvault-cyber-security-concept174251-468x360.jpg","width":468,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-468x360.jpg"},"large":{"file":"stockvault-cyber-security-concept174251-758x583.jpg","width":758,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-758x583.jpg"},"wp_review_large":{"file":"stockvault-cyber-security-concept174251-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-320x200.jpg"},"wp_review_small":{"file":"stockvault-cyber-security-concept174251-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-65x65.jpg"},"blog-large":{"file":"stockvault-cyber-security-concept174251-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-642x300.jpg"},"blog-medium":{"file":"stockvault-cyber-security-concept174251-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-306x205.jpg"},"recent-thumb":{"file":"stockvault-cyber-security-concept174251-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-350x316.jpg"},"service-featured":{"file":"stockvault-cyber-security-concept174251-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-600x330.jpg"},"wp_rp_thumbnail":{"file":"stockvault-cyber-security-concept174251-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"Security concept - Locks on digital screen","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"Security concept - Locks on digital screen","orientation":"1","keywords":["cyber","internet","network","password","crime","web","hacker","technology","security","computer","virus","online","abstract","background","tech","isolated","black","phishing","danger","data","protect","attack","information","system","code","digital","binary","hack","protection","locks","concept","screen","padlocks","access","key","safe","icon","secure","pad","privacy","safety","hole","keyhole","display","green","unlock","guard","open","secrecy","phone","login","net","lockout","authorization","pixel","mobile","close","encryption","software","safeguard","business","matrix","coding","cyberspace","dark","policy","antivirus","crack","symbol","closed","pixelated","generated","program","steal","user","red","interface","id","graphic","one","gui","touch","pc","unknown","person","spy","cracker","thief","silhouette","image","criminal","man","identity","digitally","hand","communication","hacking","fraud","scene","laptop","green","identity theft","police","tape","confiscated","cybercrime","barricade","number","cipher","evidence","line","investigation","worm","bot"]}},"post":92065,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251.jpg"},"commentcount":57,"wp_comments":[{"id":328206,"parent":0,"author":0,"author_name":"Tom","author_email":"stuff@blende345.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a4a037bcd452d3838173fa597af20da6b2cf659cbbee0db05ecb6ee5244fb1f1?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a4a037bcd452d3838173fa597af20da6b2cf659cbbee0db05ecb6ee5244fb1f1?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a4a037bcd452d3838173fa597af20da6b2cf659cbbee0db05ecb6ee5244fb1f1?s=96&d=mm&r=g"},"date":"2026-02-10T18:34:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wenn nach Ausf\u00fchren in Powershell \u00fcberall true steht sollte man fein sein:<\/p>\n<p>$var1 = Confirm-SecureBootUEFI<br \/>\n$var2 = [System.Text.Encoding]::ASCII.GetString((Get-SecureBootUEFI db).bytes) -match &#8218;Windows UEFI CA 2023&#8216;<br \/>\n$var4 = [System.Text.Encoding]::ASCII.GetString((Get-SecureBootUEFI kek).bytes) -match &#8222;Microsoft Corporation KEK 2K CA 2023&#8220;<br \/>\n$var3 = (Get-Item &#8222;C:\\Windows\\Boot\\EFI\\bootmgfw.efi&#8220;).VersionInfo  <\/p>\n<p>$text1 = &#8218;SecureBootUEFI Status:&#8216;<br \/>\n$text2 = &#8218;Zertifikat Check Windows Integriertes Zertifikat:&#8216;<br \/>\n$text4 = &#8218;Zertifikat Check BIOS Integriertes Zertifikat (KEK):&#8216;<br \/>\n$text3 = &#8218;Windows UEFI Produkt Version:&#8216;   <\/p>\n<p>echo $text1<br \/>\necho $var1<br \/>\necho $text2<br \/>\necho $var2<br \/>\necho $text4<br \/>\necho $var4<br \/>\necho $text3<br \/>\necho $var3<\/p>\n"},"status":"1"},{"id":328209,"parent":328206,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2026-02-10T18:41:31","cld_nonce":"b6d6726996","content":{"rendered":"<p>Aber gibt es nur unvollst\u00e4ndig wieder. Sat nichts dar\u00fcber aus, ob auch die DBX aktualisiert wurde, welche SVN-Version aktuell ist und ob der neue Bootmanager verwendet wird. Zeigt diesen noch nicht einmal an.<\/p>\n"},"status":"1"},{"id":328210,"parent":0,"author":3691,"author_name":"mcbloch","author_email":"mcbloch@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=96&d=mm&r=g"},"date":"2026-02-10T18:45:49","cld_nonce":"b6d6726996","content":{"rendered":"<p>Also bei mir sind einige Sachen mit einem roten X versehen statt einem gr\u00fcnen Hacken.<\/p>\n<p>X Microsoft Corporation KEK 2K CA 2023<br \/>\nX Microsoft UEFI CA 2023<br \/>\nX Microsoft Option ROM UEFI CA 2023<\/p>\n<p>Und hier steht:<\/p>\n<p>Windows Bootmgr SVN : None<br \/>\nWindows cdboot SVN  : None<br \/>\nWindows wdsmgfw SVN : None<\/p>\n<p>Muss ich mir jetzt Sorgen machen ??<\/p>\n"},"status":"1"},{"id":328211,"parent":328209,"author":0,"author_name":"Tom","author_email":"stuff@blende345.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a4a037bcd452d3838173fa597af20da6b2cf659cbbee0db05ecb6ee5244fb1f1?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a4a037bcd452d3838173fa597af20da6b2cf659cbbee0db05ecb6ee5244fb1f1?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a4a037bcd452d3838173fa597af20da6b2cf659cbbee0db05ecb6ee5244fb1f1?s=96&d=mm&r=g"},"date":"2026-02-10T18:46:33","cld_nonce":"b6d6726996","content":{"rendered":"<p>Setzt das True bei den Zertifikaten nicht das von dir erw\u00e4hnte voraus?<\/p>\n"},"status":"1"},{"id":328212,"parent":328210,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2026-02-10T18:48:55","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nein, noch nicht. Du wirst das daf\u00fcr notwendige Update noch nicht erhalten haben.<\/p>\n"},"status":"1"},{"id":328213,"parent":0,"author":0,"author_name":"R.S.","author_email":"passat3233@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/68993ef57ec01ca39cd75b06efff1d95c9e4fbbc3a5752adc5da241dc5bd5281?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/68993ef57ec01ca39cd75b06efff1d95c9e4fbbc3a5752adc5da241dc5bd5281?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/68993ef57ec01ca39cd75b06efff1d95c9e4fbbc3a5752adc5da241dc5bd5281?s=96&d=mm&r=g"},"date":"2026-02-10T18:51:14","cld_nonce":"b6d6726996","content":{"rendered":"<p>Das Script funktioniert nur bei aktivem Secure Boot.<br \/>\nHat man Secure Boot deaktiviert, wirft das Script viele Fehler.<\/p>\n<p>Und selbst wenn das Zeritifkat abgelaufen sein sollte, kann man immer noch im Secure Boot mit einem Trick booten:<br \/>\nIns UEFI starten, dort das Systemdatum zur\u00fccksetzen auf ein Datum vor Ablauf des Zertifikats, dann booten und das Datum in Windows wieder richtig stellen.<\/p>\n"},"status":"1"},{"id":328214,"parent":328213,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2026-02-10T18:52:38","cld_nonce":"b6d6726996","content":{"rendered":"<p>Macht ja auch sonst keinen Sinn, ohne Secure Boot braucht man auch die Zertifikate nicht.<\/p>\n"},"status":"1"},{"id":328215,"parent":328211,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2026-02-10T18:55:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nein. Das sagt nur aus, dass die von Dir abgefragten Zertifikate im UEFI installiert wurden.  Und du fragst auch nur zwei der vier Zertifikate ab. Keine Info, ob das CA2011 zur\u00fcckgezogen wurde, ob die DBX aktuell ist und ob der neue Bootmanager verwendet wird. Du fragst nur die Version vom alten Bootmanager mit CA2011 Zertifikat im Windows Onder, Der neue Bootmanager ist im &#8222;EFI_EX&#8220;Verzeichnis. Aber das alles sagt nichts aus, ob die &#8222;EX&#8220; Dateien auch in der Systempartition stehen.<\/p>\n"},"status":"1"},{"id":328217,"parent":328215,"author":0,"author_name":"Tom","author_email":"stuff@blende345.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a4a037bcd452d3838173fa597af20da6b2cf659cbbee0db05ecb6ee5244fb1f1?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a4a037bcd452d3838173fa597af20da6b2cf659cbbee0db05ecb6ee5244fb1f1?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a4a037bcd452d3838173fa597af20da6b2cf659cbbee0db05ecb6ee5244fb1f1?s=96&d=mm&r=g"},"date":"2026-02-10T18:57:52","cld_nonce":"b6d6726996","content":{"rendered":"<p>ok, danke f\u00fcr deine Erg\u00e4nzung&#8230;<\/p>\n"},"status":"1"},{"id":328218,"parent":328213,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2026-02-10T18:58:06","cld_nonce":"b6d6726996","content":{"rendered":"<p>Das mit dem Datum wird aber nicht funktionieren, wenn die CA2011 Zertifikate in der DBX eingetragen werden. Dann sind und bleiben die gesperrt, egal welches Datum man da eintr\u00e4gt. Die kann man, wenn mal Lust hat, auch heute schon in die DBX eintragen.<\/p>\n"},"status":"1"},{"id":328219,"parent":328214,"author":0,"author_name":"Luzifer","author_email":"serra.avatar@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3a056bca2e5e5358aae0eea162de34ea9523e13a273ccee5cce494d130ad5515?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3a056bca2e5e5358aae0eea162de34ea9523e13a273ccee5cce494d130ad5515?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3a056bca2e5e5358aae0eea162de34ea9523e13a273ccee5cce494d130ad5515?s=96&d=mm&r=g"},"date":"2026-02-10T18:58:38","cld_nonce":"b6d6726996","content":{"rendered":"<p>naja da und korrekt sollten sie aber trotzdem sein, man kann sich ja jederzeit daf\u00fcr entscheiden secure boot doch zu nutzen.<\/p>\n"},"status":"1"},{"id":328220,"parent":0,"author":6246,"author_name":"Vectorprime","author_email":"reinfeld@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=96&d=mm&r=g"},"date":"2026-02-10T19:01:22","cld_nonce":"b6d6726996","content":{"rendered":"<p>ich finde es sehr lustig dass das tool sagt das bei meinem pc und laptop secure boot deaktiviert w\u00e4re ob wohl es im uefi als eingeschaltet angezeigt wird<\/p>\n"},"status":"1"},{"id":328223,"parent":0,"author":0,"author_name":"Sp\u00f6kenkieker","author_email":"nordlicht2876@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f788da93051086668f92a0aaff3c99ccc7e1c1d9075d615a97b101a8297e1d0e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f788da93051086668f92a0aaff3c99ccc7e1c1d9075d615a97b101a8297e1d0e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f788da93051086668f92a0aaff3c99ccc7e1c1d9075d615a97b101a8297e1d0e?s=96&d=mm&r=g"},"date":"2026-02-10T19:03:52","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich habe Secure Boot nicht aktiviert und habe es freiwillig auch nicht vor, h\u00e4tte aber f\u00fcr den Fall der F\u00e4lle gerne die aktuellen Zertifikate. Gibt es eine M\u00f6glichkeit Selbige manuell zu beziehen und zu installieren?<\/p>\n"},"status":"1"},{"id":328225,"parent":0,"author":0,"author_name":"J\u00f6rg","author_email":"Guido.bueter@vodafonemail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/08aa2c3022bf6fdab5c0f0014edc857fff1d8a58bf11a3cec836a786112f12da?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/08aa2c3022bf6fdab5c0f0014edc857fff1d8a58bf11a3cec836a786112f12da?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/08aa2c3022bf6fdab5c0f0014edc857fff1d8a58bf11a3cec836a786112f12da?s=96&d=mm&r=g"},"date":"2026-02-10T19:18:24","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich habe heute mit dem Acer Support telefoniert. Dieser meint, dass es f\u00fcr meinen f\u00fcnf Jahre alten Gaming Laptop kein Windows-Update f\u00fcr die neuen Boot-Zertifikate geben wird. In meiner Ereignisanzeige von Windows 11 Home 25H2 steht:&#8220;Aktualisierte Secure Boot-Zertifikate sind auf diesem Ger\u00e4t verf\u00fcgbar, wurden jedoch noch nicht auf die Firmware angewendet. Lesen Sie die ver\u00f6ffentlichten Anweisungen, um die Aktualisierung abzuschlie\u00dfen und den vollst\u00e4ndigen Schutz aufrechtzuerhalten.&#8220;Laut Acer Support fehlen die Hardwarevoraussetzungen und diese werden laut Acer, wie schon erw\u00e4hnt, nicht \u00fcber Windows Update von Acer ausgeliefert. Sehr schade &#8230;<\/p>\n"},"status":"1"},{"id":328226,"parent":0,"author":10512,"author_name":"Rennrakete","author_email":"social@m-nb.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d358245fd3e93c0c5958f10812c53fbb230f95f0dbdb58f44f77e516368a4d65?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d358245fd3e93c0c5958f10812c53fbb230f95f0dbdb58f44f77e516368a4d65?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d358245fd3e93c0c5958f10812c53fbb230f95f0dbdb58f44f77e516368a4d65?s=96&d=mm&r=g"},"date":"2026-02-10T19:20:00","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei mir ist alles gr\u00fcn, bis auf &#8222;Microsoft Option ROM UEFI CA 2023&#8220;. Wie kann man das nun l\u00f6sen?<\/p>\n"},"status":"1"},{"id":328229,"parent":328225,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2026-02-10T19:22:14","cld_nonce":"b6d6726996","content":{"rendered":"<p>F\u00fcr ein 5 Jahre altes Ger\u00e4t? Kann ich mir kaum vorstellen.<\/p>\n"},"status":"1"},{"id":328230,"parent":328229,"author":0,"author_name":"J\u00f6rg","author_email":"Guido.bueter@vodafonemail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/08aa2c3022bf6fdab5c0f0014edc857fff1d8a58bf11a3cec836a786112f12da?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/08aa2c3022bf6fdab5c0f0014edc857fff1d8a58bf11a3cec836a786112f12da?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/08aa2c3022bf6fdab5c0f0014edc857fff1d8a58bf11a3cec836a786112f12da?s=96&d=mm&r=g"},"date":"2026-02-10T19:29:15","cld_nonce":"b6d6726996","content":{"rendered":"<p>@moinmoin: Laut Acer Support ist es wohl so. Aber die Hoffnung stirbt zuletzt und vielleicht kommt ja bis Juni doch noch etwas \u00fcber Windows Update?<\/p>\n"},"status":"1"},{"id":328233,"parent":328223,"author":0,"author_name":"Lyra Schellenbaum","author_email":"wolfring@arcor.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/392a1dfc4a255469000d1f576dc1ac4cf9f146c9e4716f868ba256795ecefc88?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/392a1dfc4a255469000d1f576dc1ac4cf9f146c9e4716f868ba256795ecefc88?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/392a1dfc4a255469000d1f576dc1ac4cf9f146c9e4716f868ba256795ecefc88?s=96&d=mm&r=g"},"date":"2026-02-10T19:54:28","cld_nonce":"b6d6726996","content":{"rendered":"<p>Kann sein, dass Dein Bios dabei zerschossen wird. Ernst gemeint.<\/p>\n"},"status":"1"},{"id":328235,"parent":328220,"author":0,"author_name":"Vectorprime","author_email":"reinfeld@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=96&d=mm&r=g"},"date":"2026-02-10T19:57:06","cld_nonce":"b6d6726996","content":{"rendered":"<p>hat sich erledigt beim PC mit dem secure Boot da war das ftpm deaktiviert weil ich ein Hardware tpm damals gekauft hatte aber das hatte so nicht geklappt mit dem secure Boot warum auch immer  <\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/apps.apple.com\/de\/app\/deskmodder\/id1478451921?l=de\" rel=\"nofollow ugc\">Deskmodder.de-App f\u00fcr iOS<\/a><\/i><\/p>\n"},"status":"1"},{"id":328236,"parent":0,"author":0,"author_name":"Zanza","author_email":"zaza484-zanzara@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b84bb14a0c671fe9592d98ef592804a887ac51167442b7347c18b737c10afa64?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b84bb14a0c671fe9592d98ef592804a887ac51167442b7347c18b737c10afa64?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b84bb14a0c671fe9592d98ef592804a887ac51167442b7347c18b737c10afa64?s=96&d=mm&r=g"},"date":"2026-02-10T19:57:07","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ok, also ist es nicht so, dass die Ger\u00e4te dann nicht mehr booten mit abgelaufenen Zertifikaten?<\/p>\n"},"status":"1"},{"id":328239,"parent":328233,"author":0,"author_name":"Sp\u00f6kenkieker","author_email":"nordlicht2876@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f788da93051086668f92a0aaff3c99ccc7e1c1d9075d615a97b101a8297e1d0e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f788da93051086668f92a0aaff3c99ccc7e1c1d9075d615a97b101a8297e1d0e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f788da93051086668f92a0aaff3c99ccc7e1c1d9075d615a97b101a8297e1d0e?s=96&d=mm&r=g"},"date":"2026-02-10T20:22:00","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ach ja, da habe ich offensichtlich zu kurz gedacht, der Kram wird ja im BIOS gespeichert. Danke f\u00fcr die Warnung.<\/p>\n"},"status":"1"},{"id":328242,"parent":328210,"author":0,"author_name":"Peter","author_email":"Peter@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a3171e9b596de6b48ca9d8396a322015a60b1cad56fb02b2fd86fc9759d0f404?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a3171e9b596de6b48ca9d8396a322015a60b1cad56fb02b2fd86fc9759d0f404?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a3171e9b596de6b48ca9d8396a322015a60b1cad56fb02b2fd86fc9759d0f404?s=96&d=mm&r=g"},"date":"2026-02-10T20:32:07","cld_nonce":"b6d6726996","content":{"rendered":"<p>@mcbloch<\/p>\n<p>Bei mir exakt dieselben positionen mit dem roten X inkl. Windows1125H2-Update von heute.<\/p>\n<p>Habe ein MSI B650 MainBoard, und du?<\/p>\n"},"status":"1"},{"id":328246,"parent":328236,"author":0,"author_name":"R.S.","author_email":"passat3233@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/68993ef57ec01ca39cd75b06efff1d95c9e4fbbc3a5752adc5da241dc5bd5281?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/68993ef57ec01ca39cd75b06efff1d95c9e4fbbc3a5752adc5da241dc5bd5281?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/68993ef57ec01ca39cd75b06efff1d95c9e4fbbc3a5752adc5da241dc5bd5281?s=96&d=mm&r=g"},"date":"2026-02-10T20:37:40","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nein.<br \/>\nFalls die Zertifkate abgelaufen sind kann man immer noch problemlos booten, wenn man Secure Boot deaktiviert.<\/p>\n"},"status":"1"},{"id":328256,"parent":0,"author":0,"author_name":"DAU123","author_email":"Foren-Nutzer@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b5412e14f02409af22a3e79f331b8cbf5cf52e4f95aa430526942fa760d0be04?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b5412e14f02409af22a3e79f331b8cbf5cf52e4f95aa430526942fa760d0be04?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b5412e14f02409af22a3e79f331b8cbf5cf52e4f95aa430526942fa760d0be04?s=96&d=mm&r=g"},"date":"2026-02-10T21:05:42","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei einem von 12 gleichartigen PC mit einem ASUS B550M-A sorgte die Installation der neuen Zertifikate f\u00fcr die Meldung &#8222;your device run into a problem&#8220;.<\/p>\n"},"status":"1"},{"id":328258,"parent":0,"author":0,"author_name":"MS Honk","author_email":"jekolbe@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d37b0c3f6189ddce8b5607111ff8236e33229006994793e002e36fea4685c8a7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d37b0c3f6189ddce8b5607111ff8236e33229006994793e002e36fea4685c8a7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d37b0c3f6189ddce8b5607111ff8236e33229006994793e002e36fea4685c8a7?s=96&d=mm&r=g"},"date":"2026-02-10T21:10:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8230;und ich bin der lachende &#8222;Dritte&#8220; mein Acer Aspire XC-710 unterst\u00fctzt den sicheren Startzustand nicht und startet via Legacy Modus <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/> bei einem eingefrorenem Win 10 Build 19045.5555 \/\/ Die Schikanen aka Redmond gibt es bei mir nicht. Never Change a Running System<\/p>\n"},"status":"1"},{"id":328267,"parent":0,"author":0,"author_name":"Max","author_email":"Max@gmx.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8ec6675b367e24af230791cfdd4e3e015a86e61774226956dafaa3384c265953?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8ec6675b367e24af230791cfdd4e3e015a86e61774226956dafaa3384c265953?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8ec6675b367e24af230791cfdd4e3e015a86e61774226956dafaa3384c265953?s=96&d=mm&r=g"},"date":"2026-02-10T22:05:28","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hallo, da ich mich nicht auskenne<br \/>\nDas Script von github gibt folgendes aus:<\/p>\n<p>\u221a Microsoft Corporation KEK CA 2011 (revoked: False)<br \/>\n\u221a Microsoft Corporation KEK 2K CA 2023 (revoked: False)<br \/>\n\u221a MSI SHIP KEK (revoked: False)   <\/p>\n<p>2025-10-14 (v1.6.0) : SUCCESS: 431 successes detected<br \/>\nWindows Bootmgr SVN : None<br \/>\nWindows cdboot SVN : None<br \/>\nWindows wdsmgfw SVN : None<\/p>\n<p>Ist das gut oder schlecht? Vor allem diese &#8222;None&#8220; machen mir sorgen.<br \/>\nDas aktuellste BIOS von MSI eine Beta, daher m\u00f6chte ich mir die ungern installieren, zumal da auch nichts bon steht das da Certificate mit geupdatet werden<\/p>\n<p>7D75v1P5(Beta version)2025-10-21<br \/>\nBeschreibung:<br \/>\n&#8211;  AGESA PI 1.2.0.3g updated.<br \/>\n&#8211;  Improved compatibility of the Ryzen 8000 series CPU.<br \/>\n&#8211;  Multiple OC solutions implemented.<\/p>\n"},"status":"1"},{"id":328276,"parent":0,"author":0,"author_name":"gaya","author_email":"scg@iesy.tv","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bafe7dc40cf2bcff851d3889f29f0fd3b51a0c9842bd04e80251c6c48fcaa2cb?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bafe7dc40cf2bcff851d3889f29f0fd3b51a0c9842bd04e80251c6c48fcaa2cb?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bafe7dc40cf2bcff851d3889f29f0fd3b51a0c9842bd04e80251c6c48fcaa2cb?s=96&d=mm&r=g"},"date":"2026-02-10T23:10:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>Beim mir auch alles gr\u00fcn ausser bei diesen steht das NONE..<br \/>\nWindows Bootmgr SVN : None<br \/>\nWindows cdboot SVN : None<br \/>\nWindows wdsmgfw SVN : None<\/p>\n"},"status":"1"},{"id":328278,"parent":328276,"author":0,"author_name":"Max","author_email":"Max@gmx.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8ec6675b367e24af230791cfdd4e3e015a86e61774226956dafaa3384c265953?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8ec6675b367e24af230791cfdd4e3e015a86e61774226956dafaa3384c265953?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8ec6675b367e24af230791cfdd4e3e015a86e61774226956dafaa3384c265953?s=96&d=mm&r=g"},"date":"2026-02-10T23:34:47","cld_nonce":"b6d6726996","content":{"rendered":"<p>Man kann ja aus dem Ordner von diesem Script von Github mit dem &#8222;Apply revocations.cmd&#8220; angeblich SVN aktualisieren, aber ich traue mich nicht und habe Angst mir mein Windows, UEFI oder SecureBoot damit zu zerschiesen und ich danach vllt. nicht mehr booten kann,<\/p>\n<p>Zitat: &#8222;Right-click Apply revocations.cmd and Run as administrator. Wait for awhile. The DBX should be updated and the Windows Production PCA 2011 cert added to it. The latest SVN will be written to the DBX as well.&#8220;<\/p>\n"},"status":"1"},{"id":328291,"parent":0,"author":0,"author_name":"Erwin","author_email":"fh1822@vivaldi.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b387e8b24f638019dd1b978f21fc79f455ceaad374cd87f703298d289a26a4b0?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b387e8b24f638019dd1b978f21fc79f455ceaad374cd87f703298d289a26a4b0?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b387e8b24f638019dd1b978f21fc79f455ceaad374cd87f703298d289a26a4b0?s=96&d=mm&r=g"},"date":"2026-02-11T06:29:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8222;Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen?&#8220; &#8230; Diese eigentliche Frage finde ich im Artikel (danke daf\u00fcr) leider nicht beantwortet bzw. kann es nicht herauslesen.<br \/>\nSchalte ich im BIOS einfach &#8222;Secure boot&#8220; ab, funktioniert mein Win10, 11, Linux, WhatsEver weiterhin &#8230; na und jetzt?<br \/>\nBin ich wirklich UNSICHERER also mit &#8222;Secure boot&#8220; unterwegs?<br \/>\nIn Unternehmen mag das in Verbindung mit Bitlocker vlt. relevant sein, im Privaten, es interessiert niemanden, geschweige denn, &#8222;Otto-Normalo&#8220; wei\u00df \u00fcberhaupt, das es das \u00fcberhaupt gibt &#8230; Pseudo-Sicherheit &#8230; m.M.n.<br \/>\n&#8222;Secure Boot&#8220; ist im Privaten (Nicht-Aluhuttr\u00e4ger und Paranoiden) genauso irrelvant wie die standardm\u00e4\u00dfige XTS-Whatever-Datentr\u00e4gerverschl\u00fcsselung, den Mist habe ich im Privaten genau abgeschaltet (nicht mit echter Bitlockerverschl\u00fcsselung verwechseln).<br \/>\nAlles Pseudo-Sicherheit, m.M.<br \/>\nWas genau bedeutet denn diese XTS-Verschl\u00fcsselung?<br \/>\nAngenommen, mein Notebook\/PC ist kaputt und ich entnehme die per XTS-whatever-verschl\u00fcsselte-SSD und baue diese in ein anderes Ger\u00e4t ein. Da funktioniert diese genau und alle Daten kann ich sofort lesen und schreiben, ohne das ich einen Schl\u00fcssel eingeben muss. Also wozu, Microsoft?<br \/>\nWo ist da der wirklich plausible und nachvollziehbare Sicherheitsgewinn bei Secure Boot und der XTS-Datentr\u00e4gerverschl\u00fcsselung, MS?<br \/>\nBitlocker OK &#8230;, aber &#8230; Naja.<\/p>\n<p>Unsicherer bin ich nur unterwegs, wenn ich weiterhin Windows-Updates benutze, da ich nach dem Reboot nicht wei\u00df, ob nach dem Update noch alles weiterhin funktioniert oder mir W10\/W11 mit einem Bluescreen wegknallt &#8230;<\/p>\n"},"status":"1"},{"id":328308,"parent":328291,"author":9647,"author_name":"EynMarc","author_email":"marcsennlaptop@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3491266aac49acc2c7ee73e0f4f1d780143cf3a37db4551a97d4783e24e77277?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3491266aac49acc2c7ee73e0f4f1d780143cf3a37db4551a97d4783e24e77277?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3491266aac49acc2c7ee73e0f4f1d780143cf3a37db4551a97d4783e24e77277?s=96&d=mm&r=g"},"date":"2026-02-11T07:57:18","cld_nonce":"b6d6726996","content":{"rendered":"<p>Aber es kann ja mal sein das Windows 11 in neuer Version oder win 12 Secure Boot aktiviert sein muss nicht nur vorhanden wie jetzt, was auch mit trm passieren k\u00f6nnte das, er aktiviert sein muss.<\/p>\n"},"status":"1"},{"id":328320,"parent":0,"author":0,"author_name":"gaya","author_email":"scg@iesy.tv","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bafe7dc40cf2bcff851d3889f29f0fd3b51a0c9842bd04e80251c6c48fcaa2cb?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bafe7dc40cf2bcff851d3889f29f0fd3b51a0c9842bd04e80251c6c48fcaa2cb?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bafe7dc40cf2bcff851d3889f29f0fd3b51a0c9842bd04e80251c6c48fcaa2cb?s=96&d=mm&r=g"},"date":"2026-02-11T09:14:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Erwin<\/p>\n<p>Im Grunde hast du Recht, der Privatanvender braucht den meisten Rotz wirklich nicht. Aber ist halt Windows, irgendwas neues muss es ja bieten um eine neue Windows Version und die Kosten zu rechtfertigen, funktioniert halt seit Jahren schon so und wir alle machen das Spiel mit.<br \/>\nIch wette, w\u00e4re das ganze angebliche Sicherheitszeug u.a. was den Rechner von Haus aus ausbremst nicht vorhanden, w\u00e4re sehr viele noch mit Core Duo 2 unterwegs.<br \/>\nWindows 10 sollte ja die letzte Version sein, nat\u00fcrlich hat man sich das schnell wieder anders \u00fcberlegt, wer wirft schon einen Goldesel einfach so weg?<\/p>\n"},"status":"1"},{"id":328322,"parent":328291,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2026-02-11T09:22:30","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wenn sie ablaufen, werden sie durch die neuen ersetzt. Wie es im Text steht. Ebenso, dass du auch mit dem alten Zertifikat deinen Rechner starten kannst.<\/p>\n"},"status":"1"},{"id":328325,"parent":0,"author":0,"author_name":"Arno","author_email":"nbsh@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c69d8341338e7b697137bba8d31209009def401777c14e851a1faf863d00ad3b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c69d8341338e7b697137bba8d31209009def401777c14e851a1faf863d00ad3b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c69d8341338e7b697137bba8d31209009def401777c14e851a1faf863d00ad3b?s=96&d=mm&r=g"},"date":"2026-02-11T10:19:26","cld_nonce":"b6d6726996","content":{"rendered":"<p>Danke f\u00fcr die Aufkl\u00e4rung, habe mich auch gefragt was nach dem Ablauf passieren wird und dies auch kommentiert beim letzten Artikel.<\/p>\n"},"status":"1"},{"id":328328,"parent":0,"author":0,"author_name":"Peter","author_email":"Peter@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a3171e9b596de6b48ca9d8396a322015a60b1cad56fb02b2fd86fc9759d0f404?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a3171e9b596de6b48ca9d8396a322015a60b1cad56fb02b2fd86fc9759d0f404?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a3171e9b596de6b48ca9d8396a322015a60b1cad56fb02b2fd86fc9759d0f404?s=96&d=mm&r=g"},"date":"2026-02-11T10:49:33","cld_nonce":"b6d6726996","content":{"rendered":"<p>K\u00f6nnte mal bitte jemand Auf-\/Erkl\u00e4ren was das bedeutet wenn das Script das auswirft:<br \/>\nWindows Bootmgr SVN : None<br \/>\nWindows cdboot SVN : None<br \/>\nWindows wdsmgfw SVN : None<\/p>\n<p>Normalerweise sollen da ja irgendwelche Zahlen\/Versionsnummern stehen.<br \/>\nIst das nun schlecht oder vollkommen irrelevant wenn da \u00fcberall None steht?<br \/>\nMu\u00df man und kann man das irgendwie beheben?<\/p>\n<p>Warum l\u00e4\u00dft deskmodder hier die Leute im Regen stehen die sich nicht so gut mit dem Thema auskennen und kl\u00e4rt nicht auf wenn man schon dieses Script zum \u00fcberpr\u00fcfen empfiehlt?<\/p>\n"},"status":"1"},{"id":328331,"parent":328278,"author":3691,"author_name":"mcbloch","author_email":"mcbloch@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=96&d=mm&r=g"},"date":"2026-02-11T10:57:22","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hat bei mir problemlos funktioniert.<\/p>\n<p>Jetzt ist bei mir auch alles gr\u00fcn und unten stehen nun auch die Versionsnummern.<\/p>\n"},"status":"1"},{"id":328333,"parent":328328,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2026-02-11T11:04:39","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wir haben das Skript nur verlinkt, nicht empfohlen.<br \/>\nAber wenn da &#8222;None&#8220; steht, ist es nicht so dramatisch.<br \/>\nWeiter oben bekommst du auch noch eine M\u00f6glichkeit, es zu korrigieren<br \/>\n<a href=\"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/#comment-328276\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/#comment-328276<\/a><\/p>\n"},"status":"1"},{"id":328342,"parent":328333,"author":0,"author_name":"Peter","author_email":"Peter@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a3171e9b596de6b48ca9d8396a322015a60b1cad56fb02b2fd86fc9759d0f404?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a3171e9b596de6b48ca9d8396a322015a60b1cad56fb02b2fd86fc9759d0f404?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a3171e9b596de6b48ca9d8396a322015a60b1cad56fb02b2fd86fc9759d0f404?s=96&d=mm&r=g"},"date":"2026-02-11T11:27:12","cld_nonce":"b6d6726996","content":{"rendered":"<p>@moinmoin<\/p>\n<p>Ok, vielen Dank das scheint geklappt zu haben<br \/>\nNun steht da:<\/p>\n<p>Windows Bootmgr SVN : 7.0<br \/>\nWindows cdboot SVN : 3.0<br \/>\nWindows wdsmgfw SVN : 3.0<\/p>\n<p>Aber kurz ist das gesamt System f\u00fcr 2 Sekunden eingefroren als das Script ausgef\u00fchrt wurde und hatte Panik bekommen das jetzt alles Schrott ist.<\/p>\n"},"status":"1"},{"id":328343,"parent":328342,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2026-02-11T11:28:35","cld_nonce":"b6d6726996","content":{"rendered":"<p>Das ist die Hauptsache, dass es geklappt hat. Auch wenn es nicht unbedingt notwendig gewesen w\u00e4re.<\/p>\n"},"status":"1"},{"id":328346,"parent":0,"author":0,"author_name":"Sclumpf Olaf","author_email":"Hans@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7d14164678fb73ea9da43f167ce7290785e812cc8ab916feab88a4bcfce3c68b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7d14164678fb73ea9da43f167ce7290785e812cc8ab916feab88a4bcfce3c68b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7d14164678fb73ea9da43f167ce7290785e812cc8ab916feab88a4bcfce3c68b?s=96&d=mm&r=g"},"date":"2026-02-11T11:49:13","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hallo, habe das Script ausgef\u00fchrt und \u00fcberall ist ein gr\u00fcner Haken, au\u00dfer bei einer Stelle:<\/p>\n<p>Microsoft Option ROM UEFI CA 2023<\/p>\n<p>Dort ist ein Rotes X<\/p>\n<p>Habe schon von Microsoft das Zertifikat Microsoft Option ROM UEFI CA 2023.crt runtergeladen und installiert, einmal bei &#8222;aktueller Nutzer&#8220; und einmal bei &#8222;lokaler Computer&#8220;<br \/>\nAber trotzdem bleibt dort ein Rotes X bei Microsoft Option ROM UEFI CA 2023<\/p>\n<p>Mu\u00df ich mir Sorgen machen?<\/p>\n"},"status":"1"},{"id":328348,"parent":328346,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2026-02-11T11:55:47","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nein, musst du nicht. Microsoft verteilt so wie gestern erst nach und nach die Zertifikate.<\/p>\n"},"status":"1"},{"id":328349,"parent":0,"author":9135,"author_name":"bezelbube","author_email":"bezelbube@freenet.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1ce157f17eef1de70a872d720d139228debecf3b7194ad7f0db921462c44cf36?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1ce157f17eef1de70a872d720d139228debecf3b7194ad7f0db921462c44cf36?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1ce157f17eef1de70a872d720d139228debecf3b7194ad7f0db921462c44cf36?s=96&d=mm&r=g"},"date":"2026-02-11T11:57:47","cld_nonce":"b6d6726996","content":{"rendered":"<p>Microsoft hat mit den gestrigen KB5077181,bez\u00fcglich der Secure Boot-Zertifikate,nochmals nachgebessert.<br \/>\nDie 3 Apply*.cmd\u00b4s aus den Github-Script,setzen lediglich nur einen Task,den Windows nach einen Neustart ausf\u00fchrt.<br \/>\nVorausetzung ist ein aktuelles Bios + Windows und aktiviertes &#8222;Secure Boot&#8220;.<\/p>\n"},"status":"1"},{"id":328351,"parent":328349,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2026-02-11T12:11:45","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nachgebessert ist die falsche Bezeichnung. Das ist das normale Rollout f\u00fcr die \u00c4nderung der Zertifikate.<\/p>\n"},"status":"1"},{"id":328354,"parent":328348,"author":0,"author_name":"Sclumpf Olaf","author_email":"Hans@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7d14164678fb73ea9da43f167ce7290785e812cc8ab916feab88a4bcfce3c68b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7d14164678fb73ea9da43f167ce7290785e812cc8ab916feab88a4bcfce3c68b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7d14164678fb73ea9da43f167ce7290785e812cc8ab916feab88a4bcfce3c68b?s=96&d=mm&r=g"},"date":"2026-02-11T12:23:00","cld_nonce":"b6d6726996","content":{"rendered":"<p>@moinmoin<\/p>\n<p>Danke erstmal f\u00fcr deine Antwort<\/p>\n<p>Habe aber gerade festgestellt das bei<br \/>\nCurrent UEFI DB<br \/>\n\u221a Microsoft Option ROM UEFI CA 2023 (revoked: False)<\/p>\n<p>ein gr\u00fcner Haken ist, es bei <\/p>\n<p>Default UEFI DB<br \/>\nX Microsoft Option ROM UEFI CA 2023<\/p>\n<p>das rote X ist.<\/p>\n<p>Kannst du mir sagen ob des Current oder das Default das entscheidende ist bzw. oder ob bei beiden es Gr\u00fcn sein sollte?<\/p>\n"},"status":"1"},{"id":328357,"parent":328354,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2026-02-11T12:28:32","cld_nonce":"b6d6726996","content":{"rendered":"<p>Current ist schon richtig.<\/p>\n"},"status":"1"},{"id":328358,"parent":328357,"author":0,"author_name":"Sclumpf Olaf","author_email":"Hans@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7d14164678fb73ea9da43f167ce7290785e812cc8ab916feab88a4bcfce3c68b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7d14164678fb73ea9da43f167ce7290785e812cc8ab916feab88a4bcfce3c68b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7d14164678fb73ea9da43f167ce7290785e812cc8ab916feab88a4bcfce3c68b?s=96&d=mm&r=g"},"date":"2026-02-11T12:31:59","cld_nonce":"b6d6726996","content":{"rendered":"<p>@moinmoin<\/p>\n<p>Super, danke dir.<br \/>\nDann kann ich ja wohl beruhigt sein.<\/p>\n"},"status":"1"},{"id":328410,"parent":328246,"author":0,"author_name":"Zanza","author_email":"zaza484-zanzara@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b84bb14a0c671fe9592d98ef592804a887ac51167442b7347c18b737c10afa64?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b84bb14a0c671fe9592d98ef592804a887ac51167442b7347c18b737c10afa64?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b84bb14a0c671fe9592d98ef592804a887ac51167442b7347c18b737c10afa64?s=96&d=mm&r=g"},"date":"2026-02-11T19:35:36","cld_nonce":"b6d6726996","content":{"rendered":"<p>ok aber mit aktivem secure boot ist dann kein booten mehr m\u00f6glich?<\/p>\n"},"status":"1"},{"id":328456,"parent":0,"author":0,"author_name":"Garak","author_email":"garak@vodafone.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=96&d=mm&r=g"},"date":"2026-02-12T12:20:24","cld_nonce":"b6d6726996","content":{"rendered":"<p>@moinmoin<\/p>\n<p>Bitte freischalten:<br \/>\n<a href=\"https:\/\/pastebin.com\/YfiBMeAp\" rel=\"nofollow ugc\">https:\/\/pastebin.com\/YfiBMeAp<\/a><\/p>\n<p>Richtet sich an Fortgeschrittene, nichts f\u00fcr anf\u00e4nger, aber man muss auch kein Experte sein.<br \/>\nDie Devise ist hartn\u00e4ckig sein. Windows will oft nicht direkt die DB oder den Bootloader updaten.<\/p>\n<p><a href=\"https:\/\/i.postimg.cc\/qvMNtXJ7\/proof.png\"  rel=\"lightbox[209109] nofollow ugc\">https:\/\/i.postimg.cc\/qvMNtXJ7\/proof.png<\/a><br \/>\nExecution Policy mit bypass wie beim Skript oben n\u00f6tig (logisch).<\/p>\n<p>Have fun, habe heute 3 Machinen startklar gemacht. Das Skript von cjee21 setzt den Fokus nicht hinreichend auf die EFI FAT32 partition der Systemfestplatte. Es ist nicht so schwer wie viele Behaupten. Windows ist nur stur.<\/p>\n"},"status":"1"},{"id":328458,"parent":328456,"author":0,"author_name":"Garak","author_email":"garak@vodafone.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=96&d=mm&r=g"},"date":"2026-02-12T12:30:13","cld_nonce":"b6d6726996","content":{"rendered":"<p>Powershell als Admin starten, aber das sollte klar sein, wenn man mounten, unmounten will <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":328517,"parent":328458,"author":0,"author_name":"Garak","author_email":"garak@vodafone.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=96&d=mm&r=g"},"date":"2026-02-12T18:22:18","cld_nonce":"b6d6726996","content":{"rendered":"<p>F\u00fcr die extremst &#8222;Nassgeschwitzten&#8220; von euch:<\/p>\n<p>4x (Revoked: True) korrekte Revozierung vor Okt\/Nov 2026<br \/>\nBeweis:<br \/>\n<a href=\"https:\/\/i.postimg.cc\/bYtfX8V9\/volle-revozierung.png\"  rel=\"lightbox[209109] nofollow ugc\">https:\/\/i.postimg.cc\/bYtfX8V9\/volle-revozierung.png<\/a><\/p>\n<p>Wie man manuell ein DBX append im UEFI BIOS oder aus dem OS selbst heraus macht wisst ihr ja.<br \/>\n(siehe: CTR-UEFI-SECURE-BOOT-CUSTOMIZATION-20230317.PDF)<\/p>\n<p>*https:\/\/www.microsoft.com\/pkiops\/certs\/MicCorKEKCA2011_2011-06-24.crt<br \/>\n*https:\/\/www.microsoft.com\/pkiops\/certs\/MicCorUEFCA2011_2011-06-27.crt<br \/>\n*https:\/\/www.microsoft.com\/pkiops\/certs\/MicWinProPCA2011_2011-10-19.crt<\/p>\n<p>Ihr solltet davon nur 2x brauchen, wenn ihr den Schritt mit 0x80 aus der CVE advisory bereits hinter euch habt.<\/p>\n<p>Jetzt k\u00f6nnen wir bis Dezember und l\u00e4nger chillen!<\/p>\n"},"status":"1"},{"id":328519,"parent":328517,"author":0,"author_name":"Garak","author_email":"garak@vodafone.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/390182e584956f6c471e3983a103bcfb082c62f758ed0a43662617b948a52ee8?s=96&d=mm&r=g"},"date":"2026-02-12T18:48:00","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nvm, es sind nat\u00fcrlich 2*3=6 mal (revoked:True)<br \/>\nDie dopplung kommt dadurch zustande, das die 3 certs in der default als auch current DB durch 3 Eintr\u00e4ge in der DBX revoziert wurden.<\/p>\n<p><a href=\"https:\/\/i.postimg.cc\/KYDCNrf4\/volle-revozierung2.png\"  rel=\"lightbox[209109] nofollow ugc\">https:\/\/i.postimg.cc\/KYDCNrf4\/volle-revozierung2.png<\/a><\/p>\n"},"status":"1"},{"id":328542,"parent":328410,"author":0,"author_name":"Frank","author_email":"zuehlke.f@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8bdd30a088be08934d759d047cae7d08cd95cb002cf7eb3212249dd77f45ba39?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8bdd30a088be08934d759d047cae7d08cd95cb002cf7eb3212249dd77f45ba39?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8bdd30a088be08934d759d047cae7d08cd95cb002cf7eb3212249dd77f45ba39?s=96&d=mm&r=g"},"date":"2026-02-13T06:31:42","cld_nonce":"b6d6726996","content":{"rendered":"<p>Du musst dann kein SecureBoot ausschalten. Selbst mit abgelaufenden Zertifikaten l\u00e4uft der Rechner trotzdem. Du wirst nur eben keine Sicherheitsupdates mehr auf Bootebene bekommen.<\/p>\n"},"status":"1"},{"id":328543,"parent":328354,"author":0,"author_name":"Frank","author_email":"zuehlke.f@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8bdd30a088be08934d759d047cae7d08cd95cb002cf7eb3212249dd77f45ba39?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8bdd30a088be08934d759d047cae7d08cd95cb002cf7eb3212249dd77f45ba39?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8bdd30a088be08934d759d047cae7d08cd95cb002cf7eb3212249dd77f45ba39?s=96&d=mm&r=g"},"date":"2026-02-13T06:41:31","cld_nonce":"b6d6726996","content":{"rendered":"<p>Current = Was eingespielt wurde<br \/>\nDefault = ist was vom Hersteller kommt\/Installiert wurde&#8230;<\/p>\n<p>Sprich wenn du den Default auch gr\u00fcn haben m\u00f6chtest, geht das nur \u00fcber ein Bios Update vom Hersteller.<br \/>\nWas aber unn\u00f6tig ist, so lange du den &#8222;Current&#8220; in der Datenbank hast, ist alles Okay&#8230; <\/p>\n<p>Default kommt wie gesagt wenn du SecureBoot im Bios mal zur\u00fccksetzt oder Aus\/Einschaltest.<\/p>\n"},"status":"1"},{"id":328544,"parent":0,"author":6246,"author_name":"Vectorprime","author_email":"reinfeld@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/50065142e47aa0f4d10efe4863577fae0e8d3efbd0ddab24335c63a8054d4b12?s=96&d=mm&r=g"},"date":"2026-02-13T06:55:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>bei mir sind nur 2 Sachen noch nicht aktuell Microsoft UEFI CA 2023 und Microsoft Option ROM UEFI CA 2023 hei\u00dft dass das diese von seitens MS noch kommen? Bei bei meinen laptop fehlen noch 3 sachen Windows Bootmgr SVN  , Windows Bootmgr SVN und Windows wdsmgfw SVN kommen die auch von ms oder vom hersteller?<\/p>\n"},"status":"1"},{"id":328588,"parent":0,"author":0,"author_name":"Jochen","author_email":"j.koehler-chemnitz@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4d2786154474dafd3f6e6f8dbefc32949c4ebd963109d29ca9f7c22b4bee376a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4d2786154474dafd3f6e6f8dbefc32949c4ebd963109d29ca9f7c22b4bee376a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4d2786154474dafd3f6e6f8dbefc32949c4ebd963109d29ca9f7c22b4bee376a?s=96&d=mm&r=g"},"date":"2026-02-13T15:38:13","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hallo,<br \/>\nich habe die neuen Zertifikate soeben allein durch ein neues BIOS-Update erhalten, nachdem ich mein Mainboard ASUS Prime B560 Plus auf die aktuelle Version 2803 aktualisiert habe.<br \/>\nZun\u00e4chst nach dem Update waren die neuen Schl\u00fcssel noch nicht vorhanden. Man muss zuerst die alten Schl\u00fcssel l\u00f6schen und dann danach die neuen aus dem BIOS-Update speichern.<\/p>\n<p>im UEFI: im Men\u00fc Sicheres Booten den &#8222;Sicheres Booten-Modus&#8220; auf &#8222;benutzerdefiniert&#8220; stellen, erst danach wird die &#8222;Schl\u00fcsselverwaltung&#8220; freigegeben. In der Schl\u00fcsselverwaltung &#8222;Secure Boot-Schl\u00fcssel&#8220; l\u00f6schen und danach<br \/>\n&#8222;Alle Secure Boot- Variablen speichern&#8220;, erst jetzt werden die neuen Schl\u00fcssel aus dem BIOS-Update \u00fcbernommen. (Voraussetzung ist allerdings, das der Hersteller ein aktualisiertes BIOS anbietet)<br \/>\nNach einem Neustart und dem schon genanten genanten Test war bei mir alles &#8222;gr\u00fcn&#8220; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":328603,"parent":328267,"author":0,"author_name":"Carl Breen","author_email":"carl.breen@posteo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/37a4a6bf085cda7144a6f8ee5372945f093e672ccfa7318be3da787fb327bb8c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/37a4a6bf085cda7144a6f8ee5372945f093e672ccfa7318be3da787fb327bb8c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/37a4a6bf085cda7144a6f8ee5372945f093e672ccfa7318be3da787fb327bb8c?s=96&d=mm&r=g"},"date":"2026-02-13T17:47:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>*https:\/\/support.microsoft.com\/en-us\/topic\/how-to-manage-the-windows-boot-manager-revocations-for-secure-boot-changes-associated-with-cve-2023-24932-41a975df-beb2-40c1-99a3-b3ff139f832d<\/p>\n<p>0x200 reg key f\u00fcr fehlende SVNs nutzen, und bitte einfach mal einlesen<\/p>\n"},"status":"1"},{"id":328735,"parent":0,"author":9400,"author_name":"Dennis50300","author_email":"dennisw50300@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f5b22f5d882dd7639157d6b873a49ac9fc020640852da831f8ff8587118f1f27?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f5b22f5d882dd7639157d6b873a49ac9fc020640852da831f8ff8587118f1f27?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f5b22f5d882dd7639157d6b873a49ac9fc020640852da831f8ff8587118f1f27?s=96&d=mm&r=g"},"date":"2026-02-15T17:07:44","cld_nonce":"b6d6726996","content":{"rendered":"<p>Dank des GitHubs konnte mein Asrock H170A-X1 das j\u00fcngste Zertifikat verpassen, wenn ich denn mal SecureBoot aktiviert haben sollte, habe ich dann keine Probleme mit veralteten Zertifikaten.<\/p>\n<p>mfG<\/p>\n"},"status":"1"},{"id":328753,"parent":0,"author":0,"author_name":"Peter V.","author_email":"asjacky@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4aa4c5ca4715c39416fb00193d4431131a00fd7e76764750ec21c94dcc35ce99?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4aa4c5ca4715c39416fb00193d4431131a00fd7e76764750ec21c94dcc35ce99?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4aa4c5ca4715c39416fb00193d4431131a00fd7e76764750ec21c94dcc35ce99?s=96&d=mm&r=g"},"date":"2026-02-15T23:56:07","cld_nonce":"b6d6726996","content":{"rendered":"<p>Dank der Anleitung mit dem Script habe ich nach etwas Anlaufproblemen auch alles auf &#8222;gr\u00fcn&#8220;.<br \/>\nLediglich ein Bios-Update hatte etwas gebraucht, nachdem die ASUS Webseite wegen &#8222;Umbauarbeiten &#8211; nicht \u00fcberall)&#8220; (siehe Artikel bei PCGH) offline ist. Auch wenn das Board schon etwas \u00e4lter ist, gibt es doch ein Update (Rog Strix B460-F).<br \/>\nDanke an euch alle und vor allem MoinMoin\/Deskmodder <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><br \/>\nVG<br \/>\nPeter<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen? - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen?\" \/>\n<meta property=\"og:description\" content=\"Microsoft hat heute einen Supportbeitrag und auch einen Blogbeitrag zum Thema Secure Boot Zertifikate ver\u00f6ffentlicht. Dabei geht es um die im Juni 2026 auslaufenden Secure Boot Zertifikate von 2011. Bis dahin werden die neuen Secure Boot Zertifikate von 2023 den&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T17:25:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T17:25:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1205\" \/>\n\t<meta property=\"og:image:height\" content=\"927\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen?\",\"datePublished\":\"2026-02-10T17:25:05+00:00\",\"dateModified\":\"2026-02-10T17:25:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/\"},\"wordCount\":214,\"commentCount\":57,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/stockvault-cyber-security-concept174251.jpg\",\"articleSection\":[\"Windows 10\",\"Windows 11\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/\",\"name\":\"Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen? - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/stockvault-cyber-security-concept174251.jpg\",\"datePublished\":\"2026-02-10T17:25:05+00:00\",\"dateModified\":\"2026-02-10T17:25:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/stockvault-cyber-security-concept174251.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/stockvault-cyber-security-concept174251.jpg\",\"width\":1205,\"height\":927,\"caption\":\"http:\\\/\\\/www.stockvault.net\\\/photo\\\/174251\\\/cyber-security-concept\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/02\\\/10\\\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen? - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/","og_locale":"de_DE","og_type":"article","og_title":"Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen?","og_description":"Microsoft hat heute einen Supportbeitrag und auch einen Blogbeitrag zum Thema Secure Boot Zertifikate ver\u00f6ffentlicht. Dabei geht es um die im Juni 2026 auslaufenden Secure Boot Zertifikate von 2011. Bis dahin werden die neuen Secure Boot Zertifikate von 2023 den&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2026-02-10T17:25:05+00:00","article_modified_time":"2026-02-10T17:25:49+00:00","og_image":[{"width":1205,"height":927,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen?","datePublished":"2026-02-10T17:25:05+00:00","dateModified":"2026-02-10T17:25:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/"},"wordCount":214,"commentCount":57,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251.jpg","articleSection":["Windows 10","Windows 11"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/","url":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/","name":"Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen? - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251.jpg","datePublished":"2026-02-10T17:25:05+00:00","dateModified":"2026-02-10T17:25:49+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251.jpg","width":1205,"height":927,"caption":"http:\/\/www.stockvault.net\/photo\/174251\/cyber-security-concept"},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/02\/10\/was-passiert-wenn-die-secure-boot-zertifikate-unter-windows-11-und-windows-10-ablaufen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Was passiert, wenn die Secure Boot-Zertifikate unter Windows 11 und Windows 10 ablaufen?"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/209109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=209109"}],"version-history":[{"count":1,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/209109\/revisions"}],"predecessor-version":[{"id":209111,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/209109\/revisions\/209111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/92066"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=209109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=209109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=209109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}