{"id":208560,"date":"2026-01-25T18:11:08","date_gmt":"2026-01-25T17:11:08","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=208560"},"modified":"2026-01-25T18:11:58","modified_gmt":"2026-01-25T17:11:58","slug":"everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/","title":{"rendered":"Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen"},"content":{"rendered":"<p>\u00dcber die Suche Everything hatten wir gerade berichtet, da <a href=\"https:\/\/www.deskmodder.de\/blog\/2026\/01\/23\/everything-1-4-1-1032-korrigiert-eine-sicherheitsluecke-und-mehr\/\" target=\"_blank\">ein Update bereitgestellt wurde<\/a>. Jetzt folgt auch das erste Update f\u00fcr Everything Toolbar in diesem Jahr mit der Versionsnummer 2.1.2. Unter Windows 10 kann es die Suche in der Taskleiste ersetzen und unter Windows 11 wird ein eigenes Icon angeheftet.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20.jpg\" rel=\"lightbox[208560]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-500x331.jpg\" alt=\"\" width=\"500\" height=\"331\" class=\"aligncenter size-medium wp-image-201947\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-500x331.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-810x537.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-306x203.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-1536x1018.jpg 1536w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20.jpg 1597w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Neu in dieser Version ist, dass eine Option zum Steuern der Funktion der Tasten Pos1 und Ende hinzugef\u00fcgt wurde. <em>(Navigieren in Suchergebnissen oder Bewegen des Cursors)<\/em> Eine \u00c4nderung ist unter anderem auch, dass der Benutzer das Taskleistensymbol nun nicht mehr deaktivieren kann, wenn das Taskleistensymbol nicht angeheftet ist. Die weiteren \u00c4nderungen sind:<\/p>\n<ul>\n<li>Standardpfad f\u00fcr Filters.csv hinzugef\u00fcgt, anstatt bei der ersten Verwendung danach zu fragen<\/li>\n<li>Problem behoben, dass Makros in benutzerdefinierten Suchbegriffen f\u00fcr Filter nicht verwendet wurden<\/li>\n<li>Zuverl\u00e4ssigkeit der Autostart-Pr\u00fcfung wurde verbessert<\/li>\n<li>Die Formulierung zu Administratorrechten im Installationsprogramm wurde pr\u00e4zisiert<\/li>\n<li>Der Arbeitsablauf f\u00fcr WinGet-Ver\u00f6ffentlichungen wurde aktualisiert<\/li>\n<\/ul>\n<h3>Die Anleitung, um EverythingToolbar zu nutzen:<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.voidtools.com\/\" rel=\"noopener\" target=\"_blank\">Everything<\/a> herunterladen. (Nicht die Lite-Version) und starten<\/li>\n<li>EverythingToolbar herunterladen, installieren und starten<\/li>\n<li>Das Icon von EverythingToolbar an die Taskleiste anheften <\/li>\n<li>Optional das Windows-Such-Icon in den Einstellungen -> Personalisierung -> Taskleiste auf &#8222;Aus&#8220; stellen<\/li>\n<li>Jetzt kann auch schon die Suche gestartet werden \u00fcber ein &#8222;Klick&#8220; auf das Icon oder die voreingestellte Tastenkombination Win + Alt + S (l\u00e4sst sich \u00e4ndern).<\/li>\n<li><em>Everything und EverythingToolbar m\u00fcssen in den Autostart.<\/em><\/li>\n<\/ul>\n<h3>Info und Download:<\/h3>\n<ul>\n<li><a href=\"https:\/\/github.com\/srwi\/EverythingToolbar\" rel=\"noopener\" target=\"_blank\">github.com\/EverythingToolbar<\/a><\/li>\n<li><a href=\"https:\/\/github.com\/srwi\/EverythingToolbar\/releases\" rel=\"noopener\" target=\"_blank\">github.com\/EverythingToolbar\/releases<\/a><\/li>\n<\/ul>\n<p>Wer die <a href=\"https:\/\/www.deskmodder.de\/blog\/?s=PowerToys\" target=\"_blank\">PowerToys eh schon laufen hat<\/a>, kann nat\u00fcrlich auch die Befehlspalette oder PowerToys Run nutzen. Auch hier habt ihr eine schnelle Suche, gegen\u00fcber der Windows-eigenen.<\/p>\n<div class=\"quelle\">Quelle: <\/div>\n<h3>Windows 11 Tutorials und Hilfe<\/h3>\n<ul>\n<li>In unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 11 Wiki<\/a> findet ihr sehr viele hilfreiche Tipps und Tricks.<\/li>\n<li>Falls ihr Fragen habt, dann stellt diese ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=353\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Forum<\/strong><\/a>.<\/li>\n<li><strong>Installationsmedien:<\/strong> Aktuelle Windows 11 ISOs findet ihr hier: <a href=\"https:\/\/www.deskmodder.de\/blog\/2025\/06\/28\/windows-11-25h2-26200-iso-esd-deutsch-english\/\" rel=\"noopener\" target=\"_blank\">25H2 26200<\/a>, oder <a href=\"https:\/\/www.deskmodder.de\/blog\/2024\/04\/27\/windows-11-24h2-26100-iso-esd-deutsch-english\/%22\" rel=\"noopener\" target=\"_blank\">24H2 26100<\/a>. Ansonsten immer in der rechten Sidebar.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_neu_clean_installieren_Tipps_und_Tricks\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 neu clean installieren Tipps und Tricks<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_auch_ohne_TPM_und_Secure_Boot_installieren\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 auch ohne TPM und Secure Boot installieren<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_mit_einem_lokalen_oder_Microsoft_Konto_installieren\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 mit lokalem Konto auch Offline installieren<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_Inplace_Upgrade_Reparatur_oder_Feature_Update\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 Inplace Upgrade Reparatur oder Feature Update<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Automatisch_anmelden_Pin_entfernen_Windows_11\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Automatisch anmelden Pin entfernen Windows 11<\/strong><\/a>.<\/li>\n<li>Alle Beitr\u00e4ge zu Windows 11 im Blog findet ihr <a href=\"https:\/\/www.deskmodder.de\/blog\/category\/windows-11\/\" rel=\"noopener\" target=\"_blank\">\u00fcber diese Seite<\/a>. Wobei auch <a href=\"https:\/\/www.deskmodder.de\/blog\/\" rel=\"noopener\" target=\"_blank\">alle anderen Artikel<\/a> interessant sein k\u00f6nnen.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcber die Suche Everything hatten wir gerade berichtet, da ein Update bereitgestellt wurde. Jetzt folgt auch das erste Update f\u00fcr Everything Toolbar in diesem Jahr mit der Versionsnummer 2.1.2. Unter Windows 10 kann es die Suche in der Taskleiste ersetzen&hellip; <\/p>\n","protected":false},"author":134,"featured_media":201947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[152],"tags":[95399],"class_list":["post-208560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software","tag-everything-toolbar-2-1-2"],"wp_featured_image":{"id":201947,"alt_text":"","description":"","media_type":"image","media_details":{"width":1597,"height":1058,"file":"2025\/08\/everythingtoolbar-20.jpg","filesize":514876,"sizes":{"medium":{"file":"everythingtoolbar-20-500x331.jpg","width":500,"height":331,"mime-type":"image\/jpeg","filesize":19312,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-500x331.jpg"},"large":{"file":"everythingtoolbar-20-810x537.jpg","width":810,"height":537,"mime-type":"image\/jpeg","filesize":40828,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-810x537.jpg"},"thumbnail":{"file":"everythingtoolbar-20-306x203.jpg","width":306,"height":203,"mime-type":"image\/jpeg","filesize":9479,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-306x203.jpg"},"1536x1536":{"file":"everythingtoolbar-20-1536x1018.jpg","width":1536,"height":1018,"mime-type":"image\/jpeg","filesize":103931,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-1536x1018.jpg"},"blog-large":{"file":"everythingtoolbar-20-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","filesize":21900,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-642x300.jpg"},"blog-medium":{"file":"everythingtoolbar-20-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","filesize":9513,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-306x205.jpg"},"recent-thumb":{"file":"everythingtoolbar-20-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","filesize":12266,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-350x316.jpg"},"service-featured":{"file":"everythingtoolbar-20-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","filesize":21763,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20-600x330.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":201946,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen\" \/>\n<meta property=\"og:description\" content=\"\u00dcber die Suche Everything hatten wir gerade berichtet, da ein Update bereitgestellt wurde. Jetzt folgt auch das erste Update f\u00fcr Everything Toolbar in diesem Jahr mit der Versionsnummer 2.1.2. Unter Windows 10 kann es die Suche in der Taskleiste ersetzen&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-25T17:11:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-25T17:11:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1597\" \/>\n\t<meta property=\"og:image:height\" content=\"1058\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen\",\"datePublished\":\"2026-01-25T17:11:08+00:00\",\"dateModified\":\"2026-01-25T17:11:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/\"},\"wordCount\":378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/everythingtoolbar-20.jpg\",\"keywords\":[\"Everything Toolbar 2.1.2\"],\"articleSection\":[\"Software &amp; Updates\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/\",\"name\":\"Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/everythingtoolbar-20.jpg\",\"datePublished\":\"2026-01-25T17:11:08+00:00\",\"dateModified\":\"2026-01-25T17:11:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/everythingtoolbar-20.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/everythingtoolbar-20.jpg\",\"width\":1597,\"height\":1058},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2026\\\/01\\\/25\\\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/","og_locale":"de_DE","og_type":"article","og_title":"Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen","og_description":"\u00dcber die Suche Everything hatten wir gerade berichtet, da ein Update bereitgestellt wurde. Jetzt folgt auch das erste Update f\u00fcr Everything Toolbar in diesem Jahr mit der Versionsnummer 2.1.2. Unter Windows 10 kann es die Suche in der Taskleiste ersetzen&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2026-01-25T17:11:08+00:00","article_modified_time":"2026-01-25T17:11:58+00:00","og_image":[{"width":1597,"height":1058,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen","datePublished":"2026-01-25T17:11:08+00:00","dateModified":"2026-01-25T17:11:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/"},"wordCount":378,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20.jpg","keywords":["Everything Toolbar 2.1.2"],"articleSection":["Software &amp; Updates"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/","url":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/","name":"Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20.jpg","datePublished":"2026-01-25T17:11:08+00:00","dateModified":"2026-01-25T17:11:58+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20.jpg","width":1597,"height":1058},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2026\/01\/25\/everything-toolbar-2-1-2-mit-neuer-tastenfunktion-fuer-pos1-und-ende-und-weitere-verbesserungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Everything Toolbar 2.1.2 mit neuer Tastenfunktion f\u00fcr Pos1 und Ende und weitere Verbesserungen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/08\/everythingtoolbar-20.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/208560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=208560"}],"version-history":[{"count":2,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/208560\/revisions"}],"predecessor-version":[{"id":208562,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/208560\/revisions\/208562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/201947"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=208560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=208560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=208560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}