{"id":202207,"date":"2025-08-07T09:47:51","date_gmt":"2025-08-07T07:47:51","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=202207"},"modified":"2025-08-07T15:43:49","modified_gmt":"2025-08-07T13:43:49","slug":"firefox-141-0-3-korrigiert-weitere-fehler","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/","title":{"rendered":"Firefox 141.0.3 korrigiert weitere Fehler"},"content":{"rendered":"<p>Mozilla hatte wohl das letzte Update entweder zu schnell herausgegeben, oder nach dem Release haben wurden dann weitere Fehler gemeldet. Wie dem auch sein, der Firefox 141.0.3 korrigiert noch einmal weitere Fehler. Ist ja erst zwei Tage her, <a href=\"https:\/\/www.deskmodder.de\/blog\/2025\/08\/05\/firefox-141-0-2-korrigiert-zwei-probleme\/\" target=\"_blank\">mit dem alten Update<\/a><\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/08\/firefox-logo-2019.png\" rel=\"lightbox[202207]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/08\/firefox-logo-2019-500x360.png\" alt=\"\" width=\"500\" height=\"360\" class=\"aligncenter size-medium wp-image-125545\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/08\/firefox-logo-2019-500x360.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/08\/firefox-logo-2019-285x205.png 285w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/08\/firefox-logo-2019.png 615w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Wenn nichts dazwischen kommt, wird das Update am Nachmittag \u00fcber die Updatefunktion im Browser verteilt werden. <strong>[Update]:<\/strong> Und es kam nichts dazwischen. Hier aber erst einmal die zwei Korrekturen.<\/p>\n<ul>\n<li>Es wurde ein Fehler behoben, der Probleme auf Websites verursachte, die mit dem Svelte-Framework erstellt wurden.<\/li>\n<li>Es wurde ein Problem behoben, bei dem Cryptominer nicht als blockiert im strengen Tracking-Schutz aufgef\u00fchrt wurden.<\/li>\n<\/ul>\n<h3>Info und Download:<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.mozilla.org\/en-US\/firefox\/141.0.3\/releasenotes\/\" target=\"_blank\">mozilla.org\/firefox\/141.0.3\/releasenotes<\/a><\/li>\n<li><a href=\"https:\/\/releases.mozilla.org\/pub\/firefox\/releases\/141.0.3\/\" target=\"_blank\">mozilla.org\/firefox\/releases\/141.0.3<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mozilla hatte wohl das letzte Update entweder zu schnell herausgegeben, oder nach dem Release haben wurden dann weitere Fehler gemeldet. Wie dem auch sein, der Firefox 141.0.3 korrigiert noch einmal weitere Fehler. Ist ja erst zwei Tage her, mit dem&hellip; <\/p>\n","protected":false},"author":134,"featured_media":143930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166],"tags":[93328],"class_list":["post-202207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","tag-firefox-141-0-3"],"wp_featured_image":{"id":143930,"alt_text":"","description":"","media_type":"image","media_details":{"width":500,"height":360,"file":"2020\/09\/firefox-logo-2019-500x360-1.png","sizes":{"medium":{"file":"firefox-logo-2019-500x360-1-500x360.png","width":500,"height":360,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1-500x360.png"},"thumbnail":{"file":"firefox-logo-2019-500x360-1-50x50.png","width":50,"height":50,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1-50x50.png"},"blog-large":{"file":"firefox-logo-2019-500x360-1-500x300.png","width":500,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1-500x300.png"},"blog-medium":{"file":"firefox-logo-2019-500x360-1-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1-306x205.png"},"recent-thumb":{"file":"firefox-logo-2019-500x360-1-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1-350x316.png"},"service-featured":{"file":"firefox-logo-2019-500x360-1-500x330.png","width":500,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1-500x330.png"},"wp_rp_thumbnail":{"file":"firefox-logo-2019-500x360-1-50x50.png","width":50,"height":50,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1-50x50.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":143928,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1.png"},"commentcount":3,"wp_comments":[{"id":309442,"parent":0,"author":0,"author_name":"Hotte","author_email":"Hotte@Hotte.Hotte","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/2ac31c97a6d69ba370654a03c3bdbd5ee9b62f37a01a2aecc8b5da578712f09a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/2ac31c97a6d69ba370654a03c3bdbd5ee9b62f37a01a2aecc8b5da578712f09a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/2ac31c97a6d69ba370654a03c3bdbd5ee9b62f37a01a2aecc8b5da578712f09a?s=96&d=mm&r=g"},"date":"2025-08-07T10:39:05","cld_nonce":"82f011626f","content":{"rendered":"<p>leider immer noch nicht diesen (neu seit 141)<br \/>\n<a href=\"https:\/\/bugzilla.mozilla.org\/show_bug.cgi?id=1973769\" rel=\"nofollow ugc\">https:\/\/bugzilla.mozilla.org\/show_bug.cgi?id=1973769<\/a><\/p>\n"},"status":"1"},{"id":309465,"parent":0,"author":0,"author_name":"Anonymous","author_email":"anonym@anonym.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3b38219a25dec6be7038c48c4ce8fdfbb32a13acd122d75d397b1f8cc56c555d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3b38219a25dec6be7038c48c4ce8fdfbb32a13acd122d75d397b1f8cc56c555d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3b38219a25dec6be7038c48c4ce8fdfbb32a13acd122d75d397b1f8cc56c555d?s=96&d=mm&r=g"},"date":"2025-08-07T17:02:00","cld_nonce":"82f011626f","content":{"rendered":"<p>Nach zwei Wochen ohne Update nun das zweite Update innerhalb von drei Tagen &#8211; ja moin &#8211; Qualit\u00e4tssicherung l\u00e4\u00dft gr\u00fc\u00dfen (und fehlt dann doch noch nach wie vor)&#8230;<\/p>\n"},"status":"1"},{"id":309482,"parent":309465,"author":0,"author_name":"Markus","author_email":"dulvic@arcor.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/766bb222cb5bb695e9be1623d6a7dd78e2f65836ff6e9c4a6440f397a1d84ddf?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/766bb222cb5bb695e9be1623d6a7dd78e2f65836ff6e9c4a6440f397a1d84ddf?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/766bb222cb5bb695e9be1623d6a7dd78e2f65836ff6e9c4a6440f397a1d84ddf?s=96&d=mm&r=g"},"date":"2025-08-07T22:39:25","cld_nonce":"82f011626f","content":{"rendered":"<p>Microsoft Edge Stable Channel<br \/>\nVersion 138.0.3351.109: July 25, 2025<br \/>\nVersion 138.0.3351.95: July 16, 2025<br \/>\nVersion 138.0.3351.83: July 10, 2025<br \/>\nVersion 138.0.3351.77: July 7, 2025<br \/>\nVersion 138.0.3351.65: July 1, 2025 usw.<br \/>\nQualit\u00e4tssicherung l\u00e4sst gr\u00fc\u00dfen&#8230;<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Firefox 141.0.3 korrigiert weitere Fehler - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Firefox 141.0.3 korrigiert weitere Fehler\" \/>\n<meta property=\"og:description\" content=\"Mozilla hatte wohl das letzte Update entweder zu schnell herausgegeben, oder nach dem Release haben wurden dann weitere Fehler gemeldet. Wie dem auch sein, der Firefox 141.0.3 korrigiert noch einmal weitere Fehler. Ist ja erst zwei Tage her, mit dem&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-07T07:47:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-07T13:43:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Firefox 141.0.3 korrigiert weitere Fehler\",\"datePublished\":\"2025-08-07T07:47:51+00:00\",\"dateModified\":\"2025-08-07T13:43:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/\"},\"wordCount\":118,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/firefox-logo-2019-500x360-1.png\",\"keywords\":[\"Firefox 141.0.3\"],\"articleSection\":[\"Browser\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/\",\"name\":\"Firefox 141.0.3 korrigiert weitere Fehler - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/firefox-logo-2019-500x360-1.png\",\"datePublished\":\"2025-08-07T07:47:51+00:00\",\"dateModified\":\"2025-08-07T13:43:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/firefox-logo-2019-500x360-1.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/firefox-logo-2019-500x360-1.png\",\"width\":500,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/08\\\/07\\\/firefox-141-0-3-korrigiert-weitere-fehler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Firefox 141.0.3 korrigiert weitere Fehler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Firefox 141.0.3 korrigiert weitere Fehler - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/","og_locale":"de_DE","og_type":"article","og_title":"Firefox 141.0.3 korrigiert weitere Fehler","og_description":"Mozilla hatte wohl das letzte Update entweder zu schnell herausgegeben, oder nach dem Release haben wurden dann weitere Fehler gemeldet. Wie dem auch sein, der Firefox 141.0.3 korrigiert noch einmal weitere Fehler. Ist ja erst zwei Tage her, mit dem&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2025-08-07T07:47:51+00:00","article_modified_time":"2025-08-07T13:43:49+00:00","og_image":[{"width":500,"height":360,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Firefox 141.0.3 korrigiert weitere Fehler","datePublished":"2025-08-07T07:47:51+00:00","dateModified":"2025-08-07T13:43:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/"},"wordCount":118,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1.png","keywords":["Firefox 141.0.3"],"articleSection":["Browser"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/","url":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/","name":"Firefox 141.0.3 korrigiert weitere Fehler - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1.png","datePublished":"2025-08-07T07:47:51+00:00","dateModified":"2025-08-07T13:43:49+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1.png","width":500,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2025\/08\/07\/firefox-141-0-3-korrigiert-weitere-fehler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Firefox 141.0.3 korrigiert weitere Fehler"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/firefox-logo-2019-500x360-1.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/202207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=202207"}],"version-history":[{"count":2,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/202207\/revisions"}],"predecessor-version":[{"id":202225,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/202207\/revisions\/202225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/143930"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=202207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=202207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=202207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}