{"id":201629,"date":"2025-07-25T10:51:51","date_gmt":"2025-07-25T08:51:51","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=201629"},"modified":"2025-07-25T10:51:51","modified_gmt":"2025-07-25T08:51:51","slug":"apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/","title":{"rendered":"Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei"},"content":{"rendered":"<p>Apple hat gestern die erste \u00f6ffentliche Beta ihrer neuen Betriebssysteme ver\u00f6ffentlicht. Mit iOS 26, iPadOS 26 und mehr entdeckt Apple erstmals nach vielen Jahren eine neue Designsprache. Das sogenannte &#8222;Liquid Glass&#8220; ver\u00e4ndert die komplette Oberfl\u00e4che der hauseigenen Softwaresysteme.<\/p>\n<figure id=\"attachment_201630\" aria-describedby=\"caption-attachment-201630\" style=\"width: 166px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/gwo2lo7w0aaorki-scaled.jpeg\" rel=\"lightbox[201629]\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-201630\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/gwo2lo7w0aaorki-166x360.jpeg\" alt=\"\" width=\"166\" height=\"360\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/gwo2lo7w0aaorki-166x360.jpeg 166w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/gwo2lo7w0aaorki-268x583.jpeg 268w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/gwo2lo7w0aaorki-94x205.jpeg 94w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/gwo2lo7w0aaorki-706x1536.jpeg 706w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/gwo2lo7w0aaorki-942x2048.jpeg 942w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/gwo2lo7w0aaorki-scaled.jpeg 1177w\" sizes=\"auto, (max-width: 166px) 100vw, 166px\" \/><\/a><figcaption id=\"caption-attachment-201630\" class=\"wp-caption-text\">iOS 26 Public Beta &#8211; Foto: <a href=\"https:\/\/x.com\/zollotech\/status\/1948429819122766294\/photo\/1\" target=\"_blank\" rel=\"noopener\">Zollotech<\/a><\/figcaption><\/figure>\n<h2>Das ist neu:<\/h2>\n<p>Hauptfokus der neuen Versionen ist das neue Design. Mit Liquid Glass wurde die komplette Benutzeroberfl\u00e4che ver\u00e4ndert. Ob iPhone, iPad, MacBook und mehr: die komplette Software wurde auf allen Ger\u00e4ten Grundlegend \u00fcberarbeitet und erstrahlt in einem neuen Look, welcher nun deutlich moderner und angepasster ist, als noch in den Jahren zuvor. Unter anderem passt man die Icons an, ver\u00e4ndert das Kontrollzentrum oder verpasst der Kamera-App eine neue Ansicht. Im Folgenden eine kurze \u00dcbersicht mancher Neuerungen:<\/p>\n<ul>\n<li>App Icons erhalten einen neuen Look<\/li>\n<li>\u00dcberarbeitetes Kontrollzentrum<\/li>\n<li>Neue Kamera-App<\/li>\n<li>Angepasstes Layout f\u00fcr die Fotos-App, Safari, FindMy und mehr<\/li>\n<li>Adaptiver Strommodus f\u00fcr verbesserte Akkulaufzeit<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/blog\/2025\/06\/09\/ios-26-und-ipados-26-vorgestellt-glasige-aussichten\/\" target=\"_blank\" rel=\"noopener\">Und vieles mehr<\/a><\/li>\n<\/ul>\n<div id='gallery-1' class='gallery galleryid-201629 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0921-scaled.png' rel=\"lightbox[201629]\"><img loading=\"lazy\" decoding=\"async\" width=\"95\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0921-95x205.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-201631\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0921-95x205.png 95w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0921-166x360.png 166w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0921-269x583.png 269w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0921-709x1536.png 709w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0921-945x2048.png 945w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0921-scaled.png 1181w\" sizes=\"auto, (max-width: 95px) 100vw, 95px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-201631'>\n\t\t\t\tIcons &#8211; Foto: Deskmodder\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0922-scaled.png' rel=\"lightbox[201629]\"><img loading=\"lazy\" decoding=\"async\" width=\"95\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0922-95x205.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-201632\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0922-95x205.png 95w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0922-166x360.png 166w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0922-269x583.png 269w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0922-709x1536.png 709w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0922-945x2048.png 945w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0922-scaled.png 1181w\" sizes=\"auto, (max-width: 95px) 100vw, 95px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-201632'>\n\t\t\t\tKamera &#8211; Foto: Deskmodder\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0923-scaled.png' rel=\"lightbox[201629]\"><img loading=\"lazy\" decoding=\"async\" width=\"95\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0923-95x205.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-201633\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0923-95x205.png 95w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0923-166x360.png 166w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0923-269x583.png 269w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0923-709x1536.png 709w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0923-945x2048.png 945w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0923-scaled.png 1181w\" sizes=\"auto, (max-width: 95px) 100vw, 95px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-201633'>\n\t\t\t\tSafari &#8211; Foto: Deskmodder\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0924-scaled.png' rel=\"lightbox[201629]\"><img loading=\"lazy\" decoding=\"async\" width=\"95\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0924-95x205.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-201634\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0924-95x205.png 95w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0924-166x360.png 166w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0924-269x583.png 269w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0924-709x1536.png 709w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0924-945x2048.png 945w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/07\/img-0924-scaled.png 1181w\" sizes=\"auto, (max-width: 95px) 100vw, 95px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-201634'>\n\t\t\t\tAdaptive Batterie &#8211; Fotos: Deskmodder\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Eine \u00dcbersicht f\u00fcr iPhones, welche das Update erhalten haben, findet ihr <a href=\"https:\/\/x.com\/zollotech\/status\/1932144352278839627\" target=\"_blank\" rel=\"noopener\">hier<\/a>. F\u00fcr die iPads <a href=\"https:\/\/x.com\/zollotech\/status\/1932144667023315428\" target=\"_blank\" rel=\"noopener\">hier<\/a>.<\/p>\n<h2>Infos zu Installation:<\/h2>\n<p>Die erste Public Beta ist ab sofort verf\u00fcgbar. Die Entwicklerversion ist mittlerweile bei Version 4 angelangt. Man kann zwar grunds\u00e4tzlich davon ausgehen, dass alles soweit stabil l\u00e4uft, aber trotzdem handelt es sich hierbei um eine Vorabversion der neuen Software. Falls ihr das ganze Installieren wollt, legt vorher unbedingt ein Backup eurer Daten an.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apple hat gestern die erste \u00f6ffentliche Beta ihrer neuen Betriebssysteme ver\u00f6ffentlicht. Mit iOS 26, iPadOS 26 und mehr entdeckt Apple erstmals nach vielen Jahren eine neue Designsprache. Das sogenannte &#8222;Liquid Glass&#8220; ver\u00e4ndert die komplette Oberfl\u00e4che der hauseigenen Softwaresysteme. Das ist&hellip; <\/p>\n","protected":false},"author":4849,"featured_media":200537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[232,152],"tags":[98,5533,6576,84251,9746,2445,63702,1125,6142,96,13998,13997],"class_list":["post-201629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ios","category-software","tag-apple","tag-apple-tv","tag-apple-watch","tag-homepod-software","tag-ios","tag-ipad","tag-ipados","tag-iphone","tag-macbook","tag-macos","tag-tvos","tag-watchos"],"wp_featured_image":{"id":200537,"alt_text":"","description":"","media_type":"image","media_details":{"width":1920,"height":1080,"file":"2025\/06\/ios26.jpeg","filesize":1255666,"sizes":{"medium":{"file":"ios26-500x281.jpeg","width":500,"height":281,"mime-type":"image\/jpeg","filesize":42636,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26-500x281.jpeg"},"large":{"file":"ios26-810x456.jpeg","width":810,"height":456,"mime-type":"image\/jpeg","filesize":85926,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26-810x456.jpeg"},"thumbnail":{"file":"ios26-306x172.jpeg","width":306,"height":172,"mime-type":"image\/jpeg","filesize":20309,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26-306x172.jpeg"},"1536x1536":{"file":"ios26-1536x864.jpeg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":214466,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26-1536x864.jpeg"},"blog-large":{"file":"ios26-642x300.jpeg","width":642,"height":300,"mime-type":"image\/jpeg","filesize":50970,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26-642x300.jpeg"},"blog-medium":{"file":"ios26-306x205.jpeg","width":306,"height":205,"mime-type":"image\/jpeg","filesize":22998,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26-306x205.jpeg"},"recent-thumb":{"file":"ios26-350x316.jpeg","width":350,"height":316,"mime-type":"image\/jpeg","filesize":31341,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26-350x316.jpeg"},"service-featured":{"file":"ios26-600x330.jpeg","width":600,"height":330,"mime-type":"image\/jpeg","filesize":55081,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26-600x330.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":200536,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26.jpeg"},"commentcount":10,"wp_comments":[{"id":308606,"parent":0,"author":7119,"author_name":"KMenssen","author_email":"kmenssen@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/deda12b78e8453f3320f38ac92a30fad1f0c7c9c554a1d0bf20b756dcb05fab6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/deda12b78e8453f3320f38ac92a30fad1f0c7c9c554a1d0bf20b756dcb05fab6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/deda12b78e8453f3320f38ac92a30fad1f0c7c9c554a1d0bf20b756dcb05fab6?s=96&d=mm&r=g"},"date":"2025-07-25T11:16:52","cld_nonce":"b6d6726996","content":{"rendered":"<p>Moin, kann man sp\u00e4ter so von der Beta auf fertige Version wechseln oder ist das nicht so ohne weiteres m\u00f6glich ?<\/p>\n"},"status":"1"},{"id":308607,"parent":308606,"author":0,"author_name":"SecIT","author_email":"lmaa.werbung@aol.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0298fa4f901f639d70ee3161cd670553117f2b9b4badd1189ca2024bd4ef16fb?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0298fa4f901f639d70ee3161cd670553117f2b9b4badd1189ca2024bd4ef16fb?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0298fa4f901f639d70ee3161cd670553117f2b9b4badd1189ca2024bd4ef16fb?s=96&d=mm&r=g"},"date":"2025-07-25T11:22:33","cld_nonce":"b6d6726996","content":{"rendered":"<p>Doch das geht wunderbar  l\u00e4uft sehr stabil bis jetzt  iPad OS und Mac OS  etwas erstaunlich.<\/p>\n"},"status":"1"},{"id":308614,"parent":0,"author":10762,"author_name":"FR3D1","author_email":"b3nj4yb0y73ll3m@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c0d10fb3185dfea1bd87400d2d48320f04ffb2f250ec146413ce233c12dc6861?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c0d10fb3185dfea1bd87400d2d48320f04ffb2f250ec146413ce233c12dc6861?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c0d10fb3185dfea1bd87400d2d48320f04ffb2f250ec146413ce233c12dc6861?s=96&d=mm&r=g"},"date":"2025-07-25T12:05:10","cld_nonce":"b6d6726996","content":{"rendered":"<p>Moin!<\/p>\n<p>Da hat man sich doch zu \u201eLiquid Glass\u201c, aus Redmond inspirieren lassen? W\u00e4re sch\u00f6n, wenn so manches aus Vista in Windows zur\u00fcckkehren w\u00fcrde. Nat\u00fcrlich k\u00f6nnte man sich auch an der einen oder anderen Custom ROM (Android) orientiert (z.B.: CrDroid?) haben.<\/p>\n<p>Dort kann man das ganze sogar auf die Spitze treiben.<\/p>\n<p>Gru\u00df Fred.<\/p>\n"},"status":"1"},{"id":308615,"parent":308606,"author":0,"author_name":"Mr. CatTime","author_email":"m.b.1991@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b17b026a892957dc47d31dfdb01171d91dfd81400696437c3b8f0150e51dfe6b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b17b026a892957dc47d31dfdb01171d91dfd81400696437c3b8f0150e51dfe6b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b17b026a892957dc47d31dfdb01171d91dfd81400696437c3b8f0150e51dfe6b?s=96&d=mm&r=g"},"date":"2025-07-25T12:51:42","cld_nonce":"b6d6726996","content":{"rendered":"<p>Zum Finale kommt ein Golden Master Update das dann das Betaprogramm beendet und dein Ger\u00e4t wieder in den offiziellen Kanal schiebt. Deine Daten bleiben alle erhalten wie bei jedem normalen Update und du bekommst keine Betas mehr bis du dich selbst wieder f\u00fcr das Betaprogramm anmeldest. Gr\u00fc\u00dfe<\/p>\n"},"status":"1"},{"id":308618,"parent":0,"author":7119,"author_name":"KMenssen","author_email":"kmenssen@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/deda12b78e8453f3320f38ac92a30fad1f0c7c9c554a1d0bf20b756dcb05fab6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/deda12b78e8453f3320f38ac92a30fad1f0c7c9c554a1d0bf20b756dcb05fab6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/deda12b78e8453f3320f38ac92a30fad1f0c7c9c554a1d0bf20b756dcb05fab6?s=96&d=mm&r=g"},"date":"2025-07-25T13:03:32","cld_nonce":"b6d6726996","content":{"rendered":"<p>@all<br \/>\nvielen lieben Dank f\u00fcr die Infos &#8230; werde es heute Abend mal testen. Danke euch und sch\u00f6nen Freitag !<\/p>\n"},"status":"1"},{"id":308620,"parent":308614,"author":0,"author_name":"Jan","author_email":"jannomag@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/08a7005f7cf15759d2b52391983cddb4d03ac3c5274a40db84c6c8af96ef131d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/08a7005f7cf15759d2b52391983cddb4d03ac3c5274a40db84c6c8af96ef131d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/08a7005f7cf15759d2b52391983cddb4d03ac3c5274a40db84c6c8af96ef131d?s=96&d=mm&r=g"},"date":"2025-07-25T13:42:34","cld_nonce":"b6d6726996","content":{"rendered":"<p>Simple Transparenzeffekte \u2260 Liquid Glass.<\/p>\n<p>Ich verstehe nicht, warum diese beknackten vergleiche aufgestellt werden. Vista sieht ganz anders aus, als Liquid Glass, hat keinerlei Verzerreffekte und die Transparenz ist ebenfalls eine ganz andere. Und unter Windows 10\/11 gibts ebenfalls Transprenz, das wird jedoch komplett au\u00dfen vor gelassen.<\/p>\n<p>Und bei Android fehlen oft jegliche Effekte, da gibt\u2019s nur stumpfe Transparenz, ohne irgendwelche Unsch\u00e4rfe. Auch bei CrDroid sieht es nicht wirklich anders aus. Bei Samsung oder Xiaomi gibt es solche Effekte, aber alles anderes als konsequent und fl\u00fcssig animiert.<\/p>\n"},"status":"1"},{"id":308622,"parent":0,"author":6042,"author_name":"Skysoul","author_email":"skydragonx@aol.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/045b13fd3d1230e8f0fef5d1c0e8f5d4cfcecb8dbf1d39363c86038b9ca5b9ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/045b13fd3d1230e8f0fef5d1c0e8f5d4cfcecb8dbf1d39363c86038b9ca5b9ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/045b13fd3d1230e8f0fef5d1c0e8f5d4cfcecb8dbf1d39363c86038b9ca5b9ca?s=96&d=mm&r=g"},"date":"2025-07-25T14:25:07","cld_nonce":"b6d6726996","content":{"rendered":"<p>Es juckt mich wirklich in den Fingern die Public Beta auf meinem iPhone zu installieren <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_razz.gif\" alt=\":P\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":308624,"parent":308620,"author":0,"author_name":"Mr. CatTime","author_email":"m.b.1991@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b17b026a892957dc47d31dfdb01171d91dfd81400696437c3b8f0150e51dfe6b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b17b026a892957dc47d31dfdb01171d91dfd81400696437c3b8f0150e51dfe6b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b17b026a892957dc47d31dfdb01171d91dfd81400696437c3b8f0150e51dfe6b?s=96&d=mm&r=g"},"date":"2025-07-25T14:49:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>Das beste was man mit Tranzparenz machen kann und das auf jedem Ger\u00e4t und in jedem OS ist abschalten. Nicht nur weil dann alles besser l\u00e4uft sondern weil auch Farben dann deutlich besser dargestellt werden.<\/p>\n"},"status":"1"},{"id":308632,"parent":308606,"author":0,"author_name":"NBA20","author_email":"luftig-03-maschen@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d1a4d588ae20680e9020dc20b45f135fedceb7beba2f570892c9e06f9ca329ed?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d1a4d588ae20680e9020dc20b45f135fedceb7beba2f570892c9e06f9ca329ed?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d1a4d588ae20680e9020dc20b45f135fedceb7beba2f570892c9e06f9ca329ed?s=96&d=mm&r=g"},"date":"2025-07-25T16:03:35","cld_nonce":"b6d6726996","content":{"rendered":"<p>Jedes Jahr dieselbe Frage\u2026 <\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/apps.apple.com\/de\/app\/deskmodder\/id1478451921?l=de\" rel=\"nofollow ugc\">Deskmodder.de-App f\u00fcr iOS<\/a><\/i><\/p>\n"},"status":"1"},{"id":308727,"parent":0,"author":2819,"author_name":"KeyserSoze","author_email":"ahmedschlickum@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ea2aef017dab1e7b1a1fb5263914c0e19c5f81495b5196683aae99b329b9e46f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ea2aef017dab1e7b1a1fb5263914c0e19c5f81495b5196683aae99b329b9e46f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ea2aef017dab1e7b1a1fb5263914c0e19c5f81495b5196683aae99b329b9e46f?s=96&d=mm&r=g"},"date":"2025-07-27T13:03:34","cld_nonce":"b6d6726996","content":{"rendered":"<p>Anstatt dieses Glas, sollte lieber mal die M\u00f6glichkeit gegeben werden,<br \/>\ndie Lautst\u00e4rken einzeln einzustellen \u2026<\/p>\n"},"status":"1"}],"wp_author":{"id":4849,"name":"Jonas","description":"Angehender Systemadministrator und technikbegeistert. Lieblingsthemen? Netzwerktechnik und Windows. Anfragen an: jonas@deskmodder.de","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7c63b4d53b4b3cb64efbc10c186da49c9a5d422cda908d8a3b5d5e0cd8322634?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7c63b4d53b4b3cb64efbc10c186da49c9a5d422cda908d8a3b5d5e0cd8322634?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7c63b4d53b4b3cb64efbc10c186da49c9a5d422cda908d8a3b5d5e0cd8322634?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei - Deskmodder.de<\/title>\n<meta name=\"description\" content=\"Apple ver\u00f6ffentlicht die erste Public Beta f\u00fcr iPhone, iPad, MacBook und mehr mit zahlreichen Neuerungen und Verbesserungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei\" \/>\n<meta property=\"og:description\" content=\"Apple ver\u00f6ffentlicht die erste Public Beta f\u00fcr iPhone, iPad, MacBook und mehr mit zahlreichen Neuerungen und Verbesserungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-25T08:51:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jonasinfarbe\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/\"},\"author\":{\"name\":\"Jonas\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/687624f6860c8c88f71df1200fc24b44\"},\"headline\":\"Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei\",\"datePublished\":\"2025-07-25T08:51:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/\"},\"wordCount\":253,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ios26.jpeg\",\"keywords\":[\"Apple\",\"apple tv\",\"Apple Watch\",\"HomePod Software\",\"iOS\",\"iPad\",\"iPadOS\",\"Iphone\",\"macbook\",\"MacOS\",\"tvOS\",\"watchOS\"],\"articleSection\":[\"iOS\",\"Software &amp; Updates\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/\",\"name\":\"Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ios26.jpeg\",\"datePublished\":\"2025-07-25T08:51:51+00:00\",\"description\":\"Apple ver\u00f6ffentlicht die erste Public Beta f\u00fcr iPhone, iPad, MacBook und mehr mit zahlreichen Neuerungen und Verbesserungen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ios26.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ios26.jpeg\",\"width\":1920,\"height\":1080,\"caption\":\"Grafik: Apple\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2025\\\/07\\\/25\\\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/687624f6860c8c88f71df1200fc24b44\",\"name\":\"Jonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c63b4d53b4b3cb64efbc10c186da49c9a5d422cda908d8a3b5d5e0cd8322634?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c63b4d53b4b3cb64efbc10c186da49c9a5d422cda908d8a3b5d5e0cd8322634?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c63b4d53b4b3cb64efbc10c186da49c9a5d422cda908d8a3b5d5e0cd8322634?s=96&d=mm&r=g\",\"caption\":\"Jonas\"},\"description\":\"Angehender Systemadministrator und technikbegeistert. Lieblingsthemen? Netzwerktechnik und Windows. Anfragen an: jonas@deskmodder.de\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/jonasinfarbe\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwBwNTIXW94vTH2NZJWfETA\"],\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/jonas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei - Deskmodder.de","description":"Apple ver\u00f6ffentlicht die erste Public Beta f\u00fcr iPhone, iPad, MacBook und mehr mit zahlreichen Neuerungen und Verbesserungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/","og_locale":"de_DE","og_type":"article","og_title":"Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei","og_description":"Apple ver\u00f6ffentlicht die erste Public Beta f\u00fcr iPhone, iPad, MacBook und mehr mit zahlreichen Neuerungen und Verbesserungen.","og_url":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2025-07-25T08:51:51+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26.jpeg","type":"image\/jpeg"}],"author":"Jonas","twitter_card":"summary_large_image","twitter_creator":"@jonasinfarbe","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/"},"author":{"name":"Jonas","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/687624f6860c8c88f71df1200fc24b44"},"headline":"Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei","datePublished":"2025-07-25T08:51:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/"},"wordCount":253,"commentCount":10,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26.jpeg","keywords":["Apple","apple tv","Apple Watch","HomePod Software","iOS","iPad","iPadOS","Iphone","macbook","MacOS","tvOS","watchOS"],"articleSection":["iOS","Software &amp; Updates"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/","url":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/","name":"Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26.jpeg","datePublished":"2025-07-25T08:51:51+00:00","description":"Apple ver\u00f6ffentlicht die erste Public Beta f\u00fcr iPhone, iPad, MacBook und mehr mit zahlreichen Neuerungen und Verbesserungen.","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26.jpeg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26.jpeg","width":1920,"height":1080,"caption":"Grafik: Apple"},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2025\/07\/25\/apple-gibt-oeffentliche-beta-fuer-ios-26-und-mehr-frei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Apple gibt \u00f6ffentliche Beta f\u00fcr iOS 26 und mehr frei"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/687624f6860c8c88f71df1200fc24b44","name":"Jonas","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7c63b4d53b4b3cb64efbc10c186da49c9a5d422cda908d8a3b5d5e0cd8322634?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c63b4d53b4b3cb64efbc10c186da49c9a5d422cda908d8a3b5d5e0cd8322634?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c63b4d53b4b3cb64efbc10c186da49c9a5d422cda908d8a3b5d5e0cd8322634?s=96&d=mm&r=g","caption":"Jonas"},"description":"Angehender Systemadministrator und technikbegeistert. Lieblingsthemen? Netzwerktechnik und Windows. Anfragen an: jonas@deskmodder.de","sameAs":["https:\/\/x.com\/jonasinfarbe","https:\/\/www.youtube.com\/channel\/UCwBwNTIXW94vTH2NZJWfETA"],"url":"https:\/\/www.deskmodder.de\/blog\/author\/jonas\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2025\/06\/ios26.jpeg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/201629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/4849"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=201629"}],"version-history":[{"count":1,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/201629\/revisions"}],"predecessor-version":[{"id":201635,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/201629\/revisions\/201635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/200537"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=201629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=201629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=201629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}