{"id":195266,"date":"2024-12-03T10:26:47","date_gmt":"2024-12-03T09:26:47","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=195266"},"modified":"2024-12-03T10:27:37","modified_gmt":"2024-12-03T09:27:37","slug":"fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/","title":{"rendered":"FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen"},"content":{"rendered":"<p>Ist zwar selten, dass wir \u00fcber die AVM Apps berichten, aber gestern hat AVM die FRITZ!App Smart Home aktualisiert und viele neue Funktionen hinzugef\u00fcgt. Mit der App ist es unter anderem m\u00f6glich, die Temperaturen in der Wohnung zu regeln und einiges mehr.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2024\/12\/fritzapp-smart-home-neue-funktionen-scaled.jpg\" rel=\"lightbox[195266]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2024\/12\/fritzapp-smart-home-neue-funktionen-500x333.jpg\" alt=\"\" width=\"500\" height=\"333\" class=\"aligncenter size-medium wp-image-195268\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2024\/12\/fritzapp-smart-home-neue-funktionen-500x333.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2024\/12\/fritzapp-smart-home-neue-funktionen-810x540.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2024\/12\/fritzapp-smart-home-neue-funktionen-306x205.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2024\/12\/fritzapp-smart-home-neue-funktionen-1536x1024.jpg 1536w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2024\/12\/fritzapp-smart-home-neue-funktionen-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>In dieser Version wurden Funktionen hinzugef\u00fcgt, die bislang nur \u00fcber das browserbasierten FRITZ!OS einstellbar waren. Die neuen Funktionen sind laut Bericht von AVM:<\/p>\n<ul>\n<li>Heizpl\u00e4ne im \u00dcberblick: Das Highlight des Releases: Komfort- und Absenktemperaturen lassen sich nun \u00fcbersichtlich direkt per App konfigurieren und anpassen. Die intuitive Verwaltung der Heizpl\u00e4ne erleichtert das Einstellen von Zeitprofilen und sorgt f\u00fcr ein perfektes Raumklima rund um die Uhr.<\/li>\n<li>Externe Temperatursensoren und Offset-Einstellungen: Eine pr\u00e4zise Temperaturregelung dank der M\u00f6glichkeit, externe Temperatursensoren zu integrieren. Zus\u00e4tzlich k\u00f6nnen Nutzer die gemessene Temperatur am Heizk\u00f6rperregler individuell anpassen, um Schwankungen auszugleichen.<\/li>\n<li>Fenster-auf-Erkennung: \u00dcber die FRITZ!App Smart Home lassen sich ab sofort die Empfindlichkeit und die Ventilverschlie\u00dfzeit der Heizk\u00f6rperregler konfigurieren.<\/li>\n<li>Bedien-\/Tastensperre: Schutz vor ungewollten \u00c4nderungen der Heizregler durch eine Sperrung der Tasten, ideal f\u00fcr Haushalte mit Kindern.<\/li>\n<li>Adaptiver Heizbeginn: Durch die Vorheizphase wird der gew\u00fcnschte Komfort zur richtigen Zeit erreicht, ganz automatisch.<\/li>\n<li>Temperaturbegrenzung: Bevorzugter Temperaturbereich f\u00fcr mehr Effizienz \u2013 die einstellbare Temperaturbegrenzung verhindert zu hohe oder zu niedrige Temperaturen bei manueller Bedienung der Heizk\u00f6rperregler.<\/li>\n<li>Erstellung und Verwaltung von Gruppen: Mehr Ordnung im Smart Home. Heizk\u00f6rperregler k\u00f6nnen jetzt auch \u00fcber die FRITZ!App Smart Home in Gruppen zusammengefasst werden \u2013 f\u00fcr eine zentrale Steuerung und mehr \u00dcbersichtlichkeit.<\/li>\n<\/ul>\n<p>Die App werdet ihr sicherlich schon haben. Hier aber noch einmal die Links zur <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=de.avm.android.smarthome\" target=\"_blank\">Android App<\/a> und <a href=\"https:\/\/apps.apple.com\/de\/app\/id1477824478\" target=\"_blank\">iOS App<\/a>. Die \u00dcbersicht aller Funktionen findet ihr <a href=\"https:\/\/avm.de\/produkte\/apps\/fritzapp-smart-home\/\" target=\"_blank\">hier<\/a>.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/avm.de\/unternehmen\/presse\/presseinformationen\/2024\/12\/noch-komfortabler-flexibler-und-effizienter-neue-funktionen-fuer-die-heizkoerperreglersteuerung-in-der-fritzapp-smart-home\/\" target=\"_blank\">avm.de<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ist zwar selten, dass wir \u00fcber die AVM Apps berichten, aber gestern hat AVM die FRITZ!App Smart Home aktualisiert und viele neue Funktionen hinzugef\u00fcgt. Mit der App ist es unter anderem m\u00f6glich, die Temperaturen in der Wohnung zu regeln und&hellip; <\/p>\n","protected":false},"author":134,"featured_media":139760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[894,232],"tags":[74813],"class_list":["post-195266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-android","category-ios","tag-fritzapp-smart-home"],"wp_featured_image":{"id":139760,"alt_text":"","description":"","media_type":"image","media_details":{"width":2560,"height":1707,"file":"2020\/06\/avm-fritzapp-smart-home-im-garten-scaled.jpg","sizes":{"medium":{"file":"avm-fritzapp-smart-home-im-garten-500x333.jpg","width":500,"height":333,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-500x333.jpg"},"large":{"file":"avm-fritzapp-smart-home-im-garten-810x540.jpg","width":810,"height":540,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-810x540.jpg"},"thumbnail":{"file":"avm-fritzapp-smart-home-im-garten-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-306x205.jpg"},"1536x1536":{"file":"avm-fritzapp-smart-home-im-garten-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-1536x1024.jpg"},"2048x2048":{"file":"avm-fritzapp-smart-home-im-garten-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-2048x1365.jpg"},"wp_review_large":{"file":"avm-fritzapp-smart-home-im-garten-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-320x200.jpg"},"wp_review_small":{"file":"avm-fritzapp-smart-home-im-garten-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-65x65.jpg"},"blog-large":{"file":"avm-fritzapp-smart-home-im-garten-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-642x300.jpg"},"blog-medium":{"file":"avm-fritzapp-smart-home-im-garten-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-306x205.jpg"},"recent-thumb":{"file":"avm-fritzapp-smart-home-im-garten-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-350x316.jpg"},"service-featured":{"file":"avm-fritzapp-smart-home-im-garten-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-600x330.jpg"},"wp_rp_thumbnail":{"file":"avm-fritzapp-smart-home-im-garten-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"iStock.com \/ Prykhodov \/ AVM Gmb","camera":"","caption":"","created_timestamp":"-62167219200","copyright":"Die Verwendung dieses Bildes ist f\u00fcr redaktionelle Zwecke honorarfrei. Verwendbar bis 06\/2023.\rUse of this image for editorial","focal_length":"0","iso":"0","shutter_speed":"0","title":"FRITZ!App Smart Home","orientation":"1","keywords":["FRITZ!","FRITZ!Box","fritzbox","Fritz-box","Smart-Home-Zentrale","smart home hub","gateway","unterwegs und zuhause","remote access","iOS","Apple","Android","Heimnetz","home network","Heimnetzwerk","Heimvernetzung","Netzwerk","Home Automation","sicher verschl\u00fcsselt","securely","encrypted","FRITZ!App","FRITZ!OS","\u00dcbersicht","schalten und steuern","switch and control","FRITZ!DECT","automatic updates","automatische Updates","Lichtsystem","lighting system","smart Lampen","smart bulb","comfort","Komfort","energieeffizient","energy efficient"]},"original_image":"avm-fritzapp-smart-home-im-garten.jpg"},"post":139753,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-scaled.jpg"},"commentcount":4,"wp_comments":[{"id":290436,"parent":0,"author":8815,"author_name":"renegade2k","author_email":"stask85@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e5417f01ba4c60ea48f2958209b5ac5237a0061bb1c14997ed744d613d1df36b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e5417f01ba4c60ea48f2958209b5ac5237a0061bb1c14997ed744d613d1df36b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e5417f01ba4c60ea48f2958209b5ac5237a0061bb1c14997ed744d613d1df36b?s=96&d=mm&r=g"},"date":"2024-12-03T11:45:38","cld_nonce":"b6d6726996","content":{"rendered":"<p>Im Beta-Kanal waren die \u00c4nderungen schon l\u00e4nger verf\u00fcgbar.<br \/>\nist echt gut geworden. Vor allem die Einstellung der Heizperioden ist sehr intuitiv und \u00fcberschaubar.<\/p>\n"},"status":"1"},{"id":290442,"parent":0,"author":0,"author_name":"Karl","author_email":"karlvomhorst@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/55ec583a597eecb954112dbad198e9f7975893fab28a81210323b01bc0e2d66c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/55ec583a597eecb954112dbad198e9f7975893fab28a81210323b01bc0e2d66c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/55ec583a597eecb954112dbad198e9f7975893fab28a81210323b01bc0e2d66c?s=96&d=mm&r=g"},"date":"2024-12-03T14:08:53","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich mache zwar prim\u00e4r alle Konfigs am PC, aber die App ist hier sehr gut weiterentwickelt. Sch\u00f6n, wenn AVM ihre Leistungen so weiterpflegen.<\/p>\n"},"status":"1"},{"id":290444,"parent":0,"author":0,"author_name":"John Doe","author_email":"JohnDoe@byom.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9429233739f733737d86793092d2b8fa3f164c22d0ba56df9406c07e934ec2e5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9429233739f733737d86793092d2b8fa3f164c22d0ba56df9406c07e934ec2e5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9429233739f733737d86793092d2b8fa3f164c22d0ba56df9406c07e934ec2e5?s=96&d=mm&r=g"},"date":"2024-12-03T14:55:51","cld_nonce":"b6d6726996","content":{"rendered":"<p>In der aktuellen Android App Version 1.8.0 habe ich keine Option &#8222;Temperaturbegrenzung&#8220;.<br \/>\nIn dem Update f\u00fcr iOS 2.3.0 ist die Option vorhanden.<\/p>\n"},"status":"1"},{"id":290493,"parent":0,"author":0,"author_name":"Daniel","author_email":"d_richter@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c43ef05c7f05da9102b8e229536977f37bffe6905494f5850fb41dabfc20c608?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c43ef05c7f05da9102b8e229536977f37bffe6905494f5850fb41dabfc20c608?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c43ef05c7f05da9102b8e229536977f37bffe6905494f5850fb41dabfc20c608?s=96&d=mm&r=g"},"date":"2024-12-04T10:34:11","cld_nonce":"b6d6726996","content":{"rendered":"<p>\u00c4rgerlich f\u00fcr alle Nutzer der 7490, die es ja noch zahlreich gibt &#8230;<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen\" \/>\n<meta property=\"og:description\" content=\"Ist zwar selten, dass wir \u00fcber die AVM Apps berichten, aber gestern hat AVM die FRITZ!App Smart Home aktualisiert und viele neue Funktionen hinzugef\u00fcgt. Mit der App ist es unter anderem m\u00f6glich, die Temperaturen in der Wohnung zu regeln und&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-03T09:26:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-03T09:27:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen\",\"datePublished\":\"2024-12-03T09:26:47+00:00\",\"dateModified\":\"2024-12-03T09:27:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/\"},\"wordCount\":301,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/avm-fritzapp-smart-home-im-garten-scaled.jpg\",\"keywords\":[\"FRITZ!App Smart Home\"],\"articleSection\":[\"Android\",\"iOS\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/\",\"name\":\"FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/avm-fritzapp-smart-home-im-garten-scaled.jpg\",\"datePublished\":\"2024-12-03T09:26:47+00:00\",\"dateModified\":\"2024-12-03T09:27:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/avm-fritzapp-smart-home-im-garten-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/avm-fritzapp-smart-home-im-garten-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/12\\\/03\\\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/","og_locale":"de_DE","og_type":"article","og_title":"FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen","og_description":"Ist zwar selten, dass wir \u00fcber die AVM Apps berichten, aber gestern hat AVM die FRITZ!App Smart Home aktualisiert und viele neue Funktionen hinzugef\u00fcgt. Mit der App ist es unter anderem m\u00f6glich, die Temperaturen in der Wohnung zu regeln und&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2024-12-03T09:26:47+00:00","article_modified_time":"2024-12-03T09:27:37+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-scaled.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen","datePublished":"2024-12-03T09:26:47+00:00","dateModified":"2024-12-03T09:27:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/"},"wordCount":301,"commentCount":4,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-scaled.jpg","keywords":["FRITZ!App Smart Home"],"articleSection":["Android","iOS"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/","url":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/","name":"FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-scaled.jpg","datePublished":"2024-12-03T09:26:47+00:00","dateModified":"2024-12-03T09:27:37+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-scaled.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2024\/12\/03\/fritzapp-smart-home-fuer-android-und-ios-mit-neuen-funktionen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"FRITZ!App Smart Home f\u00fcr Android und iOS mit neuen Funktionen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/avm-fritzapp-smart-home-im-garten-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/195266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=195266"}],"version-history":[{"count":3,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/195266\/revisions"}],"predecessor-version":[{"id":195270,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/195266\/revisions\/195270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/139760"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=195266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=195266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=195266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}