{"id":190276,"date":"2024-06-28T19:10:46","date_gmt":"2024-06-28T17:10:46","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=190276"},"modified":"2024-06-29T07:11:00","modified_gmt":"2024-06-29T05:11:00","slug":"windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/","title":{"rendered":"Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO"},"content":{"rendered":"<p>Wieder zwei Wochen vorbei und Zeit f\u00fcr eine neue Windows Server. Diesmal ist es wie bei der Windows 11 Canary die Windows Server 2025 26244 LTSC vNext. Wie schon seit einiger Zeit, stellt Microsoft keine SDK, ADK oder andere ISOs zur Verf\u00fcgung.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/windows-server-logo.png\" rel=\"lightbox[190276]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/windows-server-logo-500x299.png\" alt=\"\" width=\"500\" height=\"299\" class=\"aligncenter size-medium wp-image-137242\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/windows-server-logo-500x299.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/windows-server-logo-306x183.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/windows-server-logo.png 650w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Die Infos zu dieser neuen Version werden dann <a href=\"https:\/\/techcommunity.microsoft.com\/t5\/windows-server-insiders\/bd-p\/WindowsServerInsiders\" rel=\"noopener\" target=\"_blank\">hier erscheinen<\/a><\/p>\n<h3>Keys, f\u00fcr die Installation:<\/h3>\n<ul>\n<li>Die Server-Version ist bis zum 15.09.2024 lauff\u00e4hig.<\/li>\n<li>Server Standard: MFY9F-XBN2F-TYFMP-CCV49-RMYVH<\/li>\n<li>Datacenter: 2KNJJ-33Y9H-2GXGX-KMQWH-G6H67\n<ul>\n<li>Die Azure Version akzeptiert keine Keys.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3>Manueller Download der Windows Server 2025 26244 LTSC vNext ISO<\/h3>\n<ul>\n<li>Die Links sind tempor\u00e4r und bis 28.06.2024, bis etwa 23.00 Uhr g\u00fcltig. (Leider hat MS die Zeiten von 24 auf 4 Stunden gek\u00fcrzt).<\/li>\n<li>Hinweis: Solltet ihr die aktuelle Windows 2022 Server ISO suchen, die findet ihr <a href=\"https:\/\/www.deskmodder.de\/blog\/2021\/11\/17\/windows-server-2022-ltsc-supportstart-infos-und-neue-isos\/\" rel=\"noopener\" target=\"_blank\">immer hier<\/a>. Die 26100.1 inkl. LOF_Packages ISO immer hier.<\/li>\n<li><a href=\"https:\/\/software.download.prss.microsoft.com\/dbazure\/Windows_InsiderPreview_Server_vNext_de-de_26244.iso?t=c115f2a8-d794-4d7a-90f9-b65121ef0605&#038;P1=1719652140&#038;P2=601&#038;P3=2&#038;P4=VLfm%2feIdAG24B7OnxkWwtGAXq6qH694%2fgzsqMEP49CqBQn3rBgdT%2fNyfmNVozF6YhztWjf2AqgvQI2S8l%2fZeJXVvrm%2byLYe3jvmvnVaDiUfGR6eNuILd%2fborRL8cGHEUlV6GVeLGpFwqZ212IcKk%2f4fKsQTDnsbpNUqhQ3bOaGOUk2ABhQ24DNvt7Yx%2fViiciJ8K6hUbRfirABj55fEBHY2Nmd9OqvuOd6R6nxsfr9TvIdO475ieBGDoXvd%2flPVyNgu7revfQEYdBHG34LgwLdOOC%2fnTYfdIBGN40IGcQHWMWhRK1UrTEI4ZtVdN2Ymjbtu30U%2fXlp52yPxL%2f%2bm0sw%3d%3d\" rel=\"noopener\" target=\"_blank\">Windows_InsiderPreview_Server_vNext_de-de_26244.iso<\/a><\/li>\n<li><a href=\"https:\/\/software.download.prss.microsoft.com\/dbazure\/Windows_InsiderPreview_Server_vNext_en-us_26244.iso?t=9d0f41fb-7ea6-4860-813a-dbf4a682e850&#038;P1=1719652181&#038;P2=601&#038;P3=2&#038;P4=UN3gKHcldwHF0P5YWBWxJRkVfFaO2YBN53OSQdlpXKYXHvhXt4OPWvgiPNeHwIzq%2fFUELspF0nJTtk9QPA2B%2beya7MYdV5KgGb6GU92TJuhWJLEYEqioSkwkIhEu%2bymSZM3g0GMJTRUaxzVdF0vEBfRr3xfscUwSEo2JY5uABYYydPiW2eQF1qIf78xIztzIYgKzz12qpLoMFC9nxF8Qv9Y10jjW9hMjNVq7ycFRZAo39Y7pFfNJOUCd9P83iPbyo9sjnGfmZ5AYnZDGKd7LxN17ydZBHkhi4Y2MygDZOv9LQRKl2Z2b5wNI87SkdH1%2fA8Up5d4%2fmJRsCDtDjZtQ%2fw%3d%3d\" rel=\"noopener\" target=\"_blank\">Windows_InsiderPreview_Server_vNext_en-us_26244.iso<\/a><\/li>\n<li><a href=\"https:\/\/software.download.prss.microsoft.com\/dbazure\/Windows_InsiderPreview_ServerDatacenter_en-us_VHDX_26244.vhdx?t=fbf19b2d-d0a0-4829-b7a9-4ce47817732a&#038;P1=1719652224&#038;P2=601&#038;P3=2&#038;P4=bSw0uwuWpCgIyMhJly%2bpHVaCwrFjh6ijDn3HCxMxfB6F%2bsAUXqL5NYKmL37GZlobElq6DrV7eVZZPJaleqAmAfuBHieUHoU%2beOLuYeZoYZDVbHf0QAKS5LNosBvyUAQNckN2F2TAjkCPJXaDmlUiOAKm2N2OTYnxKIyLXpy04mFZw4IFNf7eV%2bbuBM7Zq8JvNXdUsTg17EI9dbsILmuLvTNxfIfYR5TeM%2fi6ykQBRonsAfPivNrUecqI2yvDiUDFArJBQm%2f9XjOb4%2boOc5RF1HSyDTEMgYxcYCw2dmr%2buHhIwgGcib7hGhxLYHg57%2bse34xnl3%2fnCGyOr1hTfeXldg%3d%3d\" rel=\"noopener\" target=\"_blank\">Windows_InsiderPreview_ServerDatacenter_en-us_VHDX_26244.vhdx<\/a><\/li>\n<li><a href=\"https:\/\/software.download.prss.microsoft.com\/dbazure\/Windows_InsiderPreview_ServerDatacenter_Azure_Edition_en-us_26244.iso?t=321d66d2-42d2-4dac-89e4-10ad2784e46a&#038;P1=1719608842&#038;P2=601&#038;P3=2&#038;P4=jTADeQuqBHdnK6CkVvLzst6NkDBPqcbTZfLlFMdU%2BvfyCev3XVEgRbzLgTODXVBX9nbZeKRvpLRHzzbEDsIQb8wTNyLiUoAfsnIMuVwmFynx6FleX9nYMD8AbtrkQE%2BhWsACqEnGGWGIjq6MFFuIm6elgIzEJCNLDKXkH72ccYZHd6%2FFvDI1GDF6CVzAJFIqdzlXrxoxk1%2FE9Y8slLUu3RbG57CDPEFzpLgL%2FFPG7Id%2BaGL9TiZ%2B0PW7VeOFSpQHkFvl%2BI8QupOBsvBl6n1XyZjUIzyXK7zNkXvch2GVhxuzeK3HK4vXEzMjUb4RHGuQQxWndk5NM3gv7L1nzU6BLw%3D%3D\" rel=\"noopener\" target=\"_blank\">Windows_InsiderPreview_ServerDatacenter_Azure_Edition_en-us_26244.iso<\/a><\/li>\n<li><a href=\"https:\/\/software.download.prss.microsoft.com\/dbazure\/Windows_InsiderPreview_ServerDatacenter_Azure_Edition_en-us_VHDX_26244.vhdx?t=d11e429b-663f-4a3e-8351-e9f17c5cec1f&#038;P1=1719608895&#038;P2=601&#038;P3=2&#038;P4=l7uvaeiAvKSgiKXy77siiWPiAMRMjkKkT9MfOpaaM4KkNhNjeoGBx9%2BbUkGqC6grtchyuNPsU8HUSAoUMpBj3%2B8E51YUr4PsZt0%2BR3UVkZZrJQs556%2F4V%2Fmy3RIlhaFQ%2B9HCjSFWBkmfDxS1ib9jp7cpxqu1GcxnoIErkmlSpX2C4WFtRQDf5Bz468bkHRYZnqaDtzP3ihpU2hpOHIQlgon8%2F0jh4qpO2yQS15qp15ewt9d56mVer9bvpYlLZFU5ktR9%2Byn98ICsyGqjLdynXTI2AwXC39Dfe%2BfCfotVL4txNDzHRJTkRWkvyeOR7Er4ll45ZpBTg1w1whWULG6qJw%3D%3D\" rel=\"noopener\" target=\"_blank\">Windows_InsiderPreview_ServerDatacenter_Azure_Edition_en-us_VHDX_26244.vhdx<\/a><\/li>\n<li><a href=\"https:\/\/software.download.prss.microsoft.com\/dbazure\/Microsoft_Server_InsiderPreview_LangPack_FOD_26244.iso?t=d1e57920-7108-4b64-930a-5120dc4dff81&#038;P1=1719608935&#038;P2=601&#038;P3=2&#038;P4=qjATI7hWyVoCREOVA8KqdugbxSmx8oLbtucTAvpuBR395FyuWmUL4RmP60TaCAX1J5zCdeIGs1mPT9fmIIeBSsZLK6FFNjF4BR8c4apLjtWfQC5ZKl%2FbTY515naWcm8x0qn74j2TCBB%2BzLoFffatZbIpusn%2FzWjYxTn%2B2Xxe%2BE0tHZNGK3xwondCNajLzgtYXQkhdcIVaToAD%2FpEc7MGjejgiTzEqgeyxMwDXgm70JGZsX6DvjQc1hxgJMgxUUZgB0ZnnHTh%2BJXvH6DrWRtmy89dbFdXWwjaDoFTLrXA9L%2BTGVUD3%2FCUf4zHGmX3FeN5L9bi3H2PojPPwkJkKo0l3Q%3D%3D\" rel=\"noopener\" target=\"_blank\">Microsoft_Server_InsiderPreview_LangPack_FOD_26244.iso<\/a><\/li>\n<\/ul>\n<h3>Windows 11 Tutorials und Hilfe<\/h3>\n<ul>\n<li>In unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 11 Wiki<\/a> findet ihr sehr viele hilfreiche Tipps und Tricks.<\/li>\n<li>Falls ihr Fragen habt, dann stellt diese ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=353\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Forum<\/strong><\/a>.<\/li>\n<li><strong>Installationsmedien:<\/strong> Aktuelle Windows 11 ISOs findet ihr hier: <a href=\"https:\/\/www.deskmodder.de\/blog\/2023\/05\/26\/windows-11-22631-iso-esd-deutsch-english-inkl-updates-23h2-moment-4\/\" rel=\"noopener\" target=\"_blank\">23H2 22631<\/a>, oder <a href=\"https:\/\/www.deskmodder.de\/blog\/2024\/04\/27\/windows-11-24h2-26100-iso-esd-deutsch-english\/%22\" rel=\"noopener\" target=\"_blank\">24H2 26100<\/a>. Ansonsten immer in der rechten Sidebar.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_neu_clean_installieren_Tipps_und_Tricks\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 neu clean installieren Tipps und Tricks<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_mit_einem_lokalen_oder_Microsoft_Konto_installieren\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 mit lokalem Konto auch Offline installieren<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_11_Inplace_Upgrade_Reparatur_oder_Feature_Update\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Windows 11 Inplace Upgrade Reparatur oder Feature Update<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Automatisch_anmelden_Pin_entfernen_Windows_11\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Automatisch anmelden Pin entfernen Windows 11<\/strong><\/a>.<\/li>\n<li>Alle Beitr\u00e4ge zu Windows 11 im Blog findet ihr <a href=\"https:\/\/www.deskmodder.de\/blog\/category\/windows-11\/\" rel=\"noopener\" target=\"_blank\">\u00fcber diese Seite<\/a>. Wobei auch <a href=\"https:\/\/www.deskmodder.de\/blog\/\" rel=\"noopener\" target=\"_blank\">alle anderen Artikel<\/a> interessant sein k\u00f6nnen.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Wieder zwei Wochen vorbei und Zeit f\u00fcr eine neue Windows Server. Diesmal ist es wie bei der Windows 11 Canary die Windows Server 2025 26244 LTSC vNext. Wie schon seit einiger Zeit, stellt Microsoft keine SDK, ADK oder andere ISOs&hellip; <\/p>\n","protected":false},"author":134,"featured_media":150401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[80310],"tags":[89256,38872,78520,88032],"class_list":["post-190276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-11","tag-89256","tag-ltsc","tag-vnext","tag-windows-server-2025"],"wp_featured_image":{"id":150401,"alt_text":"","description":"","media_type":"image","media_details":{"width":500,"height":299,"file":"2021\/02\/windows-server-logo-500x299-1.png","sizes":{"thumbnail":{"file":"windows-server-logo-500x299-1-306x183.png","width":306,"height":183,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1-306x183.png"},"blog-medium":{"file":"windows-server-logo-500x299-1-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1-306x205.png"},"recent-thumb":{"file":"windows-server-logo-500x299-1-350x299.png","width":350,"height":299,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1-350x299.png"},"wp_rp_thumbnail":{"file":"windows-server-logo-500x299-1-50x50.png","width":50,"height":50,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1-50x50.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":150332,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1.png"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"af1c80fd5f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO\" \/>\n<meta property=\"og:description\" content=\"Wieder zwei Wochen vorbei und Zeit f\u00fcr eine neue Windows Server. Diesmal ist es wie bei der Windows 11 Canary die Windows Server 2025 26244 LTSC vNext. Wie schon seit einiger Zeit, stellt Microsoft keine SDK, ADK oder andere ISOs&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-28T17:10:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-29T05:11:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"299\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO\",\"datePublished\":\"2024-06-28T17:10:46+00:00\",\"dateModified\":\"2024-06-29T05:11:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/\"},\"wordCount\":274,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/windows-server-logo-500x299-1.png\",\"keywords\":[\"26244\",\"LTSC\",\"vNEXT\",\"Windows Server 2025\"],\"articleSection\":[\"Windows 11\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/\",\"name\":\"Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/windows-server-logo-500x299-1.png\",\"datePublished\":\"2024-06-28T17:10:46+00:00\",\"dateModified\":\"2024-06-29T05:11:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/windows-server-logo-500x299-1.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/windows-server-logo-500x299-1.png\",\"width\":500,\"height\":299},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2024\\\/06\\\/28\\\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/","og_locale":"de_DE","og_type":"article","og_title":"Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO","og_description":"Wieder zwei Wochen vorbei und Zeit f\u00fcr eine neue Windows Server. Diesmal ist es wie bei der Windows 11 Canary die Windows Server 2025 26244 LTSC vNext. Wie schon seit einiger Zeit, stellt Microsoft keine SDK, ADK oder andere ISOs&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2024-06-28T17:10:46+00:00","article_modified_time":"2024-06-29T05:11:00+00:00","og_image":[{"width":500,"height":299,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO","datePublished":"2024-06-28T17:10:46+00:00","dateModified":"2024-06-29T05:11:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/"},"wordCount":274,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1.png","keywords":["26244","LTSC","vNEXT","Windows Server 2025"],"articleSection":["Windows 11"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/","url":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/","name":"Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1.png","datePublished":"2024-06-28T17:10:46+00:00","dateModified":"2024-06-29T05:11:00+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1.png","width":500,"height":299},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2024\/06\/28\/windows-server-2025-26244-ltsc-vnext-als-neue-insider-und-auch-als-iso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows Server 2025 26244 LTSC vNext als neue Insider und auch als ISO"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/02\/windows-server-logo-500x299-1.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/190276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=190276"}],"version-history":[{"count":2,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/190276\/revisions"}],"predecessor-version":[{"id":190302,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/190276\/revisions\/190302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/150401"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=190276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=190276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=190276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}