{"id":180916,"date":"2023-08-15T18:39:30","date_gmt":"2023-08-15T16:39:30","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=180916"},"modified":"2023-08-15T18:40:26","modified_gmt":"2023-08-15T16:40:26","slug":"google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/","title":{"rendered":"Google Chrome 116 116.0.5845.96 \/ .97 korrigiert 26 Sicherheitsl\u00fccken"},"content":{"rendered":"<p>Nachdem letzte Woche die Erly Stable erschien, kommt jetzt der Google Chrome 116 116.0.5845.96 \/ .97 in der finalen Version f\u00fcr alle. Insgesamt sind es mal wieder 26 Sicherheitsl\u00fccken, die Google geschlossen hat. Auch wieder gemeldet und daf\u00fcr mit bis zu 30.000 Dollar entlohnt.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png\" rel=\"lightbox[180916]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-500x333.png\" alt=\"\" width=\"500\" height=\"333\" class=\"aligncenter size-medium wp-image-162181\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-500x333.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-306x205.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png 600w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Von diesen Sicherheitsl\u00fccken sind 8, die mit &#8222;High&#8220; eingestuft wurden. 14 mit &#8222;Medium&#8220; und &#8222;nur&#8220; zwei mit &#8222;Low&#8220;. Auch der Chrome f\u00fcr iOS (116.0.5845.103) hat ein Update erhalten. Eine Info f\u00fcr die Android-Version fehlt derzeit noch. Aber wie immer kann man davon ausgehen, dass auch hier diese 26 Sicherheitsl\u00fccken geschlossen wurden.<\/p>\n<p>Wie immer gibt es die einzelnen Hinweise zu den L\u00fccken erst sp\u00e4ter, wenn der Gro\u00dfteil mit der neuen Version unterwegs ist. Und auch hier noch einmal der Hinweis, dass es ab Version 116 jetzt w\u00f6chentliche Sicherheitsupdates gibt. Wir hatten es ja schon im vorherigen Beitrag <a href=\"https:\/\/www.deskmodder.de\/blog\/2023\/08\/10\/google-chrome-116-early-stable-ab-jetzt-woechentliche-sicherheitsupdates\/\" rel=\"noopener\" target=\"_blank\">ausf\u00fchrlich beschrieben<\/a>.<\/p>\n<h3>Info und Download:<\/h3>\n<ul>\n<li><a href=\"https:\/\/chromereleases.googleblog.com\/2023\/08\/stable-channel-update-for-desktop_15.html\" rel=\"noopener\" target=\"_blank\">googleblog.com\/stable-channel-update-for-desktop<\/a><\/li>\n<li><a href=\"https:\/\/chromereleases.googleblog.com\/2023\/08\/chrome-stable-for-ios-update_15.html\" rel=\"noopener\" target=\"_blank\">googleblog.com\/chrome-stable-for-ios-update<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem letzte Woche die Erly Stable erschien, kommt jetzt der Google Chrome 116 116.0.5845.96 \/ .97 in der finalen Version f\u00fcr alle. Insgesamt sind es mal wieder 26 Sicherheitsl\u00fccken, die Google geschlossen hat. Auch wieder gemeldet und daf\u00fcr mit bis&hellip; <\/p>\n","protected":false},"author":134,"featured_media":162181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166],"tags":[86600,86601,86599],"class_list":["post-180916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","tag-116-0-5845-96","tag-116-0-5845-97","tag-google-chrome-116"],"wp_featured_image":{"id":162181,"alt_text":"","description":"","media_type":"image","media_details":{"width":600,"height":400,"file":"2022\/02\/google-chrome-logo-neu.png","sizes":{"medium":{"file":"google-chrome-logo-neu-500x333.png","width":500,"height":333,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-500x333.png"},"thumbnail":{"file":"google-chrome-logo-neu-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-306x205.png"},"blog-large":{"file":"google-chrome-logo-neu-600x300.png","width":600,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-600x300.png"},"blog-medium":{"file":"google-chrome-logo-neu-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-306x205.png"},"recent-thumb":{"file":"google-chrome-logo-neu-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-350x316.png"},"service-featured":{"file":"google-chrome-logo-neu-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-600x330.png"},"wp_rp_thumbnail":{"file":"google-chrome-logo-neu-50x50.png","width":50,"height":50,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu-50x50.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":162618,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png"},"commentcount":1,"wp_comments":[{"id":253072,"parent":0,"author":5818,"author_name":"alles","author_email":"alles.geheim@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=96&d=mm&r=g"},"date":"2023-08-23T10:03:59","cld_nonce":"b6d6726996","content":{"rendered":"<p>Google Chrome 116.0.5845.111<\/p>\n<p><a href=\"https:\/\/chromeenterprise.google\/intl\/de_de\/browser\/download\/\" rel=\"nofollow ugc\">https:\/\/chromeenterprise.google\/intl\/de_de\/browser\/download\/<\/a><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Google Chrome 116 116.0.5845.96 \/ .97 korrigiert 26 Sicherheitsl\u00fccken - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Chrome 116 116.0.5845.96 \/ .97 korrigiert 26 Sicherheitsl\u00fccken\" \/>\n<meta property=\"og:description\" content=\"Nachdem letzte Woche die Erly Stable erschien, kommt jetzt der Google Chrome 116 116.0.5845.96 \/ .97 in der finalen Version f\u00fcr alle. Insgesamt sind es mal wieder 26 Sicherheitsl\u00fccken, die Google geschlossen hat. Auch wieder gemeldet und daf\u00fcr mit bis&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-15T16:39:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-15T16:40:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Google Chrome 116 116.0.5845.96 \\\/ .97 korrigiert 26 Sicherheitsl\u00fccken\",\"datePublished\":\"2023-08-15T16:39:30+00:00\",\"dateModified\":\"2023-08-15T16:40:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/\"},\"wordCount\":157,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/google-chrome-logo-neu.png\",\"keywords\":[\"116.0.5845.96\",\"116.0.5845.97\",\"Google Chrome 116\"],\"articleSection\":[\"Browser\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/\",\"name\":\"Google Chrome 116 116.0.5845.96 \\\/ .97 korrigiert 26 Sicherheitsl\u00fccken - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/google-chrome-logo-neu.png\",\"datePublished\":\"2023-08-15T16:39:30+00:00\",\"dateModified\":\"2023-08-15T16:40:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/google-chrome-logo-neu.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/google-chrome-logo-neu.png\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2023\\\/08\\\/15\\\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google Chrome 116 116.0.5845.96 \\\/ .97 korrigiert 26 Sicherheitsl\u00fccken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Google Chrome 116 116.0.5845.96 \/ .97 korrigiert 26 Sicherheitsl\u00fccken - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/","og_locale":"de_DE","og_type":"article","og_title":"Google Chrome 116 116.0.5845.96 \/ .97 korrigiert 26 Sicherheitsl\u00fccken","og_description":"Nachdem letzte Woche die Erly Stable erschien, kommt jetzt der Google Chrome 116 116.0.5845.96 \/ .97 in der finalen Version f\u00fcr alle. Insgesamt sind es mal wieder 26 Sicherheitsl\u00fccken, die Google geschlossen hat. Auch wieder gemeldet und daf\u00fcr mit bis&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2023-08-15T16:39:30+00:00","article_modified_time":"2023-08-15T16:40:26+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Google Chrome 116 116.0.5845.96 \/ .97 korrigiert 26 Sicherheitsl\u00fccken","datePublished":"2023-08-15T16:39:30+00:00","dateModified":"2023-08-15T16:40:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/"},"wordCount":157,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","keywords":["116.0.5845.96","116.0.5845.97","Google Chrome 116"],"articleSection":["Browser"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/","url":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/","name":"Google Chrome 116 116.0.5845.96 \/ .97 korrigiert 26 Sicherheitsl\u00fccken - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","datePublished":"2023-08-15T16:39:30+00:00","dateModified":"2023-08-15T16:40:26+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2023\/08\/15\/google-chrome-116-116-0-5845-96-97-korrigiert-26-sicherheitsluecken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Google Chrome 116 116.0.5845.96 \/ .97 korrigiert 26 Sicherheitsl\u00fccken"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/02\/google-chrome-logo-neu.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/180916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=180916"}],"version-history":[{"count":2,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/180916\/revisions"}],"predecessor-version":[{"id":180918,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/180916\/revisions\/180918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/162181"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=180916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=180916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=180916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}