{"id":17554,"date":"2013-12-26T19:20:10","date_gmt":"2013-12-26T18:20:10","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=17554"},"modified":"2013-12-26T19:20:10","modified_gmt":"2013-12-26T18:20:10","slug":"chromebooks-erreichen-20-marktanteil-in-den-usa","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/","title":{"rendered":"Chromebooks erreichen 20% Marktanteil in den USA"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch.png\" rel=\"lightbox[17554]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-16114\" alt=\"chromebook touch\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch-150x89.png\" width=\"150\" height=\"89\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch-150x89.png 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch.png 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Google und seine Hardwarepartner k\u00f6nnen in den USA einen Erfolg verzeichnen: Die Chromebooks machten in den USA bei den Notebookverk\u00e4ufen von Januar bis November ungef\u00e4hr 20 Prozent aus. Dies will zumindest die <a href=\"https:\/\/www.npd.com\/wps\/portal\/npd\/us\/news\/press-releases\/u-s-commercial-channel-computing-device-sales-set-to-end-2013-with-double-digit-growth-according-to-npd\/\" target=\"_blank\">NPD Group<\/a>\u00a0ermittelt haben und erkl\u00e4rt weiter, dass in diesem Jahr doppelt so viele\u00a0PCs (Chromebooks und Android-Tablets)\u00a0mit einem Betriebssystem von Google verkauft wurden wie im vergangenen Jahr. <!--more--><\/p>\n<p>\u00dcbrigens: Als gr\u00f6\u00dfter Einzelanbieter bei Notebook-Neuverk\u00e4ufen hat\u00a0sich in den\u00a0Vereinigten Staaten Apple etabliert. Laut NPD Group erreicht das MacBook Air im Bereich der Ultrabooks \u00fcber <a href=\"http:\/\/appleinsider.com\/articles\/13\/07\/01\/npd-apples-macbook-air-most-popular-thin-and-light-notebook-with-56-percent-share-of-market\" target=\"_blank\">56 Prozent<\/a>\u00a0Marktanteil. Insgesamt liegt der Wert jedoch auch\u00a0niedriger.<\/p>\n<p>Nebenbei tauchte ein bisher unbekanntes Chromebook <a href=\"https:\/\/plus.google.com\/103350553702836331911\/posts\/DUKSpY7cw7C\" target=\"_blank\">im Netz<\/a> von Toshiba mit 13,3 Zoll\u00a0zu einem Preis von 280 Dollar auf. Hierbei handelt es sich um das erste Chromebook des japanischen Herstellers, welches allerdings erst 2014 auf der CES vorgestellt werden soll.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google und seine Hardwarepartner k\u00f6nnen in den USA einen Erfolg verzeichnen: Die Chromebooks machten in den USA bei den Notebookverk\u00e4ufen von Januar bis November ungef\u00e4hr 20 Prozent aus. Dies will zumindest die NPD Group\u00a0ermittelt haben und erkl\u00e4rt weiter, dass in&hellip; <\/p>\n","protected":false},"author":1525,"featured_media":16114,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286,231],"tags":[9747,3795,128],"class_list":["post-17554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","category-mobile","tag-android","tag-chromebook","tag-google"],"wp_featured_image":{"id":16114,"alt_text":"","description":"","media_type":"image","media_details":{"width":500,"height":298,"file":"2013\/11\/chromebook-touch.png","sizes":{"thumbnail":{"file":"chromebook-touch-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch-150x150.png"},"medium":{"file":"chromebook-touch-150x89.png","width":150,"height":89,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch-150x89.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":16092,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch.png"},"commentcount":0,"wp_comments":[],"wp_author":{"id":1525,"name":"W8U","description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"}},"cld_nonce":"af1c80fd5f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chromebooks erreichen 20% Marktanteil in den USA - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chromebooks erreichen 20% Marktanteil in den USA\" \/>\n<meta property=\"og:description\" content=\"Google und seine Hardwarepartner k\u00f6nnen in den USA einen Erfolg verzeichnen: Die Chromebooks machten in den USA bei den Notebookverk\u00e4ufen von Januar bis November ungef\u00e4hr 20 Prozent aus. Dies will zumindest die NPD Group\u00a0ermittelt haben und erkl\u00e4rt weiter, dass in&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-26T18:20:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"298\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"W8U\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/\"},\"author\":{\"name\":\"W8U\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\"},\"headline\":\"Chromebooks erreichen 20% Marktanteil in den USA\",\"datePublished\":\"2013-12-26T18:20:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/\"},\"wordCount\":145,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/chromebook-touch.png\",\"keywords\":[\"Android\",\"chromebook\",\"Google\"],\"articleSection\":{\"1\":\"Hardware\",\"2\":\"Mobile\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/#respond\"]}],\"copyrightYear\":\"2013\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/\",\"name\":\"Chromebooks erreichen 20% Marktanteil in den USA - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/chromebook-touch.png\",\"datePublished\":\"2013-12-26T18:20:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/chromebook-touch.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/chromebook-touch.png\",\"width\":500,\"height\":298},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/26\\\/chromebooks-erreichen-20-marktanteil-in-den-usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chromebooks erreichen 20% Marktanteil in den USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\",\"name\":\"W8U\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"caption\":\"W8U\"},\"description\":\"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/w8u\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chromebooks erreichen 20% Marktanteil in den USA - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/","og_locale":"de_DE","og_type":"article","og_title":"Chromebooks erreichen 20% Marktanteil in den USA","og_description":"Google und seine Hardwarepartner k\u00f6nnen in den USA einen Erfolg verzeichnen: Die Chromebooks machten in den USA bei den Notebookverk\u00e4ufen von Januar bis November ungef\u00e4hr 20 Prozent aus. Dies will zumindest die NPD Group\u00a0ermittelt haben und erkl\u00e4rt weiter, dass in&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2013-12-26T18:20:10+00:00","og_image":[{"width":500,"height":298,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch.png","type":"image\/png"}],"author":"W8U","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/"},"author":{"name":"W8U","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469"},"headline":"Chromebooks erreichen 20% Marktanteil in den USA","datePublished":"2013-12-26T18:20:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/"},"wordCount":145,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch.png","keywords":["Android","chromebook","Google"],"articleSection":{"1":"Hardware","2":"Mobile"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/#respond"]}],"copyrightYear":"2013","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/","url":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/","name":"Chromebooks erreichen 20% Marktanteil in den USA - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch.png","datePublished":"2013-12-26T18:20:10+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch.png","width":500,"height":298},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/26\/chromebooks-erreichen-20-marktanteil-in-den-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Chromebooks erreichen 20% Marktanteil in den USA"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469","name":"W8U","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","caption":"W8U"},"description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","url":"https:\/\/www.deskmodder.de\/blog\/author\/w8u\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/chromebook-touch.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/17554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=17554"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/17554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/16114"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=17554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=17554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=17554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}