{"id":17345,"date":"2013-12-23T10:10:23","date_gmt":"2013-12-23T09:10:23","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=17345"},"modified":"2013-12-23T10:10:23","modified_gmt":"2013-12-23T09:10:23","slug":"bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/","title":{"rendered":"Bing ver\u00f6ffentlicht die besten &#8222;Bing Wallpaper&#8220; aus 2013"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/UnderwaterMangrove1920x1200.jpg\" rel=\"lightbox[17345]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-17355\" alt=\"UnderwaterMangrove1920x1200\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/UnderwaterMangrove1920x1200-150x93.jpg\" width=\"150\" height=\"93\" \/><\/a>Bing hat sich in diesem Jahr ganz sch\u00f6n &#8222;gemausert&#8220; und pers\u00f6nlich muss ich sagen, dass mir die Startseite mit den Wallpapern und den Informationen, welche man dar\u00fcber bereits zum Bild abrufen kann, wirklich sehr gut gef\u00e4llt.<\/p>\n<p>Nun hat man einmal alle Bilder zusammengefasst und daraus die besten Wallpaper bereitgestellt. Wie oft wurde ein Bild angeklickt oder geteilt &#8211; das waren letztlich die Kriterien, welche die besten Bilder ausgemacht haben.<\/p>\n<p><!--more--><\/p>\n<p>Das komplette Pack der Bilder stellt Microsoft <a href=\"http:\/\/www.microsoft.com\/en-us\/download\/details.aspx?id=41556&amp;WT.mc_id=rss_alldownloads_all\" target=\"_blank\">HIER<\/a> zum kostenlosen Download bereit.<\/p>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bing hat sich in diesem Jahr ganz sch\u00f6n &#8222;gemausert&#8220; und pers\u00f6nlich muss ich sagen, dass mir die Startseite mit den Wallpapern und den Informationen, welche man dar\u00fcber bereits zum Bild abrufen kann, wirklich sehr gut gef\u00e4llt. Nun hat man einmal&hellip; <\/p>\n","protected":false},"author":1462,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[4040,1640,2730,3446,94],"class_list":["post-17345","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-best-of","tag-bilder","tag-bing","tag-hintergrundbild","tag-wallpaper"],"wp_featured_image":null,"commentcount":1,"wp_comments":[{"id":4370,"parent":0,"author":134,"author_name":"&#109;&#111;&#105;&#110;&#109;&#111;&#105;&#110;","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2013-12-23T13:48:09","cld_nonce":"82f011626f","content":{"rendered":"<p>Kleiner Tipp, wer es nicht installieren will.<\/p>\n<p>&#8211; DefaultPack.exe mit 7zip entpacken<br \/>\n&#8211; Danach die Bestof2013BingHomepages.cab entpacken und im Ordner befinden sich dann alle Wallpaper. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"}],"wp_author":{"id":null,"name":null,"description":null,"author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bing ver\u00f6ffentlicht die besten &quot;Bing Wallpaper&quot; aus 2013 - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bing ver\u00f6ffentlicht die besten &quot;Bing Wallpaper&quot; aus 2013\" \/>\n<meta property=\"og:description\" content=\"Bing hat sich in diesem Jahr ganz sch\u00f6n &#8222;gemausert&#8220; und pers\u00f6nlich muss ich sagen, dass mir die Startseite mit den Wallpapern und den Informationen, welche man dar\u00fcber bereits zum Bild abrufen kann, wirklich sehr gut gef\u00e4llt. Nun hat man einmal&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-23T09:10:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/UnderwaterMangrove1920x1200-150x93.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bing ver\u00f6ffentlicht die besten &#8222;Bing Wallpaper&#8220; aus 2013\",\"datePublished\":\"2013-12-23T09:10:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/\"},\"wordCount\":99,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/UnderwaterMangrove1920x1200-150x93.jpg\",\"keywords\":[\"Best of\",\"Bilder\",\"Bing\",\"Hintergrundbild\",\"Wallpaper\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/#respond\"]}],\"copyrightYear\":\"2013\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/\",\"name\":\"Bing ver\u00f6ffentlicht die besten \\\"Bing Wallpaper\\\" aus 2013 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/UnderwaterMangrove1920x1200-150x93.jpg\",\"datePublished\":\"2013-12-23T09:10:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/UnderwaterMangrove1920x1200-150x93.jpg\",\"contentUrl\":\"http:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/UnderwaterMangrove1920x1200-150x93.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/23\\\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bing ver\u00f6ffentlicht die besten &#8222;Bing Wallpaper&#8220; aus 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bing ver\u00f6ffentlicht die besten \"Bing Wallpaper\" aus 2013 - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/","og_locale":"de_DE","og_type":"article","og_title":"Bing ver\u00f6ffentlicht die besten \"Bing Wallpaper\" aus 2013","og_description":"Bing hat sich in diesem Jahr ganz sch\u00f6n &#8222;gemausert&#8220; und pers\u00f6nlich muss ich sagen, dass mir die Startseite mit den Wallpapern und den Informationen, welche man dar\u00fcber bereits zum Bild abrufen kann, wirklich sehr gut gef\u00e4llt. Nun hat man einmal&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2013-12-23T09:10:23+00:00","og_image":[{"url":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/UnderwaterMangrove1920x1200-150x93.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/"},"author":{"name":"","@id":""},"headline":"Bing ver\u00f6ffentlicht die besten &#8222;Bing Wallpaper&#8220; aus 2013","datePublished":"2013-12-23T09:10:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/"},"wordCount":99,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/#primaryimage"},"thumbnailUrl":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/UnderwaterMangrove1920x1200-150x93.jpg","keywords":["Best of","Bilder","Bing","Hintergrundbild","Wallpaper"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/#respond"]}],"copyrightYear":"2013","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/","url":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/","name":"Bing ver\u00f6ffentlicht die besten \"Bing Wallpaper\" aus 2013 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/#primaryimage"},"thumbnailUrl":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/UnderwaterMangrove1920x1200-150x93.jpg","datePublished":"2013-12-23T09:10:23+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/#primaryimage","url":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/UnderwaterMangrove1920x1200-150x93.jpg","contentUrl":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/UnderwaterMangrove1920x1200-150x93.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/23\/bing-veroeffentlicht-die-besten-bing-wallpaper-aus-2013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Bing ver\u00f6ffentlicht die besten &#8222;Bing Wallpaper&#8220; aus 2013"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"","url":"https:\/\/www.deskmodder.de\/blog\/author\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/17345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1462"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=17345"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/17345\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=17345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=17345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=17345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}